{"id":100061,"date":"2025-10-04T12:00:32","date_gmt":"2025-10-04T10:00:32","guid":{"rendered":"https:\/\/tomajazz.com\/web\/?p=100061"},"modified":"2025-10-04T10:51:31","modified_gmt":"2025-10-04T08:51:31","slug":"fieldwork-thereupon-pi-recordings-2025","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/fieldwork-thereupon-pi-recordings-2025\/","title":{"rendered":"Fieldwork: Thereupon (Pi Recordings; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]"},"content":{"rendered":"<p>Tres innovadores de la m\u00fasica contempor\u00e1nea: el saxofonista alto y compositor Steve Lehman, el pianista y compositor Vijay Iyer y el baterista y compositor Tyshawn Sorey, o lo que es lo mismo, el tr\u00edo Fieldwork, han vuelto a grabar. Han pasado diecisiete a\u00f1os desde la publicaci\u00f3n del brillante <em>Door<\/em> (Pi Recordings, 2008). Los tres han escalado durante este tiempo a la cumbre del panorama musical internacional a trav\u00e9s de sus respectivos proyectos y colaboraciones. Si cada uno por separado ha recibido elogios de la cr\u00edtica y aficionados a nivel mundial, como grupo, los calificativos se multiplican de forma exponencial. La pena es que hayan tardado tanto tiempo en reunirse para ofrecernos joyas como la que supone <em>Thereupon<\/em> (Pi Recordings, 2025), donde vuelven a dar una vuelta de tuerca a sus aportaciones a la m\u00fasica creativa.<\/p>\n<p>En palabras de Vijay Iyer, en Fieldwork \u00abhace mucho tiempo que nos decidimos por un enfoque que simplemente aprovecha al m\u00e1ximo la creatividad de cada uno de nosotros\u00bb. Y a\u00f1ade, que el secreto del tr\u00edo se centra en potenciar la imaginaci\u00f3n colectiva de los m\u00fasicos, a trav\u00e9s de un sistema de trabajo basado en un proceso de ensayo comunitario, en el que se realizan improvisaciones grupales. Reflexionando sobre su profundo v\u00ednculo musical, Steve Lehman, por su parte, se\u00f1ala que \u00abhay un sentimiento abrumador de alegr\u00eda cada vez que nos reunimos. Hemos desarrollado un lenguaje musical juntos a lo largo de los a\u00f1os para que nunca tengamos que explicarnos o contextualizar nada. Inmediatamente construimos juntos a partir de nuestra historias y comenzamos a hacer avanzar las cosas\u00bb.<\/p>\n<p>Para poner en contexto a Fieldwork hay que indicar que le debe mucho a la naturaleza exploratoria del c\u00e9lebre colectivo AACM. Sus tres miembros han colaborado en bandas lideradas por Muhal Richard Abrams, Anthony Braxton, Henry Threadgill, Roscoe Mitchell, Wadada Leo Smith y George Lewis, entre otros.<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-100062 size-medium\" title=\"Fieldwork: Thereupon (Pi Recordings; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] Tomajazz Fieldwork Thereupon 2025 Pi Recordings Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-300x300.jpg\" alt=\"Fieldwork: Thereupon (Pi Recordings; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Thereupon (Pi Recordings; 2025) es lo nuevo del innovador tr\u00edo Fieldwork. Carlos Lara repasa la grabaci\u00f3n. Fieldwork son Vijay Iyer, Steve Lehman, Tyshawn Sorey\" width=\"300\" height=\"300\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-768x768.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz-500x500.jpg 500w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Thereupon<\/em> presenta composiciones de Iyer y Lehman, con arreglos colectivos de la banda. Fieldwork ha adquirido un sonido caracter\u00edstico que marca cada una de las piezas, con independencia de qui\u00e9n la haya compuesto. El estilo del grupo se define como denso, visceral, estrechamente unificado y de alto impacto, con una misteriosa l\u00f3gica interna.<\/p>\n<p>Steve Lehman explora los registros extremos de su instrumento mediante l\u00edneas espirales con uso frecuente de t\u00e9cnicas extendidas y digitaciones microtonales. Vijay Iyer en el piano y Rhodes act\u00faa como un motor que expande notas de forma caleidosc\u00f3pica en su variedad arm\u00f3nica y t\u00edmbrica. Tyshawn Sorey es el bater\u00eda del momento y el que mejor forma presenta. Aqu\u00ed reparte su virtuosismo y proporciona un impulso inventivo sin fin y dirigiendo la m\u00fasica en todo momento con sutileza y matices.<\/p>\n<p>El disco es un monumento a la interacci\u00f3n musical a trav\u00e9s de una red de lazos, tejidos durante d\u00e9cadas. El grupo funciona como una sola entidad, sin jerarqu\u00edas. El desarrollo y las respuestas de unos a otros se realizan con un enfoque, intensidad y creatividad admirables. En temas como \u00abPropaganda\u00bb y \u00abEmbracing Difference\u00bb, se establece una tensi\u00f3n r\u00edtmica que marca el nivel general del disco. En el primero, los tres m\u00fasicos inician la pieza al un\u00edsono. Enseguida el saxo y el piano se bifurcan, mientras el bater\u00eda ocupa en\u00e9rgicamente los espacios. Es un tema que apela al v\u00e9rtigo y a la intranquilidad. En el segundo tema hay improvisaciones no lineales del piano con fraseos largos en espiral del saxo. El bater\u00eda demuestra su categor\u00eda con una inabarcable tarea de seguir el ritmo que le marcan el saxo y el piano. Vijay Iyer explora diferentes campos hasta extremos, siempre acompa\u00f1ado por el saxofonista. El engranaje del grupo nunca se tambalea y, cuando parece que el edificio no puede sostenerse, el grupo endereza de tal manera que el ritmo se mantiene coherente.<\/p>\n<p>El tema \u00abThereupon\u00bb se inspira, seg\u00fan Iyer, en \u00abun momento cerca del comienzo del Sutra de Vimalakirti (libro del budismo Mahayana), cuando se muestra que el mundo es mucho m\u00e1s de lo que parece: Acto seguido, el Buda toc\u00f3 el suelo de este universo gal\u00e1ctico de mil millones de mundos con su dedo gordo del pie, y de repente se transform\u00f3 en una enorme masa de joyas preciosas, una magn\u00edfica variedad de muchos cientos de miles de racimos de gemas preciosas&#8230;\u00bb. Este tema no deja de sorprender, ya que empieza con el piano en un tono grandilocuente y el saxo matizando todo el rato con fraseos en espiral. La bater\u00eda proporciona tal variedad de recursos y con una energ\u00eda que los tres m\u00fasicos deb\u00edan estar gozando de la sincron\u00eda encontrada. El tema llega a un punto \u00e1lgido con los tres instrumentos creando un todo compacto.<\/p>\n<p>Piezas como \u00abAstral\u00bb suponen momentos de calma en la vor\u00e1gine. El piano y la bater\u00eda entran primero y el saxo recoge el testigo en un comienzo a modo de falsa balada. El piano vuelve al primer plano y el saxo, en modo l\u00edrico, se va expandiendo, mientras que el tema va creciendo hasta cotas m\u00e1s altas. Cada uno de los m\u00fasicos aporta sus recursos creativos que enriquecen constantemente al grupo.<\/p>\n<p>Muy destacable es \u00abThe Night Before\u00bb, el tema m\u00e1s largo del disco. Es intrigante y misterioso, con el Rhodes haciendo efectos y el saxo con fraseos lentos. La pieza se desarrolla de forma pausada en un ambiente semiespacial, casi de corte n\u00f3rdico. En la propuesta sobresale un magistral solo de Lehman que nos introduce por caminos misteriosos en los que el Rhodes y la bater\u00eda contribuyen a potenciar el espacio atmosf\u00e9rico creado. Poco a poco, la luz se va acercando, el tema se va clarificando y acaba muy lentamente.<\/p>\n<p>Con este nuevo cap\u00edtulo, Fieldwork reafirma su estatus como una de las bandas m\u00e1s experimentales, transformadoras e influyentes de la \u00e9poca. Una nueva demostraci\u00f3n de que este tr\u00edo se encuentra en una dimensi\u00f3n diferente y dif\u00edcil de catalogar, porque los m\u00fasicos exprimen al m\u00e1ximo su capacidad creativa y con cada disco no dejan de sorprender. Ojal\u00e1 no tengamos que esperar otros diecisiete a\u00f1os para gozar de su nuevo trabajo.<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <strong>Carlos Lara<\/strong>, 2025<\/p>\n<hr \/>\n<h3>Fieldwork: <em>Thereupon<\/em><\/h3>\n<p>M\u00fasicos: Steve Lehman (saxo alto), Vijay Iyer (piano y Rhodes) y Tyshawn Sorey (bater\u00eda).<\/p>\n<p>Composiciones: \u201cPropaganda\u201d, \u201cEmbracing Difference\u201d, \u201cEvening Rite\u201d, \u201cFire City\u201d, \u201cDomain\u201d, \u201cFantome\u201d, \u201cAstral\u201d, \u201cAstral\u201d, \u201cAstral\u201d,\u201cThereupon\u201d y \u201cThe Night Before\u201d.<br \/>\nLos temas \u201cPropaganda\u201d, \u201cEvening Rite\u201d, \u201cFire City\u201d, \u201cThereupon\u201d y \u201cThe Night Before\u201d fueron compuestos por Vijay Iyer. Los temas \u201cEmbracing Difference\u201d, \u201cDomain\u201d, \u201cFantome\u201d y \u201cAstral\u201d, compuestos por Steve Lehman.<\/p>\n<p>Grabado el 13 de mayo de 2024, en Oktaven Audio en Mount Vernon (N.Y.).\u00a0Editado por Pi Recordings en 2025.\u00a0PI109<\/p>\n<hr \/>\n<h3>M\u00e1s sobre Fieldwork<\/h3>\n<p>La rese\u00f1a se ha realizado con consultas a rese\u00f1as y entrevistas publicadas en Tomajazz.<\/p>\n<p>El tr\u00edo Fieldwork se cre\u00f3 en el verano de 2000 en Nueva York. La primera formaci\u00f3n estaba compuesta por Vijay Iyer al piano, Aaron Stewart al saxo tenor y Ellio Humberto Kavee a la bater\u00eda. Su primer disco fue <em>Your Life Flashes<\/em> (Pi Recordings, 2002). El siguiente trabajo, <em>Simulated Progress<\/em> (Pi Recordings, 2004), fue grabado por Vijay Iyer (piano), Steve Lehman (saxo alto) y Ellio Humberto Kavee (bater\u00eda). El tercero fue <em>Door<\/em> (Pi Recordings, 2008), ya con la actual formaci\u00f3n.<\/p>\n<hr \/>\n<h3>M\u00e1s informaci\u00f3n sobre Fieldwork y Pi Recordings<\/h3>\n<p><a href=\"https:\/\/fieldworktheband.bandcamp.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/fieldworktheband.bandcamp.com\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=fieldwork&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=fieldwork&amp;submit=Search<\/a><\/p>\n<p><a href=\"https:\/\/pirecordings.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pirecordings.com\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=pi+recordings&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=pi+recordings&amp;submit=Search<\/a><\/p>\n<h3>Carlos Lara en Tomajazz<\/h3>\n<p><a href=\"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/category\/carlos-lara\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thereupon (Pi Recordings; 2025) es lo nuevo del innovador tr\u00edo Fieldwork. Carlos Lara repasa la grabaci\u00f3n. Fieldwork son Vijay Iyer, Steve Lehman, Tyshawn Sorey <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/fieldwork-thereupon-pi-recordings-2025\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":100062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,15517,1038],"tags":[84,6648,6335,6649,6864,1230],"class_list":["entry","author-pachi","has-excerpt","post-100061","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-textos","category-contenidos","tag-carlos-lara","tag-fieldwork","tag-pi-recordings","tag-steve-lehman","tag-tyshawn-sorey","tag-vijay-iyer"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Fieldwork-Thereupon-2025-Pi-Recordings-Tomajazz.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103232,"url":"https:\/\/tomajazz.com\/web\/steve-lehman-the-music-of-anthony-braxton-2025\/","url_meta":{"origin":100061,"position":0},"title":"Steve Lehman Trio + Mark Turner: The Music of Anthony Braxton (Pi Recordings: 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"8 enero, 2026","format":false,"excerpt":"The Music of Anthony Braxton (Pi Recordings: 2025) es lo nuevo de Steve Lehman Trio + Mark Turner. Carlos Lara repasa la grabaci\u00f3n. Con Steve Lehman, Mark Turner, Matt Brewer, Damion Reid","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Steve Lehman Trio + Mark Turner: The Music of Anthony Braxton (Pi Recordings: 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - The Music of Anthony Braxton (Pi Recordings: 2025) es lo nuevo de Steve Lehman Trio + Mark Turner. Carlos Lara repasa la grabaci\u00f3n. Con Steve Lehman, Mark Turner, Matt Brewer, Damion Reid","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Steve-Lehman-Trio-Mark-Turner-The-Music-of-Anthony-Braxton-Pi-Recordings-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Steve-Lehman-Trio-Mark-Turner-The-Music-of-Anthony-Braxton-Pi-Recordings-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Steve-Lehman-Trio-Mark-Turner-The-Music-of-Anthony-Braxton-Pi-Recordings-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Steve-Lehman-Trio-Mark-Turner-The-Music-of-Anthony-Braxton-Pi-Recordings-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":32304,"url":"https:\/\/tomajazz.com\/web\/hdo-312-vijay-iyer-nate-wooley-tim-berne-de-voces-personales-y-de-lo-mejor-de-2017-podcast\/","url_meta":{"origin":100061,"position":1},"title":"HDO 312. Vijay Iyer, Nate Wooley, Tim Berne: de voces personales (y de lo mejor de 2017) [Podcast]","author":"Tomajazz","date":"20 septiembre, 2017","format":false,"excerpt":"Tres voces personales en la entrega 312 con tres grabaciones reci\u00e9n estrenadas, y todas ellas m\u00e1s que recomendables, puesto que es muy elevado el grado de verosimilitud de que las tres est\u00e9n entre lo mejor del a\u00f1o 2017 en esas listas que comenzar\u00e1n a aparecer unos meses antes del final\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/09\/Tim-Bernes-Snakeoil_Incidentals_ECM_2017-e1505843271619.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/09\/Tim-Bernes-Snakeoil_Incidentals_ECM_2017-e1505843271619.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/09\/Tim-Bernes-Snakeoil_Incidentals_ECM_2017-e1505843271619.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":56280,"url":"https:\/\/tomajazz.com\/web\/jazzx5235-vijay-iyer-tyshawn-sorey-linda-may-han-oh-drummers-song-uneasy-ecm-2021-minipodcast-por-pachi-tapiz\/","url_meta":{"origin":100061,"position":2},"title":"JazzX5#235. Vijay Iyer, Tyshawn Sorey, Linda May Han Oh: \u00abDrummer&#8217;s Song\u00bb [Uneasy (ECM, 2021)] [Minipodcast] Por Pachi Tapiz","author":"Tomajazz","date":"9 agosto, 2021","format":false,"excerpt":"En JazzX5 la composici\u00f3n de Geri Allen \"Drummer's Song\" interpretada por el tr\u00edo formado por Vijay Iyer, Tyshawn Sorey, Linda May Han Oh que aparece en la grabaci\u00f3n Uneasy (ECM, 2021)","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/08\/JazzX5_235.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/08\/JazzX5_235.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/08\/JazzX5_235.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/08\/JazzX5_235.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":99816,"url":"https:\/\/tomajazz.com\/web\/linda-may-han-oh-strange-heavens-2025\/","url_meta":{"origin":100061,"position":3},"title":"Linda May Han Oh, Ambrose Akinmusire &#038; Tyshawn Sorey: Strange Heavens (Biophilia Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"29 septiembre, 2025","format":false,"excerpt":"Strange Heavens (Biophilia Records, 2025), es el nuevo disco de Linda May Han Oh. Carlos Lara repasa la grabaci\u00f3n. Con Linda May Han Oh, Ambrose Akinmusire, Tyshawn Sorey","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Linda May Han Oh, Ambrose Akinmusire & Tyshawn Sorey: Strange Heavens (Biophilia Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Strange Heavens (Biophilia Records, 2025), es el nuevo disco de Linda May Han Oh. Carlos Lara repasa la grabaci\u00f3n. Con Linda May Han Oh, Ambrose Akinmusire & Tyshawn Sorey:","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10967,"url":"https:\/\/tomajazz.com\/web\/en-la-casa-del-mundo-lxxiii-dream-of-an-ex-ranger-william-newton-ma-vijay-iyer-mike-ladd-2013\/","url_meta":{"origin":100061,"position":4},"title":"En La Casa del Mundo (LXXIII): \u201cDream Of An Ex-Ranger (William, Newton, MA)\u201d (Vijay Iyer &#038; Mike Ladd, 2013)","author":"Tomajazz","date":"11 marzo, 2014","format":false,"excerpt":"En Holding It Down: The Veteran's Dreams Project (Pi Recordings, 2013), la tercera entrega de la colaboraci\u00f3n entre el artista de hip-hop y poeta Mike Ladd, y el pianista y compositor Vijay Iyer, el leit-motiv son los sue\u00f1os (en muchos casos pesadillas debido al s\u00edndrome de stress post-traum\u00e1tico) de los\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Vijay Iyer - Mike Ladd_Holding It Down","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/Vijay-Iyer-Mike-Ladd_Holding-It-Down-200x182.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":100336,"url":"https:\/\/tomajazz.com\/web\/lluis-vidal-barcelona-art-orchestra-osmosi-fsr-2025\/","url_meta":{"origin":100061,"position":5},"title":"Lluis Vidal &#038; Barcelona Art Orchestra: Osmosi (Poema sonor i visual per a big band i dibuix en transformaci\u00f3) (Fresh Sound Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"10 octubre, 2025","format":false,"excerpt":"Osmosi (Fresh Sound Records; 2025) es la nueva grabaci\u00f3n de Lluis Vidal & Barcelona Art Orchestra. Carlos Lara repasa la grabaci\u00f3n","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Lluis Vidal & Barcelona Art Orchestra: Osmosi (Poema sonor i visual per a big band i dibuix en transformaci\u00f3) (Fresh Sound Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Osmosi (Fresh Sound Records; 2025) es la nueva grabaci\u00f3n de Lluis Vidal & Barcelona Art Orchestra. Carlos Lara repasa la grabaci\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Lluis-Vidal-Barcelona-Art-Orchestra-Osmosi-Fresh-Sound-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Lluis-Vidal-Barcelona-Art-Orchestra-Osmosi-Fresh-Sound-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Lluis-Vidal-Barcelona-Art-Orchestra-Osmosi-Fresh-Sound-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Lluis-Vidal-Barcelona-Art-Orchestra-Osmosi-Fresh-Sound-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/100061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=100061"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/100061\/revisions"}],"predecessor-version":[{"id":100064,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/100061\/revisions\/100064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/100062"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=100061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=100061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=100061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}