{"id":101856,"date":"2025-11-17T12:30:49","date_gmt":"2025-11-17T11:30:49","guid":{"rendered":"https:\/\/tomajazz.com\/web\/?p=101856"},"modified":"2025-11-17T02:08:50","modified_gmt":"2025-11-17T01:08:50","slug":"myra-melford-splash-2025","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/myra-melford-splash-2025\/","title":{"rendered":"Myra Melford: Splash (Intakt Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]"},"content":{"rendered":"<p><em>Splash<\/em> es el \u00faltimo \u00e1lbum liderado por la pianista y compositora Myra Melford, junto con el contrabajista Michael Formanek y el baterista y vibrafonista Ches Smith. Adem\u00e1s, es la primera colaboraci\u00f3n de Melford con el sello suizo Intakt Records. Esta formaci\u00f3n en tr\u00edo marca un nuevo cap\u00edtulo en la trayectoria de la pianista de Illinois, una figura fundamental en la vanguardia del jazz contempor\u00e1neo, especialmente en su exploraci\u00f3n continua de la conexi\u00f3n entre la m\u00fasica y otras disciplinas art\u00edsticas, como en este caso la pintura.<\/p>\n<p>Seg\u00fan Melford, la inspiraci\u00f3n principal del proyecto le viene del pintor postexpresionista estadounidense Cy Twombly (1928-2011). Sus obras se encuentran en las colecciones permanentes del Museo de Arte Moderno de Nueva York y el Museo del Louvre en Par\u00eds. Melford no hace una traducci\u00f3n literal del arte de Twombly al sonido, sino que busca capturar la gestualidad, el movimiento, la energ\u00eda y la espontaneidad que caracterizan sus lienzos. La pianista ha pretendido en este \u00e1lbum hacer una disposici\u00f3n ca\u00f3tica pero deliberada de las formas y evoca tanto tensi\u00f3n como fluidez, caracter\u00edsticas del enfoque abstracto y cargado de emociones de la pintura de Twombly. La cubierta del disco es una parte de la obra de este artista, titulada \u00abLepanto, Parte III\u00bb, que fue pintada en 2001.<\/p>\n<p>En el interior del disco se escribe que \u00abel tr\u00edo es capaz de evocar el dinamismo gestual y la creciente volatilidad que le da al trabajo de Twombly gran parte de su poder\u00bb. El expresivo rango de timbres, ya que Formanek toca el arco y Smith alterna el vibr\u00e1fono con la bater\u00eda, crea opciones de tr\u00edo de c\u00e1mara para Melford, como compositora e improvisadora. El resultado es una m\u00fasica de encantadora belleza, que oscila entre la pintura sonora y la reflexi\u00f3n abstracta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-101857 size-medium\" title=\"Myra Melford: Splash (Intakt Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] Tomajazz Myra Melford Splash Intakt Records; 2025 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-300x300.jpg\" alt=\"Myra Melford: Splash (Intakt Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Splash (Intakt Records; 2025) es la \u00faltima grabaci\u00f3n de Myra Melford. Carlos Lara lo repasa. Con Myra Melford, Ches Smith, Michael Formanek\" width=\"300\" height=\"300\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-768x768.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz-500x500.jpg 500w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>El disco tiene 10 temas, en los que se alternan composiciones m\u00e1s densas con tres \u00abinterludios\u00bb (Interlude I, II y III), que funcionan, con texturas delicadas, como momentos de introspecci\u00f3n, reconstrucci\u00f3n o di\u00e1logo m\u00e1s \u00edntimo dentro del tr\u00edo. Los m\u00fasicos establecen peque\u00f1os \u00e1mbitos r\u00edtmicos, que permiten la divergencia sin que se rompa la coherencia, ya sea con el arco de Formanek, el vibr\u00e1fono de Smith o el piano l\u00edrico de Melford, dibujando figuras abstractas.<\/p>\n<p>El \u00e1lbum se abre con \u00abDrift\u00bb, la pieza m\u00e1s larga, con una energ\u00eda contagiosa y experimental que refleja la evoluci\u00f3n art\u00edstica de Melford desde sus primeras incursiones en el jazz hasta sus colaboraciones m\u00e1s recientes con m\u00fasicos de la escena del <em>avant-garde<\/em>. A lo largo de los temas, <em>Splash<\/em> mantiene una sensaci\u00f3n de fluidez y libertad, al mismo tiempo que ofrece momentos de gran profundidad emocional y complejidad estructural, apoyados por ritmos enga\u00f1osamente estables del contrabajo y la bater\u00eda, lo que da una sensaci\u00f3n de constantes altibajos de tensi\u00f3n y libertad. El tr\u00edo se encamina sin ning\u00fan control hacia abismos sonoros, que se cortan con solos de contrabajo, momentos de calma a mitad de los temas o piano y vibr\u00e1fono que avanzan en d\u00faos. En algunos pasajes, Smith abre m\u00faltiples paletas t\u00edmbricas en el tr\u00edo.<\/p>\n<p>\u00abThe Wayward Line\u00bb remarca una atm\u00f3sfera introspectiva. Un contraste entre el fraseo del piano en escalas atonales con el contrabajo y la bater\u00eda. En \u00abFree Wheeler\u00bb, el peso mel\u00f3dico cambia con el contrabajo y la bater\u00eda; ambos marcan pautas firmes, mientras Myra Melford impulsa el piano con l\u00edneas decididas que se repiten, rozando el minimalismo con la entrada de los matices del vibr\u00e1fono. \u00abStreaming\u00bb comienza con un solo de bater\u00eda de amplio recorrido, con toques graves de contrabajo y apuntes del piano que va incrementando la tensi\u00f3n y arrastra a los otros dos instrumentos. El contrabajo rompe con un solo largo, y el piano y el vibr\u00e1fono van virando su orientaci\u00f3n hacia paisajes m\u00e1s despejados. El arco de Formanek y el vibr\u00e1fono trabajan a d\u00fao y el piano les acompa\u00f1a hasta el fin.<\/p>\n<p>\u00abA Line With A Mind of Its Own\u00bb es especialmente notable: cada m\u00fasico parece interpretar su propia idea del motivo central, pero aun as\u00ed logran mantener una cohesi\u00f3n sorprendente. El puzzle se va recomponiendo y se crean dibujos por parte de los tres con ritmo acelerado. \u00abDryprint\u00bb se inicia con otro solo de bater\u00eda y r\u00e1pido entra el piano, y entre los tres mantienen un equilibrio sonoro con intensidad. El contrabajo se destaca con un solo completo acompa\u00f1ado por la bater\u00eda, mientras el piano provoca acometidas largas e inconexas. El final vuelve a guardar una cierta coherencia r\u00edtmica.<\/p>\n<p>El cierre con \u00abChalk\u00bb mezcla lo meditativo con momentos de deconstrucci\u00f3n, generando una atm\u00f3sfera que se descompone en fragmentos, con piano, vibr\u00e1fono y contrabajo, pero sin perder su quietud interior. Este enfoque permite que la m\u00fasica tenga momentos \u00edntimos \u2014casi de \u00abc\u00e1mara\u00bb\u2014 y, al mismo tiempo, haya explosiones improvisadas, reflejando una tensi\u00f3n entre control compositivo y libertad expresiva que es una marca distintiva de Melford.<\/p>\n<p>Este disco es una invitaci\u00f3n a sumergirse en una conversaci\u00f3n musical sofisticada y llena de matices. Melford logra aqu\u00ed un equilibrio perfecto entre experimentaci\u00f3n y melod\u00eda, invitando a un viaje sonoro lleno de contrastes.<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <strong>Carlos Lara<\/strong>, 2025<\/p>\n<hr \/>\n<h3>Myra Melford: <em>Splash<\/em><\/h3>\n<p>M\u00fasicos: Myra Melford (piano), Michael Formanek (contrabajo) y Ches Smith (bater\u00eda).<\/p>\n<p>Temas: \u201cDrift\u201d, \u201cThe Wayward Line\u201d, \u201cInterlude I\u201d, \u201cFree Wheeler\u201d, \u201cInterlude II\u201d, \u201cStreaming\u201d, \u201cA Line With A Mind Of Its Own\u201d, \u201cInterlude III\u201d, \u201cDryprint\u201d y \u201cChalk\u201d.<br \/>\nTodas las composiciones de Myra Milford.<\/p>\n<p>Grabado en Hardstudios Winterthur (Suiza) por Michael Br\u00e4ndli, el 29 y 30 de julio de 2024.<\/p>\n<p>Pintura de portada: Cy Twombly, \u00abLepanto, 2001 [Part III]\u00bb \u00a9 Cy Twombly Foundation.<\/p>\n<p>Editado por Intakt Records en 2025.<\/p>\n<hr \/>\n<h3>M\u00e1s informaci\u00f3n sobre Myra Melford y Intakt Records<\/h3>\n<p><a href=\"https:\/\/www.myramelford.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.myramelford.com\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=myra+melford&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=myra+melford&amp;submit=Search<\/a><\/p>\n<p><a href=\"https:\/\/intaktrec.ch\/\" target=\"_blank\" rel=\"noopener\">https:\/\/intaktrec.ch\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=intakt+records&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=intakt+records&amp;submit=Search<\/a><\/p>\n<h3>Carlos Lara en Tomajazz<\/h3>\n<p><a href=\"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/category\/carlos-lara\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Splash (Intakt Records; 2025) es la \u00faltima grabaci\u00f3n de Myra Melford. Carlos Lara lo repasa. Con Myra Melford, Ches Smith, Michael Formanek <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/myra-melford-splash-2025\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":101857,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,17849,15517,1038],"tags":[84,5468,32928,5084,7673,6041],"class_list":["entry","author-pachi","has-excerpt","post-101856","post","type-post","status-publish","format-standard","has-post-thumbnail","category-grabaciones","category-carlos-lara","category-textos","category-contenidos","tag-carlos-lara","tag-ches-smith","tag-cy-twombly","tag-intakt","tag-michael-formanek","tag-myra-melford"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Myra-Melford-Splash-Intakt-Records-2025-Tomajazz.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9874,"url":"https:\/\/tomajazz.com\/web\/myra-melford-life-caries-me-this-way-firehouse-12-records-2013\/","url_meta":{"origin":101856,"position":0},"title":"Myra Melford: Life Caries Me This Way (Firehouse 12 Records, 2013)","author":"Tomajazz","date":"14 enero, 2014","format":false,"excerpt":"Con Life Carries Me This Way la veterana Myra Melford (1957) se estrena con una grabaci\u00f3n a piano solo. Para tan se\u00f1alada ocasi\u00f3n la artista realiza un homenaje a su amigo el artista Don Reich, fallecido en 2010. Las composiciones de Melford surgen inspiradas en los cuadros que dan t\u00edtulo\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/01\/Myra-Melford-life-carries-me-this-way.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2947,"url":"https:\/\/tomajazz.com\/web\/myra-melford-una-cuestion-de-perspectiva\/","url_meta":{"origin":101856,"position":1},"title":"Myra Melford: una cuesti\u00f3n de perspectiva","author":"Tomajazz","date":"27 enero, 2010","format":false,"excerpt":"A veces, por no decir siempre, las apreciaciones son simplemente una cuesti\u00f3n de perspectiva. Est\u00e1 claro que si un m\u00fasico publica como cuarta grabaci\u00f3n a su nombre un disco de la madurez de\u00a0Even The Sound Shines (Myra Melford Extended Ensemble, hatOlogy, 1995 \/ Reed. 2003), con unos acompa\u00f1antes de lujo\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":88558,"url":"https:\/\/tomajazz.com\/web\/myra-melford-vitoria-gasteiz-2024\/","url_meta":{"origin":101856,"position":2},"title":"Myra Melford Fire &#038; Water Quintet (47 Festival de Jazz de Vitoria &#8211; Gasteiz. 2024-07-12) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"28 agosto, 2024","format":false,"excerpt":"Myra Melford Fire & Water Quintet actu\u00f3 en el 47 Festival de Jazz de Vitoria - Gasteiz, el 12 de julio de 2024. Jos\u00e9 Luis Luna Rocafort retrata el concierto en INSTANTZZ. Actuaron Myra Melford, Ingrid Laubrock, Mary Halvorson, Tomeka Reid, Lesley Mok","rel":"","context":"En \u00ab47 Festival de Jazz de Vitoria Gasteiz 2024\u00bb","block_context":{"text":"47 Festival de Jazz de Vitoria Gasteiz 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/47-festival-de-jazz-de-vitoria-gasteiz-2024\/"},"img":{"alt_text":"Myra Melford Fire & Water Quintet  (47 Festival de Jazz de Vitoria - Gasteiz. 2024-07-12) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Myra Melford Fire & Water Quintet  actu\u00f3 en el 47 Festival de Jazz de Vitoria - Gasteiz, el 12 de julio de 2024. Jos\u00e9 Luis Luna Rocafort retrata el concierto en INSTANTZZ. Actuaron Myra Melford, Ingrid Laubrock, Mary Halvorson, Tomeka Reid, Lesley Mok","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/08\/destacada-Myra-Melford-Fire-And-Water-Quintet-Vitoria-2024-Tomajazz-Photo-by-Jose-Luis-Luna-Rocafort-2024-001.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/08\/destacada-Myra-Melford-Fire-And-Water-Quintet-Vitoria-2024-Tomajazz-Photo-by-Jose-Luis-Luna-Rocafort-2024-001.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/08\/destacada-Myra-Melford-Fire-And-Water-Quintet-Vitoria-2024-Tomajazz-Photo-by-Jose-Luis-Luna-Rocafort-2024-001.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9727,"url":"https:\/\/tomajazz.com\/web\/imatjazz-myra-melford\/","url_meta":{"origin":101856,"position":3},"title":"IMATJAZZ: Myra Melford","author":"Tomajazz","date":"18 diciembre, 2013","format":false,"excerpt":"Myra Melford Myra Melford - Ben Goldberg Jamboree, Barcelona. 2013-03-24 \u00a9 Joan Cort\u00e8s, 2013 \u00a0","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/IMJ027_MYRA-MELFORD-%C2%A9Joan-Cort%C3%A8s_24mar13_Myra-Melford-Ben-Goldberg_Jamboree_recorte.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5754,"url":"https:\/\/tomajazz.com\/web\/myra-melford-ben-goldberg-jamboree-barcelona-2013-03-24\/","url_meta":{"origin":101856,"position":4},"title":"Myra Melford \u2013 Ben Goldberg (Jamboree, Barcelona, 2013-03-24)","author":"Tomajazz","date":"5 abril, 2013","format":false,"excerpt":"D\u00eda: 24 de marzo de 2013 Lugar: Jamboree (Barcelona) Componentes: Myra Melford: piano Ben Goldberg: clarinete Comentario: Uno no sabe hasta qu\u00e9 punto categor\u00edas como \u201cbelleza\u201d, \u201clirismo\u201d o \u201cprofundidad\u201d, m\u00e1s est\u00e9ticas en el sentido makinavajiano del t\u00e9rmino que en el de la filosof\u00eda pura, sirven para explicar seg\u00fan qu\u00e9 cosas\u2026","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/04\/Tr%C3%ADptico02_MelfordGoldberg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/04\/Tr%C3%ADptico02_MelfordGoldberg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/04\/Tr%C3%ADptico02_MelfordGoldberg.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2949,"url":"https:\/\/tomajazz.com\/web\/myra-melford-the-whole-tree-gone\/","url_meta":{"origin":101856,"position":5},"title":"Myra Melford: The Whole Tree Gone","author":"Tomajazz","date":"26 enero, 2010","format":false,"excerpt":"Y ma\u00f1ana, un repaso a The Whole Tree Gone, lo nuevo de Myra Melford con su grupo Be Bread: una cuesti\u00f3n de perspectiva. Pachi Tapiz","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/101856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=101856"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/101856\/revisions"}],"predecessor-version":[{"id":101858,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/101856\/revisions\/101858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/101857"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=101856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=101856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=101856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}