{"id":10188,"date":"2014-02-04T11:10:53","date_gmt":"2014-02-04T10:10:53","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=10188"},"modified":"2016-11-13T22:59:50","modified_gmt":"2016-11-13T21:59:50","slug":"los-sorteos-de-tomajazz-joaquin-chacon-mariano-diaz-skytrain-nevermind-3-tree-sustrai-barik","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/los-sorteos-de-tomajazz-joaquin-chacon-mariano-diaz-skytrain-nevermind-3-tree-sustrai-barik\/","title":{"rendered":"Los sorteos de Tomajazz: Joaqu\u00edn Chac\u00f3n \u2013 Mariano D\u00edaz: <i>Skytrain<\/i> \/ Nevermind 3: <i>Tree-Sustrai Barik<\/i>"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-10190\" alt=\"Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263-200x175.jpg\" width=\"200\" height=\"175\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263-200x175.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263-150x131.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263-62x55.jpg 62w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263.jpg 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Tomajazz sortea, por cortes\u00eda de Errabal, un ejemplar de cada una de las dos novedades que el sello ha publicado el pasado mes de enero de 2014: Joaqu\u00edn Chac\u00f3n \u2013 Mariano D\u00edaz: <i>Skytrain<\/i> \/ Nevermind 3: <i>Tree-Sustrai Barik<\/i>.<\/p>\n<p style=\"text-align: justify;\">Para poder participar en el sorteo y ser el ganador de los dos ejemplares, hay que enviar un correo electr\u00f3nico a tomajazz @ gmail . com indicando en el asunto \u00abSorteo de Skytrain de Joaqu\u00edn Chac\u00f3n &#8211; Mariano D\u00edaz y Tree-Sustrai Barik de Nevermind 3\u00bb, y en el cuerpo del mensaje el t\u00edtulo de cinco grabaciones de Errabal que hayamos mencionado en Tomajazz a lo largo del tiempo, as\u00ed como el nombre del artista o grupo responsable. El plazo para participar finaliza el 16 de febrero de 2014 a las 23:59.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomajazz sortea, por cortes\u00eda de Errabal, un ejemplar de cada una de las dos novedades que el sello ha publicado el pasado mes de enero de 2014: Joaqu\u00edn Chac\u00f3n \u2013 Mariano D\u00edaz: Skytrain \/ Nevermind 3: Tree-Sustrai Barik. Para poder participar en el sorteo y ser el ganador de los<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/los-sorteos-de-tomajazz-joaquin-chacon-mariano-diaz-skytrain-nevermind-3-tree-sustrai-barik\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":10190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,1038,8156],"tags":[7259,8296,8297,8298,13435,16099,16100],"class_list":["entry","author-pachi","post-10188","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-contenidos","category-sorteo","tag-errabal","tag-joaquin-chacon","tag-mariano-diaz","tag-nevermind-3","tag-sorteo","tag-toma-jazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Joaqu\u00edn-Chac\u00f3n-Mariano-D\u00edaz_Skytrain-300x263.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12101,"url":"https:\/\/tomajazz.com\/web\/joaquin-chacon-mariano-diaz-skytrain-errabal-jazz-2014\/","url_meta":{"origin":10188,"position":0},"title":"Joaqu\u00edn Chac\u00f3n &#038; Mariano D\u00edaz: Skytrain (Errabal Jazz, 2014)","author":"Tomajazz","date":"15 mayo, 2014","format":false,"excerpt":"De todo un poco y entre col y col, lechuga. Jazz de variedad estil\u00edstica y sobre todo tamizada de intensidad y energ\u00eda a raudales. Composiciones ex profeso para la ocasi\u00f3n repartidas fundamentalmente entre Mariano D\u00edaz y Joaqu\u00edn Chac\u00f3n. Entendimiento total, funcionamiento con piloto autom\u00e1tico. Frescura creativa y originalidad repartida a\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Joaquin Chacon - Mariano Diaz_Skytrain","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/05\/Joaquin-Chacon-Mariano-Diaz_Skytrain-200x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10414,"url":"https:\/\/tomajazz.com\/web\/nevermind-3-tree-sustrai-barik-errabal-2014\/","url_meta":{"origin":10188,"position":1},"title":"Nevermind 3: Tree-Sustrai barik (Errabal, 2014)","author":"Tomajazz","date":"13 febrero, 2014","format":false,"excerpt":"Nevermind 3 cuenta en su haber con tres trabajos. El primero de ellos lleva por t\u00edtulo Nevermind People (Errabal, 2009) con versiones de Nirvana. El segundo, Be (Errabal, 2011), \u00a0acerc\u00f3 al grupo a propuestas del universo de la m\u00fasica cl\u00e1sica con versiones de Giovani Battista Pergolesi y Modest Mussorgski. El\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/02\/Nevermind-Trio.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":27428,"url":"https:\/\/tomajazz.com\/web\/instantzz-joaquin-chacon-skytrain-teatro-rialto-valencia-2016-09-30-especial-jazzene-2016-vii-galeria-fotografica\/","url_meta":{"origin":10188,"position":2},"title":"INSTANTZZ: Joaqu\u00edn Chac\u00f3n &#8211; Skytrain (Teatro Rialto, Valencia. 2016-09-30) [Especial Jazze\u00f1e 2016 VII] [Galer\u00eda fotogr\u00e1fica]","author":"Tomajazz","date":"14 noviembre, 2016","format":false,"excerpt":"Joaqu\u00edn Chac\u00f3n y su proyecto Skytrain son los protagonistas de la s\u00e9ptima entrega del especial JazzE\u00f1e 2016 de la Fundaci\u00f3n SGAE, con las im\u00e1genes de Jos\u00e9 Luis Luna Rocafort.","rel":"","context":"En \u00ab*_Jos\u00e9 Luis Luna Rocafort\u00bb","block_context":{"text":"*_Jos\u00e9 Luis Luna Rocafort","link":"https:\/\/tomajazz.com\/web\/category\/jose-luis-luna-rocafort\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/006-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/006-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/006-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17674,"url":"https:\/\/tomajazz.com\/web\/vamo-arriba-carlos-concierto-a-favor-de-carlos-carli-noticias\/","url_meta":{"origin":10188,"position":3},"title":"\u00a1Vamo arriba Carlos! Concierto a favor de Carlos Carli [Noticias]","author":"Tomajazz","date":"26 marzo, 2015","format":false,"excerpt":"Richi Ferrer, Eliseo Parra, Jayme Marques y Tato Icasto son los \u00faltimos nombres incorporados entre los participantes, quienes se unen a los de Pedro Iturralde, Pedro Ruy Blas, Miguel \u00c1ngel Chastang Quartet, Connie Philp, Speak Jazzy, Skytrain, Mariano D\u00edaz, Victor Merlo, Joaquin Chacon y Paco Garc\u00eda son algunos de los\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/Carlos-Carli_Foto-by-Sole-Gonzalez.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":26100,"url":"https:\/\/tomajazz.com\/web\/jazzene-2016-29-de-septiembre-al-1-de-octubre-de-2016-valencia-noticias\/","url_meta":{"origin":10188,"position":4},"title":"JazzE\u00f1e 2016 (29 de septiembre al 1 de octubre de 2016, Valencia) [Noticias]","author":"Tomajazz","date":"1 septiembre, 2016","format":false,"excerpt":"Chiqui Cienfuegos Tr\u00edo, Ern\u00e1n L\u00f3pez-Nussa, Ernesto Aurignac Quintet, Javier Vercher, Joan Monn\u00e9 Tr\u00edo, Joaqu\u00edn Chac\u00f3n \u201cSkytrain\u201d, Luis Verde, Marta S\u00e1nchez Quintet, Noesis Tr\u00edo, Ram\u00f3n D\u00edaz Group, Sinouj y Ver\u00f3nica Ferreiro son los grupos que participar\u00e1n en JazzE\u00f1e 2016 que organizado por la Fundaci\u00f3n SGAE, tendr\u00e1 lugar entre el 29 de\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":26455,"url":"https:\/\/tomajazz.com\/web\/hdo-167-jazzene-2016-podcast\/","url_meta":{"origin":10188,"position":5},"title":"HDO 167. JazzE\u00f1e 2016 [Podcast]","author":"Tomajazz","date":"23 septiembre, 2016","format":false,"excerpt":"Entre el mi\u00e9rcoles 28 de septiembre y el s\u00e1bado 1 de octubre de 2016, organizado por la Fundaci\u00f3n SGAE, tendr\u00e1 lugar en Valencia la III edici\u00f3n de JazzE\u00f1e. Entre el jueves 29 y el s\u00e1bado 1 tendr\u00e1n lugar doce conciertos en formato showcase (actuaciones de 45 minutos), con grupos y\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/JazzE%C3%B1e-2016.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/10188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=10188"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/10188\/revisions"}],"predecessor-version":[{"id":10192,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/10188\/revisions\/10192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/10190"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=10188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=10188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=10188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}