{"id":103295,"date":"2026-01-12T12:00:38","date_gmt":"2026-01-12T11:00:38","guid":{"rendered":"https:\/\/tomajazz.com\/web\/?p=103295"},"modified":"2026-01-11T21:15:27","modified_gmt":"2026-01-11T20:15:27","slug":"alternatilla-jazzband-version-25-3-2025","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/alternatilla-jazzband-version-25-3-2025\/","title":{"rendered":"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025. Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]"},"content":{"rendered":"<h3>Alternatilla JazzBand versi\u00f3n 25.3<\/h3>\n<h3>9\u00ba Alternatilla Jazz Festival 2025<\/h3>\n<ul>\n<li>Domingo, 07 de diciembre de 2025. 12:00h.<\/li>\n<li>9\u00ba Alternatilla Jazz Festival<\/li>\n<li>Lugar: Patio de Sa Congregaci\u00f3. Sa Pobla<\/li>\n<li>Formaci\u00f3n:<br \/>\nFernando Brox: flauta<br \/>\nMarko Lohikari: contrabajo<br \/>\nPierre Bauzerand: piano<br \/>\nSin\u00e9ad Cormican: voz, viol\u00edn<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-103296\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 001\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/001-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/001-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/001-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/001-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103297\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 002\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/002-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/002-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/002-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/002-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103298\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 003\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/003-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/003-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/003-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/003-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103299\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 004\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/004-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/004-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/004-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/004-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103300\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 005\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/005-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/005-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/005-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/005-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103301\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 006\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/006-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/006-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/006-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/006-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103302\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 007\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/007-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/007-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/007-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/007-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103303\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 008\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/008-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/008-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/008-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/008-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103304\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 009\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/009-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/009-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/009-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/009-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103305\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 010\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/010-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/010-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/010-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/010-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103306\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 011\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/011-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/011-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/011-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/011-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103307\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 012\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/012-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/012-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/012-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/012-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103308\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 013\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/013-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/013-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/013-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/013-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103309\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 014\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103310\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 015\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/015-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/015-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/015-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/015-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103311\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 016\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/016-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/016-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/016-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/016-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103312\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 017\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/017-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/017-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/017-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/017-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-103313\" title=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Tomajazz 018\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-2.jpg\" alt=\"Alternatilla JazzBand versi\u00f3n 25.3 (9\u00ba Alternatilla Jazz Festival 2025.Patio de Sa Congregaci\u00f3. Sa Pobla. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican\" width=\"600\" height=\"400\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-2-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-2-465x310.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9\u00a0<strong><a href=\"https:\/\/www.facebook.com\/joseluis.lunarocafort\" target=\"_blank\" rel=\"noopener\">Jos\u00e9 Luis Luna Rocafort<\/a><\/strong>, 2026<\/p>\n<h3>M\u00e1s informaci\u00f3n de Alternatilla JazzBand versi\u00f3n 25.3 y 9\u00ba Alternatilla Jazz Festival 2025<\/h3>\n<p><a href=\"https:\/\/www.instagram.com\/alternatilla\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/alternatilla\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=alternatilla+jazzband&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=alternatilla+jazzband&amp;submit=Search<\/a><\/p>\n<p><a href=\"https:\/\/www.alternatilla.com\/es\" target=\"_blank\" rel=\"noopener\">https:\/\/www.alternatilla.com\/es<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=alternatilla+jazz+festival&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=alternatilla+jazz+festival&amp;submit=Search<\/a><\/p>\n<h3>9\u00ba Alternatilla Jazz Festival 2025 en Tomajazz<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"65mjqlaNOP\"><p><a href=\"https:\/\/tomajazz.com\/web\/voodoo-children-collective-alternatilla-2025\/\">VooDoo Children Collective (9\u00ba Alternatilla Jazz Festival 2025. Auditori de Porreres. Mallorca. 2025-12-06) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abVooDoo Children Collective (9\u00ba Alternatilla Jazz Festival 2025. Auditori de Porreres. Mallorca. 2025-12-06) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/voodoo-children-collective-alternatilla-2025\/embed\/#?secret=6KrkyRYmDE#?secret=65mjqlaNOP\" data-secret=\"65mjqlaNOP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"zmSBVNwR78\"><p><a href=\"https:\/\/tomajazz.com\/web\/la-vella-dixieland-alternatilla-2025\/\">La Vella Dixieland. 45 anys (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal d&#8217;Inca. Mallorca. 2025-12-05) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLa Vella Dixieland. 45 anys (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal d&#8217;Inca. Mallorca. 2025-12-05) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/la-vella-dixieland-alternatilla-2025\/embed\/#?secret=1wGBvGuqkI#?secret=zmSBVNwR78\" data-secret=\"zmSBVNwR78\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"c4ohonaH8P\"><p><a href=\"https:\/\/tomajazz.com\/web\/chicuelo-marco-mezquida-alternatilla-2025\/\">Chicuelo &#038; Marco Mezquida (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal de Palma. 2025-12-03) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abChicuelo &#038; Marco Mezquida (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal de Palma. 2025-12-03) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/chicuelo-marco-mezquida-alternatilla-2025\/embed\/#?secret=qtbUHUCNi9#?secret=c4ohonaH8P\" data-secret=\"c4ohonaH8P\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"4wf4tVDSD2\"><p><a href=\"https:\/\/tomajazz.com\/web\/leila-duclos-quartet-alternatilla-2025\/\">Le\u00efla Duclos Quartet (9\u00ba Alternatilla Jazz Festival 2025. Teatre Sa Teulera, Andratx, Mallorca. 2025-11-30) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLe\u00efla Duclos Quartet (9\u00ba Alternatilla Jazz Festival 2025. Teatre Sa Teulera, Andratx, Mallorca. 2025-11-30) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/leila-duclos-quartet-alternatilla-2025\/embed\/#?secret=az6cIxD43p#?secret=4wf4tVDSD2\" data-secret=\"4wf4tVDSD2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"hAMFj0AFq5\"><p><a href=\"https:\/\/tomajazz.com\/web\/alternatilla-jazzband-version-25-2-2025\/\">Alternatilla JazzBand versi\u00f3n 25.2 (9\u00ba Alternatilla Jazz Festival 2025. Teatre de Llub\u00ed, Mallorca. 2025-11-29) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abAlternatilla JazzBand versi\u00f3n 25.2 (9\u00ba Alternatilla Jazz Festival 2025. Teatre de Llub\u00ed, Mallorca. 2025-11-29) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/alternatilla-jazzband-version-25-2-2025\/embed\/#?secret=MWbjC8Bjq6#?secret=hAMFj0AFq5\" data-secret=\"hAMFj0AFq5\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ntrPc73Tk3\"><p><a href=\"https:\/\/tomajazz.com\/web\/camille-bertault-quartet-alternatilla-2025\/\">Camille Bertault Quartet (9\u00ba Alternatilla Jazz Festival 2025. Espai 36. Sant Lloren\u00e7 des Cardassar, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abCamille Bertault Quartet (9\u00ba Alternatilla Jazz Festival 2025. Espai 36. Sant Lloren\u00e7 des Cardassar, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/camille-bertault-quartet-alternatilla-2025\/embed\/#?secret=jyV0MuK90I#?secret=ntrPc73Tk3\" data-secret=\"ntrPc73Tk3\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"cBpPqoy565\"><p><a href=\"https:\/\/tomajazz.com\/web\/levi-harvey-jeremie-lucchese-alternatilla-2025\/\">Levi Harvey &#038; J\u00e9r\u00e9mie Lucchese (9\u00ba Alternatilla Jazz Festival 2025. Claustre de Sant Bonaventura, Llucmajor, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLevi Harvey &#038; J\u00e9r\u00e9mie Lucchese (9\u00ba Alternatilla Jazz Festival 2025. Claustre de Sant Bonaventura, Llucmajor, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/levi-harvey-jeremie-lucchese-alternatilla-2025\/embed\/#?secret=YBhkdlAWcn#?secret=cBpPqoy565\" data-secret=\"cBpPqoy565\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"9vdRxgxzhj\"><p><a href=\"https:\/\/tomajazz.com\/web\/malena-moncadas-trio-alternatilla-2025\/\">Malena Moncadas Tr\u00edo (9\u00ba Alternatilla Jazz Festival 2025. Claustre des Convent, Muro, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abMalena Moncadas Tr\u00edo (9\u00ba Alternatilla Jazz Festival 2025. Claustre des Convent, Muro, Mallorca. 2025-11-23) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/malena-moncadas-trio-alternatilla-2025\/embed\/#?secret=BsBku8m7pB#?secret=9vdRxgxzhj\" data-secret=\"9vdRxgxzhj\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"AWKI9Jx1fY\"><p><a href=\"https:\/\/tomajazz.com\/web\/joachim-govin-quartet-alternatilla-2025\/\">Joachim Govin Quartet (9\u00ba Alternatilla Jazz Festival 2025. Casa des Poble, Esporles, Mallorca. 2025-11-22) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abJoachim Govin Quartet (9\u00ba Alternatilla Jazz Festival 2025. Casa des Poble, Esporles, Mallorca. 2025-11-22) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/joachim-govin-quartet-alternatilla-2025\/embed\/#?secret=bY1c0ogwnG#?secret=AWKI9Jx1fY\" data-secret=\"AWKI9Jx1fY\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h3>Jos\u00e9 Luis Luna Rocafort en Tomajazz<\/h3>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17846\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17846<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/category\/jose-luis-luna-rocafort\/\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/category\/jose-luis-luna-rocafort\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alternatilla JazzBand versi\u00f3n 25.3 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival en el Patio de Sa Congregaci\u00f3 en Sa Pobla, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Participaron Fernando Brox, Marko Lohikari, Pierre Bauzerand, Sin\u00e9ad Cormican<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/alternatilla-jazzband-version-25-3-2025\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":103312,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33038,17846,11262,15516,11261,1038],"tags":[33106,33105,11115,10088,520,23516,21744],"class_list":["entry","author-pachi","has-excerpt","post-103295","post","type-post","status-publish","format-standard","has-post-thumbnail","category-9o-alternatilla-jazz-festival-2025","category-jose-luis-luna-rocafort","category-photoblogs","category-imagenes","category-instantzz","category-contenidos","tag-alternatilla-jazzband","tag-alternatilla-jazzband-version-25-3","tag-fernando-brox","tag-jose-luis-luna-rocafort","tag-marko-lohikari","tag-pierre-bauzerand","tag-sinead-cormican"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/017-2.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103002,"url":"https:\/\/tomajazz.com\/web\/alternatilla-jazzband-version-25-2-2025\/","url_meta":{"origin":103295,"position":0},"title":"Alternatilla JazzBand versi\u00f3n 25.2 (9\u00ba Alternatilla Jazz Festival 2025. Teatre de Llub\u00ed, Mallorca. 2025-11-29) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"27 diciembre, 2025","format":false,"excerpt":"Alternatilla JazzBand versi\u00f3n 25.2 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en el Teatre de Llub\u00ed, Mallorca, el 29 de noviembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Le\u00efla Duclos, Camille Bertault, Julien Alour, Fady Farah, Joan Garc\u00edas, Enric Fuster","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"Alternatilla JazzBand versi\u00f3n 25.2 (9\u00ba Alternatilla Jazz Festival 2025. Teatre de Llub\u00ed, Mallorca. 2025-11-29) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Alternatilla JazzBand versi\u00f3n 25.2 actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en el Teatre de Llub\u00ed, Mallorca, el 29 de noviembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Le\u00efla Duclos, Camille Bertault, Julien Alour, Fady Farah, Joan Garc\u00edas, Enric Fuster","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/028.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/028.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/028.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103037,"url":"https:\/\/tomajazz.com\/web\/leila-duclos-quartet-alternatilla-2025\/","url_meta":{"origin":103295,"position":1},"title":"Le\u00efla Duclos Quartet (9\u00ba Alternatilla Jazz Festival 2025. Teatre Sa Teulera, Andratx, Mallorca. 2025-11-30) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"29 diciembre, 2025","format":false,"excerpt":"Le\u00efla Duclos Quartet actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en Andratx, Mallorca, el 30 de noviembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Le\u00efla Duclos, Leandro Aconcha, Gilles Coquard, Jean-Marc Robin","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"Le\u00efla Duclos Quartet (9\u00ba Alternatilla Jazz Festival 2025. Teatre Sa Teulera, Andratx, Mallorca. 2025-11-30) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Le\u00efla Duclos Quartet actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en Andratx, Mallorca, el 30 de noviembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Le\u00efla Duclos, Leandro Aconcha, Gilles Coquard, Jean-Marc Robin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/005-11.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/005-11.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/005-11.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103409,"url":"https:\/\/tomajazz.com\/web\/eva-fernandez-trio-alternatilla-2025\/","url_meta":{"origin":103295,"position":2},"title":"Eva Fern\u00e1ndez Tr\u00edo (9\u00ba Alternatilla Jazz Festival 2025. Esgl\u00e9sia\u00a0del Convent de Sant Domingo. Pollen\u00e7a. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"14 enero, 2026","format":false,"excerpt":"Eva Fern\u00e1ndez Tr\u00edo actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025, en la Esgl\u00e9sia\u00a0del Convent de Sant Domingo, Pollen\u00e7a, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Eva Fern\u00e1ndez, Josep Munar, Enric Fuster","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"Eva Fern\u00e1ndez Tr\u00edo (9\u00ba Alternatilla Jazz Festival 2025. Esgl\u00e9sia\u00a0del Convent de Sant Domingo. Pollen\u00e7a. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Eva Fern\u00e1ndez Tr\u00edo actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025, en la Esgl\u00e9sia\u00a0del Convent de Sant Domingo, Pollen\u00e7a, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Eva Fern\u00e1ndez, Josep Munar, Enric Fuster","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/018-3.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103245,"url":"https:\/\/tomajazz.com\/web\/voodoo-children-collective-alternatilla-2025\/","url_meta":{"origin":103295,"position":3},"title":"VooDoo Children Collective (9\u00ba Alternatilla Jazz Festival 2025. Auditori de Porreres. Mallorca. 2025-12-06) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"9 enero, 2026","format":false,"excerpt":"VooDoo Children Collective actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en el Auditori de Porreres, Mallorca, el 6 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Toni Vaquer, Diego Hervalejo, Camil Alcarazo, Joan Garcias, Ferran Mart\u00ednez, Aina Tramullas, Ant\u00f2nia Santandreu, Carlos Cort\u00e9s, Andreu Pitarch,\u2026","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"VooDoo Children Collective (9\u00ba Alternatilla Jazz Festival 2025. Auditori de Porreres. Mallorca. 2025-12-06) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - VooDoo Children Collective actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival 2025 en el Auditori de Porreres, Mallorca, el 6 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Toni Vaquer, Diego Hervalejo, Camil Alcarazo, Joan Garcias, Ferran Mart\u00ednez, Aina Tramullas, Ant\u00f2nia Santandreu, Carlos Cort\u00e9s, Andreu Pitarch, Enric Fuster, Julian S\u00e1nchez, Maria Ant\u00f2nia Gili, Pep Garau, V\u00edctor Carrascosa, Andreu Roig, Miguel Mois\u00e9s, Miquel Gay\u00e0, Tomeu Garcias, Miquel \u00c0ngel Rigo, Miguel \"Pintxo\" Villar, Roque Garc\u00eda, Tete Leal, Xavi Maldonado, Anggie Obin, Fernando Brox, Caterina Obrador, Ana Rodrigo, Joan Rotger, Roser Juli\u00e0, Shanti Easton, Sin\u00e9ad Cormican, Aina Mateu, Clementina Boeykens, Carmela Font, Maci\u00e0 Cerd\u00e0, Miquel Bennasar","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/014-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103107,"url":"https:\/\/tomajazz.com\/web\/chicuelo-marco-mezquida-alternatilla-2025\/","url_meta":{"origin":103295,"position":4},"title":"Chicuelo &#038; Marco Mezquida (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal de Palma. 2025-12-03) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"31 diciembre, 2025","format":false,"excerpt":"Chicuelo & Marco Mezquida actuaron en el 9\u00ba Alternatilla Jazz Festival en el Teatre Principal de Palma, el 3 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Chicuelo, Marco Mezquida, Paco de Mode","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"Chicuelo & Marco Mezquida (9\u00ba Alternatilla Jazz Festival 2025. Teatre Principal de Palma. 2025-12-03) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Chicuelo & Marco Mezquida actuaron en el 9\u00ba Alternatilla Jazz Festival en el Teatre Principal de Palma, el 3 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Con Chicuelo, Marco","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/020-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/020-6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/020-6.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103450,"url":"https:\/\/tomajazz.com\/web\/richard-galliano-alternatilla-2025\/","url_meta":{"origin":103295,"position":5},"title":"Richard Galliano \u00abNew Viaggio Trio\u00bb (9\u00ba Alternatilla Jazz Festival 2025. Conservatori Superior de M\u00fasica de les Illes Balears. Palma. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"16 enero, 2026","format":false,"excerpt":"Richard Galliano \"New Viaggio Trio\" actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival, en CSM de les Illes Balears en Palma, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Richard Galliano, Adrien Moignard, Philippe Aerts","rel":"","context":"En \u00ab9\u00ba Alternatilla Jazz Festival 2025\u00bb","block_context":{"text":"9\u00ba Alternatilla Jazz Festival 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/9o-alternatilla-jazz-festival-2025\/"},"img":{"alt_text":"Richard Galliano \"New Viaggio Trio\" (9\u00ba Alternatilla Jazz Festival 2025. Conservatori Superior de M\u00fasica de les Illes Balears. Palma. 2025-12-07) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Richard Galliano \"New Viaggio Trio\" actu\u00f3 en el 9\u00ba Alternatilla Jazz Festival, en CSM de les Illes Balears en Palma, el 7 de diciembre de 2025. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Richard Galliano, Adrien Moignard, Philippe Aerts","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/020-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/020-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/020-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/103295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=103295"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/103295\/revisions"}],"predecessor-version":[{"id":103410,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/103295\/revisions\/103410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/103312"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=103295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=103295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=103295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}