{"id":11010,"date":"2014-03-17T11:20:05","date_gmt":"2014-03-17T10:20:05","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=11010"},"modified":"2016-11-13T16:32:52","modified_gmt":"2016-11-13T15:32:52","slug":"11010","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/11010\/","title":{"rendered":"IMATJAZZ: Tom Chant"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11011\" alt=\"IMJ053_TOM CHANT_Photo_by_Joan Cort\u00e8s_20feb14_Free Sessions_Robadors 23_Bcn\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn.jpg\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn-99x150.jpg 99w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn-36x55.jpg 36w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<p>Tom Chant<br \/>\nFree Sessions<br \/>\nRobadors 23, Barcelona. 2014-02-13<\/p>\n<p>\u00a9 Joan Cort\u00e8s, 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tom Chant Free Sessions Robadors 23, Barcelona. 2014-02-13 \u00a9 Joan Cort\u00e8s, 2014<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/11010\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":11011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17853,15516,1038,7292,4758],"tags":[12656,15275,7462,13,1041,12657,1129,16099,77,16100],"class_list":["entry","author-pachi","post-11010","post","type-post","status-publish","format-standard","has-post-thumbnail","category-joan-cortes","category-imagenes","category-contenidos","category-imatjazz","category-blogs","tag-fotoblog","tag-galeria-fotografica","tag-imatjazz-2","tag-jazz","tag-joan-cortes","tag-photoblog","tag-tom-chant","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/IMJ053_TOM-CHANT_Photo_by_Joan-Cort\u00e8s_20feb14_Free-Sessions_Robadors-23_Bcn.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103951,"url":"https:\/\/tomajazz.com\/web\/nar-ensemble-hangar-barcelona-2025\/","url_meta":{"origin":11010,"position":0},"title":"Nar Ensemble (Hangar -Sala Ricson-, 2025-12-14 \/ Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"10 febrero, 2026","format":false,"excerpt":"Nar Ensemble actu\u00f3 en Sala Ricson de Hangar de Barcelona el 14 de diciembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Nar Ensemble son Tom Chant, Amidea Clotet, Alfredo Costa Monteiro, Mayssa Fattouh, Anxe Faraldo, Haize Lizarazu, \u00c0lex Reviriego","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Nar Ensemble (Hangar -Sala Ricson-, 2025-12-14 \/ Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Nar Ensemble actu\u00f3 en Sala Ricson de Hangar de Barcelona el 14 de diciembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Nar Ensemble son  Tom Chant, Amidea Clotet, Alfredo Costa Monteiro, Mayssa Fattouh, Anxe Faraldo, Haize Lizarazu, \u00c0lex Reviriego\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/07-Nr-nsmbl-Joan-Cortes-14dsm25-Hngr-sl-Rcsn-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/07-Nr-nsmbl-Joan-Cortes-14dsm25-Hngr-sl-Rcsn-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/07-Nr-nsmbl-Joan-Cortes-14dsm25-Hngr-sl-Rcsn-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":105267,"url":"https:\/\/tomajazz.com\/web\/chant-reviriego-hao-trio-juanse-huesca-2026\/","url_meta":{"origin":11010,"position":1},"title":"Chant \u2013 Reviriego &#8211; Hao Tr\u00edo (Juan Sebasti\u00e1n Bar, Huesca. 2026-04-30) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"8 mayo, 2026","format":false,"excerpt":"Chant \u2013 Reviriego - Hao Tr\u00edo actuaron en Juan Sebasti\u00e1n Bar de Huesca, celebrando el D\u00eda Internacional del Jazz el 30 de abril de 2026. Fabio Galicia lo retrata en INSTANTZZ. Chant \u2013 Reviriego - Hao Tr\u00edo son Tom Chant, Alex Reviriego, Zheng Hao","rel":"","context":"En \u00abJuan Sebasti\u00e1n Bar (Huesca)\u00bb","block_context":{"text":"Juan Sebasti\u00e1n Bar (Huesca)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/juan-sebastian-bar-huesca\/"},"img":{"alt_text":"https:\/\/www.instagram.com\/p\/DXbQr6yjJdA\/ (Juan Sebasti\u00e1n Bar, Huesca. 2026-04-30) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Chant \u2013 Reviriego - Hao Tr\u00edo actuaron en Juan Sebasti\u00e1n Bar de Huesca, celebrando el D\u00eda Internacional del Jazz el 30 de abril de 2026. Fabio Galicia lo retrata en INSTANTZZ. Chant \u2013 Reviriego - Hao Tr\u00edo son Tom Chant, Alex Reviriego, Zheng Hao","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260430-CHANT-REVIRIEGO-HAO-TRIO-TOMAJAZZ-110.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260430-CHANT-REVIRIEGO-HAO-TRIO-TOMAJAZZ-110.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260430-CHANT-REVIRIEGO-HAO-TRIO-TOMAJAZZ-110.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260430-CHANT-REVIRIEGO-HAO-TRIO-TOMAJAZZ-110.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260430-CHANT-REVIRIEGO-HAO-TRIO-TOMAJAZZ-110.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":103488,"url":"https:\/\/tomajazz.com\/web\/musicos-fallecidos-en-2025-un-recuerdo\/","url_meta":{"origin":11010,"position":2},"title":"M\u00fasicos fallecidos en 2025 -un recuerdo- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"17 enero, 2026","format":false,"excerpt":"M\u00fasicos fallecidos en 2025 -un recuerdo- Desde INSTANTZZ, Joan Cort\u00e8s recuerda a algunos de las y los m\u00fasicos fallecidos en el pasado 2025","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"M\u00fasicos fallecidos en 2025 -un recuerdo- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Desde INSTANTZZ, Joan Cort\u00e8s recuerda a algunos de las y los m\u00fasicos fallecidos en el pasado 2025.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/12-251026-Jck-DJnhtt-Joan-Cortes-Sl-Brts-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/12-251026-Jck-DJnhtt-Joan-Cortes-Sl-Brts-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/12-251026-Jck-DJnhtt-Joan-Cortes-Sl-Brts-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":86958,"url":"https:\/\/tomajazz.com\/web\/tom-chant-joni-sigil-vic-2024\/","url_meta":{"origin":11010,"position":3},"title":"Tom Chant &#038; Joni Sigil \u201cHomenatge a Marianne Brull\u201d (26\u00e8 Alhambra Festival de Jazz de Vic, Escenari Alhambra, 2024-05-04. Vic -Barcelona-) [III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"1 junio, 2024","format":false,"excerpt":"En concierto de Tom Chant & Joni Sigil \u201cHomenatge a Marianne Brull\u201d tuvo lugar en el 26\u00e8 Alhambra Festival de Jazz de Vic, el 4 de mayo de 2024. Joan Cort\u00e8s retrata el concierto en INSTANTZZ","rel":"","context":"En \u00ab26\u00e8 Alhambra Festival de Jazz de Vic 2024\u00bb","block_context":{"text":"26\u00e8 Alhambra Festival de Jazz de Vic 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/26e-alhambra-festival-de-jazz-de-vic-2024\/"},"img":{"alt_text":"Tom Chant & Joni Sigil \u201cHomenatge a Marianne Brull\u201d (26\u00e8 Alhambra Festival de Jazz de Vic, Escenari Alhambra, 2024-05-04. Vic -Barcelona-) [III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - En concierto de Tom Chant & Joni Sigil \u201cHomenatge a Marianne Brull\u201d tuvo lugar en el 26\u00e8 Alhambra Festival de Jazz de Vic, el 4 de mayo de 2024. Joan Cort\u00e8s retrata el concierto en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Destacada-Tom-Chant-Joni-Sigil-Vic-2024-Tomajazz-Photo-by-Joan-Cortes-2024-011.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Destacada-Tom-Chant-Joni-Sigil-Vic-2024-Tomajazz-Photo-by-Joan-Cortes-2024-011.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Destacada-Tom-Chant-Joni-Sigil-Vic-2024-Tomajazz-Photo-by-Joan-Cortes-2024-011.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104671,"url":"https:\/\/tomajazz.com\/web\/paul-stouthamer-2026-in-memoriam\/","url_meta":{"origin":11010,"position":4},"title":"Paul Stouthamer (1959-2026) In Memoriam","author":"Tomajazz","date":"2 abril, 2026","format":false,"excerpt":"El violonchelista Paul Stouthamer falleci\u00f3 en marzo de 2026. Desde Tomajazz le rendimos un peque\u00f1o homenaje","rel":"","context":"En \u00abIn Memoriam\u00bb","block_context":{"text":"In Memoriam","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/in-memoriam\/"},"img":{"alt_text":"Paul Stouthamer (2026) In Memoriam - Tomajazz - El violonchelista Paul Stouthamer falleci\u00f3 en 2026. Desde","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/260230-Pl-Stthmr-Photo-By-Joan-Cortes-19dsm18-Jmb-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/260230-Pl-Stthmr-Photo-By-Joan-Cortes-19dsm18-Jmb-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/260230-Pl-Stthmr-Photo-By-Joan-Cortes-19dsm18-Jmb-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":86595,"url":"https:\/\/tomajazz.com\/web\/felix-chant-faraldo-3r-nu-vilafranca-2024\/","url_meta":{"origin":11010,"position":5},"title":"F\u00e8lix-Chant-Faraldo \u201cHomenatge a Marianne Brull\u201d (3r Nu -cicle de m\u00fasica i vins nus-, Capella St. Joan, 2024-04-24. Vilafranca del Pened\u00e8s -Barcelona-) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"18 mayo, 2024","format":false,"excerpt":"El tr\u00edo F\u00e8lix-Chant-Faraldo realiz\u00f3 un \u201cHomenatge a Marianne Brull\u201d en el 3r Nu -cicle de m\u00fasica i vins nus-, en Vilafranca del Pened\u00e8s -Barcelona-, el 24 de abril de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron M\u00edriam F\u00e8lix, \u00c1ngel Faraldo, Tom Chant","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"F\u00e8lix-Chant-Faraldo \u201cHomenatge a Marianne Brull\u201d (3r Nu -cicle de m\u00fasica i vins nus-, Capella St. Joan, 2024-04-24. Vilafranca del Pened\u00e8s -Barcelona-) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - El tr\u00edo F\u00e8lix-Chant-Faraldo realiz\u00f3 un \u201cHomenatge a Marianne Brull\u201d en el 3r Nu -cicle de m\u00fasica i vins nus-, en Vilafranca del Pened\u00e8s -Barcelona-, el 24 de abril de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron M\u00edriam F\u00e8lix, \u00c1ngel Faraldo, Tom Chant\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/11010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=11010"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/11010\/revisions"}],"predecessor-version":[{"id":11014,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/11010\/revisions\/11014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/11011"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=11010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=11010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=11010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}