{"id":13034,"date":"2014-07-16T11:10:13","date_gmt":"2014-07-16T09:10:13","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=13034"},"modified":"2016-11-13T16:00:19","modified_gmt":"2016-11-13T15:00:19","slug":"felipe-salles-ugandan-suite-tapestry-records-2013","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/felipe-salles-ugandan-suite-tapestry-records-2013\/","title":{"rendered":"Felipe Salles: <i>Ugandan Suite<\/i> (Tapestry Records, 2013)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13036\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite-200x180.jpg\" alt=\"Felipe Salles Ugandan Suite\" width=\"200\" height=\"180\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite-200x180.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite-150x135.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite-60x55.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite.jpg 450w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>El saxofonista, clarinetista y flautista de Sao Paulo Felipe Salles ejerce desde 2010 de profesor asistente de jazz y de estudios de m\u00fasica afroamericana en la Universidad de Massachussets. Desde hace 20 a\u00f1os est\u00e1 radicado en Estados Unidos donde ha tenido la ocasi\u00f3n de trabajar y grabar con eminentes m\u00fasicos como Randy Brecker, David Liebman, George Russell, Gunther Schuller, Sam Rivers, Jerry Bergonzi, adem\u00e1s de los m\u00e1s destacados m\u00fasicos brasile\u00f1os. Entre otros, ha ganado el primer premio en el Concurso SGAE de Jazz \u00abTete Montoliu\u201d de 2001, con la composici\u00f3n \u00abThe Return of The Chromo Sapiens\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ugandan Suite es su sexto \u00e1lbum como l\u00edder, donde se dan la mano la m\u00fasica cl\u00e1sica, la africana y el jazz. Est\u00e1 concebido, seg\u00fan el orden cl\u00e1sico, por cinco movimientos, cada uno con el nombre de un animal de la selva africana. Se trata de un trabajo que va m\u00e1s all\u00e1 del jazz, adentr\u00e1ndose por territorios que suponen un itinerario en el que las armon\u00edas y el ritmo juegan un papel especial. Cada elemento se mueve con sofisticada gracia y ternura. A diferencia de otros trabajos de similares caracter\u00edsticas, Salles ha creado el veh\u00edculo perfecto para tres estilos distintos de m\u00fasica que se entrelazan conjuntamente con una cohesi\u00f3n atractiva. Para ello se vale de diversos m\u00fasicos occidentales, el m\u00e1s conocido es David Liebman, y otros africanos, que hacen uso de todo un carrusel de instrumentos percusivos y viento de ese continente.<\/p>\n<p style=\"text-align: justify;\">El trabajo compositivo y de arreglos a cargo de Felipe Salles es digno de alabanza. La m\u00fasica es plenamente accesible. El disco est\u00e1 lleno de giros, saltos y movimientos r\u00edtmicos continuos. <em>Ugandan Suite<\/em> es un viaje que transforma los sonidos habituales africanos en dulces texturas, interpretados con suma elegancia en todas sus facetas.<\/p>\n<p style=\"text-align: right;\">\u00a9 Carlos Lara, 2014<\/p>\n<p>Felipe Salles:<em>Ugandan Suite<\/em><\/p>\n<p style=\"text-align: justify;\">Felipe Salles (saxo tenor, saxo bar\u00edtono, flautas, clarinete bajo y palmas), David Liebman (saxo tenor, saxo soprano y flauta de madera), Nando Michelin (piano y palmas), Keala Kaumeheiwa (bajo el\u00e9ctrico y palmas), Damascus Kafumbe (arpa, xilof\u00f3n y diversas percusiones africanas), Rogerio Boccato (percusiones), Lucas Apostoleris (palmas) y Bertram Lehmann (bater\u00eda y palmas)<\/p>\n<p style=\"text-align: justify;\">\u201cMovement 1 &#8211; The Buffalo\u201d, \u201cMovement 2 &#8211; The Elephant\u201d, \u201cMovement 3 &#8211; The Leopard\u201d, \u201cMovement 4 &#8211; The Rhinoceros\u201d y \u201cMovement 5 &#8211; The Lion\u201d.<br \/>\nTodos los temas compuestos y arreglados por Felipe Salles.<\/p>\n<p style=\"text-align: justify;\">Grabado en Wellspring Sound Recording Studio el 29 de agosto de 2013 en Brooklyn (Nueva York). Editado en 2013 por Tapestry Records.\u00a0 TAPESTRY 76023-2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El saxofonista, clarinetista y flautista de Sao Paulo Felipe Salles ejerce desde 2010 de profesor asistente de jazz y de estudios de m\u00fasica afroamericana en la Universidad de Massachussets. Desde hace 20 a\u00f1os est\u00e1 radicado en Estados Unidos donde ha tenido la ocasi\u00f3n de trabajar y grabar con eminentes m\u00fasicos<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/felipe-salles-ugandan-suite-tapestry-records-2013\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":13036,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,1038],"tags":[9844,84,12651,9845,9841,1623,9837,7827,12696,9846,13,12415,15295,1266,9840,9843,9839,765,9842,2177,9838,6550,16099,77,16100],"class_list":["entry","author-pachi","post-13034","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-contenidos","tag-bertram-lehman","tag-carlos-lara","tag-cd","tag-concurso-sgae-de-jazz-tete-montoliu","tag-damascus-kafumbe","tag-david-liebman","tag-felipe-salles","tag-george-russell","tag-grabaciones","tag-gunther-schuller","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jerry-bergonzi","tag-keala-kaumeheiwa","tag-lucas-apostoleris","tag-nando-michelin","tag-randy-brecker","tag-rogerio-boccato","tag-sam-rivers","tag-tapestry-records","tag-tete-montoliu","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Felipe-Salles-Ugandan-Suite.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":57407,"url":"https:\/\/tomajazz.com\/web\/david-liebman-randy-brecker-marc-copland-drew-gress-joey-baron-quint5t-innervoice-jazz-2020-grabacion-de-jazz-por-carlos-lara\/","url_meta":{"origin":13034,"position":0},"title":"David Liebman, Randy Brecker, Marc Copland, Drew Gress, Joey Baron: Quint5T (Innervoice Jazz, 2020) [Grabaci\u00f3n de jazz] Por Carlos Lara","author":"Tomajazz","date":"29 septiembre, 2021","format":false,"excerpt":"Carlos Lara repasa Quint5t (InnerVoice Jazz), grabaci\u00f3n del supergrupo formado por David Liebman, Randy Brecker, Marc Copland, Drew Gress y Joey Baron.","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"David Liebman, Randy Brecker, Marc Copland, Drew Gress, Joey Baron: Quint5T (Innervoice Jazz, 2020)","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/David-Liebman-Randy-Brecker-Marc-Copland-Drew-Gress-Joey-Baron-Quint5t.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/David-Liebman-Randy-Brecker-Marc-Copland-Drew-Gress-Joey-Baron-Quint5t.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/David-Liebman-Randy-Brecker-Marc-Copland-Drew-Gress-Joey-Baron-Quint5t.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1120,"url":"https:\/\/tomajazz.com\/web\/varios-autores-art%c2%b7i%c2%b7facts-great-performances-from-40-years-of-jazz-at-nec\/","url_meta":{"origin":13034,"position":1},"title":"Varios Autores &#8211; Art\u00b7I\u00b7Facts. Great Performances From 40 Years of Jazz At NEC (","author":"Autor1","date":"17 mayo, 2011","format":false,"excerpt":"El pasado 2009 se cumpli\u00f3 el 40 aniversario de la especialidad en Jazz del New England Conservatory. Fue en su centenario, en 1967, cuando el m\u00fasico y te\u00f3rico del jazz Gunther Schuller, presidente reci\u00e9n elegido del conservatorio, impuls\u00f3 la creaci\u00f3n de los estudios de jazz en el seno de esta\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2011\/05\/artifacts1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2943,"url":"https:\/\/tomajazz.com\/web\/new-england-conservatory-jazz-studies-40-anos-dando-la-nota\/","url_meta":{"origin":13034,"position":2},"title":"New England Conservatory Jazz Studies: 40 a\u00f1os dando la nota","author":"Tomajazz","date":"12 febrero, 2010","format":false,"excerpt":"El pasado 2009 se cumpli\u00f3 el 40 aniversario de la especialidad en Jazz del New England Conservatory. Fue en su centenario, en 1967, cuando el m\u00fasico y te\u00f3rico del jazz Gunther Schuller, presidente reci\u00e9n elegido del conservatorio, impuls\u00f3 la creaci\u00f3n de los estudios de jazz en el seno de esta\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":59854,"url":"https:\/\/tomajazz.com\/web\/jazzx5379-david-liebman-randy-brecker-marc-copland-drew-gress-joey-baron-off-a-bird-quint5t-innervoice-jazz-2020-minipodcast-de-jazz-por-pachi-tapiz\/","url_meta":{"origin":13034,"position":3},"title":"JazzX5#379. David Liebman, Randy Brecker, Marc Copland, Drew Gress, Joey Baron: \u201cOff A Bird\u201d [Quint5t (Innervoice Jazz, 2020)] [Minipodcast de jazz] Por Pachi Tapiz","author":"Tomajazz","date":"30 diciembre, 2021","format":false,"excerpt":"En JazzX5 el tema \"Off A Bird\" que aparec\u00eda en la grabaci\u00f3n de David Liebman, Randy Brecker, Marc Copland, Drew Gress, Joey Baron titulada Quint5t (Innervoice Jazz, 2020). JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_379.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_379.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_379.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_379.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101417,"url":"https:\/\/tomajazz.com\/web\/cesar-joaniquet-live-at-jazz-cava-2025\/","url_meta":{"origin":13034,"position":4},"title":"C\u00e8sar Joaniquet: Live at Jazz Cava (UnderPool Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"5 noviembre, 2025","format":false,"excerpt":"Live at Jazz Cava (UnderPool Records; 2025) es la nueva grabaci\u00f3n de C\u00e8sar Joaniquet:. Carlos Lara repasa la grabaci\u00f3n. Con C\u00e8sar Joaniquet, Artur Tu\u017anik), Brice Soniano, Kasper Tom Christiansen","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"C\u00e8sar Joaniquet: Live at Jazz Cava (UnderPool Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Jazz Cava (UnderPool Records; 2025) es la nueva grabaci\u00f3n de C\u00e8sar Joaniquet:. Carlos Lara repasa la grabaci\u00f3n. Con C\u00e8sar Joaniquet, Artur Tu\u017anik), Brice Soniano, Kasper Tom Christiansen","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Cesar-Joaniquet-Live-at-Jazz-Cava-UnderPool-Records-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19961,"url":"https:\/\/tomajazz.com\/web\/jerry-bergonzi-rigamaroll-savant-records-2015-cd\/","url_meta":{"origin":13034,"position":5},"title":"Jerry Bergonzi: Rigamaroll (Savant Records, 2015; CD) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"2 octubre, 2015","format":"image","excerpt":"Carlos Lara repasa la nueva grabaci\u00f3n de Jerry Bergonzi Rigamaroll (Savant Records, 2015; CD).","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/Jerry-Bergonzi-Rigamaroll.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=13034"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13034\/revisions"}],"predecessor-version":[{"id":13037,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13034\/revisions\/13037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/13036"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=13034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=13034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=13034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}