{"id":13078,"date":"2014-07-17T11:20:04","date_gmt":"2014-07-17T09:20:04","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=13078"},"modified":"2018-05-04T11:41:56","modified_gmt":"2018-05-04T09:41:56","slug":"sonny-rollins-road-shows-volume-3-doxy-records-2014","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014\/","title":{"rendered":"Sonny Rollins: <i>Road Shows. Volume 3<\/i> ( Doxy Records, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13079\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-200x200.jpg\" alt=\"Sonny Rollins Road Shows Vol 3\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg 500w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>&#8216;Doxy&#8217; vivi\u00f3 su primera grabaci\u00f3n en junio de 1954, en el transcurso de una gloriosa sesi\u00f3n que acabar\u00eda traducida en un c\u00e9lebre disco de Miles Davis, <em>Bag&#8217;s Groove<\/em>, y durante la cual su propio autor, Sonny Rollins, la interpretar\u00eda codo a codo con el genial trompetista y con los no menos imprescindibles Horace Silver, Percy Heath y Kenny Clarke. Aquel disco albergar\u00eda otras dos composiciones m\u00e1s de Rollins, &#8216;Airegin&#8217; y &#8216;Oleo&#8217;, a las que la eternidad ya ha hecho tambi\u00e9n un hueco en su seno. &#8216;Doxy&#8217; ha amasado\u00a0 condici\u00f3n de cl\u00e1sico con el tiempo y ha sido objeto de atenci\u00f3n por parte de m\u00fasicos de todos los tiempos. Rollins ha echado mano del nombre para bautizar tambi\u00e9n su propio sello bajo cuyo auspicio ha grabado <em>Sonny, Please<\/em>\u00a0(2006), su \u00faltimo \u00e1lbum de estudio, y la serie &#8216;Road Shows&#8217;. Esta \u00faltima, suma de m\u00fasica en directo, abarca ya tres entregas, la primera de las cuales data de 2008 y hace acopio de actuaciones de Rollins a lo largo de las tres \u00faltimas d\u00e9cadas y la segunda qued\u00f3 fechada en 2011 y nutrida por algunos de los momentos de los conciertos del &#8216;colossus&#8217; en 2010, sobre todo del que llev\u00f3 a cabo en el Beacon Theatre de Nueva York en mayo de aquel a\u00f1o y en el que participaron nombres de la entidad de Ornette Coleman (absolutamente inolvidable el tema que comparten juntos los dos mitos, &#8216;Sonnymoon for two&#8217;, junto a Christian McBride y Roy Haynes), Jim Hall o Roy Hargrove, entre otros. El tercer cap\u00edtulo de la saga acaba de aparecer, incluye seis temas, registrados en Jap\u00f3n, en las localidades francesas de Toulouse, Marsella y Marciac y tambi\u00e9n en St. Louis\u00a0 entre 2001 y 2012, y sigue haciendo hincapi\u00e9, como en el resto de la serie, en la facilidad del maestro para el directo, en su indiscutible capacidad, cuando se ausenta del estudio, para la extracci\u00f3n del matiz, en su magistral convicci\u00f3n durante el ejercicio de la improvisaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Sonny Rollins anda ahora mismo por los 84 a\u00f1os. Lleva oficiando su magisterio desde hace seis d\u00e9cadas y media y ratificando continuamente su condici\u00f3n de leyenda. Su estilo, sometido al virtuosismo del que siempre ha hecho gala, destaca por su calidad como improvisador, por conferir a su m\u00fasica una personalidad propia que huye del resquicio o la duda, por hacer de la libertad creativa su principal se\u00f1a de identidad. Es un especialista en riesgos, en caminar sobre el alambre sin red, en descifrar las claves que le desvelen la salida de los laberintos en los que voluntariamente se cuela. Su pericia es objeto de demostraci\u00f3n permanente\u00a0 en los seis temas del tercer volumen de &#8216;Road Shows&#8217;. Resultan incuestionables las facultades de Sonny Rollins en la traves\u00eda emprendida por \u00e9l y de la que da testimonio esta grabaci\u00f3n. No es f\u00e1cil buscarle cosquillas a un \u00e1lbum que abunda en la solvencia y que queda encarado hacia la eficacia gracias a la autoridad de un Sonny Rollins incontestable y a la interacci\u00f3n estrecha que sostiene con el resto de los m\u00fasicos. Tambi\u00e9n, resulta realmente destacable la participaci\u00f3n de Bob Cranshaw. No hay int\u00e9rprete que conozca mejor al &#8216;colossus&#8217;. No en vano, se juraron fidelidad hace ya cincuenta a\u00f1os y a ella se han entregado con devoci\u00f3n. El contrabajista, tambi\u00e9n octogenario y al que alimenta una trayectoria de aut\u00e9ntico privilegio, ha sido el compa\u00f1ero de faenas ideal del saxofonista nortemaricano y el gu\u00eda que ha sublimado el talento de este. En este disco participa en la media docena de temas. Con rigor, con suficiencia. Constituye otro de los grandes alicientes de un \u00e1lbum realmente atractivo que incluye una composici\u00f3n in\u00e9dita, &#8216;Patanjali&#8217;, dedicada a un maestro yoga, disciplina que cultiva Rollins, quien, por supuesto y en este disco, asume de manera rotunda su condici\u00f3n de l\u00edder y maestro de ceremonias a lo largo y ancho de una propuesta que le rinde constante reverencia. Quiz\u00e1s el momento m\u00e1s impactante de todo el disco lo constituya &#8216;Why Was I Born?&#8217;, adaptaci\u00f3n de una reputad\u00edsima composici\u00f3n de Kern y Hammerstein II que supera los veinte minutos. La conoce de sobra y al detalle. Otra versi\u00f3n de este aplaudido tema, incluida en su disco en vivo (un g\u00e9nero que domina como nadie y del que es maestro y se\u00f1or) <em>Without a Song: The 9\/11 Concert<\/em>, le hizo merecedor en 2006 de un Grammy. El contagioso entusiasmo impuesto a la canci\u00f3n se convierte en sost\u00e9n fundamental de un trabajo muy bien armado en el que destacan, sobre todo, el guitarrista Bobby Broom, el baterista Steve Jordan y, por supuesto, el saxo tenor de Sonny Rollins. Tambi\u00e9n hay mucha energ\u00eda y chispa en &#8216;Don&#8217;t Stop The Carnival&#8217;, que, con aroma de <em>calypso<\/em> (otro g\u00e9nero que Rollins ha glorificado), ya ha devenido en tradici\u00f3n en el repertorio del saxofonista. Atractivos tambi\u00e9n son el poso <em>funk<\/em> de &#8216;Biji&#8217; o las facultades de Rollins para atrapar toda clase de emociones en &#8216;Someday I&#8217;Fill Find You&#8217; con la complicidad de las percusiones de Kimati Dinizulu. El t\u00edtulo del tercer tema del \u00e1lbum, &#8216;Solo Sonny&#8217;, es realmente expresivo. Rollins se pone manos a la obra y se arranca con un largu\u00edsimo solo (otra de sus grandes virtudes) de ocho minutos que da satisfacci\u00f3n a sus seguidores y engrandece su leyenda. Sonny Rollins est\u00e1 en el disco, en cada uno de sus rincones, en cada uno de los instantes que guarda. Y eso ya es motivo suficiente para no perderlo de vista y tenerlo siempre a mano.<\/p>\n<p style=\"text-align: right;\">\u00a9 L. Castellanos, 2014<\/p>\n<p>&nbsp;<\/p>\n<p>Sonny Rollins: <i>Road Shows. Volume 3<\/i><\/p>\n<p style=\"text-align: justify;\">M\u00fasicos: Sonny Rollins: saxo tenor; Bob Cranshaw, bajo; Clifton Anderson, tromb\u00f3n; Stephen Scott, piano (1); Bobby Broom, guitarra (2, 4, 5), Peter Bernstein, guitarra (3,6); Perry Wilson, bater\u00eda (1); Victor Lewis, bater\u00eda (2); Kobie Watkins, bater\u00eda (3, 4, 6); Steve Jordan, bater\u00eda (5); Kimati Dinizulu, percusi\u00f3n (1,2,5); Sammy Figueroa, percusi\u00f3n (3, 4, 6)<\/p>\n<p>Temas: \u201cBiji\u201d; \u201cSomeday I&#8217;ll Find You\u201d; \u201cPatanjali\u201d; \u201cSolo Sonny\u201d; \u201cWhy Was I Born?\u201d; \u201cDon&#8217;t Stop The Carnival\u201d<\/p>\n<p>Publicado en 2014 por Doxy Records.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Doxy&#8217; vivi\u00f3 su primera grabaci\u00f3n en junio de 1954, en el transcurso de una gloriosa sesi\u00f3n que acabar\u00eda traducida en un c\u00e9lebre disco de Miles Davis, Bag&#8217;s Groove, y durante la cual su propio autor, Sonny Rollins, la interpretar\u00eda codo a codo con el genial trompetista y con los no<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":13079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17882,5,13061,1038],"tags":[1494,9872,12651,1566,9870,9869,12696,8822,13,12415,15295,979,8234,9878,9876,7539,2004,1200,8654,9874,9873,138,2166,2178,2225,9871,9877,16099,77,16100,9875],"class_list":["entry","author-pachi","post-13078","post","type-post","status-publish","format-standard","has-post-thumbnail","category-l-castellanos","category-grabaciones","category-ornette-coleman-gracias-maestro","category-contenidos","tag-bob-cranshaw","tag-bobby-broom","tag-cd","tag-christian-mcbride","tag-clifton-anderson","tag-doxy-records","tag-grabaciones","tag-horace-silver","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jim-hall","tag-kenny-clarke","tag-kimati-dinizulu","tag-kobie-watkins","tag-l-castellanos","tag-miles-davis","tag-ornette-coleman","tag-percy-heath","tag-perry-wilson","tag-peter-bernstein","tag-roy-hargrove","tag-roy-haynes","tag-sammy-figueroa","tag-sonny-rollins","tag-stephen-scott","tag-steve-jordan","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-victor-lewis"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13607,"url":"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014-2\/","url_meta":{"origin":13078,"position":0},"title":"Sonny Rollins: Road Shows. Volume 3 ( Doxy Records, 2014)","author":"Tomajazz","date":"10 septiembre, 2014","format":false,"excerpt":"Sonny Rollins (1930), el Saxophone Colossus tal y como se le ha denominado desde los 50, sigue en activo. Han pasado casi diez a\u00f1os desde que grab\u00f3 su \u00faltimo CD en estudio, lo que no ha impedido que a\u00f1o tras a\u00f1o siga en los escenarios de los festivales de jazz\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3135,"url":"https:\/\/tomajazz.com\/web\/veteranos-en-la-brecha-xiii-sonny-rollins\/","url_meta":{"origin":13078,"position":1},"title":"Veteranos en la brecha (XIII): Sonny Rollins","author":"Tomajazz","date":"19 diciembre, 2008","format":false,"excerpt":"Sonny Rollins (1930) es otro de esos m\u00fasicos que a pesar de su avanzada edad no para. El pasado mes de julio visit\u00f3 el Festival de Jazz de Vitoria para dar uno de sus interminables conciertos. Tras el verano ha publicado el primer volumen de la serie Road Shows en\u2026","rel":"","context":"En \u00ab*_Juan Carlos Hern\u00e1ndez\u00bb","block_context":{"text":"*_Juan Carlos Hern\u00e1ndez","link":"https:\/\/tomajazz.com\/web\/category\/juan-carlos-hernandez\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":50287,"url":"https:\/\/tomajazz.com\/web\/hard-bop-xi-sonny-rollins-iii-jimmy-smith-la-odisea-de-la-musica-afroamericana-235-podcast-yomequedoencasa-istayathome\/","url_meta":{"origin":13078,"position":2},"title":"Hard Bop (XI). Sonny Rollins (III) &#8211; Jimmy Smith(I). La Odisea de la M\u00fasica Afroamericana (235) [Podcast]  #YoMeQuedoEnCasa \/ #IStayAtHome","author":"Tomajazz","date":"20 abril, 2020","format":false,"excerpt":"Como todos los lunes, un nuevo cap\u00edtulo de La Odisea de la M\u00fasica AFroamericana. En el cap\u00edtulo 235 del programa dirigido por\u00a0Luis Escalante Ozalla finaliza el repaso a la trayectoria de Sonny Rollins, y comienza la del gran Jimmy Smith. Y recuerda... #YoMeQuedoEnCasa \/ #IStayAtHome","rel":"","context":"En \u00abSonidos\u00bb","block_context":{"text":"Sonidos","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16368,"url":"https:\/\/tomajazz.com\/web\/thelonious-monk-sonny-rollins-complete-recordings-essential-jazz-classics-2014\/","url_meta":{"origin":13078,"position":3},"title":"Thelonious Monk &#038; Sonny Rollins: Complete Recordings (Essential Jazz Classics, 2014)","author":"Jes\u00fas Mateu Rossell\u00f3","date":"14 enero, 2015","format":false,"excerpt":"Much\u00edsimo se ha escrito en los libros de historia en relaci\u00f3n a los dos m\u00fasicos que hoy nos acompa\u00f1an. Y es que son dos de los grandes. Posiblemente haya alg\u00fan que otro detractor, pero creo que en un porcentaje muy elevado, pr\u00e1cticamente todas las personas a las que nos gusta\u2026","rel":"","context":"En \u00ab*_Jes\u00fas Mateu Rossell\u00f3\u00bb","block_context":{"text":"*_Jes\u00fas Mateu Rossell\u00f3","link":"https:\/\/tomajazz.com\/web\/category\/jesus-mateu-rossello\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/01\/Monk-Rollins_complete-recordings-e1421176101624.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":103207,"url":"https:\/\/tomajazz.com\/web\/al-foster-live-at-smoke-2025\/","url_meta":{"origin":13078,"position":4},"title":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30897,"url":"https:\/\/tomajazz.com\/web\/365-razones-para-amar-el-jazz-una-portada-volume-2-sonny-rollins-161-a-new-perspective-13\/","url_meta":{"origin":13078,"position":5},"title":"365 razones para amar el jazz: una portada. Volume 2 (Sonny Rollins) [161] [A New Perspective 13]","author":"Tomajazz","date":"10 junio, 2017","format":false,"excerpt":"Una portada. Volume 2\u00a0(Sonny Rollins. Blue Note, 1957). Fotograf\u00eda de Francis Wolff. Seleccionado por Jos\u00e9 Luis Luna Rocafort. D\u00e9cimo tercera entrega de la serie\u00a0A New Perspective: una selecci\u00f3n de portadas de jazz en las que la fotograf\u00eda es el elemento central. Con Sonny Rollins, Horace Silver, Thelonious Monk, Jay Jay\u2026","rel":"","context":"En \u00ab*_Jos\u00e9 Luis Luna Rocafort\u00bb","block_context":{"text":"*_Jos\u00e9 Luis Luna Rocafort","link":"https:\/\/tomajazz.com\/web\/category\/jose-luis-luna-rocafort\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/06\/Sonny-Rollins_Vol-2_Blue-Note-200x196.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=13078"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13078\/revisions"}],"predecessor-version":[{"id":13080,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13078\/revisions\/13080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/13079"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=13078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=13078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=13078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}