{"id":13105,"date":"2014-07-22T11:20:39","date_gmt":"2014-07-22T09:20:39","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=13105"},"modified":"2016-11-13T16:00:17","modified_gmt":"2016-11-13T15:00:17","slug":"jeremy-pelt-face-forward-jeremy-highnote-records-2014","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/jeremy-pelt-face-forward-jeremy-highnote-records-2014\/","title":{"rendered":"Jeremy Pelt: <i>Face Forward, Jeremy<\/i> (HighNote Records, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13106\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Face-Forward-Jeremy-200x200.jpg\" alt=\"Face-Forward-Jeremy\" width=\"200\" height=\"200\" title=\"\">El trompetista Jeremy Pelt ha dado una vuelta de tuerca m\u00e1s en su apuesta por el jazz electroac\u00fastico y se ha hecho acompa\u00f1ar de nuevo por m\u00fasicos j\u00f3venes de la escena neoyorquina. <em>Face Forward, Jeremy<\/em>, puede ser considerado una secuela de <em>Water and Earth<\/em>, su anterior trabajo. Los mismos m\u00fasicos aparecen en ambos discos, y en los dos la aportaci\u00f3n de David Bryant a los teclados es una pieza central al servicio de la trompeta de Pelt y de los ritmos complejos de Dana Hawkins, a la bater\u00eda.<\/p>\n<p style=\"text-align: justify;\">El disco consta de temas interpretados con cuerdas, electr\u00f3nica, voz y momentos de jazz improvisado, todo ello adobado con l\u00edneas de <em>bop <\/em>a cargo de Pelt, ocasionalmente tratadas con eco y proceso de reverberaci\u00f3n. El grupo proyecta una gran profundidad complementada por prudentes implementaciones de electr\u00f3nica con momentos de alta velocidad y cadencias marcadas con unas gotas de <em>jazz-funk<\/em>. Se ha comentado que una de las principales influencias de este \u00e1lbum es <em>Mwandishi<\/em> de Herbie Hancock grabado a principios de los 70.<\/p>\n<p style=\"text-align: justify;\">En \u00abStars Are Free\u00bb el grupo se lanza por derroteros de un cierto <em>groove <\/em>electrificado. El interesante Dana Hawkins combina bater\u00eda ac\u00fastica y bater\u00eda programada, cuyos tiempos tienden a sonar demasiado acelerados.<\/p>\n<p style=\"text-align: justify;\">Jeremy Pelt destaca produciendo un progresivo y especial jazz de fusi\u00f3n dotado de diversidad y frescura, incluyendo dos momentos de jazz vocal, en \u201cPrincess Charlie\u201d y \u201cRastros\u201d, a cargo de Fabiana Masili. La pieza estrella del disco es \u201cGlimpse\u201d, interpretada en un tempo alto, donde Pelt demuestra sus cualidades, y que en solitario no necesita acompa\u00f1amientos pirot\u00e9cnicos. La saxofonista Roxy Coss sigue al l\u00edder con una en\u00e9rgica aportaci\u00f3n en el tenor.<\/p>\n<p style=\"text-align: justify;\">Jeremy Pelt ha encontrado un proyecto que le da unos resultados muy eficaces. Ha vuelto a repetir un nuevo \u00e1lbum brillante y ha demostrado que adem\u00e1s de ser uno de los grandes trompetistas del momento, es un m\u00fasico inspirado con numerosas ideas.<\/p>\n<p style=\"text-align: right;\">\u00a9 Carlos Lara, 2014<\/p>\n<p>Jeremy Pelt: <em>Face Forward, Jeremy<\/em><\/p>\n<p style=\"text-align: justify;\">Jeremy Pelt (trompeta), Roxy Coss (saxo tenor, saxo soprano, clarinete bajo), Fabiana Masili (voz), Milton Suggs (voz), Brandee Younger (arpa), Jenifer Shaw (violonchelo), David Bryant (piano, \u00f3rgano, teclados), Frank Locastro (teclados), Chris Smith (contrabajo y bajo el\u00e9ctrico), Dana Hawkins (bater\u00eda, bater\u00eda programada)<\/p>\n<p style=\"text-align: justify;\">\u201cHigby Part 1\u201d, \u201cStars are Free\u201d, \u201cPrincess Charlie\u201d, \u201cThe Calm Before The Storm\u201d, \u201cGlimpse\u201d, \u201cRastros\u201d, \u201cIn My Grandfather\u2019s Words\u201d, \u201cThe Secret Code\u201d y \u201cVerse\u201d.<br \/>\nTodos los temas compuestos por Jeremy Pelt<\/p>\n<p style=\"text-align: justify;\">Grabado el 24 de septiembre de 2013 en The Bunker Studio de Brooklyn (Nueva York). Editado en 2014 por HighNote Records. Distribuye Karonte HCD 7259<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trompetista Jeremy Pelt ha dado una vuelta de tuerca m\u00e1s en su apuesta por el jazz electroac\u00fastico y se ha hecho acompa\u00f1ar de nuevo por m\u00fasicos j\u00f3venes de la escena neoyorquina. Face Forward, Jeremy, puede ser considerado una secuela de Water and Earth, su anterior trabajo. Los mismos m\u00fasicos<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/jeremy-pelt-face-forward-jeremy-highnote-records-2014\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":13106,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,1038],"tags":[9898,84,12651,9902,9903,9900,9896,9901,12696,253,9895,13,12415,15295,9899,7826,9897,8546,16099,77,16100],"class_list":["entry","author-pachi","post-13105","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-contenidos","tag-brandee-younger","tag-carlos-lara","tag-cd","tag-chris-smith","tag-dana-hawkins","tag-david-bryant","tag-fabiana-masili","tag-frank-locastro","tag-grabaciones","tag-herbie-hancock","tag-highnote-records","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jenifer-shaw","tag-jeremy-pelt","tag-milton-suggs","tag-roxy-coss","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Face-Forward-Jeremy-e1405590882272.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":20613,"url":"https:\/\/tomajazz.com\/web\/jeremy-pelt-quartet-bogui-jazz-madrid-2015-10-29\/","url_meta":{"origin":13105,"position":0},"title":"Jeremy Pelt Quartet (Bogui Jazz, Madrid. 2015-10-29)","author":"Sergio Cabanillas","date":"4 noviembre, 2015","format":false,"excerpt":"Fecha: 29 de Octubre de 2015. Lugar: Bogui Jazz (Madrid). Grupo: Jeremy Pelt, trompeta Simona Premazzi, piano Josh Ginsburg, contrabajo Darrell Green, bater\u00eda El trompetista californiano Jeremy Pelt, de 39 a\u00f1os reci\u00e9n cumplidos, es actualmente uno de los mejores representantes de un jazz en el que no est\u00e1 al margen\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Jeremy Pelt \u00a9 Sergio Cabanillas, 2015","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/JEREMY_PELT_7158_CABANIJAZZ.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/JEREMY_PELT_7158_CABANIJAZZ.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/JEREMY_PELT_7158_CABANIJAZZ.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":25346,"url":"https:\/\/tomajazz.com\/web\/hdo-143-visiones-de-jazz-jeremy-pelt-memoria-uno-murray-allen-carrington-power-trio-3x3-05-podcast\/","url_meta":{"origin":13105,"position":1},"title":"HDO 143. Visiones de jazz: Jeremy Pelt \/ Memoria Uno \/ Murray Allen &#038; Carrington Power Trio. 3X3 (05) [Podcast]","author":"Tomajazz","date":"6 julio, 2016","format":false,"excerpt":"#Jiveculture (HighNote, 2016) de\u00a0Jeremy Pelt\u00a0(a quien acompa\u00f1an Ron Carter, Billy Drummond y Danny Grissett).\u00a0Cook For Butch\u00a0(Discordian Records, 2016) de\u00a0Memoria Uno que bajo la direcci\u00f3n de\u00a0Iv\u00e1n Gonz\u00e1lez\u00a0reuni\u00f3 a\u00a0Valent\u00edn Murillo, Albert Cirera, Marcel\u00b7l\u00ed Bayer, Juli\u00e1n S\u00e1nchez, Alex Reviriego, Ramon Prats, Marco Mezquida, Oriol Fontclara, Tom Chant, Frederic Filiatre, Pol Padr\u00f3s, Marc Cuevas\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/07\/Memoria-Uno_Cook-For-Butch_Discordian_2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/07\/Memoria-Uno_Cook-For-Butch_Discordian_2016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/07\/Memoria-Uno_Cook-For-Butch_Discordian_2016.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/07\/Memoria-Uno_Cook-For-Butch_Discordian_2016.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22328,"url":"https:\/\/tomajazz.com\/web\/en-concierto-con-sebastian-chames-trio-jeremy-pelt-hdo-0074-audioblog\/","url_meta":{"origin":13105,"position":2},"title":"En concierto con&#8230; Sebasti\u00e1n Chames Tr\u00edo + Jeremy Pelt. HDO 0074 [Audioblog]","author":"Tomajazz","date":"18 febrero, 2016","format":false,"excerpt":"El pianista Sebasti\u00e1n Chames actuar\u00e1 en el Caf\u00e9 Central (Madrid) la semana del 22 al 28 de febrero de 2016 encabezando su tr\u00edo (completado con el contrabajista Antonio Miguel y el baterista Daniel Garc\u00eda Bruno), y contar\u00e1 con la colaboraci\u00f3n del trompetista Jeremy Pelt. Este trompetista ha participado en las\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/02\/Sebastian-Chames_Pick-Un-The-Phone_Youkali-Music_2016-e1455746505452.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/02\/Sebastian-Chames_Pick-Un-The-Phone_Youkali-Music_2016-e1455746505452.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/02\/Sebastian-Chames_Pick-Un-The-Phone_Youkali-Music_2016-e1455746505452.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/02\/Sebastian-Chames_Pick-Un-The-Phone_Youkali-Music_2016-e1455746505452.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11977,"url":"https:\/\/tomajazz.com\/web\/eric-alexander-chicago-fire-highnote-2014-aka-rudy-van-gelder-veteranos-en-la-brecha-lix-aka-en-la-casa-del-mundo-lxxxi-just-one-of-those-things\/","url_meta":{"origin":13105,"position":3},"title":"Eric Alexander: Chicago Fire (HighNote, 2014) aka Rudy van Gelder [Veteranos en la brecha LIX] aka En La casa del Mundo LXXXI \u00abJust One Of Those Things\u00bb","author":"Tomajazz","date":"8 mayo, 2014","format":false,"excerpt":"En Chicago Fire, la nueva grabaci\u00f3n de Eric Alexander en High Note, el saxofonista rinde homenaje a\u00a0la ciudad de Chicago, y en concreto a algunos de los saxofonistas de Windy\u00a0City. Conociendo las inclinaciones estil\u00edsticas de este m\u00fasico, est\u00e1 claro que entre los homenajeados no est\u00e1n ni algunos de los potentes\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/05\/Eric-Alexander_Chicago-Fire_HighNote.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":55872,"url":"https:\/\/tomajazz.com\/web\/instantzz-theo-hill-trio-jeremy-pelt-40e-festival-jazz-terrassa-nova-jazz-cava-terrassa-barcelona-2021-06-17-galeria-fotografica-aka-fotoblog-de-jazz-impro-y-algo-mas-por-joan-co\/","url_meta":{"origin":13105,"position":4},"title":"INSTANTZZ: Theo Hill Trio &#038; Jeremy Pelt (40\u00e8 Festival Jazz Terrassa, Nova Jazz Cava, Terrassa -Barcelona-. 2021-06-17) [Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Por Joan Cort\u00e8s","author":"Tomajazz","date":"22 julio, 2021","format":false,"excerpt":"En INSTANTZZ una galer\u00eda fotogr\u00e1fica de la actuaci\u00f3n de Theo Hill Trio junto a Jeremy Pelt en el 40\u00e8 Festival Jazz Terrassa.","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/07\/10_Th-Hll-Tr-Jrmy-Plt-Joan-Cortes_18jny21_40FJT_NJC_Trrss_bn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/07\/10_Th-Hll-Tr-Jrmy-Plt-Joan-Cortes_18jny21_40FJT_NJC_Trrss_bn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/07\/10_Th-Hll-Tr-Jrmy-Plt-Joan-Cortes_18jny21_40FJT_NJC_Trrss_bn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13134,"url":"https:\/\/tomajazz.com\/web\/fotografos-amigos-y-conocidos-ii-antonio-porcar-we-wont-forget-you-dena-derose-highnote\/","url_meta":{"origin":13105,"position":5},"title":"Fot\u00f3grafos, amigos y conocidos (II): Antonio Porcar We Won&#8217;t Forget You&#8230; (Dena DeRose; HighNote)","author":"Tomajazz","date":"23 julio, 2014","format":false,"excerpt":"Fotograf\u00eda de Antonio Porcar The Dena DeRose Trio with Special Guests Eric Alexander, Jeremy Pelt, Gary Smulyan We Won't Forget You... An Homage to Shirley Horn HighNote (2014)","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Dena-DeRose-homenaje-e1406064619108.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Dena-DeRose-homenaje-e1406064619108.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Dena-DeRose-homenaje-e1406064619108.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=13105"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13105\/revisions"}],"predecessor-version":[{"id":13119,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13105\/revisions\/13119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/13106"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=13105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=13105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=13105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}