{"id":13166,"date":"2014-07-24T11:25:32","date_gmt":"2014-07-24T09:25:32","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=13166"},"modified":"2016-11-13T23:07:28","modified_gmt":"2016-11-13T22:07:28","slug":"jimmy-cobb-the-original-mob-smoke-sessions-records-2014","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/jimmy-cobb-the-original-mob-smoke-sessions-records-2014\/","title":{"rendered":"Jimmy Cobb: <i>The Original Mob<\/i> (Smoke Sessions Records, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13167\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/cobb-200x183.jpg\" alt=\"cobb\" width=\"200\" height=\"183\" title=\"\">Cuando surge el nombre de Jimmy Cobb enseguida se deja sentir el eco amplificado de <em>Kind of Blue<\/em>, como si tan descomunal obra hubiera sido el \u00fanico m\u00e9rito contra\u00eddo por el baterista norteamericano. \u00c9l particip\u00f3 en su grabaci\u00f3n, y a gala ha de tenerlo tanto \u00e9l como el buen aficionado, pero no por ello su dilatad\u00edsima trayectoria merece quedar desdibujada frente al imperio ejercido por tama\u00f1a obra y la alargad\u00edsima sombra de sus compa\u00f1eros de aventura. Cobb suma ya ochenta y cinco a\u00f1os y muchas horas de escenario. Antes y despu\u00e9s de <em>Kind of Blue<\/em> ha sido reclamado por la excelencia de la profesi\u00f3n jazz\u00edstica y su solvencia resulta indiscutible. Desde luego no ha sido un revolucionario de la bater\u00eda ni el mejor m\u00fasico que han visto los tiempos pero s\u00ed un devoto de su oficio y un m\u00fasico propicio para el proceso creativo, sobre todo en la interacci\u00f3n con otros m\u00fasicos y en el establecimiento de toda clase de complicidades. Tambi\u00e9n ha evidenciado un ojo excelente para la detecci\u00f3n de talentos. Desde luego, se merece sin discusi\u00f3n alguna ese calificativo con el que es reconocido: leyenda.<\/p>\n<p style=\"text-align: justify;\">Uno de sus proyectos, Jimmy Cobb&#8217;s Mob, ha servido siempre de amparo a algunos de esos m\u00fasicos que ya acaparan inter\u00e9s y protagonismo en el jazz actual. Brad Mehldau, John Webber y Peter Bernstein encontraron hace dos d\u00e9cadas en Cobb un veh\u00edculo id\u00f3neo para abrirse en el cosmos musical. \u00c9l los tutel\u00f3 sin ninguna clase de cautela y ahora, ya instruidos en la experiencia y el prestigio, no olvidan al maestro y le rinden la reverencia que se merece. As\u00ed lo demuestran participando en el nuevo disco de Jimmy Cobb, una grabaci\u00f3n auspiciada por el sello Smoke Sessions Records e incorporada a la serie Smoke Sessions, que acoge ya en su seno a nombres como Louis Hayes o Harold Mabern, entre otros. La de Cobb se hizo tambi\u00e9n en el Smoke Jazz Club de Nueva York, aunque sin la presencia de p\u00fablico (rememorando, como reconoce Cobb, las viejas grabaciones en casa de Rudy Van Gelder). De esta manera, el registro disfruta de un acabado esencialmente org\u00e1nico y su entronizaci\u00f3n se manifiesta de manera plena gracias a las respectivas y solidarias contribuciones de los m\u00fasicos protagonistas, de las que queda ausente el ejercicio del ego. Y precisamente ah\u00ed, en la interactuaci\u00f3n de la que se jacta cada instante del disco, reside la mayor virtud de una propuesta alimentada por diez temas, dos de ellos (\u00abComposition 101\u00bb, \u00abRemembering U\u00bb) con firma de Cobb y tres m\u00e1s sometidos a la autor\u00eda de los dem\u00e1s componentes del elenco (\u00abUnrequited\u00bb, de Brad Mehldau; \u00abMinor Blues\u00bb, de Peter Bernstein; y \u00abLickety Split\u00bb, de John Webber). Los cinco restantes son <em>standards<\/em> recreados con evidente suficiencia y aportaciones riqu\u00edsimas en matices, como todo el disco.<\/p>\n<p style=\"text-align: justify;\"><em>The Original Mob<\/em> est\u00e1 brillantemente ejecutado, a la altura de sus protagonistas. Atrapa a la audiencia y la inunda de una suerte amplia de contentos. Cada uno de los m\u00fasicos es, ahora mismo, un aut\u00e9ntico l\u00edder, una referencia del jazz contempor\u00e1neo. Sin embargo, no hay personalismos que oscurezcan el conjunto y s\u00ed aportaciones continuas que lo enriquecen. No cabe duda de que <em>The Original Mob<\/em> supone una aproximaci\u00f3n al jazz de siempre, a su identidad, a su esencia, a trav\u00e9s de la brillantez de sus ejecutantes, al talante creativo en que se empecinan y que da lustre a un disco en el que no pod\u00eda faltar, en forma de solos, el subrayado de quien le pone nombre, de un Jimmy Cobb muy c\u00f3modo en compa\u00f1\u00eda de m\u00fasicos que insisten en poner acento a sus muchas cualidades.<\/p>\n<p style=\"text-align: justify;\">No tiene desperdicio el disco desde una concepci\u00f3n global. Pero desmenuzado resulta mucho m\u00e1s apetitoso. Los m\u00fasicos estrechan numerosos lazos a lo largo de toda la propuesta bien en conjunto (sirva \u00abLickety Split\u00bb como ejemplo aunque haya muchos m\u00e1s) bien de manera \u00edntima (como la conversaci\u00f3n entre piano y guitarra de \u00abComposition 101\u00bb a la que luego se une Cobb o la exquisitez de \u00abUnrequited\u00bb en forma de bossa que permite a piano, bater\u00eda y bajo fundir sonidos) y siempre con el prop\u00f3sito de la satisfacci\u00f3n.<\/p>\n<p style=\"text-align: right;\">\u00a9 L. Castellanos, 2014<\/p>\n<p>Jimmy Cobb: <em>The Original Mob<\/em><\/p>\n<p>M\u00fasicos: Jimmy Cobb (bater\u00eda), Peter Bernstein (guitarra) (excepto en el tema &#8216;Unrequited&#8217;), Brad Mehldau (piano), John Webber (bajo)<\/p>\n<p>Temas: \u00abOld Devil Moon\u00bb,\u00bbAmsterdam After Dark\u00bb, \u00abSunday in New York\u00bb, \u00abStranger in Paradise\u00bb, \u00abUnrequited\u00bb, \u00abComposition 101\u00bb, \u00abRemembering U\u00bb, \u00abNobody Else but Me\u00bb, &#8216;Minor Blues\u00bb, Lickety Split\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando surge el nombre de Jimmy Cobb enseguida se deja sentir el eco amplificado de Kind of Blue, como si tan descomunal obra hubiera sido el \u00fanico m\u00e9rito contra\u00eddo por el baterista norteamericano. \u00c9l particip\u00f3 en su grabaci\u00f3n, y a gala ha de tenerlo tanto \u00e9l como el buen aficionado,<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/jimmy-cobb-the-original-mob-smoke-sessions-records-2014\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":13167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17882,5,1038],"tags":[43,12651,12696,7019,13,12415,15295,9951,9148,7539,1949,2004,9873,2169,9952,9950,16099,77,16100],"class_list":["entry","author-pachi","post-13166","post","type-post","status-publish","format-standard","has-post-thumbnail","category-l-castellanos","category-grabaciones","category-contenidos","tag-brad-mehldau","tag-cd","tag-grabaciones","tag-harold-mabern","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jimmy-coff","tag-john-webber","tag-l-castellanos","tag-louis-hayes","tag-miles-davis","tag-peter-bernstein","tag-rudy-van-gelder","tag-smoke-jazz-club","tag-smoke-sessions-records","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/cobb-e1406150648450.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103207,"url":"https:\/\/tomajazz.com\/web\/al-foster-live-at-smoke-2025\/","url_meta":{"origin":13166,"position":0},"title":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101751,"url":"https:\/\/tomajazz.com\/web\/chad-taylor-smoke-shifter-2025\/","url_meta":{"origin":13166,"position":1},"title":"Chad Taylor: Smoke Shifter (Otherly Love Records; 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"14 noviembre, 2025","format":false,"excerpt":"Smoke Shifter (Otherly Love Records; 2025) es lo nuevo del baterista Chad Taylor. Pachi Tapiz repasa la grabaci\u00f3n. Con Chad Taylor, Jonathan Finlayson, Bryan Rogers, Victor Vieira-Branco, Matt Engle","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Chad Taylor: Smoke Shifter (Otherly Love Records; 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz] - Tomajazz - Smoke Shifter (Otherly Love Records; 2025) es lo nuevo del baterista Chad Taylor. Pachi Tapiz repasa la grabaci\u00f3n. Con Chad Taylor, Jonathan Finlayson, Bryan Rogers, Victor Vieira-Branco, Matt Engle","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Chad-Taylor-Smoke-Shifter-Otherly-Love-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Chad-Taylor-Smoke-Shifter-Otherly-Love-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Chad-Taylor-Smoke-Shifter-Otherly-Love-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Chad-Taylor-Smoke-Shifter-Otherly-Love-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10016,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recupera-probablemente-soy-uno-de-esos-tipos-que-moriran-sobre-el-escenario-entrevista-con-jimmy-cobb-por-carlos-lara-sergio-zeni-y-armand-llacer\/","url_meta":{"origin":13166,"position":2},"title":"Tomajazz recupera&#8230; \u00abProbablemente soy uno de esos tipos que morir\u00e1n sobre el escenario\u00bb. Entrevista con Jimmy Cobb por Carlos Lara, Sergio Zeni y Armand Ll\u00e1cer","author":"Tomajazz","date":"22 enero, 2014","format":false,"excerpt":"TOMAJAZZ: \u00bfQu\u00e9 es lo que le mueve a seguir en activo en el jazz? \u00bfHa pensado en retirarse? \u00bfPor qu\u00e9 quiere seguir? JIMMY COBB: \u00bfRetirarme de qu\u00e9? \u00bfRetirarme para hacer qu\u00e9? \u00bfD\u00f3nde? No, no he pensado en retirarme. No s\u00e9 hacer otra cosa. No piensas en retirarte cuando no conoces\u2026","rel":"","context":"En \u00ab*_Armand Ll\u00e1cer\u00bb","block_context":{"text":"*_Armand Ll\u00e1cer","link":"https:\/\/tomajazz.com\/web\/category\/armand-llacer\/"},"img":{"alt_text":"cobb_jimmy_01","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/01\/cobb_jimmy_01.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":102562,"url":"https:\/\/tomajazz.com\/web\/rahsaan-roland-kirk-seek-listen-1967-2025\/","url_meta":{"origin":13166,"position":3},"title":"Rahsaan Roland Kirk: Seek &#038; Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"4 diciembre, 2025","format":false,"excerpt":"Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) es una grabaci\u00f3n in\u00e9dita de Rahsaan Roland Kirk. Pachi Tapiz repasa la grabaci\u00f3n. Con Rahsaan Roland Kirk, Rahn Burton, Steve Novosel, Jimmy Hopps","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Rahsaan Roland Kirk: Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz] - Tomajazz - Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) es una grabaci\u00f3n in\u00e9dita de Rahsaan Roland Kirk. Pachi Tapiz repasa la grabaci\u00f3n. Con Rahsaan Roland Kirk, Rahn Burton, Steve Novosel, Jimmy Hopps","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2760,"url":"https:\/\/tomajazz.com\/web\/veteranos-en-la-brecha-xxxiv-jimmy-cobb\/","url_meta":{"origin":13166,"position":4},"title":"Veteranos en la brecha (XXXIV): Jimmy Cobb","author":"Tomajazz","date":"16 noviembre, 2010","format":false,"excerpt":"Jimmy Cobb (1929), es el \u00fanico m\u00fasico superviviente entre los m\u00fasicos que grabaron el m\u00edtico Kind Of Blue (Miles Davis, 1959). En activo todav\u00eda, sin ir m\u00e1s lejos, en el verano de 2009 gir\u00f3 por Espa\u00f1a dando varios conciertos con motivo del cincuentenario del que para algunos es la grabaci\u00f3n\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29579,"url":"https:\/\/tomajazz.com\/web\/365-razones-para-amar-el-jazz-un-disco-kind-of-blue-miles-davis-1959-70\/","url_meta":{"origin":13166,"position":5},"title":"365 razones para amar el jazz: un disco. Kind Of Blue (Miles Davis, 1959) [71]","author":"Tomajazz","date":"12 marzo, 2017","format":false,"excerpt":"Un disco.\u00a0Miles Davis:\u00a0Kind Of Blue\u00a0(Columbia, 1959) Seleccionado por\u00a0Pachi Tapiz. Con\u00a0Miles Davis, Julian \"Cannonball\" Adderley, John Coltrane, Bill Evans, Wynton Kelly, Paul Chambers, Jimmy Cobb.","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/03\/Miles-Davis_Kind-Of-Blue_Columbia_1959.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=13166"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13166\/revisions"}],"predecessor-version":[{"id":13170,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13166\/revisions\/13170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/13167"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=13166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=13166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=13166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}