{"id":13607,"date":"2014-09-10T10:20:36","date_gmt":"2014-09-10T08:20:36","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=13607"},"modified":"2016-11-13T17:13:58","modified_gmt":"2016-11-13T16:13:58","slug":"sonny-rollins-road-shows-volume-3-doxy-records-2014-2","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014-2\/","title":{"rendered":"Sonny Rollins: <i>Road Shows. Volume 3<\/i> ( Doxy Records, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13079\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-200x200.jpg\" alt=\"Sonny Rollins Road Shows Vol 3\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg 500w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Sonny Rollins (1930), el <em>Saxophone Colossus<\/em> tal y como se le ha denominado desde los 50, sigue en activo. Han pasado casi diez a\u00f1os desde que grab\u00f3 su \u00faltimo CD en estudio, lo que no ha impedido que a\u00f1o tras a\u00f1o siga en los escenarios de los festivales de jazz m\u00e1s multitudinarios. F\u00edsicamente no est\u00e1 precisamente \u00e1gil. Otra cuesti\u00f3n es cuando comienza a soplar su tenor. De repente le desaparecen tres o cuatro d\u00e9cadas de encima, convirtiendo sus espect\u00e1culos en un derroche de potencia. Aprovechando ese oto\u00f1o dorado, durante los \u00faltimos a\u00f1os ha publicado tres vol\u00famenes en la serie <em>Road Shows<\/em>. Estas son unas grabaciones que recogen cl\u00e1sicos de su carrera grabados en directo. En el tercer volumen las fechas van de 2001 a 2012. Estil\u00edsticamente no realiza apenas aportaciones a su m\u00fasica (tampoco es necesario), pero la calidad de su grupo en directo (imprescindible para su propuesta) y su energ\u00eda desbordante se transmiten al oyente, atrap\u00e1ndolo sin remisi\u00f3n con piezas como los cl\u00e1sicos \u201cWhy Was I Born?\u201d (25 minutos) y \u201cSomeday I\u2019ll Find You\u201d, o con los recientes \u201cPatanjali\u201d y \u201cBiji\u201d. Todo un fen\u00f3meno este simp\u00e1tico abuelete.<\/p>\n<p style=\"text-align: right;\">\u00a9 Pachi Tapiz, 2014<\/p>\n<p>Sonny Rollins: <i>Road Shows. Volume 3<\/i> ( Doxy Records, 2014)<\/p>\n<p>Cr\u00edtica publicada en el n\u00famero 317 de la revista\u00a0<a style=\"color: #15a3c3;\" title=\"Ruta 66. Tiempos de Rock &amp; Roll\" href=\"http:\/\/www.ruta66.es\/\" target=\"_blank\" rel=\"noopener\">Ruta 66<\/a>\u00a0de julio &#8211; agosto\u00a0de 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonny Rollins (1930), el Saxophone Colossus tal y como se le ha denominado desde los 50, sigue en activo. Han pasado casi diez a\u00f1os desde que grab\u00f3 su \u00faltimo CD en estudio, lo que no ha impedido que a\u00f1o tras a\u00f1o siga en los escenarios de los festivales de jazz<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014-2\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":13079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,5,1038],"tags":[12651,9869,12696,13,12415,15295,31,4765,2225,16099,77,16100],"class_list":["entry","author-pachi","post-13607","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-grabaciones","category-contenidos","tag-cd","tag-doxy-records","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-pachi-tapiz","tag-ruta-66","tag-sonny-rollins","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":3135,"url":"https:\/\/tomajazz.com\/web\/veteranos-en-la-brecha-xiii-sonny-rollins\/","url_meta":{"origin":13607,"position":0},"title":"Veteranos en la brecha (XIII): Sonny Rollins","author":"Tomajazz","date":"19 diciembre, 2008","format":false,"excerpt":"Sonny Rollins (1930) es otro de esos m\u00fasicos que a pesar de su avanzada edad no para. El pasado mes de julio visit\u00f3 el Festival de Jazz de Vitoria para dar uno de sus interminables conciertos. Tras el verano ha publicado el primer volumen de la serie Road Shows en\u2026","rel":"","context":"En \u00ab*_Juan Carlos Hern\u00e1ndez\u00bb","block_context":{"text":"*_Juan Carlos Hern\u00e1ndez","link":"https:\/\/tomajazz.com\/web\/category\/juan-carlos-hernandez\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13078,"url":"https:\/\/tomajazz.com\/web\/sonny-rollins-road-shows-volume-3-doxy-records-2014\/","url_meta":{"origin":13607,"position":1},"title":"Sonny Rollins: Road Shows. Volume 3 ( Doxy Records, 2014)","author":"Tomajazz","date":"17 julio, 2014","format":false,"excerpt":"'Doxy' vivi\u00f3 su primera grabaci\u00f3n en junio de 1954, en el transcurso de una gloriosa sesi\u00f3n que acabar\u00eda traducida en un c\u00e9lebre disco de Miles Davis, Bag's Groove, y durante la cual su propio autor, Sonny Rollins, la interpretar\u00eda codo a codo con el genial trompetista y con los no\u2026","rel":"","context":"En \u00ab*_L.Castellanos\u00bb","block_context":{"text":"*_L.Castellanos","link":"https:\/\/tomajazz.com\/web\/category\/l-castellanos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Sonny-Rollins-Road-Shows-Vol-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":103207,"url":"https:\/\/tomajazz.com\/web\/al-foster-live-at-smoke-2025\/","url_meta":{"origin":13607,"position":2},"title":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103965,"url":"https:\/\/tomajazz.com\/web\/gilad-hekselman-downhill-from-here-2025\/","url_meta":{"origin":13607,"position":3},"title":"Gilad Hekselman: Downhill From Here (La Reserve Records; 2026) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"10 febrero, 2026","format":false,"excerpt":"Downhill From Here (La Reserve Records; 2026) es lo nuevo de Gilad Hekselman. Carlos Lara repasa la grabaci\u00f3n. Con Gilad Hekselman, Larry Grenadier, Marcus Gilmore","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Gilad Hekselman: Downhill From Here (La Reserve Records; 2026) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Downhill From Here (La Reserve Records; 2026) es lo nuevo de Gilad Hekselman. Carlos Lara repasa la grabaci\u00f3n. Con Gilad Hekselman, Larry Grenadier, Marcus Gilmore","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Gilad-Hekselman-Downhill-From-Here-La-Reserve-Records-2026.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Gilad-Hekselman-Downhill-From-Here-La-Reserve-Records-2026.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Gilad-Hekselman-Downhill-From-Here-La-Reserve-Records-2026.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Gilad-Hekselman-Downhill-From-Here-La-Reserve-Records-2026.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101020,"url":"https:\/\/tomajazz.com\/web\/ruben-reinaldo-entrevista-fusion-olivica-2025\/","url_meta":{"origin":13607,"position":4},"title":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz]","author":"Tomajazz","date":"27 octubre, 2025","format":false,"excerpt":"El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","rel":"","context":"En \u00abEntrevistas...\u00bb","block_context":{"text":"Entrevistas...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/entrevistas-criticas\/"},"img":{"alt_text":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz] - Tomajazz - El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":102562,"url":"https:\/\/tomajazz.com\/web\/rahsaan-roland-kirk-seek-listen-1967-2025\/","url_meta":{"origin":13607,"position":5},"title":"Rahsaan Roland Kirk: Seek &#038; Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"4 diciembre, 2025","format":false,"excerpt":"Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) es una grabaci\u00f3n in\u00e9dita de Rahsaan Roland Kirk. Pachi Tapiz repasa la grabaci\u00f3n. Con Rahsaan Roland Kirk, Rahn Burton, Steve Novosel, Jimmy Hopps","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Rahsaan Roland Kirk: Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) Por Pachi Tapiz [Grabaci\u00f3n de jazz] - Tomajazz - Seek & Listen: Live at the Penthouse (Resonance Records; 1967; Publicaci\u00f3n 2025) es una grabaci\u00f3n in\u00e9dita de Rahsaan Roland Kirk. Pachi Tapiz repasa la grabaci\u00f3n. Con Rahsaan Roland Kirk, Rahn Burton, Steve Novosel, Jimmy Hopps","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Rahsaan-Roland-Kirk-Seek-and-Listen-Live-at-the-Penthouse-Resonance-Records-1967-Publicacion-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=13607"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13607\/revisions"}],"predecessor-version":[{"id":13608,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/13607\/revisions\/13608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/13079"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=13607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=13607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=13607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}