{"id":14050,"date":"2006-12-18T22:09:19","date_gmt":"2006-12-18T21:09:19","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=14050"},"modified":"2022-08-25T23:52:25","modified_gmt":"2022-08-25T21:52:25","slug":"david-berger-apuntes-para-interpretar-a-ellington","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/david-berger-apuntes-para-interpretar-a-ellington\/","title":{"rendered":"David Berger: apuntes para interpretar a Ellington"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>El compositor, arreglista y director de orquesta David Berger es reconocido internacionalmente como una autoridad en la m\u00fasica de Duke Ellington y de la era del swing en general. Director y arreglista de la Lincoln Center Jazz Orchestra entre 1988 y 1994, ha realizado transcripciones de m\u00e1s de 500 composiciones de Ellington y Strayhorn, muchas de las cuales est\u00e1n disponibles a trav\u00e9s de Alfred Music y Such Sweet Thunder. Actualmente dirige su propia banda de 16 m\u00fasicos, <a href=\"http:\/\/www.sultansofswing.com\/index2.html\" target=\"_blank\" rel=\"noopener\">The Sultans Of Swing<\/a>, con la que ha grabado 4 discos y contin\u00faa girando por Estados Unidos y Europa. <\/em><\/p>\n<p class=\"texto\" style=\"text-align: justify;\" align=\"justify\"><em>Estos \u201cApuntes para interpretar a Ellington\u201d, que traducimos aqu\u00ed con su expresa autorizaci\u00f3n, son unas notas de apoyo para <a href=\"http:\/\/www.jalc.org\/jazzED\/ee\/welcome.html\" target=\"_blank\" rel=\"noopener\">el programa \u201cEssentially Ellington\u201d del Lincoln Center<\/a>, por el que se promueve la divulgaci\u00f3n de la m\u00fasica de Duke Ellington en los institutos de Estados Unidos y Canad\u00e1, mediante la distribuci\u00f3n de partituras y la convocatoria de un concurso y un festival de big bands.<\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_14053\" aria-describedby=\"caption-attachment-14053\" style=\"width: 336px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14053\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity.jpg\" alt=\"&quot;Duke Ellington - publicity&quot; by Unknown - eBay. Licensed under Public domain via Wikimedia Commons.\" width=\"336\" height=\"434\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity.jpg 336w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity-116x150.jpg 116w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity-200x258.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity-42x55.jpg 42w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><figcaption id=\"caption-attachment-14053\" class=\"wp-caption-text\">\u00ab<a href=\"http:\/\/commons.wikimedia.org\/wiki\/File:Duke_Ellington_-_publicity.JPG#mediaviewer\/File:Duke_Ellington_-_publicity.JPG\" target=\"_blank\" rel=\"noopener\">Duke Ellington &#8211; publicity<\/a>\u00bb by Unknown &#8211; <a class=\"external text\" href=\"http:\/\/www.ebay.com\/itm\/DUKE-ELLINGTON-original-posed-portrait-b-w-publicity-still-photo-\/350759141505?pt=LH_DefaultDomain_0&amp;hash=item51aadfc081\" rel=\"nofollow noopener\" target=\"_blank\">eBay<\/a>. Licensed under Public domain via <a href=\"\/\/commons.wikimedia.org\/wiki\/\">Wikimedia Commons<\/a>.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p class=\"texto\" style=\"text-align: center;\" align=\"justify\"><strong>David Berger: apuntes para interpretar a Ellington<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Como m\u00ednimo el 95% de lo que tocan los grupos grandes de jazz hoy en d\u00eda procede de tres tradiciones: la banda de Count Basie, la de Duke Ellington y los arreglos para grupos peque\u00f1os. Los j\u00f3venes int\u00e9rpretes que se interesen por el jazz tender\u00e1n a los grupos peque\u00f1os, por las oportunidades para la improvisaci\u00f3n, y por motivos pr\u00e1cticos (es mucho m\u00e1s f\u00e1cil organizar a cuatro o cinco personas que a 15). La labor de formar a j\u00f3venes m\u00fasicos como int\u00e9rpretes de conjunto, antes en manos de las bandas de baile, ha pasado a las escuelas. Por su popularidad, la sencillez de sus arreglos y su \u00e9nfasis en el <em>Swing<\/em> y el <em>Blues<\/em>, los mejores educadores han optado casi exclusivamente por la tradici\u00f3n de Basie para ense\u00f1ar a tocar jazz en conjunto. Aun siendo un estilo maravilloso, el estilo de Basie no trata muchos de los estilos importantes que se han desarrollado bajo el gran paraguas musical que llamamos jazz. El enfoque musical de Duke Ellington, exhaustivo y ecl\u00e9ctico, ofrece una alternativa.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">La riqueza estil\u00edstica de la m\u00fasica de Ellington constituye un gran reto para educadores e int\u00e9rpretes por igual. En la m\u00fasica de Basie, las convenciones son casi siempre las mismas. En la de Ellington, hay muchas m\u00e1s excepciones a las reglas. Esto requiere un mayor conocimiento del lenguaje del jazz. Clark Terry, que dej\u00f3 la banda de Count Basie para pasar a la de Duke Ellington, dijo: \u201cCount Basie fue como la universidad, pero Duke Ellington era como un postgrado\u201d. El conocimiento de la m\u00fasica de Ellington te prepara para tocar cualquier m\u00fasica de <em>big band<\/em>. A continuaci\u00f3n se adjunta una lista de convenciones para interpretar la gran mayor\u00eda de la m\u00fasica de Ellington.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">1. Escucha atentamente y muchas veces las grabaciones de Ellington de estas piezas. Hay gran cantidad de sutilezas que en la primera escucha se le escapar\u00e1n aun al oyente m\u00e1s experimentado. Aunque Ellington nunca dese\u00f3 que se imitasen sus grabaciones, el conocimiento de estas versiones definitivas ayudar\u00e1 a los m\u00fasicos a tomar decisiones m\u00e1s fundamentadas a la hora de crear nuevas interpretaciones. La m\u00fasica de Ellington, aunque se escribi\u00f3 para individuos concretos, est\u00e1 dise\u00f1ada para incitar a los m\u00fasicos a que se expresen. Por otra parte, se percibir\u00e1n leves diferencias entre las notas de la grabaci\u00f3n y las de las transcripciones. Esto es intencionado, ya que las grabaciones contienen errores y alteraciones respecto de la m\u00fasica original. Has de hacer que tus m\u00fasicos toquen lo que pone en la partitura.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">2. Uso general del <em>swing<\/em> en el fraseo. La sensaci\u00f3n de tresillo predomina, excepto en las baladas, o donde las partituras indiquen corcheas rectas o un ritmo <em>latino<\/em>. En estos casos, se da a las corcheas el mismo valor.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">3. En la interpretaci\u00f3n de conjunto existe una jerarqu\u00eda. Los l\u00edderes de cada secci\u00f3n determinan el fraseo y el volumen de su propia secci\u00f3n, y sus compa\u00f1eros deben adaptarse al l\u00edder. Cuando los saxos o los trombones tocan con las trompetas, manda el primer trompeta. A su vez, los otros saxos y trombones deben seguir a sus propios jefes de secci\u00f3n. Cuando el clarinete toca con los cobres, \u00e9stos no deber\u00edan taparlo. Esto implica que el primer trompeta en realidad estar\u00e1 tocando como \u201csegundo\u201d. Si esto se hace de forma eficaz, el director tendr\u00e1 poco trabajo a la hora de equilibrar el sonido.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">4. En la m\u00fasica de Ellington, cada m\u00fasico deber\u00eda expresar la individualidad de la parte que le haya tocado, tratando de encontrar un equilibrio musical entre, por un lado, apoyar y seguir al l\u00edder y, por otro, sacar a relucir el car\u00e1cter de su propia partitura. Deber\u00eda animarse a cada uno de los m\u00fasicos a expresar su propia personalidad mediante la m\u00fasica. En esta m\u00fasica, las partituras secundarias se interpretan al mismo volumen y con la misma convicci\u00f3n que las principales.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">5. Las inflexiones de <em>blues<\/em> deben permear todas las partituras en todo momento, no s\u00f3lo cuando surja la ocasi\u00f3n para las principales.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">6. Se usa un poco de vibrato para dar calidez al sonido. Los saxos (que generalmente representan la sensualidad) normalmente recurren a un vibrato pronunciado en los pasajes armonizados, y a un vibrato leve en los un\u00edsonos. Las trompetas (usadas normalmente para dar calor y energ\u00eda) usan un vibrato leve en los pasajes armonizados y ninguno en los un\u00edsonos. Los trombones (s\u00edmbolo de la nobleza) no usan el vibrato de vara. En ocasiones es recomendable algo de vibrato de labio, tratando de sincronizar la frecuencia de vibrato. Los un\u00edsonos se tocan sin vibrato.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">7. Toca en <em>crescendo<\/em> cuando asciendas por la escala y en <em>diminuendo<\/em> cuando desciendas. Las notas altas de las frases reciben un acento natural, y las notas bajas apenas suenan [<em>ghost notes<\/em>]. Los saxos altos y tenores han de recurrir a los subtonos en la parte inferior de sus tesituras a fin de empastarse adecuadamente con el resto de la secci\u00f3n. Esta m\u00fasica se escribi\u00f3 originalmente sin indicaciones din\u00e1micas. En gran medida sigue las tendencias naturales de los propios instrumentos: suena fuerte en las partes fuertes del instrumento y suave en las suaves. Por ejemplo, un Do alto de una trompeta sonar\u00e1 con mucho volumen, mientras que un Do bajo sonar\u00e1 suave.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">8. Las negras generalmente se tocan cortas, a menos que se indique lo contrario. Los signos encima o debajo de una nota indican que se toque su valor completo, no s\u00f3lo larga. Las corcheas se tocan completas a menos que vengan seguidas de un silencio o que se indique lo contrario. Todas las notas superiores a la negra se tocan completas, lo que quiere decir que si vienen seguidas de un silencio, se deja de tocar la nota cuando aparece el silencio. Por ejemplo, una blanca en el primer tiempo del comp\u00e1s deber\u00e1 interrumpirse en el tercer tiempo.<\/p>\n<p class=\"texto\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.tomajazz.com\/perfiles\/ellington\/ellington_notes_berger\/ellington.jpg\" alt=\"\" width=\"350\" height=\"292\" border=\"1\" title=\"\"><br \/>\nFoto publicitaria de la orquesta en 1934 (estudios Maurice de Chicago)<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">9. A menos que sean parte de un acompa\u00f1amiento en legato, las notas largas deber\u00edan tocarse algo <em>fp<\/em> [forte-piano], acentuando y luego bajando el volumen. Esto es importante para que las partes en movimiento puedan o\u00edrse sobre las notas sostenidas. No hay que limitarse a sostener las notas largas, hay que darles vida y car\u00e1cter: es decir, vibrato, inflexi\u00f3n, <em>crescendo<\/em> o <em>diminuendo<\/em>. Esta m\u00fasica presenta muchas inflexiones, y buena parte de la misma es altamente interpretativa. Las l\u00edneas mel\u00f3dicas, sean rectas o curvas, requieren deslizamientos atonales, y las melod\u00edas ondulantes implican deslizamientos escalares (diat\u00f3nicos o crom\u00e1ticos). En general todas las figuras r\u00edtmicas requieren acentuaci\u00f3n. Los acentos otorgan vida y swing a la m\u00fasica. \u00c9ste punto es muy importante.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">10. La m\u00fasica de Ellington se basa en la individualidad: una persona por partitura. No se debe doblar porque te sobren m\u00fasicos o necesites m\u00e1s potencia. M\u00e1s de una persona por partitura os har\u00e1 sonar m\u00e1s como una orquesta formal que como una banda de jazz.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">11. Esta m\u00fasica es ac\u00fastica. Mant\u00e9n la amplificaci\u00f3n al m\u00ednimo absoluto. En los mejores auditorios la amplificaci\u00f3n apenas deber\u00eda ser necesaria. Todos los m\u00fasicos han de desarrollar un sonido potente. Le corresponde al director equilibrar el sonido de la banda. Cuando haya guitarra, debe ser r\u00edtmica, sin amplificar, de caja hueca, tocando s\u00f3lo acordes de tres notas. Es indispensable un bajo ac\u00fastico. En auditorios mediocres o pobremente dise\u00f1ados, el piano y el bajo necesitar\u00e1n algo de ayuda. Personalmente, recomiendo que se usen micr\u00f3fonos con el sistema de megafon\u00eda que haya ya instalado. Esto deber\u00eda dar un tono mucho mejor que el de un amplificador. Ten presente que la principal funci\u00f3n de la secci\u00f3n r\u00edtmica es acompa\u00f1ar. El bajo no deber\u00eda sonar tan alto como una trompeta. Esto va <em>contra natura<\/em> y causa la sobreamplificaci\u00f3n, un mal tono y limita la din\u00e1mica. Rechaza los monitores: dan una falsa sensaci\u00f3n de equilibrio.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">12. Los solos y las partes de la secci\u00f3n r\u00edtmica que no tengan acordes deben tocarse tal cual o con poca ornamentaci\u00f3n. Los solos y las partes de la secci\u00f3n r\u00edtmica con acordes deber\u00edan improvisarse. Sin embargo, los pasajes escritos deber\u00edan aprenderse de memoria, porque constituyen una parte importante de nuestro patrimonio jazz\u00edstico y ayudan al m\u00fasico a comprender la funci\u00f3n de sus solos y acompa\u00f1amientos. Los solistas deber\u00edan aprenderse las secuencias de acordes. Los solos no deber\u00edan plantearse como una oportunidad para exhibir t\u00e9cnica, diversidad de recursos o volumen, sino como una gran ocasi\u00f3n para ampliar el desarrollo del fascinante material tem\u00e1tico que nos ha legado Ellington.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">13. La notaci\u00f3n de <em>Plunger<\/em> para los cobres significa desatascador de goma de los que se pueden adquirir en ferreter\u00edas. Kirkhill es una marca excelente (sobre todo si puedes hacerte con una de las antiguas, como la que le prest\u00e9 a Wynton y que luego perdi\u00f3). Las trompetas requieren un di\u00e1metro de 5 pulgadas [12,5 cm] y los trombones, 6 pulgadas [15 cm]. Cuando se indica <em>Plunger\/Mute<\/em>, inserta una sordina <em>pixie<\/em> en la campana y usa el <em>plunger<\/em> sobre la <em>pixie<\/em>. Las <em>pixies<\/em> se pueden conseguir en Humes &amp; Berg, en Chicago. \u201cTricky Sam\u201d Nanton y sus sucesores en la silla del tromb\u00f3n <em>plunger<\/em> no usaban <em>pixies<\/em>, sino una sordina normal de trompeta Nonpareil (\u00e9sa es la marca). Nonpareil ha dejado de fabricar sordinas, pero la sordina para trompetas Tom Crown Nonpareil se parece mucho a la original. Estas sordinas crean un sonido maravilloso (muy cercano a la voz humana), pero tambi\u00e9n provocan ciertos problemas de entonaci\u00f3n, que deben corregirse exclusivamente con el labio. Ser\u00eda m\u00e1s f\u00e1cil mover la bomba de afinaci\u00f3n, pero el esfuerzo por corregir la afinaci\u00f3n forma parte del sonido. Si resulta demasiado esfuerzo, recurre a la <em>pixie<\/em>, es bastante similar.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">14. El bater\u00eda es el l\u00edder de facto de la banda. Establece el pulso y controla el volumen del conjunto. En las <em>big bands<\/em> el bater\u00eda requiere un bombo mayor que el que usar\u00eda en un combo. Se recomienda uno de 22 pulgadas [55 cm]. El bombo se toca con suavidad (casi inaudible) en cada tiempo del comp\u00e1s. Esto se llama \u201cacariciar\u201d [<em>feathering<\/em>] el bombo, y proporciona un fondo muy importante para la banda. El sonido del bombo no es ni una explosi\u00f3n ni un ruido sordo, sino algo intermedio. Se requiere un tambor m\u00e1s grande para los <em>kicks<\/em>, uno peque\u00f1o simplemente no se va a o\u00edr. La clave de este estilo es limitarse a marcar los tiempos. Un golpe en el borde [<em>rim<\/em>] de la caja en los tiempos 2 y 4 [<em>chopping wood<\/em>, \u201chacer le\u00f1a\u201d] se usa para fijar el swing. A la hora de tocar acompa\u00f1amientos [<em>fills<\/em>], cuantos menos, mejor.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">15. Los cobres deben ponerse de pie en los solos o los <em>solis<\/em> [ver glosario], o cuando toquen s\u00f3lo las trompetas o los trombones. Si el solo es de duraci\u00f3n media o larga, los cobres deben ponerse delante de la orquesta, siempre que lo permita la partitura. Esto tambi\u00e9n se aplica a la <em>pep section<\/em> (dos trompetas y un tromb\u00f3n con <em>plunger<\/em> + sordina).<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">16. Los vientos han de prestar atenci\u00f3n al ataque y el final de las frases. Todo el mundo debe golpear a la vez y terminar a la vez.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">17. Los cobres deben ser muy precisos cuando toquen notas cortas. \u00a1Las notas han de detenerse con la lengua, como hac\u00eda Louis Armstrong!<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">18. Lo m\u00e1s importante es que en todo momento la atenci\u00f3n de cada m\u00fasico deber\u00eda centrarse en el <em>swing<\/em>. Como dice el gran bajista Chuck Israels, \u201clas tres cosas m\u00e1s importantes en el jazz son: el ritmo, el ritmo y el ritmo, en ese orden\u201d. O como dijo Bubber Miley (la primera estrella de la trompeta que tuvo Ellington), \u201cIt don\u2019t mean a thing if it ain\u2019t got that swing\u201d [\u201csi no tiene swing, no importa nada\u201d].<\/p>\n<p class=\"texto\" align=\"center\"><strong>Glosario<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">A continuaci\u00f3n se incluyen algunos t\u00e9rminos que describen las convenciones de la interpretaci\u00f3n de jazz, desde el tradicional de Nueva Orleans a la vanguardia actual.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Break<\/em> [literalmente \u201cpausa\u201d]: en el contexto de un ritmo subyacente, la secci\u00f3n r\u00edtmica se detiene durante uno, dos o cuatro compases. Con frecuencia, un solista improvisar\u00e1 durante un <em>break<\/em>.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Call and response<\/em> [literalmente \u201cllamada y respuesta\u201d]: patr\u00f3n repetitivo de intercambios contrastantes, derivados del proceso t\u00edpico en las iglesias de EE UU en las que el oficiante dice algo y la congregaci\u00f3n contesta \u201cam\u00e9n\u201d. Los patrones de llamada y respuesta normalmente enfrentan a un grupo de instrumentos con otro. A veces llamamos a esto \u201c<em>trading fours<\/em>\u201d, \u201c<em>trading twos<\/em>\u201d, etc. [literalmente \u201cintercambiar tandas de cuatro o dos compases\u201d], especialmente si hay improvisaci\u00f3n de por medio. Los n\u00fameros denotan el n\u00famero de compases que toca cada solista o grupo de instrumentos. Otro t\u00e9rmino usado con frecuencia es \u201c<em>swapping fours<\/em>\u201d [mismo significado].<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Coda<\/em>: en ingl\u00e9s tambi\u00e9n conocida como \u201coutro\u201d [en contraposici\u00f3n a \u201cintro\u201d]. Las \u201c<em>tags<\/em>\u201d o \u201c<em>tag endings<\/em>\u201d son una derivaci\u00f3n de los saludos del vodevil que se usan frecuentemente como <em>codas<\/em>. Con frecuencia son cadencias enga\u00f1osas que acaban por resolverse en la t\u00f3nica, o que van de la t\u00f3nica a la subdominante y regresan de forma c\u00edclica a la t\u00f3nica: I V\/IV IV #IVo I (segunda inversi\u00f3n) V\/II V\/V V I.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Comp<\/em>: acompa\u00f1amiento improvisado (piano o guitarra).<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Groove<\/em>: ritmo combinado. Generalmente se refiere a los patrones r\u00edtmicos repetitivos combinados de la bater\u00eda, bajo, piano y guitarra, pero puede incluir tambi\u00e9n los patrones repetitivos de los vientos. Algunos <em>grooves<\/em> est\u00e1n estandarizados (como el <em>swing<\/em>, la <em>bossa nova<\/em>, la samba), mientras que otros son combinaciones originales de ritmos.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Head<\/em>: coro o \u201cvuelta\u201d completa en la que se toca la melod\u00eda.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Interlude<\/em> [interludio]: una forma diferente (de duraci\u00f3n relativamente corta) que se toca entre dos \u201cvueltas\u201d. Los interludios que implican un cambio de tonalidad se llaman simplemente \u201cmodulaciones\u201d.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Intro<\/em>: abreviatura de introducci\u00f3n.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Ride pattern<\/em>: la figura repetitiva m\u00e1s com\u00fan que el bater\u00eda toca con su mano derecha en el <em>ride cymbal<\/em> o el <em>hi-hat<\/em> [charles].<\/p>\n<p class=\"texto\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.tomajazz.com\/perfiles\/ellington\/ellington_notes_berger\/image1.jpg\" alt=\"\" width=\"213\" height=\"51\" title=\"\"><\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Riff<\/em>: figura mel\u00f3dica repetitiva. Con frecuencia, los <em>riffs<\/em> se repiten literalmente o con leves variaciones cuando cambian las armon\u00edas subyacentes.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Shout chorus<\/em> [literalmente, \u201cvuelta de alarido\u201d]: tambien conocido como el \u201c<em>out chorus<\/em>\u201d [\u201cvuelta de salida\u201d], el \u201c<em>sock chorus<\/em>\u201d, o a veces simplemente abreviado a \u201c<em>the shout<\/em>\u201d [\u201cel alarido\u201d]. Es el pasaje final del conjunto de casi todas las piezas para <em>big band<\/em> y en el que normalmente se produce el cl\u00edmax.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Soli<\/em>: un pasaje armonizado para dos o m\u00e1s instrumentos tocando el mismo ritmo. Es habitual que los vientos se pongan de pie o incluso pasen delante de la banda para tocar estos pasajes. Eso se hace para que se les oiga mejor y para mantener la atenci\u00f3n visual del p\u00fablico. La <em>pep section<\/em> es un sonido de <em>soli<\/em> particular de la m\u00fasica de Ellington que combina dos trompetas y un tromb\u00f3n, todos ellos con <em>plunger<\/em> y sordina tocando armon\u00edas tri\u00e1dicas.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Stop time<\/em>: un patr\u00f3n regular de <em>breaks<\/em> cortos (normalmente aprovechados por un solista).<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Swing<\/em>: la perfecta confluencia de la tensi\u00f3n y la relajaci\u00f3n r\u00edtmica en la m\u00fasica, por la que se genera un sentimiento de euforia, que se caracteriza por la acentuaci\u00f3n de los tiempos d\u00e9biles del comp\u00e1s (una \u201cdemocratizaci\u00f3n\u201d del ritmo) y de la primera y tercera corcheas de un tresillo. La definici\u00f3n de Ellington del <em>swing<\/em>: cuando parece que la m\u00fasica se acelera pero en realidad no es as\u00ed.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Vamp<\/em>: la repetici\u00f3n de una progresi\u00f3n de acordes de dos o cuatro compases. Con frecuencia se tocan uno o varios <em>riffs<\/em> sobre un <em>vamp<\/em>.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><em>Voicing<\/em>: la selecci\u00f3n de notas, su orden (inversi\u00f3n) y espaciado a la hora de construir un acorde. Por ejemplo, Sol 7 puede construirse de estas dos maneras:<\/p>\n<p class=\"texto\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.tomajazz.com\/perfiles\/ellington\/ellington_notes_berger\/image2.jpg\" alt=\"\" width=\"270\" height=\"113\" title=\"\"><\/p>\n<p style=\"text-align: justify;\"><span class=\"texto\"> N\u00f3tese que la primera opci\u00f3n incluye una 9\u00aa y que la segunda tiene una 9\u00aa menor y una 13\u00aa. La adici\u00f3n de 9as, 11as y 13as y sus alteraciones queda a discreci\u00f3n del pianista y el solista.<\/span><\/p>\n<p class=\"texto\" style=\"text-align: center;\"><strong>Los cuatro elementos de la m\u00fasica<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Se enumeran en orden de importancia en el jazz. Nunca se debe perder de vista de este orden de prioridades:<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">&#8211; Ritmo: m\u00e9trica, <em>tempo<\/em>, <em>groove<\/em> y forma, incluidos tanto el ritmo mel\u00f3dico como el arm\u00f3nico (velocidad y regularidad de las secuencias de acordes).<br \/>\n&#8211; Melod\u00eda: lo que tocan los m\u00fasicos, un tema o una serie de notas.<br \/>\n&#8211; Armon\u00eda: acordes y <em>voicings<\/em><br \/>\n&#8211; Orquestaci\u00f3n: instrumentaci\u00f3n y colores tonales.<\/p>\n<p class=\"texto\" style=\"text-align: right;\">\u00a91996, David Berger (del original)<br \/>\n\u00a92006, Fernando Ortiz de Urbina (de la traducci\u00f3n al espa\u00f1ol)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El compositor, arreglista y director de orquesta David Berger es reconocido internacionalmente como una autoridad en la m\u00fasica de Duke Ellington y de la era del swing en general. Director y arreglista de la Lincoln Center Jazz Orchestra entre 1988 y 1994, ha realizado transcripciones de m\u00e1s de 500 composiciones<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/david-berger-apuntes-para-interpretar-a-ellington\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":14053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17885,17863,78,15504,9,1038],"tags":[947,6845,1450,10587,6637,465],"class_list":["entry","author-pachi","post-14050","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agustin-perez-gasco","category-fernando-ortiz-de-urbina","category-afondo","category-articulos-afondo","category-perfiles","category-contenidos","tag-agustin-perez-gasco","tag-clark-terry","tag-basie-count","tag-david-berger","tag-duke-ellington","tag-fernando-ortiz-de-urbina"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":14056,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recupera-david-berger-apuntes-para-interpretar-a-ellington\/","url_meta":{"origin":14050,"position":0},"title":"Tomajazz recupera&#8230; David Berger: apuntes para interpretar a Ellington","author":"Tomajazz","date":"19 septiembre, 2014","format":false,"excerpt":"Continuamos con una nueva incorporaci\u00f3n al especial Duke Ellington. El compositor, arreglista y director de orquesta David Berger es reconocido internacionalmente como una autoridad en la m\u00fasica de Duke Ellington y de la era del swing en general. Estos \u201cApuntes para interpretar a Ellington\u201d son unas notas de apoyo para\u2026","rel":"","context":"En \u00ab*_Agust\u00edn P\u00e9rez Gasco\u00bb","block_context":{"text":"*_Agust\u00edn P\u00e9rez Gasco","link":"https:\/\/tomajazz.com\/web\/category\/agustin-perez-gasco\/"},"img":{"alt_text":"\"Duke Ellington - publicity\" by Unknown - eBay. Licensed under Public domain via Wikimedia Commons.","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2006\/12\/696px-Duke_Ellington_-_publicity-200x258.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13889,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recupera-biografia-de-duke-ellington-por-donald-clarke\/","url_meta":{"origin":14050,"position":1},"title":"Tomajazz recupera&#8230; Biograf\u00eda de Duke Ellington por Donald Clarke","author":"Tomajazz","date":"12 septiembre, 2014","format":false,"excerpt":"En \u00a0noviembre y diciembre de 2006 se public\u00f3 en Tomajazz en dos partes,\u00a0con el permiso de su autor,\u00a0la biograf\u00eda de Duke Ellington realizada\u00a0por Donald Clarke en su Enciclopedia de la m\u00fasica popular. Recuperamos la traducci\u00f3n que realizaron Agust\u00edn P\u00e9rez Gasco y Fernando Ortiz de Urbina. Duke Ellington: Biograf\u00eda por Donald\u2026","rel":"","context":"En \u00ab*_Agust\u00edn P\u00e9rez Gasco\u00bb","block_context":{"text":"*_Agust\u00edn P\u00e9rez Gasco","link":"https:\/\/tomajazz.com\/web\/category\/agustin-perez-gasco\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/640px-Duke_Ellington_Big_Band.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/640px-Duke_Ellington_Big_Band.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/640px-Duke_Ellington_Big_Band.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14183,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recupera-max-harrison-reflexiones-sobre-las-obras-extensas-de-ellington\/","url_meta":{"origin":14050,"position":2},"title":"Tomajazz recupera&#8230; Max Harrison: Reflexiones sobre las obras extensas de Ellington","author":"Tomajazz","date":"26 septiembre, 2014","format":false,"excerpt":"\"Max Harrison: Reflexiones sobre las obras extensas de Ellington\" fue inicialmente publicado en Jazz Monthly (enero de 1964) y con posterioridad fue revisado y ampliado para su publicaci\u00f3n en el libro A Jazz Retrospect (Newton Abbot, 1976; Quartet, 1991) de Max Harrison. La versi\u00f3n definitiva, que traducimos a continuaci\u00f3n con\u2026","rel":"","context":"En \u00ab*_Agust\u00edn P\u00e9rez Gasco\u00bb","block_context":{"text":"*_Agust\u00edn P\u00e9rez Gasco","link":"https:\/\/tomajazz.com\/web\/category\/agustin-perez-gasco\/"},"img":{"alt_text":"duke","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/duke.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":24068,"url":"https:\/\/tomajazz.com\/web\/especial-25-discos-de-jazz-una-guia-esencial-2005\/","url_meta":{"origin":14050,"position":3},"title":"Especial 25 Discos de Jazz: una gu\u00eda esencial (2005)","author":"Tomajazz","date":"9 mayo, 2016","format":false,"excerpt":"En Tomajazz recuperamos\u00a025 Discos de Jazz: una gu\u00eda esencial que Jorge L\u00f3pez de Guere\u00f1u, Nacho Fuentes y Agust\u00edn P\u00e9rez Gasco, bajo la direcci\u00f3n de Fernando Ortiz de Urbina realizaron en 2005. El resultado, en cinco partes, fue una recopilaci\u00f3n de CD de jazz b\u00e1sicos en cualquier colecci\u00f3n, que siguen estando\u2026","rel":"","context":"En \u00ab*_Agust\u00edn P\u00e9rez Gasco\u00bb","block_context":{"text":"*_Agust\u00edn P\u00e9rez Gasco","link":"https:\/\/tomajazz.com\/web\/category\/agustin-perez-gasco\/"},"img":{"alt_text":"Especial 25 discos de jazz: una gu\u00eda esencial [Grabaciones de jazz] Editor Fernando Ortiz de Urbina 25 discos de jazz una gu\u00eda esencial Tomajazz 9.0 - Presentaci\u00f3n del Especial 25 discos de jazz una gu\u00eda esencial. Fernando Ortiz de Urbina fue el encargado de editar y dirigir este especial, dividido en cuatro partes.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2005\/10\/25-discos-de-jazz_una-gu%C3%ADa-esencial.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2005\/10\/25-discos-de-jazz_una-gu%C3%ADa-esencial.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2005\/10\/25-discos-de-jazz_una-gu%C3%ADa-esencial.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2005\/10\/25-discos-de-jazz_una-gu%C3%ADa-esencial.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13869,"url":"https:\/\/tomajazz.com\/web\/duke-ellington-biografia-por-donald-clarke-segunda-parte-1956-1974\/","url_meta":{"origin":14050,"position":4},"title":"Duke Ellington: Biograf\u00eda por Donald Clarke (Segunda parte: 1956-1974)","author":"Tomajazz","date":"1 diciembre, 2006","format":false,"excerpt":"Duke Ellington: Biograf\u00eda por Donald Clarke (Segunda parte: 1956-1974). En Tomajazz reproducimos la biograf\u00eda de Duke Ellington de Donald Clarke gracias al permiso de su autor y a la traducci\u00f3n y buen hacer de Agust\u00edn P\u00e9rez Gasco y Fernando Ortiz de Urbina.","rel":"","context":"En \u00ab*_Agust\u00edn P\u00e9rez Gasco\u00bb","block_context":{"text":"*_Agust\u00edn P\u00e9rez Gasco","link":"https:\/\/tomajazz.com\/web\/category\/agustin-perez-gasco\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/perfiles\/ellington\/ellington_bio2\/duke015.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1208,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-especial-25-discos-de-jazz-una-guia-esencial\/","url_meta":{"origin":14050,"position":5},"title":"Tomajazz recomienda&#8230; Especial 25 Discos de Jazz: una gu\u00eda esencial","author":"Adolphus van Tenzing","date":"16 marzo, 2011","format":false,"excerpt":"Cuatro especialistas y grandes aficionados desarrollan el especial \"25 Discos de Jazz: una gu\u00eda esencial\". El resultado es una gu\u00eda fant\u00e1stica para aproximarse a la respuesta de la pregunta (hist\u00f3rica): \"\u00bfQu\u00e9 es el Jazz?\". Agust\u00edn P\u00e9rez, Ignacio Fuentes y Jorge L\u00f3pez de Guere\u00f1u, coordinados por Fernando Ortiz de Urbina han\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/03\/Masada_Sanhedrin.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=14050"}],"version-history":[{"count":5,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14050\/revisions"}],"predecessor-version":[{"id":65982,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14050\/revisions\/65982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/14053"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=14050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=14050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=14050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}