{"id":14164,"date":"2014-09-26T10:40:38","date_gmt":"2014-09-26T08:40:38","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=14164"},"modified":"2016-11-13T17:13:50","modified_gmt":"2016-11-13T16:13:50","slug":"3d-tomasz-dabrowski-kris-davis-andrew-drury-vermillion-tree-for-tune-2014","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/3d-tomasz-dabrowski-kris-davis-andrew-drury-vermillion-tree-for-tune-2014\/","title":{"rendered":"3d: Tomasz Dabrowski, Kris Davis, Andrew Drury: <i>Vermillion Tree<\/i> (For Tune, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14165 size-medium\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014-200x200.jpg\" alt=\"3D Dabrowski davis drury_vermillion tree_fortune_2014\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014.jpg 270w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><em>Vermillion Tree<\/em> es el tercer CD como l\u00edder de <strong>Tomasz Dabrowski<\/strong>, trompetista polaco afincado en Dinamarca. Una buena cosecha para un trompetista de apenas 30 a\u00f1os, que no lo es tanto por su cantidad, sino por los acompa\u00f1antes que han participado en sus grabaciones: <strong>Andrew Drury<\/strong> (bater\u00eda) y <strong>Kris Davis<\/strong> (piano) en esta \u00faltima ocasi\u00f3n; el baterista <strong>Tyshawn Sorey<\/strong> en el CD a d\u00fao <em>Steps<\/em> (For Tune, 2013).<\/p>\n<p style=\"text-align: justify;\">Al contrario de lo que ocurr\u00eda en su d\u00fao con <strong>Sorey<\/strong>, en el que <strong>Dabrowski<\/strong> era el autor de todas las composiciones, en <em>Vermillion Tree<\/em> la gran mayor\u00eda son creaciones colectivas, composiciones improvisadas por parte de los integrantes de <strong>3d<\/strong>. <strong>Dabrowski<\/strong> y <strong>Dury<\/strong> participan a lo largo de todo el CD, interviniendo la pianista <strong>Kris Davis<\/strong> puntualmente. El trompetista y el baterista se entienden a la perfecci\u00f3n en los temas creados &#8211; interpretados a d\u00fao. Ambos se muestran sumamente vers\u00e1tiles, mostrando la diversidad con la que pueden enfocar la aproximaci\u00f3n a sus instrumentos en lo que en alg\u00fan momento aparece planteado en forma de algo parecido a duplas de temas (que en el caso de \u00ablivid\u00bb y \u00abtaupe\u00bb tienen una duraci\u00f3n id\u00e9ntica, siendo \u00ableaden\u00bb y \u00abhazel\u00bb de una duraci\u00f3n similar). En estos conjuntos encontramos por un lado una cara en la que los dos m\u00fasicos una faceta din\u00e1mica, r\u00edtmica, intensa; una m\u00fasica sumamente directa en definitiva. Por otra parte esos dos mismos artistas pueden trabajar en terrenos m\u00e1s abstractos, enigm\u00e1ticos, abiertos. Un territorio musical espont\u00e1neo en el que la pianista <strong>Kris Davis<\/strong> encaja como anillo al dedo.<\/p>\n<p style=\"text-align: justify;\">Los desarrollos m\u00e1s extensos se dan en las composiciones de <strong>Dabrowski<\/strong> (\u00abVermillion Tree\u00bb, \u00abPuce\u00bb, \u00abMattock Phrasemonger\u00bb, \u00bb Ruddy Rudi\u00bb, \u00abApricot, Apricot\u00bb) y <strong>Drury<\/strong> (\u00abModules\u00bb). Frente a la abstracci\u00f3n en que se mueve el tema del baterista, est\u00e1 la concreci\u00f3n de las composiciones del trompetista, que var\u00edan del dinamismo del tema que da t\u00edtulo al disco, a la suavidad de \u00abMattock Phrasemonger\u00bb.<\/p>\n<p style=\"text-align: right;\">\u00a9 Pachi Tapiz, 2014<\/p>\n<p>3d: Tomasz Dabrowski, Kris Davis, Andrew Drury: <em>Vermillion Tree<\/em> (For Tune, 2014)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vermillion Tree es el tercer CD como l\u00edder de Tomasz Dabrowski, trompetista polaco afincado en Dinamarca. Una buena cosecha para un trompetista de apenas 30 a\u00f1os, que no lo es tanto por su cantidad, sino por los acompa\u00f1antes que han participado en sus grabaciones: Andrew Drury (bater\u00eda) y Kris Davis<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/3d-tomasz-dabrowski-kris-davis-andrew-drury-vermillion-tree-for-tune-2014\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":14165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,5,1038],"tags":[10647,10649,12651,10650,12696,13,12415,15295,24,31,16099,77,16100,10648,6864],"class_list":["entry","author-pachi","post-14164","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-grabaciones","category-contenidos","tag-3d","tag-andrew-drury","tag-cd","tag-for-tune","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-kris-davis","tag-pachi-tapiz","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-tomasz-dabrowski","tag-tyshawn-sorey"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/09\/3D-Dabrowski-davis-drury_vermillion-tree_fortune_2014.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":94273,"url":"https:\/\/tomajazz.com\/web\/kathrine-windfeld-sextet-ajf-2024\/","url_meta":{"origin":14164,"position":0},"title":"Kathrine Windfeld Sextet (8\u00ba Alternatilla Jazz Festival 2024. Espai 36. Sant Lloren\u00e7.\u00a02024-12-08) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"29 enero, 2025","format":false,"excerpt":"Kathrine Windfeld Sextet actu\u00f3 en el 8\u00ba Alternatilla Jazz Festival, en Sant Lloren\u00e7, el 8 de diciembre de 2024. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Kathrine Windfeld, Marek Konarski, Tomasz Dabrowski, Hannes Bennich, Johannes Vaht, Henrik Hansen","rel":"","context":"En \u00ab8\u00ba Festival Alternatilla Jazz 2024\u00bb","block_context":{"text":"8\u00ba Festival Alternatilla Jazz 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/8o-festival-alternatilla-jazz-2024\/"},"img":{"alt_text":"Kathrine Windfeld Sextet (8\u00ba Alternatilla Jazz Festival 2024. Espai 36. Sant Lloren\u00e7.\u00a02024-12-08) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Kathrine Windfeld Sextet actu\u00f3 en el 8\u00ba Alternatilla Jazz Festival, en Sant Lloren\u00e7, el 8 de diciembre de 2024. Jos\u00e9 Luis Luna Rocafort lo retrata en INSTANTZZ. Actuaron Kathrine Windfeld, Marek Konarski, Tomasz Dabrowski, Hannes Bennich, Johannes Vaht, Henrik Hansen","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/01\/014-11.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/01\/014-11.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/01\/014-11.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27312,"url":"https:\/\/tomajazz.com\/web\/hdo-189-ingid-laubrock-her-voice-and-her-musics-interview-by-pachi-tapiz-podcast\/","url_meta":{"origin":14164,"position":1},"title":"HDO 189. Ingrid Laubrock: her voice and her musics\u2026 interview by Pachi Tapiz [Podcast]","author":"Tomajazz","date":"5 noviembre, 2016","format":false,"excerpt":"Ingrid Laubrock will play\u00a0in Spain. Her Anti-House 4 (Laubrock herself, Mary Halvorson, Kris Davis, Tom Rainey) will play at Jamboree (Barcelona), Bogui Jazz (Jazz Con Sabor a Club - Festival Internacional de Jazz de Madrid), and Campus Jazz Festival in C\u00e1diz. Pachi Tapiz\u00a0interviews her in the\u00a0HDO\u00a0Tomajazz podcast. In this special\u2026","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/04\/03_TRO-%C2%A9Joan-Cort%C3%A8s_10mar15_Jmb_Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/04\/03_TRO-%C2%A9Joan-Cort%C3%A8s_10mar15_Jmb_Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/04\/03_TRO-%C2%A9Joan-Cort%C3%A8s_10mar15_Jmb_Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104106,"url":"https:\/\/tomajazz.com\/web\/kris-davis-the-solastalgia-suite-2026\/","url_meta":{"origin":14164,"position":2},"title":"Kris Davis &#038; Lutos\u0142awski Quartet: The Solastalgia Suite (Pyroclastic Records, 2026) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"20 febrero, 2026","format":false,"excerpt":"The Solastalgia Suite (Pyroclastic Records, 2026) es la nueva grabaci\u00f3n de Kris Davis con Lutos\u0142awski Quartet. Carlos Lara repasa la grabaci\u00f3n","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Kris Davis & Lutos\u0142awski Quartet: The Solastalgia Suite (Pyroclastic Records, 2026) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - The Solastalgia Suite (Pyroclastic Records, 2026) es la nueva grabaci\u00f3n de Kris Davis con Lutos\u0142awski Quartet","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Kris-Davis-Lutoslawski-Quartet-The-Solastalgia-Suite-Pyroclastic-Records-2026.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Kris-Davis-Lutoslawski-Quartet-The-Solastalgia-Suite-Pyroclastic-Records-2026.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Kris-Davis-Lutoslawski-Quartet-The-Solastalgia-Suite-Pyroclastic-Records-2026.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/Kris-Davis-Lutoslawski-Quartet-The-Solastalgia-Suite-Pyroclastic-Records-2026.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18859,"url":"https:\/\/tomajazz.com\/web\/kris-davis-infrasound-save-your-breath-clean-feed-2015-cd\/","url_meta":{"origin":14164,"position":3},"title":"Kris Davis Infrasound: Save Your Breath (Clean Feed, 2015; CD)","author":"Tomajazz","date":"26 junio, 2015","format":"image","excerpt":"Save Your Breath es la d\u00e9cima grabaci\u00f3n de la pianista Kris Davis como l\u00edder. Esta es una obra que muestra a una artista muy valiente, puesto que a priori no parece que sea una labor sencilla trabajar al frente de un octeto integrado por cuatro clarinetistas (Ben Goldberg, Oscar Noriega,\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/06\/Kris-Davis-Infrasound_Save-Your-Breath_Clean-Feed_2015_CD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/06\/Kris-Davis-Infrasound_Save-Your-Breath_Clean-Feed_2015_CD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/06\/Kris-Davis-Infrasound_Save-Your-Breath_Clean-Feed_2015_CD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/06\/Kris-Davis-Infrasound_Save-Your-Breath_Clean-Feed_2015_CD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8441,"url":"https:\/\/tomajazz.com\/web\/eric-revis-city-of-asylum-clean-feed-2013\/","url_meta":{"origin":14164,"position":4},"title":"Eric Revis: City Of Asylum (Clean Feed, 2013)","author":"Tomajazz","date":"17 octubre, 2013","format":false,"excerpt":"City Of Asylum aparece editado a nombre del contrabajista Eric Revis (Branford Marsalis, Tabarby), aunque igualmente podr\u00eda haberlo sido a nombre del tr\u00edo Revis \u2013 (Kris) Davis \u2013 (Andrew) Cyrille. Salvo un tema de Revis (\u201cQuestion), uno de Jarrett (\u201cPrayer\u201d) y el monkiano \u201cGallop\u2019s Gallop\u201d, los seis restantes son unas\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Eric-Revis-Trio-City-Of-Asylum.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":99816,"url":"https:\/\/tomajazz.com\/web\/linda-may-han-oh-strange-heavens-2025\/","url_meta":{"origin":14164,"position":5},"title":"Linda May Han Oh, Ambrose Akinmusire &#038; Tyshawn Sorey: Strange Heavens (Biophilia Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"29 septiembre, 2025","format":false,"excerpt":"Strange Heavens (Biophilia Records, 2025), es el nuevo disco de Linda May Han Oh. Carlos Lara repasa la grabaci\u00f3n. Con Linda May Han Oh, Ambrose Akinmusire, Tyshawn Sorey","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Linda May Han Oh, Ambrose Akinmusire & Tyshawn Sorey: Strange Heavens (Biophilia Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Strange Heavens (Biophilia Records, 2025), es el nuevo disco de Linda May Han Oh. Carlos Lara repasa la grabaci\u00f3n. Con Linda May Han Oh, Ambrose Akinmusire & Tyshawn Sorey:","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Linda-May-Han-Oh-Ambrose-Akinmusire-Tyshawn-Sorey-Strange-Heavens-Biophilia-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=14164"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14164\/revisions"}],"predecessor-version":[{"id":14166,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14164\/revisions\/14166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/14165"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=14164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=14164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=14164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}