{"id":14982,"date":"2014-10-28T10:20:13","date_gmt":"2014-10-28T09:20:13","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=14982"},"modified":"2016-11-13T22:59:47","modified_gmt":"2016-11-13T21:59:47","slug":"los-sorteos-de-tomajazz-ken-vandermarks-made-to-break-19-de-noviembre-de-2014-rock-palace-madrid","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/los-sorteos-de-tomajazz-ken-vandermarks-made-to-break-19-de-noviembre-de-2014-rock-palace-madrid\/","title":{"rendered":"Los sorteos de Tomajazz: Ken Vandermark\u2019s Made to Break. 19 de noviembre de 2014. Rock Palace. Madrid"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14983\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300-200x283.jpg\" alt=\"Made-To-Break-Madrid-2014-11-19-212x300\" width=\"200\" height=\"283\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300-200x283.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300-106x150.jpg 106w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300-38x55.jpg 38w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300.jpg 212w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Rock<\/strong> <strong>Palace<\/strong> regala dos entradas dobles que se sortear\u00e1n entre los lectores de Tomajazz para el concierto de <strong>Made to Break de Ken Vandermark<\/strong> el <strong>19 de noviembre de 2014<\/strong>. Para participar en el sorteo hay que enviar un correo electr\u00f3nico a tomajazz@gmail.com indicando lo siguiente. En el asunto del mensaje: \u00abLos sorteos de Tomajazz: Ken Vandermark\u2019s Made to Break. 19 de noviembre de 2014. Rock Palace. Madrid\u00bb. En el cuerpo del mensaje hay que se\u00f1alar cuatro grupos en los que participe en la actualidad o haya participado Ken Vandermark; el nombre y dos apellidos; DNI o documento oficial acreditativo; tel\u00e9fono m\u00f3vil. El plazo para participar estar\u00e1 abierto hasta el 18 de noviembre de 2014 a las 12:00 del mediod\u00eda. Suerte a todos los participantes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Made to Break<br \/>\nKen Vandermark: saxo tenor, clarinete<br \/>\nTim Daisy: percusi\u00f3n<br \/>\nChristof Kurzmann: electr\u00f3nica<br \/>\nJasper Stadhouders: bajo<\/p>\n<p>Mi\u00e9rcoles 19 de Noviembre, 21:30<br \/>\n12\u20ac venta anticipada:\u00a0 <a href=\"http:\/\/entradium.com\/entradas\/Made-to-Break-1528\" target=\"_blank\" rel=\"noopener\">http:\/\/entradium.com\/entradas\/Made-to-Break-1528<\/a> 13\u20ac en taquilla<br \/>\nRock Palace<br \/>\nc\/Vara del Rey, 6<br \/>\nMadrid<\/p>\n<p style=\"text-align: justify;\">M\u00e1s informaci\u00f3n: <a href=\"https:\/\/www.facebook.com\/RockPalaceMadrid\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/RockPalaceMadrid<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rock Palace regala dos entradas dobles que se sortear\u00e1n entre los lectores de Tomajazz para el concierto de Made to Break de Ken Vandermark el 19 de noviembre de 2014. Para participar en el sorteo hay que enviar un correo electr\u00f3nico a tomajazz@gmail.com indicando lo siguiente. En el asunto del<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/los-sorteos-de-tomajazz-ken-vandermarks-made-to-break-19-de-noviembre-de-2014-rock-palace-madrid\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":14983,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,1038,8156],"tags":[5662,6047,446,7684,186,11100,13435,453,16099,16100],"class_list":["entry","author-pachi","post-14982","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-contenidos","category-sorteo","tag-christof-kurzmann","tag-jasper-stadhouders","tag-ken-vandermark","tag-made-to-break","tag-madrid","tag-rock-palace","tag-sorteo","tag-tim-daisy","tag-toma-jazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Made-To-Break-Madrid-2014-11-19-212x300.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":19724,"url":"https:\/\/tomajazz.com\/web\/los-sorteos-de-tomajazz-ken-vandermarks-made-to-break-en-rock-palace-madrid-8-de-octubre-de-2015\/","url_meta":{"origin":14982,"position":0},"title":"Los sorteos de Tomajazz: Ken Vandermark\u2019s Made To Break en Rock Palace (Madrid, 8 de octubre de 2015)","author":"Tomajazz","date":"21 septiembre, 2015","format":"image","excerpt":"Rock Palace regala una entrada doble para el concierto del grupo Made To Break que tendr\u00e1 lugar el pr\u00f3ximo jueves 8 de octubre de 2015 en el local madrile\u00f1o.","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19658,"url":"https:\/\/tomajazz.com\/web\/ken-vandermarks-make-to-break-before-the-code-en-rock-palace-madrid-8-de-octubre-de-2015-noticias\/","url_meta":{"origin":14982,"position":1},"title":"Ken Vandermark&#8217;s Made To Break \u00abBefore The Code\u00bb en Rock Palace (Madrid, 8 de octubre de 2015) [Noticias]","author":"Tomajazz","date":"14 septiembre, 2015","format":"image","excerpt":"El pr\u00f3ximo jueves 8 de octubre de 2015 a las 21:30 tendr\u00e1 lugar la actuaci\u00f3n en la Sala Rock Palace (Madrid) del grupo Made To Break con Ken Vandermark (saxo tenor y clarinete), Jasper Stadhouders (bajo el\u00e9ctrico), Tim Daisy (percusi\u00f3n) y Christof Kurzmann (electr\u00f3nica). El grupo presentar\u00e1 su\u00a0pr\u00f3xima\u00a0grabaci\u00f3n Before The\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/MADE-TO-BREAK-OCT-2015_OK-e1442142092466.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15631,"url":"https:\/\/tomajazz.com\/web\/made-to-break-rock-palace-madrid-2014-11-19\/","url_meta":{"origin":14982,"position":2},"title":"Made To Break (Rock Palace, Madrid. 2014-11-19)","author":"Tomajazz","date":"24 noviembre, 2014","format":false,"excerpt":"Fecha: 19 de noviembre de 2014. Lugar: Rock Palace (Madrid). M\u00fasicos: Made To Break Ken Vandermark: saxo tenor, saxo bar\u00edtono y clarinete Christof Kurzmann: electr\u00f3nica Jasper Stadhouders: bajo el\u00e9ctrico Tim Daisy: bater\u00eda Cuando uno asiste a un concierto de alguno de los proyectos de Ken Vandermark tiene la sensaci\u00f3n de\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Made To Break \u00a9 Sergio Cabanillas, 2014","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/VANDERMARK_MADE_TO_BREAK_1616_CABANIJAZZ.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":20267,"url":"https:\/\/tomajazz.com\/web\/made-to-break-rock-palace-madrid-2015-01-08\/","url_meta":{"origin":14982,"position":3},"title":"Made To Break (Rock Palace, Madrid. 2015-01-08)","author":"Sergio Cabanillas","date":"15 octubre, 2015","format":"image","excerpt":"Fecha: 08 de octubre de 2015. Lugar: Rock Palace (Madrid). Grupo: Made To Break Ken Vandermark: saxo tenor, saxo bar\u00edtono y clarinete Christof Kurzmann: electr\u00f3nica Jasper Stadhouders: bajo el\u00e9ctrico Tim Daisy: bater\u00eda Con unos 40 minutos de demora y la correspondiente presentaci\u00f3n de los m\u00fasicos a cargo de Ken Vandermark\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Tim Daisy \u00a9 Sergio Cabanillas, 2015","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/TIM_DAISY_6938_CABANIJAZZ.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/TIM_DAISY_6938_CABANIJAZZ.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/TIM_DAISY_6938_CABANIJAZZ.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16162,"url":"https:\/\/tomajazz.com\/web\/instantzz-made-to-break-jamboree-barcelona-2014-11-20\/","url_meta":{"origin":14982,"position":4},"title":"INSTANTZZ: Made To Break (Jamboree, Barcelona. 2014-11-20)","author":"Tomajazz","date":"31 diciembre, 2014","format":false,"excerpt":"Fecha: 20 de noviembre de 2014 Lugar: Jamboree (Barcelona) Componentes: Ken Vandermark: saxos Jasper Stadhouders: bajo Timothy Daisy: bater\u00eda Christof Kurzmann: electr\u00f3nica Fotograf\u00edas: \u00a9 Elena M\u00e1rquez, 2014","rel":"","context":"En \u00ab*_Elena M\u00e1rquez\u00bb","block_context":{"text":"*_Elena M\u00e1rquez","link":"https:\/\/tomajazz.com\/web\/category\/elena-marquez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/141120_MadeToBreak-Jamboree_0099.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/141120_MadeToBreak-Jamboree_0099.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/141120_MadeToBreak-Jamboree_0099.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":20518,"url":"https:\/\/tomajazz.com\/web\/lo-nuevo-de-the-thing-y-made-to-break-vandermark-daisy-stadhouders-kurzmann-hdo-0025-audioblog\/","url_meta":{"origin":14982,"position":5},"title":"Lo nuevo de The Thing y Made to Break (Vandermark, Daisy, Stadhouders, Kurzmann). HDO (0025) [Audioblog]","author":"Tomajazz","date":"27 octubre, 2015","format":"audio","excerpt":"Espacio en HDO para escuchar en la entrega n\u00famero 25\u00a0Shake (The Thing Records, 2015) \u00a0y Before the Code (Trost Records, 2015), las nuevas grabaciones de The Thing (Mats Gustafsson, Ingebrigt Haker Flaten y Paal Nilssen-Love) y Made To Break (Ken Vandermark, Tim Daisy, Jasper Stadhouders, Christof Kurzmann) respectivamente. Lo nuevo\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/WP_20151026_007.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=14982"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14982\/revisions"}],"predecessor-version":[{"id":14987,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/14982\/revisions\/14987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/14983"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=14982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=14982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=14982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}