{"id":15587,"date":"2014-11-21T10:25:47","date_gmt":"2014-11-21T09:25:47","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=15587"},"modified":"2016-11-13T16:00:06","modified_gmt":"2016-11-13T15:00:06","slug":"tom-harrell-trip-highnote-records","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tom-harrell-trip-highnote-records\/","title":{"rendered":"Tom Harrell: <i>Trip<\/i> (Highnote Records)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-15600\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/Tom-Harrell-Trip-HighNote-2014-200x200.jpg\" alt=\"Tom Harrell Trip HighNote 2014\" width=\"200\" height=\"200\" title=\"\">Tom Harrell vuelve a la carga a sus sesenta y ocho a\u00f1os con un cuarteto poderoso en el que el m\u00fasico de Los \u00c1ngeles se ha marcado doce composiciones espl\u00e9ndidas. El saxofonista Mark Turner, el contrabajista Ugonna Okegwo y el bater\u00eda Adam Cruz componen la banda.<\/p>\n<p style=\"text-align: justify;\">El disco se abre con dos piezas fren\u00e9ticas: \u201cSunday\u201d, llena de ritmo y \u201cCycle\u201d, marcada por el impulso de Okegwo y las r\u00e1pidas variaciones de Mark Turner. Pero la pieza central, \u201cThe Adventures of a Quixotic Character,\u201d est\u00e1 concebida a modo de <em>suite <\/em>dividida en seis partes e inspirada en la obra de Miguel de Cervantes. El trabajo pretende trasladar a m\u00fasica de manera elegante el mundo imaginario y los personajes de Cervantes. Harrell ha escrito los pasajes de esta <em>suite<\/em> tanto para el cuarteto como para facilitar las improvisaciones de sus acompa\u00f1antes. El solo de Harrell en \u201cThe Ingenious Gentleman\u201d alcanza una luminosidad de muchos quilates y prueba que sigue estando en buena forma. El estilo empleado en esta peque\u00f1a <em>suite, <\/em>a algunos les ha recordado a las colaboraciones que manten\u00edan Gerry Mulligan y Chet Baker. Hay que tener en cuenta que Harrell creci\u00f3 en Los Angeles. Harrell empez\u00f3 a tocar la trompeta durante el pleno apogeo del jazz de la costa oeste. Por eso se ha dicho que este disco es una evocaci\u00f3n del cuarteto de Mulligan. El saxofonista Mark Turner est\u00e1 soberbio y su trabajo no tiene nada que envidiar al de Harrell, que a pesar de su edad, sigue manteniendo unos buenos pulmones. Ugonna Okegwo al contrabajo y Adam Cruz, que se muestra como un incisivo bater\u00eda, tampoco se quedan cortos.<\/p>\n<p style=\"text-align: justify;\">En el resto de <em>Trip<\/em> sobresalen \u201cComing Home\u201d, con un gran fraseo de Turner en una balada acompa\u00f1ado por Cruz y una envolvente melod\u00eda de Harrell al fiscorno, as\u00ed como \u201cCoastline\u201d, dando vida a la secci\u00f3n r\u00edtmica que vuelve a la carga tal y como se inici\u00f3 el disco, con un gran trabajo de Okegwo tirando del grupo, mientras Harrell se recrea en su estilo de siempre. Y Turner registra un particular solo acompasado a ritmo por el contrabajo y la bater\u00eda que impulsan el tema casi sin final. Con un solo de Cruz culmina de manera brillante. Uno de los momentos m\u00e1s inspirados de este disco. Tom Harrell se ha vuelto a renovar y nos ha dado una nueva reliquia que no tiene desperdicio.<\/p>\n<p style=\"text-align: right;\">\u00a9 Carlos Lara, 2014<\/p>\n<p>Tom Harrell: <em>Trip <\/em><\/p>\n<p>M\u00fasicos: Tom Harrell (trompeta y fliscorno), Mark Turner (saxo tenor), Ugonna Okegwo (contrabajo) y Adam Cruz (bater\u00eda).<\/p>\n<p>Composiciones: \u201cSunday\u201d, \u201cCycle\u201d, \u201cThe Adventures of A Quixotic Character\u201d, que incluye: \u201cThe Ingenious Gentleman\u201d, \u201cThe Duke and The Duchess\u201d, \u201cEnchanted\u201d, \u201cSancho and Rocinante\u201d, \u201cThe Princess\u201d y \u201cWindmills\u201d; \u201cComing Home\u201d, \u201cCoastline\u201d, \u201cAfter The game is Over\u201d y \u201cThere\u201d.<br \/>\nTodos los temas compuestos por Tom Harrell<\/p>\n<p>Grabado el 24 de octubre de 2014 en Water Music en Hoboken (Nueva Jersey). Editado en 2014 por Highnote Records. HCD 7261<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tom Harrell vuelve a la carga a sus sesenta y ocho a\u00f1os con un cuarteto poderoso en el que el m\u00fasico de Los \u00c1ngeles se ha marcado doce composiciones espl\u00e9ndidas. El saxofonista Mark Turner, el contrabajista Ugonna Okegwo y el bater\u00eda Adam Cruz componen la banda. El disco se abre<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tom-harrell-trip-highnote-records\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":15600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,1038],"tags":[5257,84,12651,7034,11420,8284,12696,9895,13,12415,15295,6517,11419,5253,16099,77,16100,5256],"class_list":["entry","author-pachi","post-15587","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-contenidos","tag-adam-cruz","tag-carlos-lara","tag-cd","tag-chet-baker","tag-don-quijote","tag-gerry-mulligan","tag-grabaciones","tag-highnote-records","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-mark-turner","tag-miguel-de-cervantes","tag-tom-harrell","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-ugonna-okegwo"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/Tom-Harrell-Trip-HighNote-2014-e1416507245304.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":66630,"url":"https:\/\/tomajazz.com\/web\/tom-harrell-oak-tree-2022\/","url_meta":{"origin":15587,"position":0},"title":"Tom Harrell: Oak Tree (High Note Records, 2022) Por Juan F. Trillo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"13 septiembre, 2022","format":false,"excerpt":"Juan F. Trillo repasa Oak Tree (HighNote, 2022), grabaci\u00f3n del veterano trompetista Tom Harrell.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Tom Harrell: Oak Tree (High Note Records, 2022) Por Juan F. Trillo [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Tom-Harrell-Oak-Tree-HighNote-2022WEB.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Tom-Harrell-Oak-Tree-HighNote-2022WEB.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Tom-Harrell-Oak-Tree-HighNote-2022WEB.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":30410,"url":"https:\/\/tomajazz.com\/web\/instantzz-tom-harrell-trip-nova-jazz-cava-36e-jazz-terrassa-festival-terrassa-2017-03-25-galeria-fotografica\/","url_meta":{"origin":15587,"position":1},"title":"INSTANTZZ: Tom Harrell Trip (Nova Jazz Cava, 36\u00e8 Jazz Terrassa Festival. Terrassa. 2017-03-25) [Galer\u00eda fotogr\u00e1fica]","author":"Tomajazz","date":"2 mayo, 2017","format":false,"excerpt":"Fecha: S\u00e1bado, 25 de marzo de 2017 Lugar: Nova Jazz Cava (Terrassa \u2013Barcelona-) Grupo: Tom Harrell Trip Tom Harrell, trompeta y fiscorno. Santi de la Rubia, saxo tenor. Ugonna Okegwo, contrabajo. Adam Cruz, bater\u00eda. Tomajazz: \u00a9 Joan Cort\u00e8s, 2017","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/06_Tm-Hrrll-Qrtt-%C2%A9Joan-Cort%C3%A8s_25mar17_36JTF_NvJzzCv_Trrss.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/06_Tm-Hrrll-Qrtt-%C2%A9Joan-Cort%C3%A8s_25mar17_36JTF_NvJzzCv_Trrss.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/06_Tm-Hrrll-Qrtt-%C2%A9Joan-Cort%C3%A8s_25mar17_36JTF_NvJzzCv_Trrss.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4670,"url":"https:\/\/tomajazz.com\/web\/tom-harrell-quartet-xv-jazzfermin-2012-pamplona-navarra-10-vii-2012\/","url_meta":{"origin":15587,"position":2},"title":"Tom Harrell Quartet (XV Jazzferm\u00edn 2012, Pamplona, Navarra, 10-VII-2012)","author":"Tomajazz","date":"10 julio, 2012","format":false,"excerpt":"XV Jazzferm\u00edn 2012 Fecha:\u00a010 de julio de 2012. Lugar:\u00a0Plaza de los Burgos, Pamplona(Navarra). Componentes: Tom Harrell: trompeta y fiscorno. Wayne Escoffery: saxo tenor. Ugonna Okegwo: contrabajo. Adam Cruz: bater\u00eda. Comentario: En 2012 la cita\u00a0sanferminera\u00a0Jazzferm\u00edn ha llegado a su d\u00e9cimo quinta edici\u00f3n. Un festival que, compuesto por cuatro conciertos (que en\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/IMG_6119_JAZZFERMIN2012_conmarco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/IMG_6119_JAZZFERMIN2012_conmarco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/IMG_6119_JAZZFERMIN2012_conmarco.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2286,"url":"https:\/\/tomajazz.com\/web\/tom-harrell-number-five-highnote-2012\/","url_meta":{"origin":15587,"position":3},"title":"Tom Harrell: Number Five (HighNote, 2012)","author":"Tomajazz","date":"5 julio, 2012","format":false,"excerpt":"Number Five arranca con Tom Harrell a d\u00fao con el baterista Jonathan Blake con una vibrante versi\u00f3n del standard \u201cBlue \u2018n\u2019 Boogie\u201d lo que es toda una declaraci\u00f3n de intenciones y una fant\u00e1stica tarjeta de visita. En cuanto a lo segundo, en ese primer tema el trompetista muestra que a\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"tom harrell no 5","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2012\/07\/tom-harrell-no-5.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4664,"url":"https:\/\/tomajazz.com\/web\/tom-harrell-quintet-xv-festival-internacional-de-jazz-san-javier-san-javier-murcia-13-vii-2012\/","url_meta":{"origin":15587,"position":4},"title":"Tom Harrell Quintet (XV Festival Internacional de Jazz San Javier, San Javier, Murcia, 13-VII-2012)","author":"Tomajazz","date":"13 julio, 2012","format":false,"excerpt":"XV Festival Internacional de Jazz San Javier Fecha:\u00a013 de julio de 2012. Lugar:\u00a0Auditorio Parque Almansa, San Javier (Murcia). Componentes: Tom Harrell: trompeta y fiscorno. Wayne Escoffery: saxo tenor. Danny Grissett: piano. Ugonna Okegwo: contrabajo. Adam Cruz: bater\u00eda. Comentario: Hay m\u00fasicos de jazz que tienen tan reconocida su larga carrera musical,\u2026","rel":"","context":"En \u00ab*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez\u00bb","block_context":{"text":"*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez","link":"https:\/\/tomajazz.com\/web\/category\/jose-antonio-garcia-lopez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/tom-harrell.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/tom-harrell.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/01\/tom-harrell.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":67210,"url":"https:\/\/tomajazz.com\/web\/tom-harrell-oak-tree-jazzx5\/","url_meta":{"origin":15587,"position":5},"title":"\u201cZatoichi\u201d [Tom Harrell Oak Tree (High Note Records, 2022)] Por Pachi Tapiz. JazzX5 #531 [Minipodcast de jazz]","author":"Tomajazz","date":"3 octubre, 2022","format":false,"excerpt":"En JazzX5 suena el tema \"Zatoichi\" incluido en Tom Harrell Oak Tree (High Note Records, 2022). JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"\u201cZatoichi\u201d [Tom Harrell Oak Tree (High Note Records, 2022)] Por Pachi Tapiz. JazzX5 #531 [Minipodcast de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/10\/JazzX5_0531.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/10\/JazzX5_0531.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/10\/JazzX5_0531.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/10\/JazzX5_0531.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=15587"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15587\/revisions"}],"predecessor-version":[{"id":15603,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15587\/revisions\/15603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/15600"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=15587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=15587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=15587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}