{"id":15645,"date":"2014-11-25T11:00:59","date_gmt":"2014-11-25T10:00:59","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=15645"},"modified":"2016-11-13T16:32:26","modified_gmt":"2016-11-13T15:32:26","slug":"instantzz-lee-konitz-quartet-2o-san-miguel-jamboree-jazz-club-festival-jamboree-barcelona-2014-11-15","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/instantzz-lee-konitz-quartet-2o-san-miguel-jamboree-jazz-club-festival-jamboree-barcelona-2014-11-15\/","title":{"rendered":"INSTANTZZ: Lee Konitz Quartet (2\u00ba San Miguel Jamboree Jazz Club Festival, Jamboree, Barcelona. 2014-11-15)"},"content":{"rendered":"<p>2\u00ba San Miguel Jamboree Jazz Club Festival<\/p>\n<p>Lee Konitz Quartet<\/p>\n<ul>\n<li>Fecha: S\u00e1bado, 15 de noviembre de 2014<\/li>\n<li>Lugar: Jamboree (Barcelona)<\/li>\n<li>Componentes:<br \/>\nLee Konitz, saxo alto<br \/>\nDan Tepfer, piano<br \/>\nJeremy Stratton, contrabajo<br \/>\nGeorge Schuller, bater\u00eda<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15646\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"01_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-150x99.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/01_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-120x80.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15647\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/02_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"02_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/02_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/02_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-99x150.jpg 99w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/02_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/02_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-36x55.jpg 36w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15648\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/03_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"03_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/03_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/03_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-99x150.jpg 99w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/03_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/03_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-36x55.jpg 36w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15649\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"04_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-150x99.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/04_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-120x80.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15650\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"05_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-150x99.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/05_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-120x80.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15651\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"06_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-150x99.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/06_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-120x80.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15652\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg\" alt=\"07_LK4t (u00A9Joan Cortu00E8s)_15nov14_2SMJJCF_Jamboree\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-99x150.jpg 99w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree-36x55.jpg 36w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<p style=\"text-align: right;\">Fotograf\u00edas: \u00a9 Joan Cort\u00e8s, 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2\u00ba San Miguel Jamboree Jazz Club Festival Lee Konitz Quartet Fecha: S\u00e1bado, 15 de noviembre de 2014 Lugar: Jamboree (Barcelona) Componentes: Lee Konitz, saxo alto Dan Tepfer, piano Jeremy Stratton, contrabajo George Schuller, bater\u00eda Fotograf\u00edas: \u00a9 Joan Cort\u00e8s, 2014<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/instantzz-lee-konitz-quartet-2o-san-miguel-jamboree-jazz-club-festival-jamboree-barcelona-2014-11-15\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":15652,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17853,11262,15516,11261,1038],"tags":[11265,329,12656,15275,326,11263,1046,13,330,1041,7851,11441,12657,11295,16099,77,16100],"class_list":["entry","author-pachi","post-15645","post","type-post","status-publish","format-standard","has-post-thumbnail","category-joan-cortes","category-photoblogs","category-imagenes","category-instantzz","category-contenidos","tag-2o-san-miguel-jamboree-jazz-club-festival","tag-dan-tepfer","tag-fotoblog","tag-galeria-fotografica","tag-george-schuller","tag-instantzz-2","tag-jamboree","tag-jazz","tag-jeremy-stratton","tag-joan-cortes","tag-lee-konitz","tag-lee-konitz-quartet","tag-photoblog","tag-san-miguel-jamboree-jazz-club-festival","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/11\/07_LK4t-u00A9Joan-Cortu00E8s_15nov14_2SMJJCF_Jamboree.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":52120,"url":"https:\/\/tomajazz.com\/web\/instantzz-dan-tepfer-monografico-galeria-fotografica-aka-fotoblog-de-jazz-impro-y-algo-mas-por-joan-cortes\/","url_meta":{"origin":15645,"position":0},"title":"INSTANTZZ: Dan Tepfer (monogr\u00e1fico) [Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro&#8230; y algo m\u00e1s] Por Joan Cort\u00e8s","author":"Tomajazz","date":"17 septiembre, 2020","format":false,"excerpt":"Once im\u00e1genes (cuatro de ellas in\u00e9ditas), aparecen en el monogr\u00e1fico de INSTANTZZ que Joan Cort\u00e8s dedica a Dan Tepfer.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/06_1DnTpfr_VrcnsGlbrg-Joan-Cortes_12mar08_Vstbl-Ttr-dtr_Snt-Cgt.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/06_1DnTpfr_VrcnsGlbrg-Joan-Cortes_12mar08_Vstbl-Ttr-dtr_Snt-Cgt.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/06_1DnTpfr_VrcnsGlbrg-Joan-Cortes_12mar08_Vstbl-Ttr-dtr_Snt-Cgt.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15828,"url":"https:\/\/tomajazz.com\/web\/instantzz-lee-konitz-quartet-amr-sud-des-alpes-ginebra-suiza-2014-11-28\/","url_meta":{"origin":15645,"position":1},"title":"INSTANTZZ: Lee Konitz Quartet (AMR, Sud Des Alpes, Ginebra, Suiza. 2014-11-28)","author":"Tomajazz","date":"11 diciembre, 2014","format":false,"excerpt":"Fecha: viernes, 28 de noviembre de 2014 Lugar: AMR, Sud Des Alpes, Ginebra, Suiza Componentes: Lee Konitz Quartet Lee Konitz: saxo alto Dan Tepfer: piano Jeremy Stratton, contrabajo George Schuller: bater\u00eda \u00a0 Fotograf\u00edas: \u00a9 Juan Carlos Hern\u00e1ndez, 2014","rel":"","context":"En \u00ab*_Juan Carlos Hern\u00e1ndez\u00bb","block_context":{"text":"*_Juan Carlos Hern\u00e1ndez","link":"https:\/\/tomajazz.com\/web\/category\/juan-carlos-hernandez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Lee-Konitz-4tetAMRGeneva-28112014-227-by-JC-Hernandez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Lee-Konitz-4tetAMRGeneva-28112014-227-by-JC-Hernandez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Lee-Konitz-4tetAMRGeneva-28112014-227-by-JC-Hernandez.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Lee-Konitz-4tetAMRGeneva-28112014-227-by-JC-Hernandez.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104436,"url":"https:\/\/tomajazz.com\/web\/juanma-trujillo-baldo-martinez-cdj25-2026\/","url_meta":{"origin":15645,"position":2},"title":"Juanma Trujillo &#038; Baldo Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"17 marzo, 2026","format":false,"excerpt":"Juanma Trujillo & Baldo Mart\u00ednez actuaron en Jamboree en el 25 aniversario de Club de Jazz. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"Juanma Trujillo & Baldo Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Juanma Trujillo & Baldo Mart\u00ednez actuaron en Jamboree en el 25 aniversario de Club de Jazz. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104591,"url":"https:\/\/tomajazz.com\/web\/marco-mezquida-25cdj-2026\/","url_meta":{"origin":15645,"position":3},"title":"Marco Mezquida (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [y III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"26 marzo, 2026","format":false,"excerpt":"Marco Mezquida actu\u00f3 en Jamboree en la celebraci\u00f3n CDJ25, el 14 de febrero de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Marco Mezquida (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [y III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Marco Mezquida actu\u00f3 en Jamboree en la celebraci\u00f3n CDJ25, el 14 de febrero de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103144,"url":"https:\/\/tomajazz.com\/web\/paul-cornish-trio-barcelona-2025\/","url_meta":{"origin":15645,"position":4},"title":"Paul Cornish Trio \u201cYou\u2019re Exaggerating!\u201d (57\u00e8 Festival de Jazz de Barcelona \/ Jamboree, 2025-11-24 \/ Barcelona) [04] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"1 enero, 2026","format":false,"excerpt":"Paul Cornish Trio \u201cYou\u2019re Exaggerating!\u201d actu\u00f3 en el 57\u00e8 Festival de Jazz de Barcelona, en Jamboree, el 24 de noviembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron Paul Cornish, Jermaine Paul, Jonathan Pinson","rel":"","context":"En \u00ab57 Festival de Jazz de Barcelona 2025\u00bb","block_context":{"text":"57 Festival de Jazz de Barcelona 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/57-festival-de-jazz-de-barcelona-2025\/"},"img":{"alt_text":"Paul Cornish Trio \u201cYou\u2019re Exaggerating!\u201d (57\u00e8 Festival de Jazz de Barcelona \/ Jamboree, 2025-11-24 \/ Barcelona) [04] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Paul Cornish Trio \u201cYou\u2019re Exaggerating!\u201d actu\u00f3 en el 57\u00e8 Festival de Jazz de Barcelona, en Jamboree, el 24 de noviembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron Paul Cornish, Jermaine Paul, Jonathan Pinson\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/destacada-08-Pl-Crnsh-Tr-Photo-By-Joan-Cortes-24nvm25-CdL-59FJBcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/destacada-08-Pl-Crnsh-Tr-Photo-By-Joan-Cortes-24nvm25-CdL-59FJBcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/destacada-08-Pl-Crnsh-Tr-Photo-By-Joan-Cortes-24nvm25-CdL-59FJBcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104518,"url":"https:\/\/tomajazz.com\/web\/agusti-fernandez-sonia-sanchez-lucia-martinez-cdj25-2026\/","url_meta":{"origin":15645,"position":5},"title":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez &#038; Luc\u00eda Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"22 marzo, 2026","format":false,"excerpt":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez actuaron en Jamboree, Barcelona, en el 25 aniversario de CDJ. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez actuaron en Jamboree, Barcelona, en el 25 aniversario de CDJ. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=15645"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15645\/revisions"}],"predecessor-version":[{"id":15653,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/15645\/revisions\/15653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/15652"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=15645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=15645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=15645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}