{"id":16139,"date":"2014-12-31T10:50:08","date_gmt":"2014-12-31T09:50:08","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=16139"},"modified":"2016-11-13T22:24:21","modified_gmt":"2016-11-13T21:24:21","slug":"tomas-fujiwara-trio-variable-bets-relative-pitch-records-2014","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tomas-fujiwara-trio-variable-bets-relative-pitch-records-2014\/","title":{"rendered":"Tomas Fujiwara Tr\u00edo: <i>Variable Bets<\/i> (Relative Pitch Records, 2014)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-16142\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014-200x181.jpg\" alt=\"Tomas Fujiwara Trio. Variable Bets.Relative Pitch Records.2014\" width=\"200\" height=\"181\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014-200x181.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014-150x136.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014-61x55.jpg 61w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014.jpg 403w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Hace unos meses me estren\u00e9 en Tomajazz rese\u00f1ando el disco <a title=\"Taylor Ho Bynum &amp; Tomas Fujiwara: Through Foundation (Autoedici\u00f3n, 2014)\" href=\"http:\/\/www.tomajazz.com\/web\/?p=13020\" target=\"_blank\"><em>Through Foundation<\/em> (Autoedici\u00f3n, 2014)<\/a> del cornetista Taylor Ho Bynum y del baterista protagonista de esta nueva rese\u00f1a, <strong>Tomas Fujiwara<\/strong>. Poco despu\u00e9s, nos hac\u00edamos eco del disco <a title=\"Mary Halvorson: Reverse Blue (Relative Pitch Records, 2014)\" href=\"http:\/\/www.tomajazz.com\/web\/?p=14668\" target=\"_blank\"><em>Reverse Blue<\/em> (Relative Pitch Records, 2014)<\/a> de la guitarrista Mary Halvorson en el que tambi\u00e9n aparec\u00eda nuestro protagonista. Si en la primera rese\u00f1a dejaba constancia de las buenas maneras del baterista, en esta \u00faltima ya confirmaba mi admiraci\u00f3n por Fujiwara y literalmente dec\u00eda que quedaba a la espera de la publicaci\u00f3n del disco que nos ocupa: <em>Variable Bets<\/em> (Relative Pitch Records, 2014), proyecto a tr\u00edo en el que le acompa\u00f1an <strong>Ralph Alessi<\/strong> a la trompeta y <strong>Brandon Seabrook<\/strong> a la guitarra.<\/p>\n<p style=\"text-align: justify;\">Aparte de los tres proyectos que me han llegado directamente para rese\u00f1ar, durante este a\u00f1o 2014 Fujiwara ha publicado m\u00e1s referencias entre las que se encuentran: <a title=\"Mary Halvorson, Michael Formanek, Tomas Fujiwara: Thumbscrew (Cuneiform Records, 2014)\" href=\"http:\/\/www.tomajazz.com\/web\/?p=11292\" target=\"_blank\"><em>Thumbscrew <\/em>(Cuneiform Records 2014)<\/a> nuevamente con Mary Halvorson y con Michael Formanek; <em>Beating The Teens <\/em>(Cuneiform Records, 2014) del conjunto Ideal Bread (con Jon Sinton, Kirk Knuffke y Adam Hopkins) o <em>Trio New Haven 2013<\/em> (New Braxton House, 2014) junto con Anthony Braxton y Tom Rainey. Efectivamente, la producci\u00f3n es inagotable y la calidad de la misma es excelente.<\/p>\n<p style=\"text-align: justify;\"><em>Variable Bets<\/em> comprende ocho cortes. Todos ellos composiciones originales de Tomas Fujiwara. Aunque por lo que a m\u00ed respecta, el disco es un \u00fanico tema, o m\u00e1s bien una sesi\u00f3n que precisa ser escuchada de principio a fin. Y si, lo s\u00e9. Son tiempos en los que todo va en <em>sprint<\/em>. En los que la gente busca la inmediatez en cualquier tema. Por lo que es muy recomendable que si uno no se quiere involucrar desde el inicio m\u00e1s vale ocupe su tiempo en lo que crea m\u00e1s conveniente. Pero si hay alguien valiente que quiera perderse entre torrentes de notas percutidas, entre distorsiones y agresivos <em>riffs<\/em>, entre soplidos precisos y punzantes\u2026 Si quiere adentrarse en las marismas del jazz y m\u00fasica improvisada de la escena de New York, este disco es desde ya un referente.<\/p>\n<p style=\"text-align: justify;\">Hace poco escrib\u00eda acerca de los sonidos especiales seg\u00fan la regi\u00f3n. Es algo que me parece evidente y l\u00f3gico. Y seguro que siempre habr\u00e1 quien escape de cualquier parecido a otro, pero a veces, incluso as\u00ed, no se consigue. Entonces, en el disco que nos ocupa, creo que podemos hablar de sonido vanguardista de New York. Especifico porque en este caso, solo mencionar la regi\u00f3n, abarcar\u00eda demasiados estilos por lo que me parece justo para situarnos. \u00bfEstamos hablando de m\u00fasica independiente subterr\u00e1nea? Realmente me da lo mismo (s\u00ed, lo s\u00e9, y lo acabo de etiquetar m\u00e1s arriba), lo que est\u00e1 claro es que es tremendamente expresiva y en lo que a m\u00ed respeta, me succiona. Me aspira. Me absorbe y produce la fusi\u00f3n entre m\u00fasico y escuchante. Mi abstracci\u00f3n del mundo real durante lo que dura la sesi\u00f3n es una conjunci\u00f3n entre enfermiza y gratificante. Una palabra malsonante y preocupante acude a m\u00ed. Droga. Puedo llegar a entender lo que puede sentir alguien que es adicto a alguna sustancia estupefaciente. En este caso, y sin ning\u00fan remordimiento, confirmo que soy drogadicto.<\/p>\n<p style=\"text-align: justify;\">A tenor de todo lo que he dicho y a pocos d\u00edas de acabar este a\u00f1o 2014, afirmo que <em>Variable Bets <\/em>ocupa el sitio m\u00e1s alto (de mi hipot\u00e9tica lista) de los discos que he podido escuchar durante todo el a\u00f1o. Un continuo escalofr\u00edo durante los cincuenta y ocho minutos que dura la sesi\u00f3n.<\/p>\n<p style=\"text-align: right;\">\u00a9\u00a0<a href=\"http:\/\/1984cronicas.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener\">Jes\u00fas Mateu Rossell\u00f3<\/a>, 2014<\/p>\n<p style=\"text-align: justify;\"><em>Tomas Fujiwara Trio: Variable Bets<\/em> (Relative Pitch Records, 2014)<\/p>\n<p style=\"text-align: justify;\">Tomas Fujiwara (bater\u00eda) Ralph Alessi (trompeta) Brandon Seabrook (guitarra)<\/p>\n<p style=\"text-align: justify;\">\u201cMr. Or in Pivot\u201d, \u201cInsonmiac\u2019s Delight\u201d, \u201cNovember Wept I\u201d, \u201cThe Comb\u201d, \u201cHarp Ran Blond\u201d, \u201cA Table\u2019s Stem (Variations on them of Benny Golson)\u201d, \u201cLord Sumo\u201d y \u201cNudgeStorms\u201d<br \/>\nTodos los temas compuestos por Tomas Fujiwara<\/p>\n<p style=\"text-align: justify;\">Grabado en directo el d\u00eda 11 de septiembre del a\u00f1o 2013 en Barbes, Brooklyn, New York.<\/p>\n<p style=\"text-align: justify;\">Editado por Relative Pitch Records.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos meses me estren\u00e9 en Tomajazz rese\u00f1ando el disco Through Foundation (Autoedici\u00f3n, 2014) del cornetista Taylor Ho Bynum y del baterista protagonista de esta nueva rese\u00f1a, Tomas Fujiwara. Poco despu\u00e9s, nos hac\u00edamos eco del disco Reverse Blue (Relative Pitch Records, 2014) de la guitarrista Mary Halvorson en el que<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tomas-fujiwara-trio-variable-bets-relative-pitch-records-2014\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1003599,"featured_media":16142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17851,5,1038],"tags":[11689,63,7229,12651,5476,12696,11687,13,12415,15295,9830,11688,8846,5584,11686,11690,1246,6079,650,16099,77,16100,8754],"class_list":["entry","author-jesusmateurossello","post-16139","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jesus-mateu-rossello","category-grabaciones","category-contenidos","tag-adam-hopkins","tag-anthony-braxton","tag-brandon-seabrook","tag-cd","tag-cuneiform-records","tag-grabaciones","tag-ideal-bread","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jesus-mateu-rossello","tag-jon-sinton","tag-kirk-knuffke","tag-mary-halvorson","tag-michael-formane","tag-new-braxton-house","tag-ralph-alessi","tag-relative-pitch-records","tag-tom-rainey","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-tomas-fujiwara"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":14668,"url":"https:\/\/tomajazz.com\/web\/mary-halvorson-reverse-blue-relative-pitch-records-2014\/","url_meta":{"origin":16139,"position":0},"title":"Mary Halvorson: Reverse Blue (Relative Pitch Records, 2014)","author":"Jes\u00fas Mateu Rossell\u00f3","date":"14 octubre, 2014","format":false,"excerpt":"Mary Halvorson es una guitarrista muy activa en la escena de Nueva York. Es poseedora de una discograf\u00eda de lujo en muy pocos a\u00f1os. Desde sus participaciones como sideman con Anthony Braxton, pasando por el sexteto y otras formaciones del cornetista Taylor Ho Bynum, hasta colaborando con la creme de\u2026","rel":"","context":"En \u00ab*_Jes\u00fas Mateu Rossell\u00f3\u00bb","block_context":{"text":"*_Jes\u00fas Mateu Rossell\u00f3","link":"https:\/\/tomajazz.com\/web\/category\/jesus-mateu-rossello\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Mary-Halvorson-Reverse-Blue1-e1413229535979.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Mary-Halvorson-Reverse-Blue1-e1413229535979.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/Mary-Halvorson-Reverse-Blue1-e1413229535979.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":30708,"url":"https:\/\/tomajazz.com\/web\/365-razones-para-amar-el-jazz-un-cd-variable-beats-tomas-fujiwara-148\/","url_meta":{"origin":16139,"position":1},"title":"365 razones para amar el jazz: un CD. Variable Beats (Tomas Fujiwara) [148]","author":"Tomajazz","date":"28 mayo, 2017","format":false,"excerpt":"Un CD.\u00a0Variable Beats (Tomas Fujiwara Trio. Relative Pitch Records, 2014) Seleccionado por Jes\u00fas Mateu Rossell\u00f3 Con Tomas Fujiwara, Ralph Alessi, Brandon Seabrook","rel":"","context":"En \u00ab*_Jes\u00fas Mateu Rossell\u00f3\u00bb","block_context":{"text":"*_Jes\u00fas Mateu Rossell\u00f3","link":"https:\/\/tomajazz.com\/web\/category\/jesus-mateu-rossello\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/12\/Tomas-Fujiwara-Trio.-Variable-Bets.Relative-Pitch-Records.2014.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":26376,"url":"https:\/\/tomajazz.com\/web\/hdo-163-en-concierto-con-ingrid-laubrock-y-tom-rainey-mas-ab-baars-e-ig-henneman-podcast\/","url_meta":{"origin":16139,"position":2},"title":"HDO 163. En concierto con Ingrid Laubrock y Tom Rainey&#8230; m\u00e1s Ab Baars e Ig Henneman [Podcast]","author":"Tomajazz","date":"15 septiembre, 2016","format":false,"excerpt":"La saxofonista\u00a0Ingrid Laubrock (figura a reivindicar entre lo m\u00e1s interesante aparecido en la escena de la improvisaci\u00f3n en los \u00faltimos a\u00f1os -y van unos cuantos), acaba de publicar dos grabaciones en directo en el interesante sello\u00a0Relative Pitch Records, en el que han publicado grabaciones artistas como Joe Morris, Michael Bisio,\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/09\/Perch-Hen-Brock-Rain_Live-At-The-Jazz-Happening-Tampere_Relative-Pitch-Records_2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11292,"url":"https:\/\/tomajazz.com\/web\/mary-halvorson-michael-formanek-tomas-fujiwara-thumbscrew-cuneiform-records-2014\/","url_meta":{"origin":16139,"position":3},"title":"Mary Halvorson, Michael Formanek, Tomas Fujiwara: Thumbscrew (Cuneiform Records, 2014)","author":"Tomajazz","date":"28 marzo, 2014","format":false,"excerpt":"Thumbscrew no s\u00f3lo es el t\u00edtulo de un estreno discogr\u00e1fico, sino que es a su vez el nombre del nuevo proyecto del contrabajista Michael Formanek, la guitarrista Mary Halvorson, y el baterista y percusionista Tomas Fujiwara. Repasar el curr\u00edculum de estos tres m\u00fasicos es demasiado largo para el espacio disponible\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/Thumbscrew.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/Thumbscrew.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/03\/Thumbscrew.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":52027,"url":"https:\/\/tomajazz.com\/web\/thumbscrew-the-anthony-braxton-project-cuneiform-records-grabacion-de-jazz\/","url_meta":{"origin":16139,"position":4},"title":"Thumbscrew: The Anthony Braxton Project (Cuneiform Records) [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"11 septiembre, 2020","format":false,"excerpt":"Por\u00a0Pachi Tapiz. El tr\u00edo Thumbscrew (Mary Halvorson en guitarra, Tomas Fujiwara en bater\u00eda y vibr\u00e1fono, y Michael Formanek en contrabajo), publica su quinta grabaci\u00f3n, titulada The Anthony Braxton Project. Una obra que est\u00e1 centrada en la interpretaci\u00f3n de once composiciones no grabadas de Anthony Braxton. Los tres integrantes del grupo\u2026","rel":"","context":"En \u00abTextos\u00bb","block_context":{"text":"Textos","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/Thumbscrew-The-Anthony-Braxton-Project-Cuneiform-Records.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/Thumbscrew-The-Anthony-Braxton-Project-Cuneiform-Records.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/Thumbscrew-The-Anthony-Braxton-Project-Cuneiform-Records.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/Thumbscrew-The-Anthony-Braxton-Project-Cuneiform-Records.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/09\/Thumbscrew-The-Anthony-Braxton-Project-Cuneiform-Records.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13020,"url":"https:\/\/tomajazz.com\/web\/taylor-ho-bynum-tomas-fujiwara-through-foundation-autoedicion-2014\/","url_meta":{"origin":16139,"position":5},"title":"Taylor Ho Bynum &#038; Tomas Fujiwara: Through Foundation (Autoedici\u00f3n, 2014) Por Jes\u00fas Mateu Rossell\u00f3 [Grabaci\u00f3n de jazz]","author":"Jes\u00fas Mateu Rossell\u00f3","date":"15 julio, 2014","format":false,"excerpt":"Jes\u00fas Mateu Rossell\u00f3 repasa la grabaci\u00f3n de Taylor Ho Bynum & Tomas Fujiwara: Through Foundation (Autoedici\u00f3n, 2014).","rel":"","context":"En \u00ab*_Jes\u00fas Mateu Rossell\u00f3\u00bb","block_context":{"text":"*_Jes\u00fas Mateu Rossell\u00f3","link":"https:\/\/tomajazz.com\/web\/category\/jesus-mateu-rossello\/"},"img":{"alt_text":"Taylor Ho Bynum & Tomas Fujiwara: Through Foundation (Autoedici\u00f3n, 2014) Por Jes\u00fas Mateu Rossell\u00f3 [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/07\/Fujiwara-Bynum.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/16139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1003599"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=16139"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/16139\/revisions"}],"predecessor-version":[{"id":16143,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/16139\/revisions\/16143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/16142"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=16139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=16139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=16139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}