{"id":17677,"date":"2015-03-23T17:30:06","date_gmt":"2015-03-23T16:30:06","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=17677"},"modified":"2016-11-13T17:11:36","modified_gmt":"2016-11-13T16:11:36","slug":"rudresh-mahanthappa-bird-calls-act-2015","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappa-bird-calls-act-2015\/","title":{"rendered":"Rudresh Mahanthappa: <i>Bird Calls<\/i> (ACT, 2015)"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-17678\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/Rudresh-Mahanthappa_Bird-Calls_ACT_2015-200x180.jpg\" alt=\"Layout 1\" width=\"200\" height=\"180\" title=\"\">Charlie Parker<\/strong> es uno de los m\u00fasicos de la historia del jazz cuya figura art\u00edstica merece ser reivindicada una y otra vez. En <a title=\"The Big Free Tongue: escuchar, escuchar y escuchar. Entrevista por Pachi Tapiz\" href=\"http:\/\/www.tomajazz.com\/web\/?p=17526\" target=\"_blank\">la entrevista al grupo The Big Free Tongue<\/a>, el saxofonista <strong>I\u00f1aki Rodriguez<\/strong> reflexionaba acerca de la ense\u00f1anza del jazz y la rapidez con la que se recorre toda su historia, sin profundizar en los distintos estilos que han ido componi\u00e9ndola. Si bien el <em>be-bop<\/em> es un estilo que se estudia con cierto detenimiento, lo cierto es que despojado de su contexto, transformado en partituras, y reducido a una serie de giros caracter\u00edsticos de sus instrumentistas principales, este movimiento pierde una parte fundamental de su esencia como son las condiciones que motivaron su surgimiento, la revoluci\u00f3n que supuso respecto de lo previo, y la influencia en todo lo que vendr\u00eda despu\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Frente a un cierto adocenamiento a la hora de ejecutar el repertorio del gran <strong>Bird<\/strong> en la actualidad y el alejamiento de lo que hab\u00eda detr\u00e1s de la creaci\u00f3n de esta m\u00fasica, el saxofonista alto <strong>Rudresh Mahanthappa<\/strong> trae a la actualidad el repertorio <em>parkeriano<\/em>. No lo hace de un modo directo, mediante nuevas versiones al estilo de lo que hizo en su momento <strong>Anthony Braxton<\/strong> con el recomendabil\u00edsimo <strong>Charlie Parker Project<\/strong>, sino que as\u00ed como la mayor\u00eda de los cl\u00e1sicos creados por Bird se basaban en <em>standards<\/em>, Mahanthappa construye a su vez la mayor parte de su repertorio (ocho de las trece piezas) a partir de cl\u00e1sicos del repertorio de Charlie Parker. Uniendo estas composiciones est\u00e1n los cinco breves interludios (titulados gen\u00e9ricamente \u00abBird Calls\u00bb y numerados del 1 al 5), en los que una formaci\u00f3n m\u00e1s reducida que la del quinteto que interpreta la mayor parte del CD, sirven para presentar y unir los distintos temas. La m\u00fasica del saxofonista de origen hind\u00fa recupera la inmediatez y el atractivo mel\u00f3dico caracter\u00edsticos de la m\u00fasica del gran Charlie Parker. <em>Bird Calls<\/em> es un disco compuesto de grandes temas, tanto en el caso de las composiciones m\u00e1s extensas, como en las breves \u00abBird Calls\u00bb. El trompetista <strong>Adam O&#8217;Farrill<\/strong> (de la saga de los O&#8217;Farrill), el pianista <strong>Matt Mitchell<\/strong>, el contrabajista F<strong>ran\u00e7ois Moutin<\/strong>, y el baterista <strong>Rudy Royston<\/strong> se unen al saxofonisa para dar cuerpo a un gran CD, sumamente atractivo para todos los aficionados al jazz. Una grabaci\u00f3n que sin duda es ya una firme candidata a estar en las consabidas listas de\u00a0 lo mejor de 2015.<\/p>\n<p style=\"text-align: right;\">\u00a9 Pachi Tapiz, 2015<\/p>\n<p style=\"text-align: justify;\">Rudresh Mahanthappa: <em>Bird Calls<\/em><\/p>\n<p style=\"text-align: justify;\">Rudresh Mahanthappa (saxo alto, composiciones), Adam O&#8217;Farrill (trompeta), Matt Mitchell (piano), Fran\u00e7ois Moutin (contrabajo), Rudy Royston (bater\u00eda)<\/p>\n<p style=\"text-align: justify;\">\u00abBird Calls #1\u00bb, \u00abOn the DL\u00bb, \u00abBird Calls #2\u00bb, \u00abChillin'\u00bb, \u00abBird Calls #3\u00bb, \u00abTalin is Thinking\u00bb, \u00abBoth Hands\u00bb, \u00abBird Calls #4\u00bb, \u00abGopuram\u00bb, \u00abMaybe Later\u00bb, \u00abBird Calls #5\u00bb, \u00abSure Why Not?\u00bb, \u00abMan Thanks for Coming\u00bb<\/p>\n<p style=\"text-align: justify;\">Grabado el 4 y 5 de agosto de 2014 en Systems Two, New York, New York. Publicado en 2015 por ACT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlie Parker es uno de los m\u00fasicos de la historia del jazz cuya figura art\u00edstica merece ser reivindicada una y otra vez. En la entrevista al grupo The Big Free Tongue, el saxofonista I\u00f1aki Rodriguez reflexionaba acerca de la ense\u00f1anza del jazz y la rapidez con la que se recorre<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/rudresh-mahanthappa-bird-calls-act-2015\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":17678,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,5,1038],"tags":[1376,1237,12651,7079,12453,12696,13,12415,15295,5372,31,6647,7299,16099,77,16100],"class_list":["entry","author-pachi","post-17677","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-grabaciones","category-contenidos","tag-act","tag-adam-ofarrill","tag-cd","tag-charlie-parker","tag-francois-moutin","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-matt-mitchell","tag-pachi-tapiz","tag-rudresh-mahanthappa","tag-rudy-royston","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/Rudresh-Mahanthappa_Bird-Calls_ACT_2015-e1427062244537.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2447,"url":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappa-samdhi2011\/","url_meta":{"origin":17677,"position":0},"title":"Rudresh Mahanthappa: Samdhi\u00a0(ACT, 2011) [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"30 diciembre, 2011","format":false,"excerpt":"Samdhi del indio Rudresh Mahanthappa es un magn\u00edfico muestrario de la historia musical del joven saxofonista. Fusi\u00f3n en el m\u00e1s amplio sentido del t\u00e9rmino, m\u00e1s all\u00e1 de las limitaciones que impone el estilo de jazz, en su m\u00fasica se encuentran ecos de Charlie Parker y su parcial puesta al d\u00eda\u2026","rel":"","context":"En \u00abTextos\u00bb","block_context":{"text":"Textos","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/"},"img":{"alt_text":"Rudresh Mahanthappa: Samdhi\u00a0(ACT, 2011) [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/12\/Rudresh-Mahanthappa_Samdhi.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/12\/Rudresh-Mahanthappa_Samdhi.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/12\/Rudresh-Mahanthappa_Samdhi.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":20929,"url":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappa-bird-calls-36o-festival-internacional-de-jazz-de-granada-2015-11-14\/","url_meta":{"origin":17677,"position":1},"title":"Rudresh Mahanthappa Bird Calls (36\u00ba Festival Internacional de Jazz de Granada. 2015-11-14)","author":"Tomajazz","date":"23 noviembre, 2015","format":false,"excerpt":"El Festival Internacional de Jazz de Granada cerr\u00f3 su 36\u00aa edici\u00f3n con un potent\u00edsimo concierto del quinteto de Rudresh Mahanthappa homenajeando a Charlie Parker. A trav\u00e9s de su premiado proyecto Bird Calls (ACT, 2015), se dedic\u00f3 a explorar durante dos horas todas las posibilidades sonoras y t\u00edmbricas que se han\u2026","rel":"","context":"En \u00ab*_Diego Ortega Alonso\u00bb","block_context":{"text":"*_Diego Ortega Alonso","link":"https:\/\/tomajazz.com\/web\/category\/diego-ortega-alonso\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_20151114_211257-e1448211931546.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_20151114_211257-e1448211931546.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_20151114_211257-e1448211931546.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_20151114_211257-e1448211931546.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":51015,"url":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappa-hero-trio-whirlwind-recordings-2020-grabacion-de-jazz\/","url_meta":{"origin":17677,"position":2},"title":"Rudresh Mahanthappa: Hero Trio (Whirlwind Recordings, 2020) [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"3 julio, 2020","format":false,"excerpt":"Juan F. Trillo repasa Hero Trio, la nueva grabaci\u00f3n del saxofonista Rudresh Mahanthappa, un homenaje de este m\u00fasico a algunos de sus h\u00e9roes realizado en compa\u00f1\u00eda de Rudy Royston y Fran\u00e7ois Moutin.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/07\/Mahanthappa-Hero-Trio-Mahanthappa-Album-Cover-scaled.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":27689,"url":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappas-bird-calls-festival-internacional-de-jazz-de-madrid-auditorio-conde-duque-madrid-2016-11-17\/","url_meta":{"origin":17677,"position":3},"title":"Rudresh Mahanthappa\u00b4s Bird Calls (Festival Internacional de Jazz de Madrid, Auditorio Conde Duque, Madrid. 2016-11-17) [Concierto]","author":"Tomajazz","date":"22 noviembre, 2016","format":false,"excerpt":"Carlos Lara y Enrique Farelo repasan la actuaci\u00f3n de Rudresh Mahanthappa\u00b4s Bird Calls en el Festival Internacional de Jazz de Madrid.","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/Rudresh-Mahanthappa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/Rudresh-Mahanthappa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/Rudresh-Mahanthappa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/Rudresh-Mahanthappa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33172,"url":"https:\/\/tomajazz.com\/web\/hdo-338-dubois-abbasi-kadawa-mahanthappa-toxydoll-podcast\/","url_meta":{"origin":17677,"position":4},"title":"HDO 338. Dubois &#8211; Abbasi &#8211; Kadawa &#8211; Mahanthappa &#8211; Toxydoll [Podcast]","author":"Tomajazz","date":"8 noviembre, 2017","format":false,"excerpt":"Cinco grabaciones en la edici\u00f3n\u00a0338 de\u00a0HDO: el excelente\u00a0Autumn Wind\u00a0(ACT, 2017) del guitarrista\u00a0Scott Dubois\u00a0(que Enrique Farelo repasaba hace unas semanas), que cuenta nuevamente con la colaboraci\u00f3n de Gebhard Ullmann, Thomas Morgan y Kresten Osgood (como en sus anteriores grabaciones), y tambi\u00e9n de un cuarteto de cuerda y distintos instrumentistas que aportan\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/10\/Scott-Dubois_Autumn-Wind.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":61084,"url":"https:\/\/tomajazz.com\/web\/rudresh-mahanthappas-hero-trio-faith-animal-crossing-ep-whirlwind-recordings-2022-por-pachi-tapiz-jazzx5417-minipodcast-de-jazz-aka-malditos-jazztardos\/","url_meta":{"origin":17677,"position":5},"title":"Rudresh Mahanthappa&#8217;s Hero Trio: \u00abFaith\u00bb [Animal Crossing EP (Whirlwind Recordings, 2022)] Por Pachi Tapiz. JazzX5#417 [Minipodcast de jazz AKA Malditos Jazztardos]","author":"Tomajazz","date":"12 febrero, 2022","format":false,"excerpt":"La versi\u00f3n de \"Faith\" (de George Michael) que cierra Animal Crossing EP (Whirlwind Recordings, 2022) de Rudresh Mahanthappa's Hero Trio suena en JazzX5, en un tema que pasa a la secci\u00f3n Malditos Jazztardos. JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/JazzX5_417.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/JazzX5_417.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/JazzX5_417.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/JazzX5_417.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/17677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=17677"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/17677\/revisions"}],"predecessor-version":[{"id":17685,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/17677\/revisions\/17685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/17678"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=17677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=17677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=17677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}