{"id":19447,"date":"2015-09-04T10:30:41","date_gmt":"2015-09-04T08:30:41","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=19447"},"modified":"2016-11-13T15:59:52","modified_gmt":"2016-11-13T14:59:52","slug":"brad-myers-prime-numbers-colloquy-records-2015-cd","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/brad-myers-prime-numbers-colloquy-records-2015-cd\/","title":{"rendered":"Brad Myers: Prime Numbers (Colloquy Records, 2015; CD)"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19448\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers-200x200.jpg\" alt=\"brad myers prime numbers\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers-50x50.jpg 50w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers.jpg 500w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Prime Numbers<\/em> es el debut como director de banda de Brad Myers, guitarrista y compositor afincado en Cincinnati (Ohio). En el bagaje profesional de este m\u00fasico destacan colaboraciones con, entre otros, John Scofield, Bela Fleck, Victor Wooten, Stanley Jordan y Jeff Coffin. Este disco supone la culminaci\u00f3n de cinco a\u00f1os de trabajo de este grupo, en el que destaca especialmente la combinaci\u00f3n del saxo tenor, la guitarra y el vibr\u00e1fono, lo que le aporta un cautivador sonido y sugerentes ritmos. La m\u00fasica contenida en <em>Prime Numbers<\/em> establece constantes di\u00e1logos a tr\u00edos y d\u00faos, pero sin perder nunca el rigor como colectivo.<\/p>\n<p style=\"text-align: justify;\">Myers, a la guitarra, y Barrick, al vibr\u00e1fono, se expresan en arm\u00f3nicas interacciones plet\u00f3ricas de creatividad. Por su parte Gemus al contrabajo y Buckley a la bater\u00eda, cumplen a la perfecci\u00f3n como piezas de un engranaje muy bien medido.<\/p>\n<p style=\"text-align: justify;\">El repertorio consta de seis temas de Myers, un par de arreglos de standars, y un par de composiciones de Thelonius Monk y de Wayne Shorter, que superan con nota la prueba. Los aires brasile\u00f1os se dejan notar en \u201cSunset in Curasao\u201d, con ritmo de samba en una contagiosa melod\u00eda donde la combinaci\u00f3n de tenor y guitarra son mecidos por el vibr\u00e1fono. \u201cThere is space for Us\u201d, flirtea con la <em>bossa<\/em>, en un mel\u00f3dico solo protagonizado por el fiscorno de Mavridoglou. Tambi\u00e9n hay espacio para la balada en \u201cYou are here\u201d, con guitarra y tenor en primer plano. Destaca la originalidad de \u201cSprerical\u201d, caracterizada por tempos acelerados y disminuidos, con la sucesi\u00f3n de excitantes solos de vibr\u00e1fono y tenor, con la guitarra remarcando; todos apoyados por una secci\u00f3n r\u00edtmica impecable. Un disco en el que se funde convincentemente lo moderno con lo cl\u00e1sico y se da rienda suelta a la imaginaci\u00f3n colectiva del grupo con grandes espacios para la improvisaci\u00f3n.<\/p>\n<p style=\"text-align: right;\">\u00a9 Carlos Lara, 2015<\/p>\n<p>Brad Myers: <em>Prime Numbers<\/em><\/p>\n<p>Brad Myers (guitarra), Chris Barrick (vibr\u00e1fono), Ben Walkenhauer (saxo tenor), Michael Mavridoglou (trompeta y fiscorno), Dominic Marino (tromb\u00f3n), Peter Gemus (contrabajo), Tom Buckley (bater\u00eda y percusi\u00f3n).<\/p>\n<p>\u201cBentley\u00b4s Blues\u201d, \u201cEvidence\u201d, \u201cSunset in Cura\u04abao\u201d, \u201cSpherical\u201d, \u201cRule of Threes\u201d, \u201cThe Big Push\u201d, \u201cYou Are Here\u201d, \u201cThere is Space for Us\u201d y \u201cInvitation\u201d.<br \/>\nTodos los temas compuestos y arreglados por Brad Myers, excepto \u201cEvidence\u201d, por Thelonius Monk, \u201cThe Big Push\u201d, por Wayne Shorter y \u201cInvitation\u201d, por Bronislau Kaper y Paul Francis Webster.<\/p>\n<p>Grabado el 23 de noviembre de 2014, y el 5 y 12 de febrero de 2015 en Cincinnati (Ohio). Editado en 2015 por Colloquy Records. 1357<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prime Numbers es el debut como director de banda de Brad Myers, guitarrista y compositor afincado en Cincinnati (Ohio). En el bagaje profesional de este m\u00fasico destacan colaboraciones con, entre otros, John Scofield, Bela Fleck, Victor Wooten, Stanley Jordan y Jeff Coffin. Este disco supone la culminaci\u00f3n de cinco a\u00f1os<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/brad-myers-prime-numbers-colloquy-records-2015-cd\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":19448,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,1038],"tags":[13574,13572,84,12651,13573,13579,13576,12696,13,12415,15295,13575,13577,5083,13578,16099,77,16100,2337],"class_list":["entry","author-pachi","post-19447","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-contenidos","tag-ben-walkenhauer","tag-brad-myers","tag-carlos-lara","tag-cd","tag-chris-barrick","tag-colloquy-records","tag-dominic-marino","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-michael-mavridoglou","tag-peter-gemus","tag-thelonious-monk","tag-tom-buckley","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-wayne-shorter"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/brad-myers-prime-numbers.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103207,"url":"https:\/\/tomajazz.com\/web\/al-foster-live-at-smoke-2025\/","url_meta":{"origin":19447,"position":0},"title":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100717,"url":"https:\/\/tomajazz.com\/web\/entrevista-ruben-reinaldo-a-proposito-de-fusion-olivica-2025\/","url_meta":{"origin":19447,"position":1},"title":"Pr\u00f3ximamente&#8230; Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz]","author":"Tomajazz","date":"20 octubre, 2025","format":false,"excerpt":"El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","rel":"","context":"En \u00abEntrevistas...\u00bb","block_context":{"text":"Entrevistas...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/entrevistas-criticas\/"},"img":{"alt_text":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz] - Tomajazz - El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101020,"url":"https:\/\/tomajazz.com\/web\/ruben-reinaldo-entrevista-fusion-olivica-2025\/","url_meta":{"origin":19447,"position":2},"title":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz]","author":"Tomajazz","date":"27 octubre, 2025","format":false,"excerpt":"El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","rel":"","context":"En \u00abEntrevistas...\u00bb","block_context":{"text":"Entrevistas...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/entrevistas-criticas\/"},"img":{"alt_text":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz] - Tomajazz - El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101417,"url":"https:\/\/tomajazz.com\/web\/cesar-joaniquet-live-at-jazz-cava-2025\/","url_meta":{"origin":19447,"position":3},"title":"C\u00e8sar Joaniquet: Live at Jazz Cava (UnderPool Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"5 noviembre, 2025","format":false,"excerpt":"Live at Jazz Cava (UnderPool Records; 2025) es la nueva grabaci\u00f3n de C\u00e8sar Joaniquet:. Carlos Lara repasa la grabaci\u00f3n. Con C\u00e8sar Joaniquet, Artur Tu\u017anik), Brice Soniano, Kasper Tom Christiansen","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"C\u00e8sar Joaniquet: Live at Jazz Cava (UnderPool Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Jazz Cava (UnderPool Records; 2025) es la nueva grabaci\u00f3n de C\u00e8sar Joaniquet:. Carlos Lara repasa la grabaci\u00f3n. Con C\u00e8sar Joaniquet, Artur Tu\u017anik), Brice Soniano, Kasper Tom Christiansen","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Cesar-Joaniquet-Live-at-Jazz-Cava-UnderPool-Records-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":102403,"url":"https:\/\/tomajazz.com\/web\/joachim-kuhn-echappee-2025\/","url_meta":{"origin":19447,"position":4},"title":"Joachim K\u00fchn: \u00c9chapp\u00e9e (Intakt Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"1 diciembre, 2025","format":false,"excerpt":"\u00c9chapp\u00e9e (Intakt Records; 2025) es la nueva grabaci\u00f3n en solitario de Joachim K\u00fchn. Carlos Lara repasa la grabaci\u00f3n","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Joachim K\u00fchn: \u00c9chapp\u00e9e (Intakt Records; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - \u00c9chapp\u00e9e (Intakt Records; 2025) es la nueva grabaci\u00f3n en solitario de Joachim K\u00fchn. Carlos Lara repasa la grabaci\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/Joachim-Kuhn-Echappee-Intakt-Records-2025-Tomajazz.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2586,"url":"https:\/\/tomajazz.com\/web\/terrence-mcmanus-mark-helias-gerry-hemingway-transcendental-numbers-nobusiness-records-2011\/","url_meta":{"origin":19447,"position":5},"title":"Terrence McManus \/ Mark Helias \/ Gerry Hemingway: Transcendental Numbers (NoBusiness Records, 2011)","author":"Tomajazz","date":"1 julio, 2011","format":false,"excerpt":"Nueva colaboraci\u00f3n entre el guitarrista Terrence McManus y Gerry Hemingway. Tras el disco en d\u00fao Below the Surface of publicado por el baterista en su sello, la formaci\u00f3n se ampl\u00eda con el a\u00f1adido de Mark Helias. El resultado, Trascendental Numbers, improvisaciones de evocaci\u00f3n matem\u00e1tica, aparece publicado en el inquieto y\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-yfslfVhM7Kw\/Tg3GNC4CjKI\/AAAAAAAAC_4\/0VbsoKUdm98\/s200\/mcmanus-helias-hemingway_trasc.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/19447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=19447"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/19447\/revisions"}],"predecessor-version":[{"id":19449,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/19447\/revisions\/19449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/19448"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=19447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=19447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=19447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}