{"id":1983,"date":"2011-05-02T08:00:33","date_gmt":"2011-05-02T06:00:33","guid":{"rendered":"http:\/\/torec.tomajazz.com\/?p=1334"},"modified":"2016-11-13T20:11:06","modified_gmt":"2016-11-13T19:11:06","slug":"tomajazz-recomienda-una-caja-oscar-peterson-the-songbooks","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-una-caja-oscar-peterson-the-songbooks\/","title":{"rendered":"Tomajazz recomienda&#8230; una caja: Oscar Peterson &#8211; the Songbooks"},"content":{"rendered":"<figure style=\"width: 150px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/i43.tower.com\/images\/mm113497240\/songbooks-oscar-peterson-cd-cover-art.jpg\" alt=\"\" width=\"150\" height=\"150\" title=\"\"><figcaption class=\"wp-caption-text\">Oscar Peterson - the Songbooks<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Entre la desaparici\u00f3n de la venta de ced\u00e9s como negocio y la, \u00bfpor qu\u00e9 no decirlo?, aparente mezcla de ignorancia, desinter\u00e9s, desidia, y falta de medios de las casas propietarias de archivos que las sobrepasan en cantidad y calidad, lo cierto es que los amantes del jazz hemos de andarnos con mucha vista para que no nos metan un gol.<\/p>\n<p style=\"text-align: justify\">En el decenio de los cincuenta y a instancias del productor Norman Granz,\u00a0Peterson grab\u00f3 con sus tr\u00edos\u00a0dos colecciones de <em>songbooks<\/em> o \u00abcancioneros\u00bb, vinilos (LP o EP) dedicados a diez compositores, a saber, Cole Porter, Richard Rodgers, Irving Berlin, Jerome Kern, Duke Ellington, Harold Arlen, George Gershwin, Jimmy McHugh, Harry Warren y Vincent Youmans. La primera serie se registr\u00f3 entre 1952 y 1953, con Barney Kessel a la guitarra (el disco\u00a0con repertorio de\u00a0Harold Arlen es de 1954, con Herb Ellis); la segunda, la que nos ocupa, lleg\u00f3 en 1959, al principio de una nueva etapa para Peterson: acababa de sustituir la guitarra de Herb Ellis por la bater\u00eda de Ed Thigpen, abriendo una nueva etapa de su tr\u00edo, con\u00a0un cambio que dar\u00eda nuevos aires y mayor soltura al grupo.<\/p>\n<p style=\"text-align: justify\">La primera serie de cancioneros se puede obtener con relativa facilidad. La segunda, al menos como caja completa, <span style=\"text-decoration: underline\">solamente se ha publicado en Canad\u00e1<\/span>, algo del todo incomprensible no s\u00f3lo por su valor hist\u00f3rico, sino porque la m\u00fasica es electrizante y merecedora de m\u00e1s atenci\u00f3n por parte de sus propietarios.\u00a0Grabados en un marat\u00f3n de tres semanas del verano de 1959 en Chicago, lo que en su d\u00eda fueron nueve elep\u00e9s (Warren y Youmans compartieron vinilo)\u00a0contienen los primeros, y brillantes, pasos de uno de los grupos\u00a0m\u00e1s populares de la\u00a0historia de esta m\u00fasica, en su formaci\u00f3n m\u00e1s cl\u00e1sica. La caja en s\u00ed es de presentaci\u00f3n espartana, sin aparato innecesario: contiene los discos, toda la informaci\u00f3n discogr\u00e1fica, y un par de p\u00e1ginas de anotaciones.<\/p>\n<p style=\"text-align: justify\">Disponible como<\/p>\n<p style=\"text-align: justify\">Oscar Peterson<em>: the Songbooks<\/em> (Verve\/Universal VERW3922072)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre la desaparici\u00f3n de la venta de ced\u00e9s como negocio y la, \u00bfpor qu\u00e9 no decirlo?, aparente mezcla de ignorancia, desinter\u00e9s, desidia, y falta de medios de las casas propietarias de archivos que las sobrepasan en cantidad y calidad, lo cierto es que los amantes del jazz hemos de andarnos<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-una-caja-oscar-peterson-the-songbooks\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1001004,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17860,1278,1291,1273],"tags":[1517,6637,1750,2091,2282,16099,77,16100,2305,2316],"class_list":["entry","author-adolphus-van-tenzing","post-1983","post","type-post","status-publish","format-standard","category-adolphus-van-tenzing","category-disco","category-reedicion","category-tomajazz-recomienda","tag-brown-ray","tag-duke-ellington","tag-granz-norman","tag-peterson-oscar","tag-thigpen-ed","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-universal","tag-verve"],"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":21608,"url":"https:\/\/tomajazz.com\/web\/seattle-1956-jazz-at-the-philarmonic-hdo-0055-audioblog\/","url_meta":{"origin":1983,"position":0},"title":"Seattle 1956. Jazz At The Philharmonic. HDO (0055) [Audioblog]","author":"Tomajazz","date":"30 diciembre, 2015","format":"audio","excerpt":"El jazz como una fiesta. La fiesta de las giras y conciertos de los espect\u00e1culos Jazz At The Philharmonic promovidos por el empresario Norman Granz que tuvieron lugar entre mediados de los a\u00f1os 40 y el inicio de la d\u00e9cada de los a\u00f1os 80 del pasado siglo. En el caso\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/12\/Jazz-at-the-philarmonic-Seattle-1956.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":99474,"url":"https:\/\/tomajazz.com\/web\/oscar-peterson-mi-vida-en-el-jazz-memorias-2025\/","url_meta":{"origin":1983,"position":1},"title":"Oscar Peterson: Mi vida en el jazz. Memorias (Libros del Kultrum; 2025): Una odisea musical entre la perfecci\u00f3n, la lucha y el swing eterno. Por Pachi Tapiz [Libro de jazz]","author":"Tomajazz","date":"21 septiembre, 2025","format":false,"excerpt":"Libros del Kultrum ha publicado Oscar Peterson: Mi vida en el jazz. Memorias (2025). Pachi Tapiz repasa la obra en Una odisea musical entre la perfecci\u00f3n, la lucha y el swing eterno","rel":"","context":"En \u00abLibros...\u00bb","block_context":{"text":"Libros...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/libros\/"},"img":{"alt_text":"Oscar Peterson: Mi vida en el jazz. Memorias (Libros del Kultrum; 2025): Una odisea musical entre la perfecci\u00f3n, la lucha y el swing eterno. Por Pachi Tapiz [Libro de jazz] - Tomajazz - Libros del Kultrum ha publicado Oscar Peterson: Mi vida en el jazz. Memorias (2025). Pachi Tapiz repasa la obra en Una odisea musical entre la perfecci\u00f3n, la lucha y el swing eterno. Por Pachi Tapiz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Oscar-Peterson-Mi-vida-en-el-jazz-Memorias-Libros-del-Kultrum-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Oscar-Peterson-Mi-vida-en-el-jazz-Memorias-Libros-del-Kultrum-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Oscar-Peterson-Mi-vida-en-el-jazz-Memorias-Libros-del-Kultrum-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/09\/Oscar-Peterson-Mi-vida-en-el-jazz-Memorias-Libros-del-Kultrum-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2050,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-you-look-goog-to-me-oscar-peterson-trio-1964-2\/","url_meta":{"origin":1983,"position":2},"title":"Tomajazz recomienda&#8230; un tema: \u00abYou Look Good To Me\u00bb (Oscar Peterson Trio, 1964)","author":"Adolphus van Tenzing","date":"19 marzo, 2012","format":false,"excerpt":"Estos inmortales versos de B\u00e9cquer se pueden adaptar a muchas cosas y, especialmente, a muchas figuras clave para una u otra doctrina. A veces puede resultar fr\u00edvolo, pero pocas tan acertado como si Oscar Peterson, Ray Brown o Ed Thigpen nos preguntasen inocentemente \u201c\u00bfqu\u00e9 es el swing?\u201d. Entonces, la \u00fanica\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/03\/The-Oscar-Peterson-Trio-We-Get-Requests.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/03\/The-Oscar-Peterson-Trio-We-Get-Requests.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/03\/The-Oscar-Peterson-Trio-We-Get-Requests.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22597,"url":"https:\/\/tomajazz.com\/web\/la-musica-de-lodlma-tomajazz-recomienda-un-tema-bye-bye-blues-por-count-basie\/","url_meta":{"origin":1983,"position":3},"title":"La m\u00fasica de LODLMA. Tomajazz recomienda\u2026 un tema: \u201cBye, Bye Blues\u201d por Count Basie","author":"Tomajazz","date":"28 marzo, 2016","format":false,"excerpt":"Norman Granz. H\u00e9roe para muchos, villano para unos cuantos. En cualquier caso, la caterva de aficionados al jazz le debemos unos cu\u00e1ntos momentos, discogr\u00e1ficos para todos, en vivo para los m\u00e1s veteranos. De los tres elep\u00e9s de jams publicados originalmente (el segundo y tercero con la formaci\u00f3n que detallaremos a\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/03\/Count-Basie-Jam-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1885,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-bye-bye-blues-por-count-basie\/","url_meta":{"origin":1983,"position":4},"title":"Tomajazz recomienda&#8230; un tema: \u00abBye, Bye Blues\u00bb por Count Basie","author":"Adolphus van Tenzing","date":"5 julio, 2010","format":false,"excerpt":"Norman Granz. H\u00e9roe para muchos, villano para unos cuantos. En cualquier caso, la caterva de aficionados al jazz le debemos unos cu\u00e1ntos momentos, discogr\u00e1ficos para todos, en vivo para los m\u00e1s veteranos. En su \u00faltima etapa como productor se encarg\u00f3 de rescatar a viejas glorias. Con Count Basie, por ejemplo,\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/03\/Count-Basie-Jam-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1859,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-liza-por-el-trio-de-oscar-peterson\/","url_meta":{"origin":1983,"position":5},"title":"Tomajazz recomienda&#8230; un tema: \u00abLiza\u00bb por el tr\u00edo de Oscar Peterson","author":"Adolphus van Tenzing","date":"19 octubre, 2009","format":false,"excerpt":"Oscar Peterson es uno de los pianistas m\u00e1s reconocidos y populares de la historia del jazz, aunque no le faltan detractores que, no sin motivo, le han achacado cierta falta de sutileza y matices. Lo que nadie puede negar es su capacidad de generar swing. Tras a\u00f1os al frente de\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/muzycznastrefa.com\/libary\/albums\/18398.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1001004"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=1983"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/1983\/revisions"}],"predecessor-version":[{"id":3796,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/1983\/revisions\/3796"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=1983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=1983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}