{"id":2076,"date":"2012-12-10T17:32:39","date_gmt":"2012-12-10T15:32:39","guid":{"rendered":"http:\/\/torec.tomajazz.com\/?p=2065"},"modified":"2016-11-13T20:10:19","modified_gmt":"2016-11-13T19:10:19","slug":"tomajazz-recomienda-un-tema-the-bridge-sonny-rollins-1962","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-the-bridge-sonny-rollins-1962\/","title":{"rendered":"Tomajazz recomienda&#8230; un tema: \u00abThe Bridge\u00bb (Sonny Rollins, 1962)"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-11319\" alt=\"Sonny_Rollins-The_Bridge\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/Sonny_Rollins-The_Bridge-200x200.jpg\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/Sonny_Rollins-The_Bridge-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/Sonny_Rollins-The_Bridge-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/Sonny_Rollins-The_Bridge-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/Sonny_Rollins-The_Bridge.jpg 336w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>La historia es de sobra conocida: en plena crisis creativa Sonny Rollins se retir\u00f3 en 1959, practicando regularmente a solas en el neoyorquino puente de Williamsburg. Tres a\u00f1os despu\u00e9s volvi\u00f3 por todo lo alto con su disco <em>The Bridge<\/em> (\u00abel puente\u00bb), lleno de fuerza e imaginaci\u00f3n, y con una formaci\u00f3n de cuarteto con guitarra poco habitual por aquellos tiempos.<\/p>\n<p style=\"text-align: justify;\">La an\u00e9cdota es destacada en la carrera de Rollins, pero posiblemente tambi\u00e9n haya empa\u00f1ado en cierto modo el contenido del CD. El tema que le da t\u00edtulo es un <em>rhythm changes<\/em> de melod\u00eda retorcida donde el saxo tenor suena con fiereza, el solo de Jim Hall a la guitarra anticipa sonoridades futuras y el de Bob Cranshaw al contrabajo se convierte en fen\u00f3meno de estudio para cualquier amanuense del instrumento. No debe pasarse por alto el abrupto final del tema, a juego con el resto del contenido. \u00abThe Bridge\u00bb constituye una obra de un adelantado a su tiempo que, adem\u00e1s, nunca deja de lado la tradici\u00f3n.<\/p>\n<p style=\"text-align: right;\">\u00a9 Adolphus van Tenzing, 2012<\/p>\n<p style=\"text-align: justify;\"><em>The Bridge\u00a0<\/em>(Sonny Rollins), RCA 96252<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia es de sobra conocida: en plena crisis creativa Sonny Rollins se retir\u00f3 en 1959, practicando regularmente a solas en el neoyorquino puente de Williamsburg. Tres a\u00f1os despu\u00e9s volvi\u00f3 por todo lo alto con su disco The Bridge (\u00abel puente\u00bb), lleno de fuerza e imaginaci\u00f3n, y con una formaci\u00f3n<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-the-bridge-sonny-rollins-1962\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1001004,"featured_media":2121,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17860,1277,5,1038,1273],"tags":[1459,1494,12651,12696,13,12415,15295,979,2122,2225,2278,16099,77,16100],"class_list":["entry","author-adolphus-van-tenzing","post-2076","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adolphus-van-tenzing","category-cancion","category-grabaciones","category-contenidos","category-tomajazz-recomienda","tag-ben-riley","tag-bob-cranshaw","tag-cd","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jim-hall","tag-rca","tag-sonny-rollins","tag-the-bridge","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2012\/12\/recomienda1.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":105599,"url":"https:\/\/tomajazz.com\/web\/sonny-rollins-1930-2026-in-memoriam\/","url_meta":{"origin":2076,"position":0},"title":"Sonny Rollins (1930-2026) In Memoriam","author":"Tomajazz","date":"26 mayo, 2026","format":false,"excerpt":"Sonny Rollins falleci\u00f3 el 25 de mayo de 2026. Descanse en paz Saxophone Colossus","rel":"","context":"En \u00abIn Memoriam\u00bb","block_context":{"text":"In Memoriam","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/in-memoriam\/"},"img":{"alt_text":"Sonny Rollins (1930-2026) In Memoriam - Tomajazz - Sonny Rollins falleci\u00f3 el 25 de mayo de 2026. Descanse en paz Saxophone Colossus","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/260525-Snny-Rllns-n-Mmrm-Joan-Cortes.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":105602,"url":"https:\/\/tomajazz.com\/web\/sonny-rollins-en-su-salsa-erdc-2026-05\/","url_meta":{"origin":2076,"position":1},"title":"Sonny Rollins en su salsa. Por Chema Garc\u00eda [Escrito de jazz AKA El Rinc\u00f3n de Chema] [Mayo de 2026]","author":"Tomajazz","date":"26 mayo, 2026","format":false,"excerpt":"Sonny Rollins en su salsa. Chema Garc\u00eda recuerda al saxofonista, fallecido el 25 de mayo de 2026, con una entrevista realizada en 2006","rel":"","context":"En \u00abEl rinc\u00f3n de Chema\u00bb","block_context":{"text":"El rinc\u00f3n de Chema","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/el-rincon-de-chema\/"},"img":{"alt_text":"Sonny Rollins en su salsa. Por Chema Garc\u00eda [Escrito de jazz AKA El Rinc\u00f3n de Chema] [Mayo de 2026] - Tomajazz - Sonny Rollins en su salsa. Chema Garc\u00eda recuerda al saxofonista, fallecido el 25 de mayo de 2026, con una entrevista realizada en 2006","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/Sonny-Rollins-grande-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/Sonny-Rollins-grande-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/Sonny-Rollins-grande-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2074,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-cd-sonny-side-up-dizzy-gillespie-1957\/","url_meta":{"origin":2076,"position":2},"title":"Tomajazz recomienda&#8230; un CD: Sonny Side Up (Dizzy Gillespie, 1957)","author":"Adolphus van Tenzing","date":"12 noviembre, 2012","format":false,"excerpt":"El mero hecho de reunir en una sesi\u00f3n de grabaci\u00f3n a Dizzy Gillespie con Sonny Stitt \u2013otro abanderado del be-bop\u2013 y Sonny Rollins \u2013saxofonista de moda en la \u00e9poca\u2013 ya es suficiente para hacer de Sonny Side Up un disco imprescindible. En esta ocasi\u00f3n lo que nos llama la atenci\u00f3n\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"Sonny Side Up","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2012\/11\/Sonny-Side-Up-200x199.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":103207,"url":"https:\/\/tomajazz.com\/web\/al-foster-live-at-smoke-2025\/","url_meta":{"origin":2076,"position":3},"title":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Al Foster: Live at Smoke (Smoke Sessions Records, 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Live at Smoke (Smoke Sessions Records, 2025) es una grabaci\u00f3n en directo de Al Foster, registrada unos meses antes de su fallecimiento. Carlos Lara la repasa. Con Al Foster, Chris Potter, Brad Mehldau, Joe Martin","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Al-Foster-Live-at-Smoke-Smoke-Sessions-Records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2357,"url":"https:\/\/tomajazz.com\/web\/joe-mcphee-ingebrigt-haker-flaten-brooklyn-dna-clean-feed-2012\/","url_meta":{"origin":2076,"position":4},"title":"Joe McPhee &#8211; Ingebrigt Haker Flaten: Brooklyn DNA (Clean Feed, 2012)","author":"Tomajazz","date":"16 abril, 2012","format":false,"excerpt":"Brooklyn DNA es un homenaje y reivindicaci\u00f3n del papel de Brooklyn en la historia del jazz. A d\u00fao, Joe McPhee e Ingebrigt Haker Flaten, realizan una sesi\u00f3n de jazz improvisado estructurada en piezas que a pesar de los t\u00edtulos no pretenden ser m\u00fasica program\u00e1tica, pero en las que sin embargo\u2026","rel":"","context":"En \u00abToma Jazz\u00bb","block_context":{"text":"Toma Jazz","link":"https:\/\/tomajazz.com\/web\/tag\/toma-jazz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-sRVj6k8L6jk\/T4xlXnnTrpI\/AAAAAAAAEeM\/RRJ_Pe8Fyf4\/s200\/mcphee-haker-flaten_brooklyn-dna.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":31631,"url":"https:\/\/tomajazz.com\/web\/365-razones-para-amar-el-jazz-el-puente-de-williamsburg-sonny-rollins-205\/","url_meta":{"origin":2076,"position":5},"title":"365 razones para amar el jazz: el puente de Williamsburg (Sonny Rollins) [205]","author":"Tomajazz","date":"24 julio, 2017","format":false,"excerpt":"Sonny Rollins y el puente de Williamsburg. Seleccionado por\u00a0Juan Antonio Serrano Cervantes En la foto una rara portada del cl\u00e1sico\u00a0Saxophone Colossus\u00a0de\u00a0Sonny Rollins, en la que se puede ver el puente de Williamsburg.","rel":"","context":"En \u00ab*_Juan Antonio Serrano Cervantes\u00bb","block_context":{"text":"*_Juan Antonio Serrano Cervantes","link":"https:\/\/tomajazz.com\/web\/category\/juan-antonio-serrano-cervantes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Sonny-Rollins-Williamsburg-Bridge_Saxophone-Colossus.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/2076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1001004"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=2076"}],"version-history":[{"count":5,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/2076\/revisions"}],"predecessor-version":[{"id":11320,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/2076\/revisions\/11320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/2121"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=2076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=2076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=2076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}