{"id":21824,"date":"2016-01-13T11:00:40","date_gmt":"2016-01-13T10:00:40","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=21824"},"modified":"2021-08-22T22:30:21","modified_gmt":"2021-08-22T20:30:21","slug":"mikel-andueza-cada-5-segundos-errabal-jazz-2015-cd","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/mikel-andueza-cada-5-segundos-errabal-jazz-2015-cd\/","title":{"rendered":"Mikel Andueza: Cada 5 segundos (Errabal Jazz, 2015; CD) [Grabaci\u00f3n de jazz] Por Mikel Andueza"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-20075\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos-200x180.jpg\" alt=\"mikel andueza portada cada cinco segundos\" width=\"200\" height=\"180\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos-200x180.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos-150x135.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos-61x55.jpg 61w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos.jpg 266w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>El navarro <strong>Mikel Andueza<\/strong> es una garant\u00eda de calidad en cada proyecto que acomete. Su t\u00e9cnica depurada al saxo alto, sus buenas composiciones y su acierto en la elecci\u00f3n de los m\u00fasicos llenan de valor sus discos. Cada 5 segundos, <em>su \u00faltimo trabajo, <\/em>lo viene a confirmar una vez m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">El disco lo conforman nueve temas, ocho compuestos por el propio Andueza y otro popular navarro, interpretados por un sexteto de lujo en el que est\u00e1n <strong>I\u00f1aki Salvador<\/strong>, <strong>Dani P\u00e9rez<\/strong>, <strong>Chris Kase<\/strong>, <strong>Gonzalo Tejada<\/strong> y <strong>Gonzalo del Val<\/strong>, todos magn\u00edficos en su participaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El motivo del disco es el tiempo y la muerte de los ni\u00f1os en \u00c1frica. Una llamada de atenci\u00f3n ante una de las masacres m\u00e1s silenciosas y olvidadas de este planeta. A esos ni\u00f1os est\u00e1 dedicado <em>Cada 5 segundos.<\/em><\/p>\n<p style=\"text-align: justify;\">El disco tiene un cierto car\u00e1cter mel\u00f3dico en el comienzo de las piezas. Sus temas son reflexiones arm\u00f3nicas que se desarrollan a trav\u00e9s de improvisaciones de Andueza con un estilo sencillo, pero impecable en cuanto a su ejecuci\u00f3n. Escuchar este disco es plenamente reconfortante. La complicidad establecida entre los m\u00fasicos desde que empieza con el tema que da t\u00edtulo al disco hasta que acaba con \u201cJan Steps\u201d da una sensaci\u00f3n de historias muy bien contadas, con unos personajes-m\u00fasicos que encajan a la perfecci\u00f3n y unos ritmos dirigidos por Andueza, dignos de admiraci\u00f3n. Buena culpa de ello la tiene la capacidad compositiva de este m\u00fasico. Lo mismo encontramos temas intensos como \u201cUnderground\u201d, que preciosos solos de Chris Kase a la trompeta y otro de I\u00f1aki Salvador al piano en \u201cAxuri Beltza\u201d, o exposiciones de Mikel Andueza y Dani P\u00e9rez a la guitarra en \u201cPonle letra\u201d o \u201cMr M.B.\u201d. En realidad ning\u00fan tema tiene desperdicio.<\/p>\n<p style=\"text-align: justify;\">El disco es jazz plenamente contempor\u00e1neo, con unos temas dotados de una fuerza que les hace siempre salir airosos, sin fisuras y con un desarrollo redondo. Un nuevo acierto de Mikel Andueza.<\/p>\n<p style=\"text-align: right;\">\u00a9 Carlos Lara, 2016<\/p>\n<p style=\"text-align: justify;\">Mikel Andueza: <em>Cada 5 segundos<\/em><\/p>\n<p style=\"text-align: justify;\">Miguel Andueza (saxo alto), Dani P\u00e9rez (guitarra), Chris Kase (trompeta), I\u00f1aki Salvador (piano y \u00f3rgano), Gonzalo Tejada (contrabajo) y Gonzalo del Val (bater\u00eda).<\/p>\n<p style=\"text-align: justify;\">\u201cCada 5 Segundos\u201d, \u201cZortziko para Mauro\u201d, \u201cMajito\u201d, \u201cAxuri Beltza\u201d, \u201cUnderground\u201d, \u201cMr M.B.\u201d, \u201cKenny\u201d, \u201cPonle Letra\u201d y \u201cJan Steps\u201d.<br \/>\nTodos los temas compuestos por Mikel Andueza, excepto \u201cAxuri Beltza\u201d, danza popular navarra arreglada por Mikel Andueza.<\/p>\n<p style=\"text-align: justify;\">Grabado el 20 y 21 de marzo de 2015 en los estudios Mecca Recording Studio de Donostia. Editado en 2015 por Errabal Jazz. ER.078<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Lara repasa Cada 5 Segundos (Errabal Jazz, 2015), del saxofonista Mikel Andueza. <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/mikel-andueza-cada-5-segundos-errabal-jazz-2015-cd\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":20075,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,15517,1038],"tags":[15783,15782,15781,84,12651,10667,519,4990,413,435,12696,433,13,12415,15295,7704,15780,16099,77,16100],"class_list":["entry","author-pachi","has-excerpt","post-21824","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-textos","category-contenidos","tag-cada-5-segundos-de-mikel-andueza","tag-cada-5-segundos-mikel-andueza","tag-cada-5-segundos-nueva-grabacion-de-mikel-andueza","tag-carlos-lara","tag-cd","tag-chris-kase","tag-dani-perez","tag-errabal-jazz","tag-gonzalo-del-val","tag-gonzalo-tejada","tag-grabaciones","tag-inaki-salvador","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-mikel-andueza","tag-mikel-andueza-cada-5-segundos","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/mikel-andueza-portada-cada-cinco-segundos.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":23944,"url":"https:\/\/tomajazz.com\/web\/hdo-en-concierto-con-mikel-andueza-en-bogui-jazz-0104-podcast\/","url_meta":{"origin":21824,"position":0},"title":"HDO 104. En concierto con\u2026 Mikel Andueza en Bogui Jazz [Podcast]","author":"Tomajazz","date":"3 mayo, 2016","format":false,"excerpt":"Los pr\u00f3ximos viernes 6 y s\u00e1bado 7 de mayo el saxofonista Mikel Andueza estar\u00e1 actuando en Bogui Jazz junto a Chris Kase (trompeta), Dani P\u00e9rez (guitarra), Gonzalo Tejada (contrabajo y bajo el\u00e9ctrico), y Gonzalo del Val (bater\u00eda). El quinteto presentar\u00e1 en directo Cada 5 segundos (Errabal Jazz, 2015), la \u00faltima\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/05\/Mikel-Andueza-Cada-5-Segundos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":20335,"url":"https:\/\/tomajazz.com\/web\/mikel-andueza-quartet-murajazz-2015-baluarte-pamplona-2015-10-09\/","url_meta":{"origin":21824,"position":1},"title":"Mikel Andueza Quartet (Murajazz 2015, Baluarte, Pamplona. 2015-10-09)","author":"Tomajazz","date":"20 octubre, 2015","format":false,"excerpt":"Murajazz 2015 Fecha: viernes, 9 de octubre de 2015 Lugar: Sala de la Muralla, Auditorio Baluarte, Pamplona, Navarra Grupo: Mikel Andueza Quartet Mikel Andueza: saxos alto y soprano, y composiciones Dani P\u00e9rez: guitarra el\u00e9ctrica Gonzalo Tejada: contrabajo y bajo el\u00e9ctrico Gonzalo del Val: bater\u00eda En el segundo concierto de la\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/IMG_9839.JPG-Mikel-anduezawm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/IMG_9839.JPG-Mikel-anduezawm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/IMG_9839.JPG-Mikel-anduezawm.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":21826,"url":"https:\/\/tomajazz.com\/web\/all-jazz-sera-mikel-andueza-gonzalo-tejada\/","url_meta":{"origin":21824,"position":2},"title":"All Jazz Sera: Mikel Andueza &#8211; Gonzalo Tejada","author":"Tomajazz","date":"13 enero, 2016","format":"image","excerpt":"Mikel Andueza (izquierda) - Gonzalo Tejada (derecha) Mikel Andueza Quartet Murajazz 2015. Sala de la Muralla. Auditorio Baluarte. Pamplona. 2015-10-02 \u00a9 Sera Mart\u00edn, 2015","rel":"","context":"En \u00ab*_Sera Mart\u00edn\u00bb","block_context":{"text":"*_Sera Mart\u00edn","link":"https:\/\/tomajazz.com\/web\/category\/sera-martin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_9761.JPG-Mikel-Anduezawm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_9761.JPG-Mikel-Anduezawm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/IMG_9761.JPG-Mikel-Anduezawm.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":20263,"url":"https:\/\/tomajazz.com\/web\/all-jazz-sera-mikel-andueza-3\/","url_meta":{"origin":21824,"position":3},"title":"All Jazz Sera: Mikel Andueza","author":"Tomajazz","date":"15 octubre, 2015","format":"image","excerpt":"Mikel Andueza Mikel Andueza Quartet Murajazz 2015. Sala de la Muralla. Auditorio Baluarte. Pamplona. 2015-10-02 \u00a9 Sera Mart\u00edn, 2015 \u00a0","rel":"","context":"En \u00ab*_Sera Mart\u00edn\u00bb","block_context":{"text":"*_Sera Mart\u00edn","link":"https:\/\/tomajazz.com\/web\/category\/sera-martin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/IMG_9766.JPG-Mikel-Anduezawm.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":20072,"url":"https:\/\/tomajazz.com\/web\/mikel-andueza-cada-cinco-segundos-murajazz-2015-ii\/","url_meta":{"origin":21824,"position":4},"title":"Mikel Andueza: Cada cinco segundos (Murajazz 2015- II)","author":"Tomajazz","date":"7 octubre, 2015","format":"image","excerpt":"El segundo concierto del ciclo Murajazz 2015 estar\u00e1 protagonizado por Mikel Andueza, que al frente de un cuarteto de muchos kilates presentar\u00e1 Cada cinco segundos (Errabal), un CD\u00a0que muchos aficionados llevan esperando desde hace a\u00f1os, puesto que todas las grabaciones de Andueza han sido m\u00e1s que notables. Pachi Tapiz lo\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/Mikel-Andueza-Cuarteto_peq.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/Mikel-Andueza-Cuarteto_peq.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/10\/Mikel-Andueza-Cuarteto_peq.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19798,"url":"https:\/\/tomajazz.com\/web\/murajazz-2015-baluarte-pamplona-octubre-2015-noticias\/","url_meta":{"origin":21824,"position":5},"title":"MuraJazz 2015 (Baluarte, Pamplona. Octubre 2015) [Noticias]","author":"Tomajazz","date":"22 septiembre, 2015","format":"image","excerpt":"El ciclo MuraJazz, que se celebrar\u00e1 en octubre en la Sala de la Muralla de Baluarte de Pamplona, llega en 2015 a \u00a0su tercera edici\u00f3n, en la que nuevamente consistir\u00e1 en tres conciertos. El viernes 2 de octubre actuar\u00e1 Tommy Caggiani Therion Project. El quinteto presentar\u00e1 su grabaci\u00f3n The Energy\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/Presentacion-Murajazz-2015.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/Presentacion-Murajazz-2015.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/Presentacion-Murajazz-2015.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/Presentacion-Murajazz-2015.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/21824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=21824"}],"version-history":[{"count":3,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/21824\/revisions"}],"predecessor-version":[{"id":56633,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/21824\/revisions\/56633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/20075"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=21824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=21824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=21824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}