{"id":28041,"date":"2010-12-09T08:28:46","date_gmt":"2010-12-09T07:28:46","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=28041"},"modified":"2016-12-09T08:42:34","modified_gmt":"2016-12-09T07:42:34","slug":"derek-bailey-la-improvisacion-su-naturaleza-y-su-practica-en-la-musica-ediciones-trea-2010-extracto-libro","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/derek-bailey-la-improvisacion-su-naturaleza-y-su-practica-en-la-musica-ediciones-trea-2010-extracto-libro\/","title":{"rendered":"Derek Bailey: La improvisaci\u00f3n. Su naturaleza y su pr\u00e1ctica en la m\u00fasica (Ediciones Trea, 2010) [Extracto. Libro]"},"content":{"rendered":"<p align=\"justify\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28043 size-medium\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010-183x300.jpg\" width=\"183\" height=\"300\" alt=\"\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010-183x300.jpg 183w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010-768x1256.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010-367x600.jpg 367w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010-34x55.jpg 34w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010.jpg 800w\" sizes=\"auto, (max-width: 183px) 100vw, 183px\" \/>Extracto de <em>La improvisaci\u00f3n. Su naturaleza y su pr\u00e1ctica en la m\u00fasica<\/em> de Derek Bailey. Reproducido con permiso de Ediciones Trea.<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">El jazz nos proporciona un buen ejemplo de los peligros del mimetismo en una m\u00fasica que es en gran medida improvisada. R. Strinavasan habla del mismo problema en relaci\u00f3n con la m\u00fasica india: \u00abEl enemigo es la mera imitaci\u00f3n sin inspiraci\u00f3n, que es lo que convierte al arte en algo vivo\u00bb. La tendencia a la copia, el predominio de la imitaci\u00f3n en todas las formas de la improvisaci\u00f3n idiom\u00e1tica, parece haber conducido, en el campo del jazz, a una situaci\u00f3n en que todo el g\u00e9nero se identifica cada vez m\u00e1s con el estilo interpretativo de un pu\u00f1ado de m\u00fasicos. Curiosamente, el n\u00famero de modelos aceptables parece disminuir con el paso del tiempo. El estilo interpretativo de los dem\u00e1s, la gran mayor\u00eda de los m\u00fasicos, se identifica invariablemente asoci\u00e1ndolo con alguno de los \u00abgrandes\u00bb de su instrumento, o haciendo referencia a \u00e9l: se dice que alguien toca como tal o cual maestro y eso es todo lo que se necesita saber sobre un nuevo m\u00fasico. De hecho, en el mundo del jazz es habitual encontrar r\u00e9plicas absolutamente id\u00e9nticas de los estilistas m\u00e1s conocidos. Nadie se enga\u00f1a, por supuesto, con estas imitaciones, salvo quiz\u00e1 el imitador[1], pero la situaci\u00f3n se acepta y se considera normal. Una alta proporci\u00f3n de la m\u00fasica que se toca es casi totalmente imitativa.<\/p>\n<p style=\"text-align: justify;\">Esto, que tal vez sea uno de los principales inconvenientes de cualquier m\u00fasica improvisada, surge, por supuesto, de pr\u00e1cticas intr\u00ednsecas a ella. En primer lugar, el m\u00e9todo de aprendizaje de cualquier improvisaci\u00f3n idiom\u00e1tica conlleva unos peligros evidentes. Est\u00e1 claro que los tres pasos sucesivos que, en principio, forman parte de este m\u00e9todo \u2014elegir un maestro, asimilar sus conocimientos por medio de la imitaci\u00f3n pr\u00e1ctica y desarrollar un estilo y un enfoque individuales a partir de ah\u00ed\u2014 suelen quedarse en dos, omitiendo el paso m\u00e1s dif\u00edcil, el \u00faltimo. Imitar el estilo y adquirir la t\u00e9cnica instrumental de un instrumentista famoso que muy probablemente sea un virtuoso no es nada f\u00e1cil y, una vez se consigue, puede proporcionar a un m\u00fasico importantes satisfacciones. Una de ellas, no poco relevante, es la admiraci\u00f3n de aquellos m\u00fasicos que no han tenido tanto \u00e9xito al intentar lo mismo que \u00e9l. En el mundo del jazz, decir de alguien que \u00absuena igual\u00bb que un m\u00fasico conocido suele considerarse un elogio. Por lo tanto, la presi\u00f3n para conformarse con no ser m\u00e1s que un buen imitador es bastante fuerte. El segundo peligro est\u00e1 en la b\u00fasqueda de autenticidad.<\/p>\n<p style=\"text-align: justify;\">Un m\u00fasico que busca la autenticidad suele evitar f\u00e1cilmente caer en el formalismo cuando se expresa de forma espont\u00e1nea. Tambi\u00e9n el elemento natural de innovaci\u00f3n y creatividad de la improvisaci\u00f3n lo aparta de ese riesgo. Sin embargo, cuando se rompe el equilibrio entre estas dos fuerzas \u2014la preocupaci\u00f3n por la autenticidad de la m\u00fasica y la naturaleza esencialmente investigadora de la improvisaci\u00f3n\u2014, la m\u00fasica se inclina hacia uno de los dos lados, avanzando en una direcci\u00f3n totalmente innovadora o convirti\u00e9n\u00acdose en una parodia inconsciente de s\u00ed misma.<\/p>\n<p style=\"text-align: justify;\">Es innegable que algo fue mal con el equilibrio del jazz. La creatividad qued\u00f3 cada vez m\u00e1s en manos de un peque\u00f1o grupo de \u00abinnovadores\u00bb, mientras el resto se dedic\u00f3 simplemente a imitar a los maestros.<\/p>\n<p style=\"text-align: justify;\">Nota: [1] Hay una an\u00e9cdota de Lester Young que parece improbable pero seguramente sea cierta. Uno de sus admiradores, un saxofonista tenor cuya forma de tocar se basaba exclusivamente en la de Lester, hizo un largo viaje para escuchar a su \u00eddolo. Young, un m\u00fasico magn\u00edficamente impredecible, no toc\u00f3 como era habitual en \u00e9l. El disc\u00edpulo, enfurecido, le grit\u00f3: \u00ab\u00a1T\u00fa no eres t\u00fa, yo soy t\u00fa!\u00bb.<\/p>\n<p style=\"text-align: right;\">\u00a9 Herederos de Derek Bailey, 1980, 1992, 2010<br \/>\n\u00a9 de la traducci\u00f3n, Mariano Peyrou, 2010<br \/>\n\u00a9 de la ilustraci\u00f3n de cubierta, Jorge P\u00e9rez, 2010<br \/>\n\u00a9 de la edici\u00f3n en castellano: Ediciones Trea, S.L.<\/p>\n<p style=\"text-align: left;\"><strong>Derek Bailey.<\/strong><em> La improvisaci\u00f3n. Su naturaleza y su pr\u00e1ctica en la m\u00fasica<br \/>\n<\/em>Pr\u00f3logos de Ildefonso Rodr\u00edguez y Agust\u00ed Fern\u00e1ndez<br \/>\nTraducci\u00f3n de Mariano Peyrou<br \/>\n<a href=\"http:\/\/www.trea.es\/ficha.php?idLibro=00001078\" target=\"_blank\" rel=\"noopener\">Ediciones Trea <\/a><br \/>\nColecci\u00f3n: Trea Artes<br \/>\nFormato 12 x 20 cm<br \/>\n276 p\u00e1ginas<br \/>\nISBN 978-84-9704-530-8<br \/>\nA\u00f1o 2010<br \/>\nPVP 25,00\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extracto de La improvisaci\u00f3n. Su naturaleza y su pr\u00e1ctica en la m\u00fasica de Derek Bailey. Reproducido con permiso de Ediciones Trea. El jazz nos proporciona un buen ejemplo de los peligros del mimetismo en una m\u00fasica que es en gran medida improvisada. R. Strinavasan habla del mismo problema en relaci\u00f3n<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/derek-bailey-la-improvisacion-su-naturaleza-y-su-practica-en-la-musica-ediciones-trea-2010-extracto-libro\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":28043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,78,113,3,15517,1038],"tags":[280,15953,11487,18138,18140,6737,13,12415,15295,384,15710,15669,16125,18139,16099,77,16100],"class_list":["entry","author-pachi","post-28041","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-afondo","category-extractos","category-libros","category-textos","category-contenidos","tag-agusti-fernandez","tag-alberto-arteta-group-alberto-arteta-jorge-abadias-satxa-soriazu-kike-arza-juanma-urriza","tag-derek-bailey","tag-ediciones-trea","tag-ildefonso-rodrigue","tag-ildefonso-rodriguez","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jorge-perez","tag-la-actualidad-del-jazz-en-espana","tag-libros-de-jazz","tag-libros-sobre-jazz","tag-mariano-peyrou","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Derek-Bailey_La-improvisaci\u00f3n_Ediciones-Trea_2010.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2731,"url":"https:\/\/tomajazz.com\/web\/derek-bailey-sobre-el-jazz\/","url_meta":{"origin":28041,"position":0},"title":"Derek Bailey sobre el jazz","author":"Tomajazz","date":"22 diciembre, 2010","format":false,"excerpt":"\"La tendencia a la copia, el predominio de la imitaci\u00f3n en todas las formas de la improvisaci\u00f3n idiom\u00e1tica, parece haber conducido, en el campo del jazz, a una situaci\u00f3n en que todo el g\u00e9nero se identifica cada vez m\u00e1s con el estilo interpretativo de un pu\u00f1ado de m\u00fasicos.\"Derek Bailey en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/3.bp.blogspot.com\/_huJnG8dEQz8\/TQIKYL1b20I\/AAAAAAAACQE\/tcO7LPcWDqI\/s320\/bailey_la-improvisacion.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2712,"url":"https:\/\/tomajazz.com\/web\/la-diferencia-entre-composicion-e-improvisacion-segun-steve-lacy\/","url_meta":{"origin":28041,"position":1},"title":"La diferencia entre composici\u00f3n e improvisaci\u00f3n seg\u00fan Steve Lacy","author":"Tomajazz","date":"12 enero, 2011","format":false,"excerpt":"\"En 1968 me encontr\u00e9 a Steve Lacy por la calle, en Roma. Saqu\u00e9 mi grabadora y le ped\u00ed que me explicara, en quince segundos, la diferencia entre la composici\u00f3n y la improvisaci\u00f3n. Dijo: 'En quince segundos, la diferencia entre la composici\u00f3n y la improvisaci\u00f3n es que en la composici\u00f3n tienes\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/01\/lacy-evidence.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/01\/lacy-evidence.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2011\/01\/lacy-evidence.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":43746,"url":"https:\/\/tomajazz.com\/web\/hdo-512-tres-gigantes-de-la-improvisacion-derek-bailey-evan-parker-y-han-bennink-podcast\/","url_meta":{"origin":28041,"position":2},"title":"HDO 512. Tres gigantes de la improvisaci\u00f3n: Derek Bailey, Evan Parker y Han Bennink [Podcast]","author":"Tomajazz","date":"11 junio, 2019","format":false,"excerpt":"Por\u00a0Pachi Tapiz. En HDO 512 suena una improvisaci\u00f3n grabada por el tr\u00edo formado por Derek Bailey, Evan Parker y Han Bennink el 3 de abril de 1981, contenida en el cu\u00e1druple CD Topographie Parisienne, que publica en 2019 el sello franc\u00e9s FOU Records. Hablar de Derek Bailey, Evan Parker y\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Collage_programa-0512_Bailey-Parker-Bennink.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Collage_programa-0512_Bailey-Parker-Bennink.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Collage_programa-0512_Bailey-Parker-Bennink.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Collage_programa-0512_Bailey-Parker-Bennink.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20807,"url":"https:\/\/tomajazz.com\/web\/anthony-braxton-y-derek-bailey-steve-lacy-quintet-weston-rose-marshall-novedades-en-emanem-hdo-0034\/","url_meta":{"origin":28041,"position":3},"title":"Anthony Braxton y Derek Bailey, Steve Lacy Quintet, Weston &#8211; Rose &#8211; Marshall: novedades en EMANEM. HDO (0034) [Audioblog]","author":"Tomajazz","date":"12 noviembre, 2015","format":false,"excerpt":"\u00bfCu\u00e1ntas veces habr\u00e9 escrito que la labor de Martin Davidson al frente del sello Emanem es impagable? Alejado en su residencia del Reino Unido, de Londres, sigue sin embargo empe\u00f1ado en documentar la escena improvisadora brit\u00e1nica. Su trabajo tiene dos, que quiz\u00e1s podr\u00edan ser, vertientes: la publicaci\u00f3n de grabaciones recientes\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"anthony braxton - derek bailey_first duo concert_emanem_2015","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/anthony-braxton-derek-bailey_first-duo-concert_emanem_2015-200x200.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25582,"url":"https:\/\/tomajazz.com\/web\/hdo-147-emanem-musicas-del-pasado-y-del-presente-que-miran-hacia-el-futuro-podcast\/","url_meta":{"origin":28041,"position":4},"title":"HDO 147. Emanem: m\u00fasicas del pasado y del presente que miran hacia el futuro [Podcast]","author":"Tomajazz","date":"20 julio, 2016","format":false,"excerpt":"Pachi Tapiz repasa brevemente y lleva al podcast HDO cuatro referencias publicadas por el sello Emanem de Kent Carter, Tony Marsh - Chefa Alonso, Duck Baker y el Spontaneous Music Ensemble de John Stevens con Evan Parker, Barry Guy, Derek Bailey, Trevor Watts, Kenny Wheeler...","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Duck Baker_Outside_Emanem_2016","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/07\/Duck-Baker_Outside_Emanem_2016-200x200.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":81347,"url":"https:\/\/tomajazz.com\/web\/derek-bailey-paul-motian-duo-in-concert-2023\/","url_meta":{"origin":28041,"position":5},"title":"Derek Bailey \u2013 Paul Motian: Duo in Concert (Frozen Reeds; 2023) Por Guillermo Bazzola [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"7 diciembre, 2023","format":false,"excerpt":"Duo in Concert (Frozen Reeds; 2023) es el t\u00edtulo de la grabaci\u00f3n en directo de Derek Bailey \u2013 Paul Motian. Guillermo Bazzola repasa la grabaci\u00f3n de los maestros de la guitarra y bater\u00eda.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Derek Bailey \u2013 Paul Motian: Duo in Concert (Frozen Reeds; 2023) Por Guillermo Bazzola [Grabaci\u00f3n de jazz] - Tomajazz 9.0 - Duo in Concert es el t\u00edtulo de la grabaci\u00f3n en directo de Derek Bailey \u2013 Paul Motian : Duo in Concert (Frozen Reeds; 2023) Por Guillermo Bazzola [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/Derek-Bailey-Paul-Motian-In-Concert.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/Derek-Bailey-Paul-Motian-In-Concert.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/Derek-Bailey-Paul-Motian-In-Concert.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/Derek-Bailey-Paul-Motian-In-Concert.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/Derek-Bailey-Paul-Motian-In-Concert.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=28041"}],"version-history":[{"count":3,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28041\/revisions"}],"predecessor-version":[{"id":28046,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28041\/revisions\/28046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/28043"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=28041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=28041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=28041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}