{"id":28144,"date":"2016-12-19T10:59:24","date_gmt":"2016-12-19T09:59:24","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=28144"},"modified":"2021-07-18T14:17:13","modified_gmt":"2021-07-18T12:17:13","slug":"jazz-numero-42-diciembre-2016-noticias","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/jazz-numero-42-diciembre-2016-noticias\/","title":{"rendered":"+Jazz (N\u00famero 42. Diciembre 2016) [Noticias]"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28145\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/0001-600x424.jpg\" alt=\"\" width=\"600\" height=\"424\" title=\"\"><\/p>\n<p style=\"text-align: justify;\">Ya est\u00e1 a la venta el n\u00famero 42 de la revista <em>+Jazz<\/em>. En portada \u00ab<strong>Ximo Tebar<\/strong> por Borja Quintana. El Son Mediterr\u00e1nea de Ximo Tebar\u00bb. Otros contenidos: \u00ab<strong>Jo\u00eblle L\u00e9andre<\/strong>, o de c\u00f3mo llegar a la improvisaci\u00f3n m\u00e1s radical desde la m\u00fasica cl\u00e1sica\u00bb por Pachi Tapiz; \u00abLa nueva ola del jazz israel\u00ed\u00bb por Jordi Torregrosa; \u00abConversaci\u00f3n con <strong>M.A.P.<\/strong> -Mezquida, Aurignac, Prats-\u00bb por Joan Carles Abelenda; \u00abImprovisaci\u00f3n y entorno en el<em> jazz movie<\/em>\u00bb por Giuliano Parisi; \u00abEl esoterismo en la m\u00fasica\u00bb por Federico Schmied. El n\u00famero est\u00e1 dedicado a <strong>El\u00edas Vivas<\/strong>. 6 euros, 68 p\u00e1ginas a todo color.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 a la venta el n\u00famero 42 de la revista +Jazz. En portada \u00abXimo Tebar por Borja Quintana. El Son Mediterr\u00e1nea de Ximo Tebar\u00bb. Otros contenidos: \u00abJo\u00eblle L\u00e9andre, o de c\u00f3mo llegar a la improvisaci\u00f3n m\u00e1s radical desde la m\u00fasica cl\u00e1sica\u00bb por Pachi Tapiz; \u00abLa nueva ola del jazz<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/jazz-numero-42-diciembre-2016-noticias\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":28145,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,15795,1038],"tags":[15299,12415,15297,8105,11856,15296,15298],"class_list":["entry","author-pachi","post-28144","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-noticias-2","category-contenidos","tag-espana-en-jazz","tag-jazz-en-espana","tag-jazz-news","tag-mas-jazz","tag-noticias","tag-noticias-de-jazz","tag-noticias-de-jazz-en-espana"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/0001-e1482094871773.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":27417,"url":"https:\/\/tomajazz.com\/web\/hdo-194-redux\/","url_meta":{"origin":28144,"position":0},"title":"HDO 194 Redux [Podcast]","author":"Tomajazz","date":"9 noviembre, 2016","format":false,"excerpt":"En breve pasar\u00e1 por HDO el guitarrista Ximo T\u00e9bar. El motivo es la publicaci\u00f3n de su nueva grabaci\u00f3n titulada Soleo, la publicaci\u00f3n del magn\u00edfico libro Ximo T\u00e9bar, la guitarra del jazz mediterr\u00e1neo. Son Mediterr\u00e1neo, 25 aniversario, 1990-2015 de Jos\u00e9 Pru\u00f1onosa, y su actuaci\u00f3n en el Festival de Jazz de Madrid\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/10\/Ximo-T%C3%A9bar_Soleo_2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/10\/Ximo-T%C3%A9bar_Soleo_2016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/10\/Ximo-T%C3%A9bar_Soleo_2016.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/10\/Ximo-T%C3%A9bar_Soleo_2016.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27452,"url":"https:\/\/tomajazz.com\/web\/hdo-194-ximo-tebar-y-su-son-mediterraneo-sus-palabras-y-sus-musicas-entrevista-por-pachi-tapiz-podcast\/","url_meta":{"origin":28144,"position":1},"title":"HDO 194. Ximo T\u00e9bar y su Son Mediterr\u00e1neo: sus palabras y sus m\u00fasicas. Entrevista por Pachi Tapiz [Podcast]","author":"Tomajazz","date":"12 noviembre, 2016","format":false,"excerpt":"El guitarrista Ximo T\u00e9bar es el protagonista de la entrega 194 de\u00a0HDO. El\u00a0motivo es su actuaci\u00f3n en el Festival de Jazz de Madrid el jueves 17 de noviembre (de 2016), en el que presentar\u00e1 Soleo, una grabaci\u00f3n que le sirve para conmemorar y poner al d\u00eda -25 a\u00f1os despu\u00e9s-,\u00a0Son Mediterr\u00e1neo.\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/ximo-tebar_Fotograf%C3%ADa-por-Rafa-M%C3%A1rquez.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":103886,"url":"https:\/\/tomajazz.com\/web\/2025-en-25-imagenes-2\/","url_meta":{"origin":28144,"position":2},"title":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (segunda parte) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"3 febrero, 2026","format":false,"excerpt":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- )en esta ocasi\u00f3n con la segunda parte) es un cl\u00e1sico de Joan Cort\u00e8s cada inicio de a\u00f1o en INSTANTZZ","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (segunda parte) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - 2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- )en esta ocasi\u00f3n con la segunda parte) es un cl\u00e1sico de Joan Cort\u00e8s cada inicio de a\u00f1o en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-22-Blsr-Dcrt-Brn-Photo-by-Joan-Cortes-20nvm25-JzzCv-Vc.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-22-Blsr-Dcrt-Brn-Photo-by-Joan-Cortes-20nvm25-JzzCv-Vc.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-22-Blsr-Dcrt-Brn-Photo-by-Joan-Cortes-20nvm25-JzzCv-Vc.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103649,"url":"https:\/\/tomajazz.com\/web\/2025-en-25-imagenes-1\/","url_meta":{"origin":28144,"position":3},"title":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (primera parte) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"22 enero, 2026","format":false,"excerpt":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (primera parte) es un cl\u00e1sico de Joan Cort\u00e8s cada inicio de a\u00f1o en INSTANTZZ","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (primera parte) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - 2025 en 25 im\u00e1genes -jazz, improvisaci\u00f3n y flamenco- (primera parte) es un cl\u00e1sico de Joan Cort\u00e8s cada inicio de a\u00f1o en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacado-03-Nr-ndrr-sqllrm-Photo-by-Joan-Cortes-22fbr25-L-dtr-S1-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacado-03-Nr-ndrr-sqllrm-Photo-by-Joan-Cortes-22fbr25-L-dtr-S1-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacado-03-Nr-ndrr-sqllrm-Photo-by-Joan-Cortes-22fbr25-L-dtr-S1-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27298,"url":"https:\/\/tomajazz.com\/web\/ximotebar-la-guitarra-del-jazz-mediterraneo-son-mediterraneo-25-aniversario-1990-2015-piles-editorial-de-musica-s-a-valencia-2016-libro\/","url_meta":{"origin":28144,"position":4},"title":"Ximo T\u00e9bar, la guitarra del jazz mediterr\u00e1neo. Son Mediterr\u00e1neo, 25 aniversario, 1990-2015 (Jos\u00e9 Pru\u00f1onosa. Piles, Editorial de M\u00fasica S.A., Valencia, 2016) Por Juli\u00e1n Ruesga Bono [Libro]","author":"Tomajazz","date":"4 noviembre, 2016","format":false,"excerpt":"No es frecuente la publicaci\u00f3n de monograf\u00edas sobre m\u00fasicos de jazz espa\u00f1oles. Recordando, s\u00f3lo me viene a la memoria la dedicada a Tete Montoliu. Quiz\u00e1s haya otras que no recuerdo. As\u00ed que esta publicaci\u00f3n, XimoT\u00e9bar, La guitarra del jazz mediterr\u00e1neo, que ya lleva varios meses en la calle, es una\u2026","rel":"","context":"En \u00ab*_Juli\u00e1n Ruesga Bono\u00bb","block_context":{"text":"*_Juli\u00e1n Ruesga Bono","link":"https:\/\/tomajazz.com\/web\/category\/julian-ruesga-bono\/"},"img":{"alt_text":"jose-prunonosa_ximo-tebar_la-guitarra-del-jazz-mediterraneo_libro_2016","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/11\/Jos%C3%A9-Pru%C3%B1onosa_Ximo-Tebar_La-guitarra-del-Jazz-mediterr%C3%A1neo_libro_2016-197x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25048,"url":"https:\/\/tomajazz.com\/web\/39-edicion-festival-jazz-de-vitoria-gasteiz-14-al-18-de-julio-de-2016-vitoria-noticias\/","url_meta":{"origin":28144,"position":5},"title":"40 Edici\u00f3n Festival Jazz de Vitoria-Gasteiz (12 al 16 de Julio de 2016. Vitoria) [Noticias]","author":"Tomajazz","date":"24 junio, 2016","format":false,"excerpt":"Entre el 12 y el 16 de julio de 2016 se celebrar\u00e1 en Vitoria - Gasteiz la 40\u00a0Edici\u00f3n del Festival de Jazz de Vitoria - Gasteiz. Entre otros actuar\u00e1n Pat Metheny, Tom Harrell, Joshua Redman, Kenny Barron, Dave Holland, Ron Carter, Ximo Tebar, Pablo M. Caminero, GoGo Penguin, Yaron Herman\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/40-Festival-de-Jazz-de-Vitoria-Gasteiz-e1466366722998.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/40-Festival-de-Jazz-de-Vitoria-Gasteiz-e1466366722998.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/40-Festival-de-Jazz-de-Vitoria-Gasteiz-e1466366722998.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=28144"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28144\/revisions"}],"predecessor-version":[{"id":28146,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28144\/revisions\/28146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/28145"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=28144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=28144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=28144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}