{"id":28159,"date":"2016-12-19T11:00:45","date_gmt":"2016-12-19T10:00:45","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=28159"},"modified":"2016-12-19T11:29:08","modified_gmt":"2016-12-19T10:29:08","slug":"mosaikorea-matadero-madrid-2016-12-17-concierto","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/mosaikorea-matadero-madrid-2016-12-17-concierto\/","title":{"rendered":"Mosaikorea (Matadero, Madrid. 2016-12-17) [Concierto]"},"content":{"rendered":"<p>Melod\u00eda Dispersa-II Edici\u00f3n de la Navide\u00f1a: Feria Internacional de las Culturas (15-23 dic.)<\/p>\n<ul>\n<li>Fecha: 17 de diciembre de 2016<\/li>\n<li>Lugar: Matadero, Madrid<\/li>\n<li>Grupo:<br \/>\n<strong>Mosaikorea<\/strong><br \/>\nHeo Yunjeong (Geomungo, \u201cC\u00edtara negra\u00bb)<br \/>\nKim Jeong-Hi (Percusiones)<br \/>\nGang Gwon-Sun (Vocalista <em>Gukak<\/em>)<br \/>\nLee Ah-Ram (Daegeum, Flautas traveseras coreanas de bamb\u00fa)<br \/>\nKim Yong-Ha (Haegeum, Viol\u00edn tradicional coreano y Percusi\u00f3n)<br \/>\nLee Won-Sul (Contrabajo)<br \/>\nOh Jeong-Su (Guitarra El\u00e9ctrica)<br \/>\nShin Hyunpil (Saxos tenor y soprano)<br \/>\nShinDong-jin (Bater\u00eda)<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28160\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-768x511.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-83x55.jpg 83w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\">Comentario: <strong>Mosaikorea<\/strong> creado en el a\u00f1o 2014 actuaron en el festival Jazztopad de Polonia y en el festival de Jazz de Corea en Alemania y ahora lo hacen en Madrid siendo toda una sorpresa y un espect\u00e1culo fresco e in\u00e9dito que unos no supieron entender y que la mayor\u00eda disfrut\u00f3. Mosaikorea ofreci\u00f3 una combinaci\u00f3n de elementos propios del <em>Gukak<\/em> (m\u00fasica tradicional coreana) y el jazz vanguardista del S.XXI, vali\u00e9ndose de una instrumentaci\u00f3n divida en grupos de instrumentos, por un lado Lee Won-Sul (contrabajo), Oh Jeong-Su (guitarra el\u00e9trica), Shin Hyunpil (saxos tenor y soprano) y ShinDong-jin (bater\u00eda) representando el jazz y por el otro la m\u00fasica tradicional coreana con Heo Yunjeong (<em>geomungo<\/em>, \u201cC\u00edtara negra\u00bb), Kim Jeong-Hi (percusiones), Gang Gwon-Sun (vocalista <em>Gukak<\/em>), Lee Ah-Ram (<em>daegeum<\/em>, flautas traveseras coreanas de bamb\u00fa) y Kim Yong-Ha (<em>haegeum<\/em>, viol\u00edn tradicional coreano y Percusi\u00f3n).<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28172\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/02-Gang-Gwon-Sun-432x600.jpg\" alt=\"\" width=\"432\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/02-Gang-Gwon-Sun-432x600.jpg 432w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/02-Gang-Gwon-Sun-200x278.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/02-Gang-Gwon-Sun-40x55.jpg 40w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/02-Gang-Gwon-Sun.jpg 738w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28161\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong-600x479.jpg\" alt=\"\" width=\"600\" height=\"479\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong-600x479.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong-200x160.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong-768x613.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong-69x55.jpg 69w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/01-Heo-Yunjeong.jpg 1000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\">El noneto se estructura bas\u00e1ndose en diversas divisiones de grupos ya sean a tr\u00edo, d\u00fao o solo sin acompa\u00f1amiento como si de la mu\u00f1ecas rusas <em>matrioskas<\/em> se tratara, como una representaci\u00f3n de sonidos cu\u00e1nticos que se multiplican en infinitas posibilidades y cuyos instrumentistas aportan su sabidur\u00eda y espiritualidad a trav\u00e9s de su virtuosismo.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28162\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/03-Kim-Jeong-Hi-600x441.jpg\" alt=\"\" width=\"600\" height=\"441\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/03-Kim-Jeong-Hi-600x441.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/03-Kim-Jeong-Hi-200x147.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/03-Kim-Jeong-Hi-75x55.jpg 75w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/03-Kim-Jeong-Hi.jpg 735w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28163\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil-530x600.jpg\" alt=\"\" width=\"530\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil-530x600.jpg 530w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil-200x227.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil-768x870.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil-49x55.jpg 49w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/04-Oh-Jeong-Su-Shin-Hyunpil.jpg 883w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">Mosaikorea se mueve en aguas ecl\u00e9cticas donde tiene cabida el jazz y el <em>rock<\/em> progresivo y por supuesto el <em>Gukak<\/em> y lo demuestran con solidez gran\u00edtica donde cada miembro es importante tanto individual como colectivamente.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28164\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/05-Lee-Ah-Ram-414x600.jpg\" alt=\"\" width=\"414\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/05-Lee-Ah-Ram-414x600.jpg 414w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/05-Lee-Ah-Ram-200x290.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/05-Lee-Ah-Ram-38x55.jpg 38w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/05-Lee-Ah-Ram.jpg 690w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\" \/><\/p>\n<p style=\"text-align: justify;\">Brillantes pasajes a tr\u00edo con Oh Jeong-Su, Lee Won-Sul y ShinDong-jin con un solo de guitarra el\u00e9ctrica del primero muy en la l\u00ednea del noruego Terje Rypdal en un ejercicio de jazz progresivo superlativo al que termin\u00f3 uni\u00e9ndose de manera suave Lee Ah-Ram a la flauta travesera de bamb\u00fa para ir r\u00e1pidamente subiendo en intensidad hasta alcanzar un punto delirante y fogoso hasta la extenuaci\u00f3n con el resto del grupo.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28165\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/06-Lee-Won-Sul-337x600.jpg\" alt=\"\" width=\"337\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/06-Lee-Won-Sul-337x600.jpg 337w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/06-Lee-Won-Sul-168x300.jpg 168w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/06-Lee-Won-Sul-31x55.jpg 31w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/06-Lee-Won-Sul.jpg 561w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/p>\n<p style=\"text-align: justify;\">No menos impactante la vocalista Gang Gwon-Sun tan pasional y potente como espiritual que pareci\u00f3 exhalar el alma por la voz o el bell\u00edsimo solo sin acompa\u00f1amiento de Heo Yunjeong a la \u201cC\u00edtara negra\u00bb (<em>geomungo<\/em>), Shin Hyunpil a los saxos son\u00f3 moderno y <em>cool<\/em> o Kim Yong-Ha al <em>haegeum<\/em> (viol\u00edn tradicional coreano) y no digamos ya, el esplendoroso e improvisado solo de la \u201cfr\u00e1gil\u201d baterista ShinDong-jin que son\u00f3 de maravilla o los d\u00faos de los mencionados Kim Yong-Ha y Heo Yunjeong por destacar algo entre tanto.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28166\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin-516x600.jpg\" alt=\"\" width=\"516\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin-516x600.jpg 516w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin-200x233.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin-768x893.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin-47x55.jpg 47w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/07-ShinDong-jin.jpg 860w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/p>\n<p style=\"text-align: justify;\">En definitiva m\u00fasica espont\u00e1nea y emotiva que parte de ritmos lentos y apacibles cercanos a la meditaci\u00f3n y la espiritualidad asi\u00e1tica para alcanzar el cenit de la pasi\u00f3n fogosa y delirante apoyado en percusiones hipn\u00f3ticas de trance.<\/p>\n<p style=\"text-align: justify;\">Con un bis se despidieron entre aclamaciones y no hubo para m\u00e1s. Pareci\u00f3 poco pero muy gozoso e inolvidable.<\/p>\n<p style=\"text-align: right;\">Fotograf\u00edas y Texto: \u00a9, Enrique Farelo 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Melod\u00eda Dispersa-II Edici\u00f3n de la Navide\u00f1a: Feria Internacional de las Culturas (15-23 dic.) Fecha: 17 de diciembre de 2016 Lugar: Matadero, Madrid Grupo: Mosaikorea Heo Yunjeong (Geomungo, \u201cC\u00edtara negra\u00bb) Kim Jeong-Hi (Percusiones) Gang Gwon-Sun (Vocalista Gukak) Lee Ah-Ram (Daegeum, Flautas traveseras coreanas de bamb\u00fa) Kim Yong-Ha (Haegeum, Viol\u00edn tradicional coreano<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/mosaikorea-matadero-madrid-2016-12-17-concierto\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":28160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17848,4,15517,1038],"tags":[12836,15314,18255,18253,13,15312,12415,15295,15313,18254,18257,15710,18256,18258,18167,18259,18260,18261,16099,77,16100],"class_list":["entry","author-pachi","post-28159","post","type-post","status-publish","format-standard","has-post-thumbnail","category-enrique-farelo","category-conciertos","category-textos","category-contenidos","tag-concierto","tag-concierto-de-jazz","tag-gang-gwon-sun","tag-heo-yunjeong","tag-jazz","tag-jazz-en-directo","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jazz-en-vivo","tag-kim-jeong-hi","tag-kim-yong-ha","tag-la-actualidad-del-jazz-en-espana","tag-lee-ah-ram","tag-lee-won-sul","tag-matadero-madrid","tag-oh-jeong-su","tag-shin-hyunpil","tag-shindong-jin","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/Mosaikorea.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":100247,"url":"https:\/\/tomajazz.com\/web\/milena-casado-48-vitoria-2025\/","url_meta":{"origin":28159,"position":0},"title":"Milena Casado (48 Festival de Jazz de Vitoria. 2025-07-19) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"8 octubre, 2025","format":false,"excerpt":"Milena Casado actu\u00f3 en el 48 Festival de Jazz de Vitoria 2025. Jos\u00e9 Luis Luna Rocafort la retrata en INSTANTZZ. Actuaron Milena Casado, Morgan Guerin, Lex Korten, Kanoa Mendenhall, Jongkuk Kim","rel":"","context":"En \u00ab48 Festival de Jazz de Vitoria 2025\u00bb","block_context":{"text":"48 Festival de Jazz de Vitoria 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/48-festival-de-jazz-de-vitoria-2025\/"},"img":{"alt_text":"Milena Casado (48 Festival de Jazz de Vitoria. 2025-07-19) Por Jos\u00e9 Luis Luna Rocafort [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Milena Casado actu\u00f3 en el 48 Festival de Jazz de Vitoria 2025. Jos\u00e9 Luis Luna Rocafort la retrata en INSTANTZZ. Actuaron Milena Casado, Morgan Guerin, Lex Korten, Kanoa Mendenhall, Jongkuk Kim","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/015-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/015-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/015-3.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":28083,"url":"https:\/\/tomajazz.com\/web\/mosaikorea-en-concierto-madrid-15-y-17-de-diciembre-de-2016-noticias\/","url_meta":{"origin":28159,"position":1},"title":"Mosaikorea en concierto (Madrid. 15 y 17 de diciembre de 2016) [Noticias]","author":"Tomajazz","date":"13 diciembre, 2016","format":false,"excerpt":"Mosaikorea \"Melod\u00eda Dispersa\" en concierto.\u00a0II Edici\u00f3n de la Feria Internacional de las Culturas, Madrid Jueves 15 de diciembre. 19:00. Auditorio Casa del Reloj. Matadero (Paseo Chopera, 14) - Plaza de Legazpi, 8. S\u00e1bado 17 de diciembre. 21:00. Nave 1. Matadero (Paseo Chopera, 14) - Plaza de Legazpi, 8.","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/MosaiKOREA_Conciertos_2016-12.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/MosaiKOREA_Conciertos_2016-12.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/12\/MosaiKOREA_Conciertos_2016-12.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103064,"url":"https:\/\/tomajazz.com\/web\/noah-preminger-dark-days-2025\/","url_meta":{"origin":28159,"position":2},"title":"Noah Preminger: Dark Days (Criss Cross Jazz; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"29 diciembre, 2025","format":false,"excerpt":"Dark Days (Criss Cross Jazz; 2025) es lo nuevo de Noah Preminger. Carlos Lara repasa la grabaci\u00f3n. Con Noah Preminger, Ely Perlman, Kim Cass, Terreon Gully","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Noah Preminger: Dark Days (Criss Cross Jazz; 2025) Por Carlos Lara [Grabaci\u00f3n de jazz] - Tomajazz - Dark Days (Criss Cross Jazz; 2025) es lo nuevo de Noah Preminger. Carlos Lara repasa la grabaci\u00f3n. Con Noah Preminger, Ely Perlman, Kim Cass, Terreon Gully","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Noah-Preminger-Dark-Days-Criss-Cross-Jazz-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Noah-Preminger-Dark-Days-Criss-Cross-Jazz-2025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Noah-Preminger-Dark-Days-Criss-Cross-Jazz-2025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Noah-Preminger-Dark-Days-Criss-Cross-Jazz-2025.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":80131,"url":"https:\/\/tomajazz.com\/web\/groove-2023\/","url_meta":{"origin":28159,"position":3},"title":"Groove&#038; (5\u00ba FeminaJazz Festival 2023. Centro Cultural Carril del Conde, Madrid. 2023-10-27) Por Enrique Farelo [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"5 noviembre, 2023","format":false,"excerpt":"El grupo coreano Groove& actu\u00f3 en el 5\u00ba FeminaJazz Festival 2023 en Centro Cultural Carril del Conde de Madrid el 27 de octubre de 2023. Enrique Farelo retrata en INSTANTZZ su actuaci\u00f3n.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Groove& (5\u00ba FeminaJazz Festival 2023. Centro Cultural Carril del Conde, Madrid. 2023-10-27) Por Enrique Farelo [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0 - El grupo coreano Groove& actu\u00f3 en el 5\u00ba FeminaJazz Festival 2023 en Centro Cultural Carril del Conde de Madrid el 27 de octubre de 2023. Enrique Farelo retrata en INSTANTZZ su actuaci\u00f3n.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/Min-ju-Sohn-I-Groove-5o-FeminaJazz-Festival-2023-Centro-Cultural-Carril-del-Conde-Madrid-2023-10-27-Por-Enrique-Farelo-INSTANTZZ.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/Min-ju-Sohn-I-Groove-5o-FeminaJazz-Festival-2023-Centro-Cultural-Carril-del-Conde-Madrid-2023-10-27-Por-Enrique-Farelo-INSTANTZZ.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/Min-ju-Sohn-I-Groove-5o-FeminaJazz-Festival-2023-Centro-Cultural-Carril-del-Conde-Madrid-2023-10-27-Por-Enrique-Farelo-INSTANTZZ.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":102831,"url":"https:\/\/tomajazz.com\/web\/ivan-melon-lewis-babylon-jazz-club-sorteo-tomajazz-2025\/","url_meta":{"origin":28159,"position":4},"title":"Iv\u00e1n Melon Lewis \u00abLuces y Sombras\u00bb (Sorteo de entradas para el estreno de Babylon Jazz Club de Madrid, el 19 de diciembre de 2025) [Noticias de jazz]","author":"Tomajazz","date":"14 diciembre, 2025","format":false,"excerpt":"En Tomajazz sorteamos una entrada doble para el concierto de Iv\u00e1n Melon Lewis, que estrenar\u00e1 la nueva sala Babylon Jazz Club de Madrid, el 19 de diciembre de 2025 #Noticiasdejazz","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Iv\u00e1n Melon Lewis \"Luces y Sombras\" (Sorteo de entradas para el estreno de Babylon Jazz Club de Madrid, el 19 de diciembre de 2025) [Noticias de jazz] - Tomajazz - En Tomajazz sorteamos una entrada doble para el concierto de Iv\u00e1n Melon Lewis, que estrenar\u00e1 la nueva sala Babylon Jazz Club de Madrid, el  #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Ivan-Melon-Lewis-Babylon-Madrid.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Ivan-Melon-Lewis-Babylon-Madrid.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Ivan-Melon-Lewis-Babylon-Madrid.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Ivan-Melon-Lewis-Babylon-Madrid.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/Ivan-Melon-Lewis-Babylon-Madrid.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":102870,"url":"https:\/\/tomajazz.com\/web\/alejandro-reyes-1944-2025-in-memoriam\/","url_meta":{"origin":28159,"position":5},"title":"Alejandro Reyes (1944-2025) In Memoriam","author":"Tomajazz","date":"22 diciembre, 2025","format":false,"excerpt":"Alejandro Reyes, el gran dinamizador del Jazz y del Flamenco desde el m\u00edtico Johnny con ese a\u00f1orado Club de M\u00fasica y Jazz San Juan Evangelista de Madrid, fallec\u00eda el 17 de diciembre de 2025 en su Almer\u00eda natal. Desde Tomajazz le rendimos homenaje con una cita y una imagen de\u2026","rel":"","context":"En \u00ab*_Sergio Cabanillas\u00bb","block_context":{"text":"*_Sergio Cabanillas","link":"https:\/\/tomajazz.com\/web\/category\/sergio-cabanillas\/"},"img":{"alt_text":"Alejandro Reyes (1944-2025) In Memoriam - Tomajazz - Alejandro Reyes, el gran dinamizador del Jazz y del Flamenco desde el m\u00edtico Johnny con ese a\u00f1orado Club de M\u00fasica y Jazz San Juan Evangelista de Madrid, fallec\u00eda el 17 de diciembre de 2025 en su Almer\u00eda natal. Desde Tomajazz le rendimos homenaje con una cita y una imag","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/ALEJANDRO-REYES-7625-2025-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/ALEJANDRO-REYES-7625-2025-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/ALEJANDRO-REYES-7625-2025-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/12\/ALEJANDRO-REYES-7625-2025-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=28159"}],"version-history":[{"count":3,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28159\/revisions"}],"predecessor-version":[{"id":28173,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28159\/revisions\/28173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/28160"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=28159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=28159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=28159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}