{"id":28842,"date":"2017-01-19T20:34:27","date_gmt":"2017-01-19T19:34:27","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=28842"},"modified":"2021-07-18T14:19:20","modified_gmt":"2021-07-18T12:19:20","slug":"vivabebop-nuevo-programa-de-radio-de-jazz-madrid-enero-2017","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/vivabebop-nuevo-programa-de-radio-de-jazz-madrid-enero-2017\/","title":{"rendered":"VivaBeBop: nuevo programa de radio de jazz (Madrid. Enero 2017)"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28843\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio-600x181.jpg\" alt=\"\" width=\"600\" height=\"181\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio-600x181.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio-200x60.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio-768x232.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio-182x55.jpg 182w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio.jpg 1127w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: left;\">El viernes 20 de enero de 2017 arranca el programa de radio <em>VivaBeBop<\/em> dirigido por <strong>Pablo Sanz<\/strong>. El programa se emitir\u00e1 los viernes de 12:00 a 13:00 en\u00a0<strong>M21<\/strong> en el 88.6 FM de Madrid y se podr\u00e1 escuchar en <em>streaming<\/em> desde la web <a href=\"https:\/\/www.m21radio.es\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.m21radio.es\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 20 de enero de 2017 arranca el programa de radio VivaBeBop dirigido por Pablo Sanz. El programa se emitir\u00e1 los viernes de 12:00 a 13:00 en\u00a0M21 en el 88.6 FM de Madrid y se podr\u00e1 escuchar en streaming desde la web https:\/\/www.m21radio.es\/<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/vivabebop-nuevo-programa-de-radio-de-jazz-madrid-enero-2017\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":28843,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,15795,1038],"tags":[15299,13,12415,15295,18722,15297,18724,15710,18672,11856,15296,15298,7196,18721,18723,16099,77,16100,18673],"class_list":["entry","author-pachi","post-28842","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-noticias-2","category-contenidos","tag-espana-en-jazz","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jazz-en-la-radio","tag-jazz-news","tag-jazz-radio","tag-la-actualidad-del-jazz-en-espana","tag-m21-madrid","tag-noticias","tag-noticias-de-jazz","tag-noticias-de-jazz-en-espana","tag-pablo-sanz","tag-programas-de-radio-de-jazz","tag-radio-jazz","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-vivabebop"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/m21radio.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":103919,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p16-2025-26\/","url_meta":{"origin":28842,"position":0},"title":"Universos Paralelos: primer programa de 2026 (UP.T.31 P.16) [Noticias de jazz]","author":"Tomajazz","date":"8 febrero, 2026","format":false,"excerpt":"El programa de radio Universos Paralelos retoma su actividad en 2026 tras el par\u00f3n de enero. El en programa del 5 de febrero de 2026 suena m\u00fasica de Sumrr\u00e1, Fieldworks, Ra\u00fan Mannola & Juan Carlos Aracil y otros... #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: primer programa de 2026 (UP.T.31 P.16) [Noticias de jazz] - Tomajazz - El programa de radio Universos Paralelos retoma su actividad en 2026 tras el par\u00f3n de enero. El en programa del 5 de febrero de 2026 suena m\u00fasica de Sumrr\u00e1, Fieldworks, Ra\u00fan Mannola & Juan Carlos Aracil y otros... #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-Sumrra-Revoluti8n-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-Sumrra-Revoluti8n-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-Sumrra-Revoluti8n-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-Sumrra-Revoluti8n-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103194,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p14-p15-2025-26\/","url_meta":{"origin":28842,"position":1},"title":"Universos Paralelos: final de a\u00f1o 2025 (UP.T.31 P.14 y 15) [Noticias de jazz]","author":"Tomajazz","date":"7 enero, 2026","format":false,"excerpt":"Universos Paralelos junto con su presentador, Sergio Cabanillas, se toma un descanso en enero de 2026. El programa finaliz\u00f3 diciembre de 2026 con sendos programas, incluyendo un programa extra el d\u00eda de Navidad #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: final de a\u00f1o 2025 (UP.T.31 P.14 y 15) [Noticias de jazz] - Tomajazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/00-destacada-Jorge-Cabadas-Algunas-Piezas-Inauditas-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/00-destacada-Jorge-Cabadas-Algunas-Piezas-Inauditas-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/00-destacada-Jorge-Cabadas-Algunas-Piezas-Inauditas-1080.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":105261,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-up-t31-p28-2025-26\/","url_meta":{"origin":28842,"position":2},"title":"Universos Paralelos: emisi\u00f3n 7 de mayo de 2026 (UP.T.31 P.28) [Noticias de jazz]","author":"Tomajazz","date":"7 mayo, 2026","format":false,"excerpt":"En los Universos Paralelos de Sergio Cabanillas, el 7 de mayo de 2026, Nexus de Jordi Farr\u00e9s es el disco de portada #Noticiasde jazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 7 de mayo de 2026 (UP.T.31 P.28) [Noticias de jazz] - Tomajazz - En los Universos Paralelos de Sergio Cabanillas, el 7 de mayo de 2026, Nexus de Jordi Farr\u00e9s es el disco de portada #Noticiasde jazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":103475,"url":"https:\/\/tomajazz.com\/web\/txeih-jazz-factory-gira-girando-por-salas-gps16-2026\/","url_meta":{"origin":28842,"position":3},"title":"Txeih Jazz Factory inicia su gira de seis conciertos con Girando Por Salas #GPS16 (enero \u2013 abril 2026) [Noticias de jazz]","author":"Tomajazz","date":"16 enero, 2026","format":false,"excerpt":"Entre enero y abril de 2026, el quinteto navarro Txeih Jazz Factory realizar\u00e1 una gira de seis conciertos dentro del programa Girando Por Salas #GPS16 #Noticiasdejazz","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Txeih Jazz Factory inicia su gira de seis conciertos con Girando Por Salas #GPS16 (enero \u2013 abril 2026) [Noticias de jazz] - Tomajazz - Entre enero y abril de 2026, el quinteto navarro Txeih Jazz Factory realizar\u00e1 una gira de seis conciertos dentro del programa Girando Por Salas #GPS16 #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Txeih-Jazz-Factory-Gira-GPS16.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Txeih-Jazz-Factory-Gira-GPS16.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Txeih-Jazz-Factory-Gira-GPS16.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Txeih-Jazz-Factory-Gira-GPS16.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101457,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p08-2025-26\/","url_meta":{"origin":28842,"position":4},"title":"Universos Paralelos: emisi\u00f3n 6 de noviembre de 2025 (UP.T.31 P.08) [Noticias de jazz]","author":"Tomajazz","date":"6 noviembre, 2025","format":false,"excerpt":"En la edici\u00f3n del 6 de noviembre de 2025 de Universos Paralelos, Sergio Cabanillas elige el nuevo disco de Max Villavecchia como disco de portada, pero no es lo \u00fanico... #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 6 de noviembre de 2025 (UP.T.31 P.08) [Noticias de jazz] - Tomajazz - En la edici\u00f3n del 6 de noviembre de 2025 de Universos Paralelos, Sergio Cabanillas elige el nuevo disco de Max Villavecchia como disco de portada, pero no es lo \u00fanico... #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100946,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p06-2025-26\/","url_meta":{"origin":28842,"position":5},"title":"Universos Paralelos: emisi\u00f3n 23 de octubre de 2025 (UP.T.31 P.06) [Noticias de jazz]","author":"Tomajazz","date":"25 octubre, 2025","format":false,"excerpt":"Lo nuevo de Xose Migu\u00e9lez es la portada de Universos Paralelos del 23 de octubre de 2025. Pero no es la \u00fanica m\u00fasica elegida por Sergio Cabanillas... #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 23 de octubre de 2025 (UP.T.31 P.06) [Noticias de jazz] - Tomajazz - Lo nuevo de Xose Migu\u00e9lez es la portada de Universos Paralelos del 23 de octubre de 2025. Pero no es la \u00fanica m\u00fasica elegida por Sergio Cabanillas... #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-02-Xose-Miguelez-Live-Colon-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-02-Xose-Miguelez-Live-Colon-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-02-Xose-Miguelez-Live-Colon-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-02-Xose-Miguelez-Live-Colon-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=28842"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28842\/revisions"}],"predecessor-version":[{"id":55708,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/28842\/revisions\/55708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/28843"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=28842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=28842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=28842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}