{"id":3152,"date":"2008-10-12T10:13:00","date_gmt":"2008-10-12T08:13:00","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=3152"},"modified":"2016-04-10T23:07:02","modified_gmt":"2016-04-10T21:07:02","slug":"clepton","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/clepton\/","title":{"rendered":"Clepton"},"content":{"rendered":"<p><a href=\"http:\/\/www.tomajazz.com\/bun\/uploaded_images\/Howard-Clepton-793724.jpg\"><img decoding=\"async\" src=\"http:\/\/www.tomajazz.com\/bun\/uploaded_images\/Howard-Clepton-793719.jpg\" alt=\"\" border=\"1\" title=\"\"><\/a><\/p>\n<div>Tres piezas componen <span>Clepton <\/span>de Earl Howard. La que le da t\u00edtulo es el estreno en directo de un encargo del veterano festival alem\u00e1n de m\u00fasica contempor\u00e1nea Donaueschinger Musikatge, que inici\u00f3 su andadura all\u00e1 en un lejano 1921. Dividida en diez secciones, esta obra de Howard para piano, chelo, bater\u00eda, sintetizador y tratamiento sonoro en directo, se basa tanto en la composici\u00f3n como en la improvisaci\u00f3n. A Howard le acompa\u00f1a una formaci\u00f3n de lujo: el tr\u00edo compuesto por George Graewe, Ernst Reijsiger y especialmente Gerry Hemingway. \u00c9ste \u00faltimo, adem\u00e1s de ser un viejo compa\u00f1ero de Howard, tiene un brillante historial como acompa\u00f1ante de Anthony Braxton. Un m\u00fasico con un universo propio que muestra elementos coincidentes con el de Howard. El CD incluye una corta improvisaci\u00f3n basada en esta composici\u00f3n y un d\u00fao con Hemingway de 1989.\n<\/div>\n<p>\u00bfJazz o no jazz? M\u00fasica fascinante y que derriba barreras en cualquier caso.<\/p>\n<p>Pachi Tapiz<\/p>\n<p>Earl Howard <span>Clepton<\/span><br \/>Earl Howard (sintetizador, procesamiento de sonido), George Graewe (piano), Ernst Reijsiger (violonchelo), Gerry Hemingway (bater\u00eda)<br \/>Grabado en 2006 y 1989.<br \/>New World Records 80670-2<br \/>**** sobre *****<\/p>\n<p>Rese\u00f1a publicada en Cuadernos de Jazz n\u00ba 106, Mayo \/ Junio 2008<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres piezas componen Clepton de Earl Howard. La que le da t\u00edtulo es el estreno en directo de un encargo del veterano festival alem\u00e1n de m\u00fasica contempor\u00e1nea Donaueschinger Musikatge, que inici\u00f3 su andadura all\u00e1 en un lejano 1921. Dividida en diez secciones, esta obra de Howard para piano, chelo, bater\u00eda,<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/clepton\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[12651,12696,13,12415,15295,77],"class_list":["entry","author-pachi","post-3152","post","type-post","status-publish","format-standard","category-grabaciones","tag-cd","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-tomajazz"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1901,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-lovers-schizophrenic-blues-noah-howard-quartet-1997\/","url_meta":{"origin":3152,"position":0},"title":"Tomajazz recomienda\u2026 un tema: \u201cLovers \/ Schizophrenic Blues\u201d (Noah Howard Quartet, 1997)","author":"Adolphus van Tenzing","date":"20 septiembre, 2010","format":false,"excerpt":"En el a\u00f1o 2000 el sueco Jan Str\u00f6m pon\u00eda en marcha, tras pedir los correspondientes permisos a sus herederos para utilizar el nombre, Ayler Records. Teniendo en su t\u00edtulo toda una declaraci\u00f3n de intenciones musicales, su primera referencia era Live At The Unity Temple del cuarteto del saxofonista Noah Howard.\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"Noah Howard Quartet. Live At The Unity Temple. Ayler Records","src":"https:\/\/i0.wp.com\/torec.tomajazz.com\/wp-content\/uploads\/2010\/09\/aylcd-001.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2015,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-tema-o-raggedy-man-por-howard-johnson\/","url_meta":{"origin":3152,"position":1},"title":"Tomajazz recomienda&#8230; un tema: \u00abO Raggedy Man\u00bb (Howard Johnson, 1998)","author":"Adolphus van Tenzing","date":"15 agosto, 2011","format":false,"excerpt":"Una de las virtudes de la m\u00fasica de jazz es que no hay convenci\u00f3n que valga. Por mucho que abunden los quintetos de saxo-trompeta-piano-bajo-bater\u00eda, no hay regla que proh\u00edba nada. Por este motivo, no debe sorprender que un int\u00e9rprete de tuba como Howard Johnson haya podido tener una carrera con\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ecx.images-amazon.com\/images\/I\/51qEm7W3oTL._SL500_AA300_.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2008,"url":"https:\/\/tomajazz.com\/web\/tomajazz-recomienda-un-cd-till-we-have-faces-gary-thomas-1992\/","url_meta":{"origin":3152,"position":2},"title":"Tomajazz Recomienda&#8230; un cd: Till We Have Faces (Gary Thomas, 1992)","author":"Adolphus van Tenzing","date":"6 julio, 2011","format":false,"excerpt":"Infravalorado miembro del colectivo M-Base, el saxofonista Gary Thomas nos presenta un personal acercamiento a cl\u00e1sicos standards de jazz en este CD de 1992. Le acompa\u00f1an el pianista Tim Murphy, los bajistas Anthony Cox y Ed Howard, la baterista Terri Lyne Carrington, el percusionista Steve Moss y un desconocido Pat\u2026","rel":"","context":"En \u00ab*_Adolphus van Tenzing\u00bb","block_context":{"text":"*_Adolphus van Tenzing","link":"https:\/\/tomajazz.com\/web\/category\/adolphus-van-tenzing\/"},"img":{"alt_text":"Till We Have Faces. Gary Thomas","src":"https:\/\/i0.wp.com\/torec.tomajazz.com\/wp-content\/uploads\/2011\/06\/gary_thomas.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":82338,"url":"https:\/\/tomajazz.com\/web\/sylvia-howard-toni-sola-quintet-2023\/","url_meta":{"origin":3152,"position":3},"title":"Sylvia Howard &#038; Toni Sol\u00e0 Quintet (XXX Jazz Tardor 2023. Festival de Jazz de Lleida. Caf\u00e8 del Teatre, Lleida. 2023-11-17) Por Joan Abella [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"6 enero, 2024","format":false,"excerpt":"Sylvia Howard & Toni Sol\u00e0 Quintet actuaron en el XXX Jazz Tardor. Festival de Jazz de Lleida, el 17 de noviembre de 2023, en el Caf\u00e8 del Teatre. Joan Abella se estrena en 2024 en Tomajazz retratando el concierto en INSTANTZZ. Actuaron Sylvia Howard, Toni Sol\u00e0, Gerard Nieto, Garry Fimister,\u2026","rel":"","context":"En \u00abXXX JazzTardor 2023. Festival de Jazz de Lleida\u00bb","block_context":{"text":"XXX JazzTardor 2023. Festival de Jazz de Lleida","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/xxx-jazztardor-2023-festival-de-jazz-de-lleida\/"},"img":{"alt_text":"Sylvia Howard & Toni Sol\u00e0 Quintet  (XXX Jazz Tardor 2023. Festival de Jazz de Lleida. Caf\u00e8 del Teatre, Lleida. 2023-11-17) Por Joan Abella [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Sylvia Howard & Toni Sol\u00e0 Quintet actuaron en el XXX Jazz Tardor. Festival de Jazz de Lleida, el 17 de noviembre de 2023, en el Caf\u00e8 del Teatre. Joan Abella se estrena en 2024 en Tomajazz retratando el concierto en INSTANTZZ. Actuaron Sylvia Howard, Toni Sol\u00e0, Gerard Nieto, Garry Fimister, Xavi Hinojosa","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/4-Sylvia-Howard-Toni-Sola-Quintet-XXX-Jazz-Tardor-2023-Festival-de-Jazz-de-Lleida-2023-11-17-Por-Joan-Abella-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/4-Sylvia-Howard-Toni-Sola-Quintet-XXX-Jazz-Tardor-2023-Festival-de-Jazz-de-Lleida-2023-11-17-Por-Joan-Abella-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/4-Sylvia-Howard-Toni-Sola-Quintet-XXX-Jazz-Tardor-2023-Festival-de-Jazz-de-Lleida-2023-11-17-Por-Joan-Abella-INSTANTZZ-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/4-Sylvia-Howard-Toni-Sola-Quintet-XXX-Jazz-Tardor-2023-Festival-de-Jazz-de-Lleida-2023-11-17-Por-Joan-Abella-INSTANTZZ-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":43460,"url":"https:\/\/tomajazz.com\/web\/fats-navarro-howard-mcghee-la-odisea-de-la-musica-afroamericana-192-podcast\/","url_meta":{"origin":3152,"position":4},"title":"Fats Navarro &#8211; Howard McGhee. La Odisea de la M\u00fasica Afroamericana (192) [Podcast]","author":"Tomajazz","date":"20 mayo, 2019","format":false,"excerpt":"Por Luis Escalante Ozalla. La Odisea de la M\u00fasica Afroamericana es un programa de radio dirigido, presentado y producido por Luis Escalante Ozalla, autor de los libros Nueva Orleans (1717-1917): Sexo, Raza y Jass y Y se hace m\u00fasica al andar con swing. En el cap\u00edtulo 192 de La Odisea\u2026","rel":"","context":"En \u00ab*_Luis Escalante Ozalla\u00bb","block_context":{"text":"*_Luis Escalante Ozalla","link":"https:\/\/tomajazz.com\/web\/category\/luis-escalante-ozalla\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/The-Fabulous-Fats-Navarro.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":60537,"url":"https:\/\/tomajazz.com\/web\/tomajazz-remembers-9-george-howard-love-will-conquer-all-minipodcast-de-jazz-por-juan-f-trillo\/","url_meta":{"origin":3152,"position":5},"title":"Tomajazz Remembers #9. George Howard: \u201cLove Will Conquer All\u201d [Minipodcast de jazz] Por Juan F. Trillo","author":"Tomajazz","date":"24 enero, 2022","format":false,"excerpt":"En Tomajazz Remembers suena el tema \"Love Will Conquer All\" de George Howard. Tomajazz Remembers es una secci\u00f3n semanal de Juan F. Trillo.","rel":"","context":"En \u00abTomajazz Remembers (Podcast de jazz)\u00bb","block_context":{"text":"Tomajazz Remembers (Podcast de jazz)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/a_time_to_remember\/"},"img":{"alt_text":"Tomajazz Remembers #9. George Howard: \u201cLove Will Conquer All\u201d [Minipodcast de jazz] Por Juan F. Trillo","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_009.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_009.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_009.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_009.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"predecessor-version":[{"id":23199,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/3152\/revisions\/23199"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}