{"id":31696,"date":"2017-07-29T11:00:31","date_gmt":"2017-07-29T09:00:31","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=31696"},"modified":"2022-01-20T23:25:47","modified_gmt":"2022-01-20T22:25:47","slug":"hdo-295-una-hora-con-frank-wess-podcast","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/hdo-295-una-hora-con-frank-wess-podcast\/","title":{"rendered":"HDO 295. Una hora con\u2026 Frank Wess [Podcast]"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31697 size-medium\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Steamin_Prestige_1963-200x204.jpg\" alt=\"\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Steamin_Prestige_1963-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Steamin_Prestige_1963-54x55.jpg 54w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Steamin_Prestige_1963-50x50.jpg 50w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31698 size-medium\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Jazz-For-Playboys_1956-200x196.jpg\" alt=\"\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Jazz-For-Playboys_1956-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Jazz-For-Playboys_1956-56x55.jpg 56w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Jazz-For-Playboys_1956-50x50.jpg 50w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p style=\"text-align: left;\"><strong>Frank Wess\u00a0<\/strong>(1922 &#8211; 2013) es un flautista y saxofonista bien conocido por su pertenencia durante m\u00e1s de una d\u00e9cada a la orquesta de\u00a0<strong>Count Basie<\/strong>, con una larga carrera como\u00a0<em>sideman\u00a0<\/em>y acompa\u00f1ante de otros artistas. En\u00a0<strong>HDO 295<\/strong> dedicamos una nueva entrega de\u00a0<em>Una hora con&#8230;\u00a0<\/em>a sus grabaciones de mediados de los a\u00f1os 50\u00a0<em>Jazz For Playboys\u00a0<\/em>y\u00a0<em>Steamin&#8217;<\/em>, en las que le acompa\u00f1an m\u00fasicos de las categor\u00eda de\u00a0<strong>Paul Chambers, Mal Waldron, Kenny Burrell, Thad Jones\u00a0<\/strong>o\u00a0<strong>Art Taylor<\/strong>.<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 Pachi Tapiz, 2017<\/p>\n<p>HDO es un podcast editado, presentado y producido por Pachi Tapiz.<\/p>\n<p><iframe id=\"audio_20018581\" style=\"border: 1px solid #EEE; box-sizing: border-box; width: 100%;\" src=\"https:\/\/www.ivoox.com\/player_ej_20018581_4_1.html?c1=ff6600\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frank Wess\u00a0(1922 &#8211; 2013) es un flautista y saxofonista bien conocido por su pertenencia durante m\u00e1s de una d\u00e9cada a la orquesta de\u00a0Count Basie, con una larga carrera como\u00a0sideman\u00a0y acompa\u00f1ante de otros artistas. En\u00a0HDO 295 dedicamos una nueva entrega de\u00a0Una hora con&#8230;\u00a0a sus grabaciones de mediados de los a\u00f1os 50\u00a0Jazz<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/hdo-295-una-hora-con-frank-wess-podcast\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":31697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,13298,12814,15518,1038,19730],"tags":[5567,13370,7507,13300,13299,15712,15713,15714,13,12415,15295,15278,960,7037,15710,2326,31,2083,12818,15310,15709,15711,8635,16099,77,16100,19735],"class_list":["entry","author-pachi","post-31696","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-hablando-de-oidas-hdo","category-podcast","category-sonidos","category-contenidos","category-una-hora-con","tag-art-taylor","tag-audioblog","tag-frank-wess","tag-hablando-de-oidas","tag-hdo","tag-hdo-el-podcast-de-jazz-de-pachi-tapiz","tag-hdo-el-podcast-de-pachi-tapiz","tag-hdo-hablando-de-oidas","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jazz-podcast","tag-jose-francisco-tapiz","tag-kenny-burrell","tag-la-actualidad-del-jazz-en-espana","tag-waldron-mal","tag-pachi-tapiz","tag-paul-chambers","tag-podcast","tag-podcast-de-jazz","tag-podcast-de-jazz-en-espana","tag-podcast-de-jazz-en-espanol","tag-thad-jones","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-una-hora-con"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/Frank-Wess_Steamin_Prestige_1963.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":30529,"url":"https:\/\/tomajazz.com\/web\/hdo-270-en-concierto-con-charlie-watts-phronesis-catalano-chamberlin-podcast\/","url_meta":{"origin":31696,"position":0},"title":"HDO 270. En concierto con\u2026 Charlie Watts, Phronesis, Catalano &#8211; Chamberlin [Podcast]","author":"Tomajazz","date":"11 mayo, 2017","format":false,"excerpt":"Repaso a tres grabaciones en HDO 270:\u00a0Charlie Watts meets The Danish Radio Big Band\u00a0(Impulse!, 2017),\u00a0The Behemoth (Phronesis, Julian Arg\u00fcelles, Frankfurt Radio Big Band; Edition Records, 2017),\u00a0Tokyo Number 9\u00a0(Frank Catalano - Jimmy Chamberlin; RopeADope, 2017).","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/Charlie-Watts-meets-The-Danish-Radio-Big-Band-e1494450079990.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/Charlie-Watts-meets-The-Danish-Radio-Big-Band-e1494450079990.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/Charlie-Watts-meets-The-Danish-Radio-Big-Band-e1494450079990.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":29916,"url":"https:\/\/tomajazz.com\/web\/hdo-253-perico-sambeat-sus-palabras-y-su-revision-de-la-musica-de-frank-zappa-entrevista-por-pachi-tapiz-podcast\/","url_meta":{"origin":31696,"position":1},"title":"HDO 253. Perico Sambeat: sus palabras y su revisi\u00f3n de la m\u00fasica de Frank Zappa. Entrevista por Pachi Tapiz [Podcast]","author":"Tomajazz","date":"28 marzo, 2017","format":false,"excerpt":"En el final del a\u00f1o 2016, el saxofonista\u00a0Perico Sambeat publicaba en Karonte el CD\u00a0Perico Sambeat Ensemble Plays Zappa. Esta es la grabaci\u00f3n de un proyecto nacido como iniciativa del Jimmy Glass Jazz Bar (incansable local con una sobresaliente programaci\u00f3n de jazz en directo en Valencia).\u00a0Sambeat\u00a0charl\u00f3 con\u00a0Pachi Tapiz sobre esta grabaci\u00f3n,\u2026","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/03\/01_Prc-Snbt-nsmbl-Plys-Zpp-%C2%A9Joan-Cort%C3%A8s_04feb17_Jmbr_Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/03\/01_Prc-Snbt-nsmbl-Plys-Zpp-%C2%A9Joan-Cort%C3%A8s_04feb17_Jmbr_Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/03\/01_Prc-Snbt-nsmbl-Plys-Zpp-%C2%A9Joan-Cort%C3%A8s_04feb17_Jmbr_Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":59944,"url":"https:\/\/tomajazz.com\/web\/jazzx5-centennial-384-frank-wess-all-too-soon-magic-101-ipo-recordings-2013-minipodcast-de-jazz-por-pachi-tapiz-jazzx5-centennial-001\/","url_meta":{"origin":31696,"position":2},"title":"JazzX5 Centennial #384: Frank Wess. \u00abAll Too Soon\u00bb [Magic 101 (IPO Recordings, 2013)] [Minipodcast de jazz] Por Pachi Tapiz [JazzX5 Centennial 001]","author":"Tomajazz","date":"4 enero, 2022","format":false,"excerpt":"En 2022 se cumple el centenario del nacimiento de Frank Wess. En JazzX5 el tema \"All Too Soon\" que se publicaba en Magic 101 (IPO Recordings, 2013). JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"JazzX5 Centennial #384: Frank Wess. \"All Too Soon\" [Magic 101 (IPO Recordings, 2013)] [Minipodcast de jazz] Por Pachi Tapiz [JazzX5 Centennial 001]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/JazzX5_384.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/JazzX5_384.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/JazzX5_384.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/JazzX5_384.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19074,"url":"https:\/\/tomajazz.com\/web\/hdo-presentacion-con-the-rempis-percussion-quartet-entrega-0001-podcast\/","url_meta":{"origin":31696,"position":3},"title":"The Rempis Percussion Quartet. HDO: presentaci\u00f3n (entrega 0001) [Podcast]","author":"Tomajazz","date":"16 julio, 2015","format":"audio","excerpt":"Primera entrega de HDO. A lo largo casi una hora, hay espacio para dos bloques bien diferenciados. En primer lugar la presentaci\u00f3n de este nuevo audioblog: qu\u00e9, d\u00f3nde, cu\u00e1ndo, por qu\u00e9, qui\u00e9n y c\u00f3mo (no necesariamente en este orden) surge esta nueva propuesta. Preguntas, envidias, tristezas, hartazgos, comparaciones, compromisos (\u00e9ticos\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/The-Rempis-Percussion-Quartet_Cash-And-Carry_big.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/The-Rempis-Percussion-Quartet_Cash-And-Carry_big.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/The-Rempis-Percussion-Quartet_Cash-And-Carry_big.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/The-Rempis-Percussion-Quartet_Cash-And-Carry_big.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29320,"url":"https:\/\/tomajazz.com\/web\/hdo-238-leo-records-las-dimensiones-de-la-improvisacion-con-loz-speyer-gratkowski-nabatov-ensemble-5-stuart-popejoy-podcast\/","url_meta":{"origin":31696,"position":4},"title":"HDO 238. Leo Records: las dimensiones de la improvisaci\u00f3n con Loz Speyer, Gratkowski &#8211; Nabatov, Ensemble 5, Stuart Popejoy [Podcast]","author":"Tomajazz","date":"15 febrero, 2017","format":false,"excerpt":"En HDO 238 (15 de febrero de 2017), catamos las cuatro \u00faltimas novedades del cat\u00e1logo de\u00a0Leo Records, en las que aparecen distintas visiones de la improvisaci\u00f3n, a saber, las de\u00a0Loz Speyer's Inner Space en Life On the Edge\u00a0(Chris Biscoe, Rachel Musson, Olie Brice, Gary Willcox, Loz Speyer);\u00a0Ensemble 5 en Live\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/02\/Loz-Speyers-Inner-Space_Life-On-the-Edge_Leo-Records_2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":31676,"url":"https:\/\/tomajazz.com\/web\/hdo-292-una-hora-con-george-russell-podcast\/","url_meta":{"origin":31696,"position":5},"title":"HDO 292. Una hora con&#8230; George Russell [Podcast]","author":"Tomajazz","date":"26 julio, 2017","format":false,"excerpt":"Una hora con\u00a0George Russell en la entrega 292 de\u00a0HDO. Un m\u00fasico con una carrera que va bastante m\u00e1s all\u00e1 del desarrollo del concepto lidio crom\u00e1tico, con unas cuantas grabaciones m\u00e1s que recomendables. En concreto, en esta entrega de HDO escuchamos\u00a0las grabaciones\u00a0New York, N.Y.\u00a0(Decca, 1959), y la obra maestra\u00a0Jazz In The\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/07\/George-Russell_Jazz_in_the_Space_Age_Decca_1960.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=31696"}],"version-history":[{"count":3,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31696\/revisions"}],"predecessor-version":[{"id":60446,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31696\/revisions\/60446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/31697"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=31696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=31696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=31696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}