{"id":31804,"date":"2017-08-17T11:00:58","date_gmt":"2017-08-17T09:00:58","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=31804"},"modified":"2017-08-15T22:23:28","modified_gmt":"2017-08-15T20:23:28","slug":"tajmo-the-taj-mahal-keb-mo-band-xx-festival-internacional-de-jazz-san-javier-2017-07-14-conciertos","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tajmo-the-taj-mahal-keb-mo-band-xx-festival-internacional-de-jazz-san-javier-2017-07-14-conciertos\/","title":{"rendered":"Tajmo\u2019: The Taj Mahal &#038; Keb\u2019 Mo\u2019 Band (XX Festival Internacional de Jazz San Javier. 2017-07-14) [Conciertos]"},"content":{"rendered":"<p>XX Festival Internacional de Jazz San Javier<\/p>\n<ul>\n<li>Fecha: 14 de julio de 2017<\/li>\n<li>Lugar: Auditorio Parque Almansa (San Javier, Murcia)<\/li>\n<li>Grupo:<br \/>\n<strong>Tajmo\u2019: The Taj Mahal &amp; Keb\u2019 Mo\u2019 Band<\/strong><br \/>\nTaj Mahal: voz y guitarras.<br \/>\nKeb\u2019 Mo\u2019: voz y guitarras.<br \/>\nDana Robbins: saxo.<br \/>\nQuentin Ware: trompeta.<br \/>\nDavid Rodgers: teclados.<br \/>\nStan Sergeant: bajo.<br \/>\nMarcus Finnie: bater\u00eda.<br \/>\nDeva Mahal: coros.<br \/>\nZoe Mahal: coros.<\/li>\n<\/ul>\n<p><center><figure id=\"attachment_31806\" aria-describedby=\"caption-attachment-31806\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31806\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-768x512.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-099-Rafa-Mellado.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-31806\" class=\"wp-caption-text\">Taj Mahal. Concierto de TAJMO el 14 de julio en el XX Festival de Jazz de San Javier<\/figcaption><\/figure><\/center><\/p>\n<p><center><figure id=\"attachment_31807\" aria-describedby=\"caption-attachment-31807\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31807\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-768x512.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-128-Rafa-Mellado.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-31807\" class=\"wp-caption-text\">Keb\u2019 Mo\u2019. Concierto de TAJMO el 14 de julio en el XX Festival de Jazz de San Javier<\/figcaption><\/figure><\/center><\/p>\n<p style=\"text-align: justify;\">El gran atractivo para muchos seguidores de Jazz San Javier, en la jornada del 14 de julio, fue el concierto protagonizado por dos figuras relevantes del <em>blues<\/em>, Taj Mahal y Keb\u2019 Mo\u2019. Cualquier motivo puede ser bueno para reunir a estos dos gigantes, a\u00fan m\u00e1s cuando ambos preparan juntos un nuevo \u00e1lbum, un recopilatorio con los temas m\u00e1s emblem\u00e1ticos de cada uno. Un aforo casi al completo esperaba expectante el comienzo del concierto.<\/p>\n<p><center><figure id=\"attachment_31808\" aria-describedby=\"caption-attachment-31808\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31808\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-768x512.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-184-Rafa-Mellado.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-31808\" class=\"wp-caption-text\">Concierto de TAJMO el 14 de julio en el XX Festival de Jazz de San Javier<\/figcaption><\/figure><\/p>\n<figure id=\"attachment_31809\" aria-describedby=\"caption-attachment-31809\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31809\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-768x512.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-83x55.jpg 83w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-200-Rafa-Mellado.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-31809\" class=\"wp-caption-text\">Concierto de TAJMO el 14 de julio en el XX Festival de Jazz de San Javier<\/figcaption><\/figure>\n<p><figure id=\"attachment_31810\" aria-describedby=\"caption-attachment-31810\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31810\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-600x400.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-200x133.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-768x512.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado-120x80.jpg 120w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-31810\" class=\"wp-caption-text\">Concierto de TAJMO el 14 de julio en el XX Festival de Jazz de San Javier<\/figcaption><\/figure><\/center><\/p>\n<p style=\"text-align: justify;\">\u201cSe\u00f1or Blues\u201d, fue el primer tema que dio inicio a la sesi\u00f3n, compartiendo voces entre los dos lideres. Generosos y dispuestos a darlo todo, conformaron un largo repertorio \u2013 19 temas en total \u2013 que hicieron las delicias del p\u00fablico. Piezas como: \u201cDon\u2019t Leave Me Here\u201d, \u201cGov\u2019t Cheese\u201d, \u201cThat\u2019s Who I Am\u201d, y el blues \u201cDivin\u2019 Duck Blues\u201d, cantado por Taj Mahal, fueron animando un recital que invocaba a sus seguidores a bajar de las gradas y bailar. No fue as\u00ed porque la organizaci\u00f3n ya hab\u00eda advertido de no ocupar el foso previo al escenario, hasta que no pasara una hora de concierto. El grupo, dio continuidad a la sesi\u00f3n con: \u201cEvery Morning\u201d, \u201cAm I Wrong\u201d, \u201cShe Dance\u201d, \u201cGiant Step\u201d y \u201cThe Worst\u201d. La arm\u00f3nica y la voz quebrada de Taj Mahal, sembraban de matices el espacio, ahondando en las almas de los oyentes. Palabras y mensajes de dicha y desdicha, de amor y desamor, de vida y de esperanza, un lenguaje propio que es inherente a las canciones de <em>blues<\/em>. Completando la escena, el guitarrista y cantante Keb\u2019 Mo\u2019, un m\u00fasico carism\u00e1tico con un gusto exquisito para componer y una voz profunda que te llega hasta las entra\u00f1as. A estas alturas del concierto, parte del p\u00fablico opt\u00f3 por acercarse al foso para bailar y disfrutar m\u00e1s cerca del grupo, con m\u00e1s canciones: \u201cShe Caught The Katy\u201d, \u201cOm Sweet Om\u201d, \u201cGimmie What You Got\u201d, \u201cLeavin\u2019 Trunk\u201d, y \u201cAll Around The World\u201d, entre otras. La banda despidi\u00f3 su concierto con \u201cSoul\u201d, arropada por las ovaciones de los presentes.<\/p>\n<p style=\"text-align: justify;\">Otro concierto que ha pasado a formar parte de los anales del festival.<\/p>\n<p style=\"text-align: right;\">Texto: \u00a9 Jos\u00e9 Antonio Garc\u00eda L\u00f3pez, 2017<br \/>\nFotograf\u00edas: \u00a9 Rafa Mellado, Jazz San Javier, 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>XX Festival Internacional de Jazz San Javier Fecha: 14 de julio de 2017 Lugar: Auditorio Parque Almansa (San Javier, Murcia) Grupo: Tajmo\u2019: The Taj Mahal &amp; Keb\u2019 Mo\u2019 Band Taj Mahal: voz y guitarras. Keb\u2019 Mo\u2019: voz y guitarras. Dana Robbins: saxo. Quentin Ware: trompeta. David Rodgers: teclados. Stan Sergeant:<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tajmo-the-taj-mahal-keb-mo-band-xx-festival-internacional-de-jazz-san-javier-2017-07-14-conciertos\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":31810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17875,17876,4,15517,1038],"tags":[16888,12836,15314,19972,19974,19977,13,15312,12415,15295,15313,19971,15710,19976,19979,19973,16890,19975,14750,19969,19968,19970,16099,77,16100,19980,19978],"class_list":["entry","author-pachi","post-31804","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jose-antonio-garcia-lopez","category-rafa-mellado","category-conciertos","category-textos","category-contenidos","tag-auditorio-parque-almansa-san-javier-murcia","tag-concierto","tag-concierto-de-jazz","tag-dana-robbins","tag-david-rodgers","tag-deva-mahal","tag-jazz","tag-jazz-en-directo","tag-jazz-en-espana","tag-jazz-en-espanol","tag-jazz-en-vivo","tag-keb-mo","tag-la-actualidad-del-jazz-en-espana","tag-marcus-finnie","tag-ose-antonio-garcia-lopez","tag-quentin-ware","tag-rafa-mellado","tag-stan-sergeant","tag-taj-mahal","tag-tajmo","tag-tajmo-the-taj-mahal-keb-mo-band","tag-the-taj-mahal-keb-mo-band","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-xx-festival-internacional-de-jazz-san-jav","tag-zoe-mahal"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":30776,"url":"https:\/\/tomajazz.com\/web\/xx-festival-internacional-jazz-san-javier-2017-30-de-junio-al-30-de-julio-de-2017-noticias\/","url_meta":{"origin":31804,"position":0},"title":"XX Festival Internacional Jazz San Javier 2017 (30 de junio al 30 de julio de 2017) [Noticias]","author":"Tomajazz","date":"5 junio, 2017","format":false,"excerpt":"XX Festival Internacional Jazz San Javier 2017. San Javier, Murcia Del 30 de junio al 30 de julio de 2017 Viernes 30 Junio Ximo Tebar Invitada Especial: Carmen Rodr\u00edguez Sole Gim\u00e9nez Invitado Especial: Antonio Carmona S\u00e1bado 1 Julio Charenee Wade Chantz Powell Meets Shakin\u2019 All Mi\u00e9rcoles 5 Julio Allan Harris\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/06\/XX-Festival-Jazz-San-Javier-2017-e1496593254442.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/06\/XX-Festival-Jazz-San-Javier-2017-e1496593254442.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/06\/XX-Festival-Jazz-San-Javier-2017-e1496593254442.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":21814,"url":"https:\/\/tomajazz.com\/web\/helen-humes-la-odisea-de-la-musica-afroamericana-032-podcast\/","url_meta":{"origin":31804,"position":1},"title":"Helen Humes. La Odisea de la M\u00fasica Afroamericana (032) [Podcast]","author":"Tomajazz","date":"11 enero, 2016","format":"audio","excerpt":"La Odisea de la M\u00fasica Afroamericana. Programa de radio dirigido, presentado y producido por Luis Escalante Ozalla, autor del libro Y se hace m\u00fasica al andar con swing. La cantante de blues y jazz\u00a0Helem Humes es la protagonista absoluta de la\u00a0entrega n\u00famero 32 de La Odisea de la M\u00fasica Afroamericana.\u2026","rel":"","context":"En \u00ab*_Luis Escalante Ozalla\u00bb","block_context":{"text":"*_Luis Escalante Ozalla","link":"https:\/\/tomajazz.com\/web\/category\/luis-escalante-ozalla\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/01\/Helen-humes.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":106093,"url":"https:\/\/tomajazz.com\/web\/lizz-wright-san-javier-2026\/","url_meta":{"origin":31804,"position":2},"title":"Lizz Wright (XXVIII Festival Internacional de Jazz de San Javier 2026 &#8211; Murcia. 2026-07-07)  Por Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez [Concierto de jazz]","author":"Tomajazz","date":"4 agosto, 2026","format":false,"excerpt":"Lizz Wright actu\u00f3 en el XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez repasan el concierto. Actuaron Lizz Wright, Kenny Banks, Adam Levy, Kyle Miles, Marlon Patton","rel":"","context":"En \u00abXXVIII Festival Internacional de Jazz de San Javier 2026\u00bb","block_context":{"text":"XXVIII Festival Internacional de Jazz de San Javier 2026","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/xxviii-festival-internacional-de-jazz-de-san-javier-2026\/"},"img":{"alt_text":"Lizz Wright (XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. 2026-07-07)  Por Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez [Concierto de jazz] - Tomajazz - Lizz Wright actu\u00f3 en el XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez repasan el concierto. Actuaron Lizz Wright, Kenny Banks, Adam Levy, Kyle Miles, Marlon Patton\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Lizz-Wright-04.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Lizz-Wright-04.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Lizz-Wright-04.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Lizz-Wright-04.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":105649,"url":"https:\/\/tomajazz.com\/web\/festival-internacional-de-jazz-de-san-javier-2026-nws\/","url_meta":{"origin":31804,"position":3},"title":"XXVIII Festival Internacional de Jazz de San Javier 2026 (San Javier. 26 de junio al 24 de julio de 2026)","author":"Tomajazz","date":"28 mayo, 2026","format":false,"excerpt":"Entre el 26 de junio y el 24 de julio de 2026 se celebrar\u00e1 la XXVIII edici\u00f3n del Festival Internacional de Jazz de San Javier 2026. Pat Metheny, Fusion Experience Quartet, Lizz Wright o Antonio Serrano & Kaele Jim\u00e9nez Cuarteto son algunos de los artistas de la edici\u00f3n de 2026\u2026","rel":"","context":"En \u00abXXVIII Festival Internacional de Jazz de San Javier 2026\u00bb","block_context":{"text":"XXVIII Festival Internacional de Jazz de San Javier 2026","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/xxviii-festival-internacional-de-jazz-de-san-javier-2026\/"},"img":{"alt_text":"XXVIII Festival Internacional de Jazz de San Javier 2026 (San Javier. 26 de junio al 24 de julio de 2026) - Tomajazz - Entre el 26 de junio y el 24 de julio de 2026 se celebrar\u00e1 la XXVIII edici\u00f3n del Festival Internacional de Jazz de San Javier. Pat Metheny, Fusion Experience Quartet, Lizz Wright o Antonio Serrano & Kaele Jim\u00e9nez Cuarteto son algunos d","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/28-Festival-de-Jazz-de-San-Javier-Tomajazz-Noticias.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/28-Festival-de-Jazz-de-San-Javier-Tomajazz-Noticias.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/28-Festival-de-Jazz-de-San-Javier-Tomajazz-Noticias.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/28-Festival-de-Jazz-de-San-Javier-Tomajazz-Noticias.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31812,"url":"https:\/\/tomajazz.com\/web\/pegasus-featuring-monica-green-xx-festival-internacional-de-jazz-san-javier-2017-07-14-conciertos\/","url_meta":{"origin":31804,"position":4},"title":"Pegasus featuring M\u00f3nica Green (XX Festival Internacional de Jazz San Javier. 2017-07-14) [Conciertos]","author":"Tomajazz","date":"18 agosto, 2017","format":false,"excerpt":"XX Festival Internacional de Jazz San Javier Fecha: 14 de julio de 2017 Lugar: Auditorio Parque Almansa (San Javier, Murcia) Grupo: Pegasus featuring M\u00f3nica Green Josep Mas \u201cKitflus\u201d: teclados. Max Sunyer: guitarra. Rafael Escot\u00e9: bajo. Santi Arisa: bater\u00eda. M\u00f3nica Green: voz. La m\u00edtica banda catalana de jazz fusion, Pegasus, fue\u2026","rel":"","context":"En \u00ab*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez\u00bb","block_context":{"text":"*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez","link":"https:\/\/tomajazz.com\/web\/category\/jose-antonio-garcia-lopez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/Pegasus-022-Rafa-Mellado.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/Pegasus-022-Rafa-Mellado.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/Pegasus-022-Rafa-Mellado.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/Pegasus-022-Rafa-Mellado.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/Pegasus-022-Rafa-Mellado.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":106150,"url":"https:\/\/tomajazz.com\/web\/rafa-m-guillen-clarence-bekker-san-javier-2026\/","url_meta":{"origin":31804,"position":5},"title":"Rafa M. Guill\u00e9n &#038; The Jazz Walkers \/ Clarence Bekker Band + Berget Lewis (XXVIII Festival Internacional de Jazz de San Javier 2026 &#8211; Murcia. 2026-07-11)  Por Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez [Concierto de jazz]","author":"Tomajazz","date":"5 agosto, 2026","format":false,"excerpt":"Rafa M. Guill\u00e9n & The Jazz Walkers y Clarence Bekker Band + Berget Lewis actuaron en el XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez relatan el concierto. Actuaron Rafa Mart\u00ednez Guill\u00e9n, Amy Gaviria, Vicent Maci\u00e1n, \u00c1ngel Andr\u00e9s Mu\u00f1oz, Abel\u2026","rel":"","context":"En \u00abXXVIII Festival Internacional de Jazz de San Javier 2026\u00bb","block_context":{"text":"XXVIII Festival Internacional de Jazz de San Javier 2026","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/xxviii-festival-internacional-de-jazz-de-san-javier-2026\/"},"img":{"alt_text":"Rafa M. Guill\u00e9n & The Jazz Walkers \/ Clarence Bekker Band + Berget Lewis (XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. 2026-07-11)  Por Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez [Concierto de jazz] - Tomajazz - Rafa M. Guill\u00e9n & The Jazz Walkers y Clarence Bekker Band + Berget Lewis actuaron en el XXVIII Festival Internacional de Jazz de San Javier 2026 - Murcia. Jos\u00e9 Antonio Garc\u00eda L\u00f3pez y Pedro S\u00e1ez relatan el concierto. Actuaron Rafa Mart\u00ednez Guill\u00e9n, Amy Gaviria, Vicent Maci\u00e1n, \u00c1ngel Andr\u00e9s Mu\u00f1oz, Abel Sanabria, Miquel Asensio, Carlos Llid\u00f3, Clarence Bekker, Berget Lewis, Arecio Smith, Francisco Guisado \u201cRubio\u201d, Leo Torres, Roberto Albrecia, Pol Padr\u00f3s, Charlie Cuevas, Carlos L\u00f3pez","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Clarence-Bekker-Band-Berget-Lewis-10.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Clarence-Bekker-Band-Berget-Lewis-10.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Clarence-Bekker-Band-Berget-Lewis-10.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/08\/destacada-Clarence-Bekker-Band-Berget-Lewis-10.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/08\/TAJMO-209-Rafa-Mellado.jpg","_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=31804"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31804\/revisions"}],"predecessor-version":[{"id":31811,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/31804\/revisions\/31811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/31810"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=31804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=31804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=31804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}