{"id":37170,"date":"2018-06-07T10:45:03","date_gmt":"2018-06-07T08:45:03","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=37170"},"modified":"2024-10-09T20:54:26","modified_gmt":"2024-10-09T18:54:26","slug":"universos-paralelos-emision-7-de-junio-de-2018-noticias","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/universos-paralelos-emision-7-de-junio-de-2018-noticias\/","title":{"rendered":"Universos Paralelos. Emisi\u00f3n 7 de junio de 2018 [Noticias]"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-33503\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2.jpg\" alt=\"\" width=\"350\" height=\"350\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2-50x50.jpg 50w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<blockquote><p>22 A\u00f1os en el aire (y unos pocos en la red)&#8230; \u00a1y seguimos descubriendo buena m\u00fasica!<\/p><\/blockquote>\n<div>Ya est\u00e1 disponible una nueva emisi\u00f3n de Universos Paralelos, el programa de radio dirigido por\u00a0<strong>Sergio Cabanillas<\/strong>.<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-37171 size-medium\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia-200x200.jpg\" alt=\"\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia-50x50.jpg 50w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/06\/Marko_Churnchetz_Ruthenia.jpg 250w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>En el programa del 7 de junio de 2018: Jan Hammer Group, Tim Miller Trio, Dan Stern, Marko Churnchetz, Lorenzo Azcona, Juyma Est\u00e9vez Trio, Feefifofum Quartet, Sergi Sirvent Trumpet Affairs.<\/div>\n<div>Disponible en <a href=\"https:\/\/universosparalelosradioshow.blogspot.com\/2018\/06\/emision-31052018.html\" target=\"_blank\" rel=\"noopener\">universosparalelosradioshow.blogspot.com.es<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>22 A\u00f1os en el aire (y unos pocos en la red)&#8230; \u00a1y seguimos descubriendo buena m\u00fasica! Ya est\u00e1 disponible una nueva emisi\u00f3n de Universos Paralelos, el programa de radio dirigido por\u00a0Sergio Cabanillas. En el programa del 7 de junio de 2018: Jan Hammer Group, Tim Miller Trio, Dan Stern, Marko<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/universos-paralelos-emision-7-de-junio-de-2018-noticias\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":33503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,15795,1038,31550],"tags":[11856,15296],"class_list":["entry","author-pachi","post-37170","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-noticias-2","category-contenidos","category-universos-paralelos-up","tag-noticias","tag-noticias-de-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2017\/11\/UP_AVATAR2.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":104808,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p24-2025-26\/","url_meta":{"origin":37170,"position":0},"title":"Universos Paralelos: emisi\u00f3n 9 de abril de 2026 (UP.T.31 P.24) [Noticias de jazz]","author":"Tomajazz","date":"9 abril, 2026","format":false,"excerpt":"En el programa del 9 de abril de 2026 de Universos Paralelos - UP, Sergio Cabanillas selecciona m\u00fasica de las nuevas grabaciones de Hugo Fern\u00e1ndez, Diego Pi\u00f1era 4+4, Ben Wendel, Miguel \u00c2ngelo Trio, Sumrr\u00e1, Pocket Corner.","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 9 de abril de 2026 (UP.T.31 P.24) [Noticias de jazz] - Tomajazz - En el programa del 9 de abril de 2026 de Universos Paralelos - UP, Sergio Cabanillas selecciona m\u00fasica de las nuevas grabaciones de Hugo Fern\u00e1ndez, Diego Pi\u00f1era 4+4, Ben Wendel, Miguel \u00c2ngelo Trio, Sumrr\u00e1, Pocket Corner.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-02-Hugo-Fernandez-Rivermind-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-02-Hugo-Fernandez-Rivermind-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-02-Hugo-Fernandez-Rivermind-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-02-Hugo-Fernandez-Rivermind-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104729,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p23-2025-26\/","url_meta":{"origin":37170,"position":1},"title":"Universos Paralelos: emisi\u00f3n 26 de marzo de 2026 (UP.T.31 P.23) [Noticias de jazz]","author":"Tomajazz","date":"6 abril, 2026","format":false,"excerpt":"En el programa del 26 de marzo de 2026 de Universos Paralelos, Sergio Cabanillas selecciona m\u00fasicas de Ricardo Formoso, Ant Law & Alex Hitchcock, Deadeye, \u00c1lvaro Torres Trio, Eddie Mej\u00eda","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 26 de marzo de 2026 (UP.T.31 P.23) [Noticias de jazz] - Tomajazz - En el programa del 26 de marzo de 2026 de Universos Paralelos, Sergio Cabanillas selecciona m\u00fasicas de Ricardo Formoso, Ant Law & Alex Hitchcock, Deadeye, \u00c1lvaro Torres Trio, Eddie Mej\u00eda","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-Alvaro-Torres-Trio-Mairena-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-Alvaro-Torres-Trio-Mairena-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-Alvaro-Torres-Trio-Mairena-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/destacada-Alvaro-Torres-Trio-Mairena-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100330,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p04-2025-26\/","url_meta":{"origin":37170,"position":2},"title":"Universos Paralelos: emisi\u00f3n 9 de octubre de 2025 (UP.T.31 P.04) [Noticias de jazz]","author":"Tomajazz","date":"9 octubre, 2025","format":false,"excerpt":"En los Universos Paralelos dirigidos por Sergio Cabanillas, el 9 de octubre de 2025 suena m\u00fasica de Chronojazz, Gilad Hekselman, Hakan Ba\u015far, Miguel \u00c2ngelo Trio, Diego Alonso, Matthias Loibner #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 9 de octubre de 2025 (UP.T.31 P.04) [Noticias de jazz] - Tomajazz - En los Universos Paralelos dirigidos por Sergio Cabanillas, el 9 de octubre de 2025 suena m\u00fasica de Chronojazz, Gilad Hekselman, Hakan Ba\u015far, Miguel \u00c2ngelo Trio, Diego Alonso, Matthias Loibner #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacado-Matthias-Loibner-Aussichten-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacado-Matthias-Loibner-Aussichten-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacado-Matthias-Loibner-Aussichten-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacado-Matthias-Loibner-Aussichten-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":105026,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-up-t31-p25-2025-26\/","url_meta":{"origin":37170,"position":3},"title":"Universos Paralelos: emisi\u00f3n 16 de abril de 2026 (UP.T.31 P.25) [Noticias de jazz]","author":"Tomajazz","date":"22 abril, 2026","format":false,"excerpt":"En Universos Paralelos del 16 de abril de 2026, Sergio Cabanillas elige lo nuevo de V\u00edctor de Diego como disco de portada. Adem\u00e1s suena m\u00fasica de Juzz, Rai Castells, Manuel \u00c1lvarez Trio, Baptiste Bailly \/ Matthew Baker \/ Efr\u00e9n L\u00f3pez #Noticiasdejazz","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 16 de abril de 2026 (UP.T.31 P.25) [Noticias de jazz] - Tomajazz - En Universos Paralelos del 16 de abril de 2026, Sergio Cabanillas elige lo nuevo de V\u00edctor de Diego como disco de portada. Adem\u00e1s suena m\u00fasica de Juzz, Rai Castells, Manuel \u00c1lvarez Trio, Baptiste Bailly \/ Matthew Baker \/ Efr\u00e9n L\u00f3pez #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/portada-Victor-De-Diego-Haize-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/portada-Victor-De-Diego-Haize-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/portada-Victor-De-Diego-Haize-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/04\/portada-Victor-De-Diego-Haize-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101457,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-t31-p08-2025-26\/","url_meta":{"origin":37170,"position":4},"title":"Universos Paralelos: emisi\u00f3n 6 de noviembre de 2025 (UP.T.31 P.08) [Noticias de jazz]","author":"Tomajazz","date":"6 noviembre, 2025","format":false,"excerpt":"En la edici\u00f3n del 6 de noviembre de 2025 de Universos Paralelos, Sergio Cabanillas elige el nuevo disco de Max Villavecchia como disco de portada, pero no es lo \u00fanico... #Noticiasdejazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 6 de noviembre de 2025 (UP.T.31 P.08) [Noticias de jazz] - Tomajazz - En la edici\u00f3n del 6 de noviembre de 2025 de Universos Paralelos, Sergio Cabanillas elige el nuevo disco de Max Villavecchia como disco de portada, pero no es lo \u00fanico... #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/11\/destacada-Max-Villavecchia-Entre-Mar-i-Roca-1080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":105261,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-up-t31-p28-2025-26\/","url_meta":{"origin":37170,"position":5},"title":"Universos Paralelos: emisi\u00f3n 7 de mayo de 2026 (UP.T.31 P.28) [Noticias de jazz]","author":"Tomajazz","date":"7 mayo, 2026","format":false,"excerpt":"En los Universos Paralelos de Sergio Cabanillas, el 7 de mayo de 2026, Nexus de Jordi Farr\u00e9s es el disco de portada #Noticiasde jazz","rel":"","context":"En \u00abUniversos Paralelos - UP\u00bb","block_context":{"text":"Universos Paralelos - UP","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/universos-paralelos-up\/"},"img":{"alt_text":"Universos Paralelos: emisi\u00f3n 7 de mayo de 2026 (UP.T.31 P.28) [Noticias de jazz] - Tomajazz - En los Universos Paralelos de Sergio Cabanillas, el 7 de mayo de 2026, Nexus de Jordi Farr\u00e9s es el disco de portada #Noticiasde jazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-02-Jordi-Farres-Nexus-1080.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/37170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=37170"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/37170\/revisions"}],"predecessor-version":[{"id":37172,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/37170\/revisions\/37172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/33503"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=37170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=37170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=37170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}