{"id":41978,"date":"2019-02-20T17:45:21","date_gmt":"2019-02-20T16:45:21","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=41978"},"modified":"2022-08-28T15:30:15","modified_gmt":"2022-08-28T13:30:15","slug":"balanya-lopez-furious-yellow-huesca-2019-02-24-concierto","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/balanya-lopez-furious-yellow-huesca-2019-02-24-concierto\/","title":{"rendered":"Balany\u00e0 &#8211; L\u00f3pez: Furious Yellow (Huesca. 2019-02-24) [Noticias]"},"content":{"rendered":"<p>Por\u00a0<strong>Redacci\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-41979\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt-600x495.jpg\" alt=\"\" width=\"600\" height=\"495\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt-600x495.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt-200x165.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt-67x55.jpg 67w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt.jpg 636w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Balany\u00e0 &#8211; L\u00f3pez: Furious Yellow<br \/>\nJosep-Maria Balany\u00e0 (piano, voz) &#8211; Ram\u00f3n L\u00f3pez (bater\u00eda, tabla)<br \/>\n24 de febrero de 2019. 19:30<br \/>\nCentro Cultural Manuel Benito Moliner<br \/>\nAvda. Mart\u00ednez de Velasco, 6<br \/>\n22005 Huesca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Redacci\u00f3n. Balany\u00e0 &#8211; L\u00f3pez: Furious Yellow Josep-Maria Balany\u00e0 (piano, voz) &#8211; Ram\u00f3n L\u00f3pez (bater\u00eda, tabla) 24 de febrero de 2019. 19:30 Centro Cultural Manuel Benito Moliner Avda. Mart\u00ednez de Velasco, 6 22005 Huesca<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/balanya-lopez-furious-yellow-huesca-2019-02-24-concierto\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":41979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,15795,1038],"tags":[12117,11856,15296,284],"class_list":["entry","author-pachi","post-41978","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-noticias-2","category-contenidos","tag-josep-maria-balanya","tag-noticias","tag-noticias-de-jazz","tag-ramon-lopez"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/Balanya-Lopez_Huesca_20190224_rcrt.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":42220,"url":"https:\/\/tomajazz.com\/web\/instantzz-balanya-lopez-centro-cultural-manuel-benito-moliner-huesca\/","url_meta":{"origin":41978,"position":0},"title":"INSTANTZZ: Balany\u00e0-L\u00f3pez: Furious Yellow (Centro Cultural Manuel Benito Moliner,Huesca. 2019-02-24) [Galer\u00eda fotogr\u00e1fica]","author":"Tomajazz","date":"6 marzo, 2019","format":false,"excerpt":"Por\u00a0Fabio Galicia. Lugar: Centro Cultural Manuel Benito Moliner (Huesca) Fecha: domingo, 24 de febrero de 2019 Grupo: Josep-Mar\u00eda Balany\u00e0 & Ram\u00f3n L\u00f3pez: Furious Yellow Josep-Mar\u00eda Balany\u00e0: piano Ram\u00f3n L\u00f3pez: Bater\u00eda Tomajazz: \u00a9\u00a0Fabio Galicia, 2019","rel":"","context":"En \u00ab*_Fabio Galicia\u00bb","block_context":{"text":"*_Fabio Galicia","link":"https:\/\/tomajazz.com\/web\/category\/_fabio-galicia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/03\/03_DSC3434-BN_1-TOMAJAZZ-Balany%C3%A1-L%C3%B3pez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/03\/03_DSC3434-BN_1-TOMAJAZZ-Balany%C3%A1-L%C3%B3pez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/03\/03_DSC3434-BN_1-TOMAJAZZ-Balany%C3%A1-L%C3%B3pez.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":42096,"url":"https:\/\/tomajazz.com\/web\/instantzz-josep-maria-balanya-ramon-lopez-furious-yellow-prueba-de-sonido-y-concierto-nota-79-barcelona-2019-01-17-galeria-fotografica\/","url_meta":{"origin":41978,"position":1},"title":"INSTANTZZ: Josep Maria Balany\u00e0 &#038; Ram\u00f3n L\u00f3pez \u201cFurious Yellow\u201d -prueba de sonido y concierto- (Nota 79, Barcelona. 2019-01-17) [Galer\u00eda fotogr\u00e1fica]","author":"Tomajazz","date":"2 marzo, 2019","format":false,"excerpt":"Por\u00a0Joan Cort\u00e8s. Fecha: Jueves, 17 de enero de 2019 Lugar: Nota 79 (Barcelona) Grupo: Josep Maria Balany\u00e0 & Ram\u00f3n L\u00f3pez \u201cFurious Yellow\u201d Josep Maria Balany\u00e0, piano y voz Ram\u00f3n L\u00f3pez, bater\u00eda y tabla Tomajazz: \u00a9 Joan Cort\u00e8s, 2019","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/05_JMBlny-RmnLpz-%C2%A9Joan-Cort%C3%A8s_Nota-79_Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/05_JMBlny-RmnLpz-%C2%A9Joan-Cort%C3%A8s_Nota-79_Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/02\/05_JMBlny-RmnLpz-%C2%A9Joan-Cort%C3%A8s_Nota-79_Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":50877,"url":"https:\/\/tomajazz.com\/web\/instantzz-ramon-lopez-monografico-galeria-fotografica-aka-fotoblog-de-jazz-impro-y-algo-mas\/","url_meta":{"origin":41978,"position":2},"title":"INSTANTZZ: Ram\u00f3n L\u00f3pez (monogr\u00e1fico) [Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro&#8230; y algo m\u00e1s]","author":"Tomajazz","date":"23 junio, 2020","format":false,"excerpt":"Ram\u00f3n L\u00f3pez es el protagonista del segundo especial de Joan Cort\u00e8s en INSTANTZZ. Este recoge trece im\u00e1genes tomadas entre 2013 y 2019, en glorioso blanco y negro del baterista, pintor y artista gr\u00e1fico en distintas formaciones, proyectos y propuestas art\u00edsticas.","rel":"","context":"En \u00abFotoblog - Galer\u00eda fotogr\u00e1fica\u00bb","block_context":{"text":"Fotoblog - Galer\u00eda fotogr\u00e1fica","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/06\/12_Bl-Shr-%C2%A9Joan-Cort%C3%A8s_07set19_Msn-d-Tmps-Lbr_LNds.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/06\/12_Bl-Shr-%C2%A9Joan-Cort%C3%A8s_07set19_Msn-d-Tmps-Lbr_LNds.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/06\/12_Bl-Shr-%C2%A9Joan-Cort%C3%A8s_07set19_Msn-d-Tmps-Lbr_LNds.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":50519,"url":"https:\/\/tomajazz.com\/web\/hdo-529-al-habla-con-ramon-lopez-podcast\/","url_meta":{"origin":41978,"position":3},"title":"HDO 529. Al habla con&#8230; Ram\u00f3n L\u00f3pez [Podcast] Por Pachi Tapiz","author":"Tomajazz","date":"6 mayo, 2020","format":false,"excerpt":"En HDO 529 publicamos una extensa entrevista con el baterista y percusionista alicantino Ram\u00f3n L\u00f3pez en la que adem\u00e1s de las palabras del artista (adem\u00e1s de m\u00fasico es pintor), se escucha m\u00fasica de algunas de sus \u00faltimas grabaciones en compa\u00f1\u00eda de algunos de los mejores artistas de la escena de\u2026","rel":"","context":"En \u00abSonidos\u00bb","block_context":{"text":"Sonidos","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/05\/Collage_programa-0529_Al-habla-con...-Ram%C3%B3n-L%C3%B3pez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/05\/Collage_programa-0529_Al-habla-con...-Ram%C3%B3n-L%C3%B3pez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/05\/Collage_programa-0529_Al-habla-con...-Ram%C3%B3n-L%C3%B3pez.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/05\/Collage_programa-0529_Al-habla-con...-Ram%C3%B3n-L%C3%B3pez.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22394,"url":"https:\/\/tomajazz.com\/web\/josep-maria-balanya-agenda-de-conciertos-barcelona-febrero-marzo-2016-noticias\/","url_meta":{"origin":41978,"position":4},"title":"Josep-Maria Balany\u00e0: agenda de conciertos Barcelona (febrero &#8211; marzo 2016) [Noticias]","author":"Tomajazz","date":"24 febrero, 2016","format":false,"excerpt":"Jueves 25 de febrero. Impro Session Josep-Maria Balany\u00e0, Ramon Prats y otros Robadors 23 Robadors 23 08001 Barcelona Domingo 6 de marzo. 20:00 y 22:00 Presentaci\u00f3n oficial del CD Don't Mind Josep-Maria Balany\u00e0 (piano solo) Jamboree Pla\u00e7a Reial 17 08002 Barcelona Todos los conciertos y toda la informaci\u00f3n en www.balanya.net\u00a0\/\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/Josep-Maria-Balanya_Dont-Mind_Laika_2015.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/Josep-Maria-Balanya_Dont-Mind_Laika_2015.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/11\/Josep-Maria-Balanya_Dont-Mind_Laika_2015.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":28760,"url":"https:\/\/tomajazz.com\/web\/josep-maria-balanya-agenda-de-conciertos-espana-portugal-final-enero-2017-noticias\/","url_meta":{"origin":41978,"position":5},"title":"Josep-Maria Balany\u00e0: agenda de conciertos (Espa\u00f1a &#8211; Portugal. Final enero 2017) [Noticias]","author":"Tomajazz","date":"16 enero, 2017","format":false,"excerpt":"Agenda de conciertos de Josep-Maria Balany\u00e0 en Espa\u00f1a y Portugal. 17 al 25 de enero de 2017. Martes 17. Josep-Maria Balany\u00e0 - Lorena Izquierdo. Taller de Fuencisla. Valencia Mi\u00e9rcoles 18. Josep Llu\u00eds Galiana - Josep-Maria Balany\u00e0. Universitat de Val\u00e8ncia Jueves 19. Josep-Maria Balany\u00e0. Masterclass. Clasijazz. Almer\u00eda Jueves 19. Josep-Maria Balany\u00e0.\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/Josep-Maria-Balany%C3%A0_conciertos-Espa%C3%B1a-Portugal_2017-enero-fin-e1484556339473.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/Josep-Maria-Balany%C3%A0_conciertos-Espa%C3%B1a-Portugal_2017-enero-fin-e1484556339473.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/01\/Josep-Maria-Balany%C3%A0_conciertos-Espa%C3%B1a-Portugal_2017-enero-fin-e1484556339473.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/41978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=41978"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/41978\/revisions"}],"predecessor-version":[{"id":66120,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/41978\/revisions\/66120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/41979"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=41978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=41978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=41978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}