{"id":43709,"date":"2019-06-05T18:00:20","date_gmt":"2019-06-05T16:00:20","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=43709"},"modified":"2022-08-27T14:13:57","modified_gmt":"2022-08-27T12:13:57","slug":"jazz-en-espanol-emision-4-de-junio-de-2019-noticias","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-4-de-junio-de-2019-noticias\/","title":{"rendered":"Jazz en espa\u00f1ol. Emisi\u00f3n 4 de junio de 2019 [Noticias]"},"content":{"rendered":"<p>Por <b>Redacci\u00f3n<\/b>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-38034\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2-600x185.jpg\" alt=\"\" width=\"600\" height=\"185\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2-600x185.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2-200x62.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2-179x55.jpg 179w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2.jpg 650w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>Juli\u00e1n Ruesga<\/strong> presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: <em>Jazz en espa\u00f1ol.<\/em><\/p>\n<p>En la semana del 4 de junio de 2019 en Jazz en espa\u00f1ol de Juli\u00e1n Ruesga Bono, suena el \u00e1lbum <em>Condao<\/em>, de Reinier Elizarde. Tambi\u00e9n suena la m\u00fasica de Marta S\u00e1nchez y Ariel Brinquez.<span style=\"color: #323232;\"><br \/>\n<\/span><\/p>\n<p>Disponible en <a href=\"http:\/\/www.emartv.es\/jazz-en-espanol\/#.WhU8c7ZDmMI\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.emartv.es\/jazz-en-espanol\/#.WhU8c7ZDmMI<\/a> y <a href=\"https:\/\/www.ivoox.com\/podcast-jazz-espanol_sq_f1478867_1.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ivoox.com\/podcast-jazz-espanol_sq_f1478867_1.html<\/a><\/p>\n<p><iframe id=\"audio_36660862\" style=\"border: 1px solid #EEE; box-sizing: border-box; width: 100%;\" src=\"https:\/\/www.ivoox.com\/player_ej_36660862_4_1.html?c1=ff6600\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 4 de junio de 2019 en Jazz en espa\u00f1ol de Juli\u00e1n Ruesga Bono, suena el<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-4-de-junio-de-2019-noticias\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":38034,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17858,15795,1038],"tags":[15295,603,11856,15296],"class_list":["entry","author-pachi","post-43709","post","type-post","status-publish","format-standard","has-post-thumbnail","category-redaccion","category-noticias-2","category-contenidos","tag-jazz-en-espanol","tag-julian-ruesga-bono","tag-noticias","tag-noticias-de-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa\u00f1ol_LogoJulio2018-2.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":100004,"url":"https:\/\/tomajazz.com\/web\/todo-es-flamenco-rock-efe-eme-2025\/","url_meta":{"origin":43709,"position":0},"title":"Todo es flamenco rock (Efe Eme; 2025) por Antonio Jes\u00fas Garc\u00eda y Ram\u00f3n Garc\u00eda. Por Juli\u00e1n Ruesga Bono [Libro de jazz]","author":"Tomajazz","date":"2 octubre, 2025","format":false,"excerpt":"Juli\u00e1n Ruesga repasa el libro Todo es flamenco rock (Efe Eme; 2025) de Antonio Jes\u00fas Garc\u00eda y Ram\u00f3n Garc\u00eda","rel":"","context":"En \u00abLibros...\u00bb","block_context":{"text":"Libros...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/libros\/"},"img":{"alt_text":"Todo es flamenco rock (Efe Eme; 2025) por Antonio Jes\u00fas Garc\u00eda y Ram\u00f3n Garc\u00eda. Por Juli\u00e1n Ruesga Bono [Libro de jazz] - Tomajazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Antonio-Jesus-Garcia-y-Ramon-Garcia-Todo-es-flamenco-rock-2025-EfeEme-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Antonio-Jesus-Garcia-y-Ramon-Garcia-Todo-es-flamenco-rock-2025-EfeEme-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Antonio-Jesus-Garcia-y-Ramon-Garcia-Todo-es-flamenco-rock-2025-EfeEme-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Antonio-Jesus-Garcia-y-Ramon-Garcia-Todo-es-flamenco-rock-2025-EfeEme-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":43944,"url":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-18-de-junio-de-2019-noticias\/","url_meta":{"origin":43709,"position":1},"title":"Jazz en espa\u00f1ol. Emisi\u00f3n 18 de junio de 2019 [Noticias]","author":"Tomajazz","date":"19 junio, 2019","format":false,"excerpt":"Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 18 de junio de 2019 en Jazz en espa\u00f1ol de Juli\u00e1n Ruesga Bono, un repaso\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Jazz en Espa\u00f1ol","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":43805,"url":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-12-de-junio-de-2019-noticias\/","url_meta":{"origin":43709,"position":2},"title":"Jazz en espa\u00f1ol. Emisi\u00f3n 12 de junio de 2019 [Noticias]","author":"Tomajazz","date":"13 junio, 2019","format":false,"excerpt":"Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 12 de junio de 2019 en Jazz en espa\u00f1ol de Juli\u00e1n Ruesga Bono, presenta el\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":44048,"url":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-25-de-junio-de-2019-noticias\/","url_meta":{"origin":43709,"position":3},"title":"Jazz en espa\u00f1ol. Emisi\u00f3n 25 de junio de 2019 [Noticias]","author":"Tomajazz","date":"27 junio, 2019","format":false,"excerpt":"Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 25 de junio de 2019 en Jazz en espa\u00f1ol de Juli\u00e1n Ruesga Bono, el programa\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Jazz en Espa\u00f1ol","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/06\/Jazz-en-espa%C3%B1ol_LogoJunio2019-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":42378,"url":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-14-de-marzo-de-2019-noticias\/","url_meta":{"origin":43709,"position":4},"title":"Jazz en espa\u00f1ol. Emisi\u00f3n 14 de marzo de 2019 [Noticias]","author":"Tomajazz","date":"14 marzo, 2019","format":false,"excerpt":"Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 14 de marzo de 2019 Juli\u00e1n Ruesga Bono dedica el programa al saxofonista cubano Rom\u00e1n\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":42300,"url":"https:\/\/tomajazz.com\/web\/jazz-en-espanol-emision-7-de-marzo-de-2019-noticias\/","url_meta":{"origin":43709,"position":5},"title":"Jazz en espa\u00f1ol. Emisi\u00f3n 7 de marzo de 2019 [Noticias]","author":"Tomajazz","date":"8 marzo, 2019","format":false,"excerpt":"Por Redacci\u00f3n. Juli\u00e1n Ruesga presenta un programa que explora y difunde el jazz de Hispanoam\u00e9rica y Espa\u00f1a. Un vuelo a los mundos sonoros del jazz de dos continentes: Jazz en espa\u00f1ol. En la semana del 7 de marzo de 2019 Juli\u00e1n Ruesga Bono realiza un repaso a la programaci\u00f3n de\u2026","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2018\/07\/Jazz-en-espa%C3%B1ol_LogoJulio2018-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/43709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=43709"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/43709\/revisions"}],"predecessor-version":[{"id":43710,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/43709\/revisions\/43710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/38034"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=43709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=43709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=43709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}