{"id":45762,"date":"2019-09-17T12:15:45","date_gmt":"2019-09-17T10:15:45","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=45762"},"modified":"2022-01-20T18:23:12","modified_gmt":"2022-01-20T17:23:12","slug":"victor-anton-group-changing-gears-errabal-jazz-2019-grabacion","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/victor-anton-group-changing-gears-errabal-jazz-2019-grabacion\/","title":{"rendered":"V\u00edctor Ant\u00f3n Group: Changing Gears (Errabal Jazz, 2019) [Grabaci\u00f3n]"},"content":{"rendered":"<p>Por\u00a0<strong>Carlos Lara<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43497 size-medium\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-200x200.jpg\" alt=\"\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-55x55.jpg 55w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears-50x50.jpg 50w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears.jpg 620w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Segundo disco para el sello Errabal Jazz del guitarrista zamorano afincado en Valladolid, V\u00edctor Ant\u00f3n, con un quinteto de magn\u00edficos m\u00fasicos.<\/p>\n<p>Con un d\u00fao de guitarra y saxo interpretando la misma melod\u00eda evolucionando\u00a0\u00a0 pl\u00e1cidamente hasta que el saxo navega solo arropado por el resto del grupo, empieza el tema \u201cConexiones\u201d. V\u00edctor Ant\u00f3n toca la guitarra con un sonido limpio, sincero y con mucho <em>swing.<\/em><\/p>\n<p>Precisos punteos en \u201cAquarius\u201d sirven\u00a0 de introducci\u00f3n a una balada sugerente con gran participaci\u00f3n de la secci\u00f3n r\u00edtmica que incrementa la intensidad de la pieza. El saxo de Roberto Nieva le da al tema otra vuelta m\u00e1s de calidad, y el tema nos atrapa, hasta que Ant\u00f3n vuelve a retomar sus\u00a0 de nuevo a punteos\u00a0 en un final muy brillante. Con retazos <em>boperos<\/em>, \u201cDon\u00b4t Look Back\u201d, se desarrolla a medio tempo donde la guitarra delante arrastra a todo el conjunto de la r\u00edtmica con mucho <em>swing<\/em>. Destaca el pianista con su decisi\u00f3n en la toma de relevo y acompa\u00f1ado del resto de la r\u00edtmica engarzan un fragmento lleno de elegancia. La guitarra enlaza de nuevo para seguir en clave de <em>swing<\/em>. \u201cUntitled\u201d comienza con el conjunto y el\u00a0 piano y la guitarra altern\u00e1ndose\u00a0 en su conversaci\u00f3n. Ricardo Nieva entra con sus sinuosos fraseos y la guitarra toma el relevo con sus finos toques. \u201cNew Home\u201d guitarra sola para comenzar dando la entrada a bater\u00eda y contrabajo y piano.\u00a0 Ritmos alegres y sugerentes por su amplitud en \u201cCruzar el charco\u201d. Hay fraseos precisos de Roberto Nieva y grandes punteos de V\u00edctor Ant\u00f3n para finalizar.<\/p>\n<p>Una estupenda balada, \u201cThe Key\u201d, donde la guitarra va desplegando las notas poco a poco con el saxo de Ricardo Nieva llevando la iniciativa. Para finalizar \u201cOn a Train\u201d,\u00a0 una pieza cargada de mucha r\u00edtmica y llena de colorido, primero a la guitarra y luego a cargo del piano, siempre muy bien arropado por el contrabajo y la bater\u00eda.<\/p>\n<p><em>Changing Gears<\/em> son ocho magn\u00edficas composiciones interpretadas con claridad meridiana y una excelente producci\u00f3n. El resultado: un disco muy bien trabajado previamente en el taller de creatividad y una oda al buen gusto musical.<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <strong>Carlos Lara<\/strong>, 2019<\/p>\n<p>V\u00edctor Ant\u00f3n Group:<em> Changing Gears<\/em><\/p>\n<p>M\u00fasicos: V\u00edctor Ant\u00f3n (guitarra), Roberto Nieva (saxo alto), Juan Sebasti\u00e1n V\u00e1zquez (piano), Chuchi Garc\u00eda (contrabajo) y Juanma Barroso (bater\u00eda).<\/p>\n<p>Composiciones: \u201cConexiones\u201d, \u201cAquarius\u201d, \u201cDon\u00b4t Look Back\u201d, \u201cUntitled\u201d, \u201cNew Home\u201d, \u201cCruzar el charco\u201d, \u201cThe Key\u201d y \u201cOn a Train\u201d.<br \/>\nTemas compuestos por V\u00edctor Ant\u00f3n.<\/p>\n<p>Grabado en Cascabel Producciones (Valladolid), los d\u00edas 11 y 12 de junio de 2018.<\/p>\n<p>Editado por Errabal Jazz en 2019.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Carlos Lara. Segundo disco para el sello Errabal Jazz del guitarrista zamorano afincado en Valladolid, V\u00edctor Ant\u00f3n, con un quinteto de magn\u00edficos m\u00fasicos. Con un d\u00fao de guitarra y saxo interpretando la misma melod\u00eda evolucionando\u00a0\u00a0 pl\u00e1cidamente hasta que el saxo navega solo arropado por el resto del grupo, empieza el<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/victor-anton-group-changing-gears-errabal-jazz-2019-grabacion\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":43497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,15517,1038],"tags":[84,15559,4990,22051,555,18301,15557,15561],"class_list":["entry","author-pachi","post-45762","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-textos","category-contenidos","tag-carlos-lara","tag-chuchi-garcia","tag-errabal-jazz","tag-juan-sebastian-vazquez","tag-juanma-barroso","tag-roberto-nieva","tag-victor-anton","tag-victor-anton-group"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2019\/05\/Victor-Anton-Group-Changing-Gears.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":45783,"url":"https:\/\/tomajazz.com\/web\/jazzx5080-victor-anton-group-dont-look-back-minipodcast\/","url_meta":{"origin":45762,"position":0},"title":"JazzX5#080. V\u00edctor Ant\u00f3n Group: Don&#8217;t Look Back [Minipodcast]","author":"Tomajazz","date":"18 septiembre, 2019","format":false,"excerpt":"Por\u00a0Pachi Tapiz con la colaboraci\u00f3n de Carlos Lara. \"Una buena muestra del excelente swing que se respira en cada nota.\" Carlos Lara \"Don't Look Back\". V\u00edctor Ant\u00f3n Group: Changing Gears (Errabal Jazz) V\u00edctor Ant\u00f3n, Juan Sebasti\u00e1n V\u00e1zquez, Roberto Nieva, Chuchi Garc\u00eda, Juanma Barroso Tema seleccionado por Carlos Lara, autor de\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"JazzX5#080. V\u00edctor Ant\u00f3n Group: Don't Look Back [Minipodcast]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/09\/JazzX5_080.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/09\/JazzX5_080.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/09\/JazzX5_080.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/09\/JazzX5_080.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70167,"url":"https:\/\/tomajazz.com\/web\/victor-anton-group-centennial-light-jazzx5\/","url_meta":{"origin":45762,"position":1},"title":"\u00abBLM\u00bb [V\u00edctor Ant\u00f3n Group: Centennial Light (Errabal, 2022)] Por Pachi Tapiz. JazzX5 #555 [Minipodcast de jazz]","author":"Tomajazz","date":"21 enero, 2023","format":false,"excerpt":"En JazzX5 suena el tema \"BLM\", que abre Centennial Light (Errabal, 2022) del V\u00edctor Ant\u00f3n Group. JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"En JazzX5 suena el tema \"BLM\", que abre Centennial Light (Errabal, 2022) del V\u00edctor Ant\u00f3n Group. JazzX5 es un podcast de Pachi Tapiz.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/JazzX5_0555.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/JazzX5_0555.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/JazzX5_0555.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/JazzX5_0555.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":62505,"url":"https:\/\/tomajazz.com\/web\/in-walked-bud-victor-anton-standards-session-errabal-jazz-2022-por-pachi-tapiz-jazzx5469-minipodcast-de-jazz\/","url_meta":{"origin":45762,"position":2},"title":"\u00abIn Walked Bud\u00bb [V\u00edctor Ant\u00f3n Standards Session (Errabal Jazz, 2022)] Por Pachi Tapiz. JazzX5#469 [Minipodcast de jazz]","author":"Tomajazz","date":"31 marzo, 2022","format":false,"excerpt":"En JazzX5 suena la versi\u00f3n del Monkiano \"In Walked Bud\" que aparece en Standards Session (Errabal Jazz, 2022) del guitarrista V\u00edctor Ant\u00f3n. JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/03\/JazzX5_0469.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/03\/JazzX5_0469.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/03\/JazzX5_0469.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/03\/JazzX5_0469.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":73303,"url":"https:\/\/tomajazz.com\/web\/errabal-jazz-4\/","url_meta":{"origin":45762,"position":3},"title":"Errabal Jazz IV: RS Faktor Basque, V\u00edctor Ant\u00f3n, Jer\u00f3nimo Mart\u00edn, Symbiosis 5. Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"27 abril, 2023","format":false,"excerpt":"Errabal Jazz IV. Enrique Farelo repasa las nuevas grabaciones de RS Faktor Basque, V\u00edctor Ant\u00f3n, Jer\u00f3nimo Mart\u00edn, y Symbiosis 5 en el sello Errabal Jazz.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Errabal Jazz IV: RS Faktor Basque, V\u00edctor Ant\u00f3n, Jer\u00f3nimo Mart\u00edn, Symbiosis 5. Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz 9.0 - Errabal Jazz IV. Enrique Farelo repasa las nuevas grabaciones de  RS Faktor Basque, V\u00edctor Ant\u00f3n, Jer\u00f3nimo Mart\u00edn, Symbiosis 5. Por Enrique Farelo [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/Collage-Errabal-Jazz-IV-2023.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/Collage-Errabal-Jazz-IV-2023.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/Collage-Errabal-Jazz-IV-2023.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/Collage-Errabal-Jazz-IV-2023.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23753,"url":"https:\/\/tomajazz.com\/web\/hdo-jazzpain-takeo-takahashi-jorge-garrido-monk-trio-rafa-madagascar-ancestral-project-victor-anton-group-102\/","url_meta":{"origin":45762,"position":4},"title":"HDO 102. Jazzpain: Takeo Takahashi, Jorge Garrido Monk Tr\u00edo, Rafa Madagascar Ancestral Project, V\u00edctor Anton Group [Podcast]","author":"Tomajazz","date":"23 abril, 2016","format":false,"excerpt":"(Casi) una hora de m\u00fasica \"sin interrupciones\" (m\u00e1s all\u00e1 de las necesarias) para escuchar\u00a0Eight Songs for Nine Years\u00a0(Takeo Takahashi),\u00a0Vintage (Jorge Garrido Monk Tr\u00edo),\u00a0Illumination (Rafa Madagascar Ancestral Project), y\u00a0Motion (V\u00edctor Anton Group). Cuatro propuestas que bien merecen una escucha. Pasen y oigan. \u00a9 Pachi Tapiz, 2016 HDO es un\u00a0podcast\u00a0editado, producido y\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/04\/Rafa-Madagascar-Ancestral-Project_Illumination_Quadrant_2016.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/04\/Rafa-Madagascar-Ancestral-Project_Illumination_Quadrant_2016.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/04\/Rafa-Madagascar-Ancestral-Project_Illumination_Quadrant_2016.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/04\/Rafa-Madagascar-Ancestral-Project_Illumination_Quadrant_2016.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":63748,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-emision-26-de-mayo-de-2022-t-27-p-32-noticias-de-jazz\/","url_meta":{"origin":45762,"position":5},"title":"Universos Paralelos: emisi\u00f3n 26 de mayo de 2022 (T.27 P.32) [Noticias de jazz]","author":"Tomajazz","date":"26 mayo, 2022","format":false,"excerpt":"Ya est\u00e1 disponible la edici\u00f3n del 26 de mayo de Universos Paralelos. La nueva grabaci\u00f3n del guitarrista V\u00edctor Ant\u00f3n es la portada destacada del programa. Universos Paralelos es un programa de radio presentado, editado y dirigido por Sergio Cabanillas.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/"},"img":{"alt_text":"V\u00edctor Ant\u00f3n Standards Session (Errabal, 2022) Universos Paralelos: emisi\u00f3n 26 de mayo de 2022 (T.27 P.32) [Noticias de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/03\/Victor-Anton_Standards-Session_Errabal_2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/45762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=45762"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/45762\/revisions"}],"predecessor-version":[{"id":45764,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/45762\/revisions\/45764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/43497"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=45762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=45762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=45762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}