{"id":48250,"date":"2020-01-07T13:00:47","date_gmt":"2020-01-07T12:00:47","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=48250"},"modified":"2020-02-16T20:08:26","modified_gmt":"2020-02-16T19:08:26","slug":"north-east-skajazz-orchestra-kafe-antzokia-bilbao-concierto","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/north-east-skajazz-orchestra-kafe-antzokia-bilbao-concierto\/","title":{"rendered":"North East Ska*Jazz Orchestra (Kafe Antzokia, Bilbao) [Concierto]"},"content":{"rendered":"<p>Por\u00a0<strong>Juan F. Trillo.<\/strong><\/p>\n<ul>\n<li>Fecha: <strong>3 de enero de 2020<\/strong>.<\/li>\n<li>Lugar: <strong>Kafe Antzokia, Bilbao<\/strong>.<\/li>\n<li>Grupo: <strong>North East Ska*Jazz Orchestra (Italia)<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48251\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-425x600.jpg\" alt=\"\" width=\"425\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-425x600.jpg 425w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-200x282.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-768x1084.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-1089x1536.jpg 1089w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-1451x2048.jpg 1451w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-39x55.jpg 39w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO_enero_2020_flyer-scaled.jpg 1814w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n<h4>North East Ska*Jazz Orchestra: Si hoy es viernes, esto es Bilbao.<\/h4>\n<p>Reci\u00e9n llegados de La Bisbal (Sala L\u2019Alternativa), la primera parada en su gira por Espa\u00f1a, y antes de que empiece el concierto dos veteranos de la banda, Freddy Frenzy (voces, <em>showman<\/em>) y Davide Mauro (saxo) se sientan conmigo para charlar y ponerme al tanto de lo que supone mover una orquesta de 18 m\u00fasicos y lograr que suenen coordinados como las piezas de un reloj.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48252\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-1_peq.jpg\" alt=\"\" width=\"577\" height=\"433\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-1_peq.jpg 577w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-1_peq-200x150.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-1_peq-73x55.jpg 73w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Davide asegura que es f\u00e1cil trabajar con los miembros del grupo, pues a pesar de que la mayor\u00eda son muy j\u00f3venes &#8211; entre los veinte y los treinta &#8211; tienen una excelente formaci\u00f3n musical. \u00ab<em>Que todos sepan leer m\u00fasica es algo que facilita mucho las cosas<\/em>\u00ab, dice. Sin duda, el veterano del grupo (62 a\u00f1os) es Freddy, delgado, alto, pelo blanco &#8211; aunque escaso &#8211; que lleva en melena y acompa\u00f1a con una barba igualmente blanca. Podr\u00eda pasar por un m\u00edstico anacoreta, si no fuese porque su vitalidad es por completo de este mundo, como lo demuestra cada vez que se sube al escenario.<\/p>\n<p>A nuestro alrededor, el equipo de la sala acarrea cajas de bebidas para aprovisionar las dos barras y una camarera empuja rodando un barril de cerveza tras otro. Les conviene estar bien aprovisionados; el <em>ska<\/em> incita a bailar a los oyentes y esto, a su vez, despierta la sed. El <em>ska jazz<\/em> lleva sonando desde finales de los ochenta, como una (otra m\u00e1s) evoluci\u00f3n de aquel <em>ska<\/em> que los Skatalitics hab\u00edan puesto en marcha veinte a\u00f1os antes. El estilo tiene, por tanto, fuertes ra\u00edces jamaicanas, lo que significa metales, percusi\u00f3n, una puesta en escena desenfadada y una actitud como de \u00ab<em>t\u00edo, estamos aqu\u00ed para divertirnos, \u00bfvale?<\/em>\u00ab. Y junto con todo ello, un alto componente de improvisaci\u00f3n a la hora de desarrollar las melod\u00edas, de ah\u00ed lo del <em>jazz<\/em>. Freddy Frenzy: \u00ab<em>Aqu\u00ed no hay problemas de egos encontrados. Todo el mundo tiene su oportunidad de salir al frente, hacer un solo siguiendo su inspiraci\u00f3n y demostrar su destreza con el instrumento<\/em>\u00ab.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48253\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-2_peq.jpg\" alt=\"\" width=\"577\" height=\"433\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-2_peq.jpg 577w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-2_peq-200x150.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-2_peq-73x55.jpg 73w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/p>\n<p>Fue Fred Reiter (Steady Freddie), l\u00edder de la primigenia banda New York Ska-Jazz Ensemble quien bautiz\u00f3 a esta derivaci\u00f3n del original, que muchos consideran a su vez un subg\u00e9nero de la Tercera Ola del <em>ska<\/em> (de influencia punk). El caso es que este divertido estilo suena actualmente por todo el mundo y encontramos bandas de <em>ska jazz<\/em> en Holanda (Rotterdam Ska-Jazz Foundation), Canada (Montreal Ska-Jazz Ensemble), Jap\u00f3n (Tokyo Ska Paradise Orchestra) o Italia, como es el caso de North East Ska*Jazz Orchestra (NESJO), que llevan funcionando desde 2012.<\/p>\n<p>Mientras hablamos, a seis metros sobre nuestras cabezas, en la oscuridad de las alturas, brilla la linterna de un t\u00e9cnico que trabaja en la pasarela de los focos. Un trozo de cinta aislante cae a nuestro lado y cruzo los dedos para que todo lo dem\u00e1s est\u00e9 bien ajustado. Me intriga la cuesti\u00f3n econ\u00f3mica, pues no tiene que ser f\u00e1cil generar ingresos suficientes para mantener una orquesta &#8211; de hecho, esa fue la raz\u00f3n de que desapareciesen las grandes bandas -, pero tanto Freddy como Davide coinciden en que para estos m\u00fasicos el dinero no es una prioridad. \u00ab<em>Todos ellos llevan una vida bastante bohemia<\/em>\u00ab, dicen. M\u00e9rito a\u00f1adido y una garant\u00eda de autenticidad, ya que cuando alguien hace algo porque le gusta y no por la pasta, se nota en el resultado.<\/p>\n<p>El tiempo pasa y Freddy y Davide se despiden para unirse al resto de la banda que ya est\u00e1 sobre el escenario afinando y coordin\u00e1ndose con los t\u00e9cnicos de sonido. Finalmente, todo queda listo; dejan los instrumentos y se acercan a la barra a tomarse un caf\u00e9 antes de que empiece el espect\u00e1culo.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48254\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-3_peq-600x338.jpg\" alt=\"\" width=\"600\" height=\"338\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-3_peq-600x338.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-3_peq-200x113.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-3_peq-98x55.jpg 98w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-3_peq.jpg 666w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Las puertas se abren con retraso y el p\u00fablico no tarda en llenar la sala. Sin embargo, sesenta minutos despu\u00e9s de la hora prevista de comienzo todav\u00eda seguimos esperando. La buena noticia es que a nadie parece importarle lo m\u00e1s m\u00ednimo; los asistentes charlan en grupos, beben, se hacen fotos, siguen bebiendo y parece que impera el buen rollo, as\u00ed que cuando por fin suenan los primeros metales todo el mundo est\u00e1 de buen humor.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48255\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-4_peq-600x338.jpg\" alt=\"\" width=\"600\" height=\"338\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-4_peq-600x338.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-4_peq-200x113.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-4_peq-98x55.jpg 98w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-4_peq.jpg 666w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Los temas instrumentales se alternan con los vocales y a los pocos minutos la sala entera baila con ritmo jamaicano. Buena parte del m\u00e9rito es de Freddy Frenzy, que salta, gira y se contorsiona; ahora hace el robot, ahora el <em>zombie walking<\/em>. Y, adem\u00e1s, canta. Un espect\u00e1culo que sorprende adem\u00e1s por su aspecto fr\u00e1gil y, digamos, venerable, pero no cabe duda de que al p\u00fablico le gusta e intenta imitar sus movimientos.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48256\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-5_peq.jpg\" alt=\"\" width=\"577\" height=\"433\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-5_peq.jpg 577w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-5_peq-200x150.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-5_peq-73x55.jpg 73w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/p>\n<p>Max Ravanello dirige, compone y arregla los temas que la NESJO interpreta y, a pesar de que en sus inicios fue una banda instrumental, su gran acierto fue incorporar las voces de Rosa Mussin y Michela Gena. Esta noche no cabe duda de que la fuerza que la banda transmite se debe en buena medida a estas dos excelentes cantantes, que a\u00fanan ritmo, armon\u00eda y energ\u00eda vocal. El repertorio est\u00e1 formado por los temas de su \u00faltimo \u00e1lbum, <em>North East Ska*Jazz Orchestra<\/em>, editado por el sello bilba\u00edno Brixton Records, de entre los que sobresale \u201cThe Sunny Side of My Heart\u201d y dejan las versiones de cl\u00e1sicos jazz para los bises: \u00abIt Ain&#8217;t Necessarily So\u00bb (Gerswin, <em>Porgy and Bess<\/em>) y, sobre todo, un extenso y excelente \u00abTake Five\u00bb que por s\u00ed solo vale por todo el concierto. Aqu\u00ed, las voces de Rosa y Michela elevaron el tema de Desmond y Brubeck al nivel de las mejores versiones que nunca se han hecho. Y para colmo el Gran Denis, tromb\u00f3n de varas, introdujo un solo, breve, pero memorable, que dej\u00f3 al p\u00fablico boquiabierto ante la potencia que es capaz de extraer de su instrumento y se llev\u00f3 un aplauso apote\u00f3sico. Las trompetas que derribaron las murallas de Jeric\u00f3 debieron de sonar m\u00e1s o menos as\u00ed. Un tema <em>funky jazz<\/em> puso el cierre a una noche en la que el p\u00fablico recibi\u00f3 lo que hab\u00eda ido buscando: espect\u00e1culo, m\u00fasica bailable y diversi\u00f3n.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48257\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-6_peq.jpg\" alt=\"\" width=\"577\" height=\"433\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-6_peq.jpg 577w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-6_peq-200x150.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-6_peq-73x55.jpg 73w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/p>\n<p>Para los miembros de la orquesta, un breve descanso y de nuevo a la carretera. En menos de 24 horas estar\u00e1n otra vez sobre el escenario (Madrid, Independance Club) y lo mismo al d\u00eda siguiente (Valencia, 16 Toneladas). En total, la gira por Espa\u00f1a habr\u00e1 supuesto 1700 kil\u00f3metros en cuatro jornadas, m\u00e1s la ida y la vuela a Italia. Lo dicho; estos m\u00fasicos tienen vocaci\u00f3n. Hay que quitarse el sombrero.<\/p>\n<p style=\"text-align: right;\">Texto y fotograf\u00edas: \u00a9 <strong>Juan F. Trillo<\/strong>, 2020 \/ <a href=\"https:\/\/siunleonhablase.wordpress.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/siunleonhablase.wordpress.com\/<\/a> &#8211; <a href=\"https:\/\/www.facebook.com\/jan.tilkut\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/jan.tilkut<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>North East Ska*Jazz Orchestra: Si hoy es viernes, esto es Bilbao.  Juan F. Trillo repasa la actuaci\u00f3n del grupo en Kafe Antzokia de Bilbao. <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/north-east-skajazz-orchestra-kafe-antzokia-bilbao-concierto\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":48252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,24111,15517,1038],"tags":[24112,24153],"class_list":["entry","author-pachi","has-excerpt","post-48250","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conciertos","category-_juan-f-trillo","category-textos","category-contenidos","tag-juan-f-trillo","tag-north-east-skajazz-orchestra"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/NESJO-1_peq.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":101040,"url":"https:\/\/tomajazz.com\/web\/le-discobole-orchestra-jazzebre-2025\/","url_meta":{"origin":48250,"position":0},"title":"Le Discobole Orchestra invit\u00e9 Christine Salem \u00abKaf\u00e9 Gry\u00e9\u00bb (37 Jazz\u00e8bre \/ Th\u00e9\u00e2tre Municipal, 2025-10-11 \/ Perpignan -France-) [5] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"28 octubre, 2025","format":false,"excerpt":"Le Discobole Orchestra invit\u00e9 Christine Salem \u00abKaf\u00e9 Gry\u00e9\u00bb actu\u00f3 en el 37 Jazz\u00e8bre el 11 de octubre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab37 Jazz\u00e8bre 2025\u00bb","block_context":{"text":"37 Jazz\u00e8bre 2025","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/37-jazzebre-2025\/"},"img":{"alt_text":"Le Discobole Orchestra invit\u00e9 Christine Salem \u00abKaf\u00e9 Gry\u00e9\u00bb (37 Jazz\u00e8bre \/ Th\u00e9\u00e2tre Municipal, 2025-10-11 \/ Perpignan -France-) [5] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Le Discobole Orchestra invit\u00e9 Christine Salem \u00abKaf\u00e9 Gry\u00e9\u00bb actu\u00f3 en el 37 Jazz\u00e8bre el 11 de octubre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-11-L-Dscbl-rchstr-Photo-By-Joan-Cortes-11ctb25-37Jzzbr-TM-Prpgnn-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-11-L-Dscbl-rchstr-Photo-By-Joan-Cortes-11ctb25-37Jzzbr-TM-Prpgnn-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/destacada-11-L-Dscbl-rchstr-Photo-By-Joan-Cortes-11ctb25-37Jzzbr-TM-Prpgnn-.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":48084,"url":"https:\/\/tomajazz.com\/web\/joshua-edelman-christmas-in-manhattan-jazz-cultural-theatre-bilbao-concierto\/","url_meta":{"origin":48250,"position":1},"title":"Joshua Edelman &#038; Christmas In Manhattan (Jazz Cultural Theatre, Bilbao) [Concierto]","author":"Tomajazz","date":"30 diciembre, 2019","format":false,"excerpt":"Juan F. Trillo se estrena en Tomajazz con una cr\u00f3nica del concierto Joshua Edelman & Christmas In Manhattan, que tuvo lugar hace unos d\u00edas en el Jazz Cultural Theatre de Bilbao, instituci\u00f3n educativa que dirige el pianista norteamericano.","rel":"","context":"En \u00abTextos\u00bb","block_context":{"text":"Textos","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2019\/12\/Joshua-Edelman_IMG-20191222-WA0004.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25128,"url":"https:\/\/tomajazz.com\/web\/jazzber-2016-bermeo-vizcaya-29-de-junio-al-1-de-julio-de-2016-noticias\/","url_meta":{"origin":48250,"position":2},"title":"Jazzber 2016 (Bermeo, Vizcaya. 29 de junio al 1 de julio de 2016) [Noticias]","author":"Tomajazz","date":"28 junio, 2016","format":false,"excerpt":"Jazzber 2016 Bermeoko XIX Jazzaldia. XIX Festival de Jazz de Bermeo Del 29 de junio al 1 de julio de 2016 Bermeoko Kafe Antzokia. Conciertos a partir de las 20:30 29 de junio. Tomasz Wendt Trio 30 de junio. Wilfried Wilde Quintett 1 de julio. Night Dreamers","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/Bermeo.-Festival-de-Jazz.-Jazzber-2016-Cartel-e1466878283792.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/Bermeo.-Festival-de-Jazz.-Jazzber-2016-Cartel-e1466878283792.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/06\/Bermeo.-Festival-de-Jazz.-Jazzber-2016-Cartel-e1466878283792.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":67106,"url":"https:\/\/tomajazz.com\/web\/milwaukee-jazz-orchestra-take-it-all-2022\/","url_meta":{"origin":48250,"position":3},"title":"Milwaukee Jazz Orchestra Take It All (Blujazz Productions; 2022) Por Juan F. Trillo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"29 septiembre, 2022","format":false,"excerpt":"Rese\u00f1a de la grabaci\u00f3n de la Milwaukee Jazz Orchestra Take It All (Blujazz Productions; 2022), por Juan F. Trillo.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Milwaukee Jazz Orchestra Take It All (Blujazz Productions; 2022. Por Juan F. Trillo [Grabaci\u00f3n de jazz]","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Milwaukee-Jazz-Orchestra-Take-It-All-WEB.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Milwaukee-Jazz-Orchestra-Take-It-All-WEB.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/09\/Milwaukee-Jazz-Orchestra-Take-It-All-WEB.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":63897,"url":"https:\/\/tomajazz.com\/web\/the-count-basie-orchestra-live-at-birdland-candid-records-2022-por-juan-f-trillo-grabacion-de-jazz\/","url_meta":{"origin":48250,"position":4},"title":"The Count Basie Orchestra: Live at Birdland (Candid Records, 2022) Por Juan F. Trillo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"3 junio, 2022","format":false,"excerpt":"Juan F. Trillo repasa la grabaci\u00f3n The Count Basie Orchestra Live At Birdland (Candid, 2022).","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"The Count Basie Orchestra Live At Birdland (Candid, 2022)","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/06\/The-Count-Basie-Orchestra-Live-At-Birdland-Candid-2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/06\/The-Count-Basie-Orchestra-Live-At-Birdland-Candid-2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/06\/The-Count-Basie-Orchestra-Live-At-Birdland-Candid-2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/06\/The-Count-Basie-Orchestra-Live-At-Birdland-Candid-2022.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/06\/The-Count-Basie-Orchestra-Live-At-Birdland-Candid-2022.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":49258,"url":"https:\/\/tomajazz.com\/web\/music-fest-25-jazz-en-los-tuneles-del-metro-por-juan-f-trillo-conciertos\/","url_meta":{"origin":48250,"position":5},"title":"Music Fest 25. Jazz en los t\u00faneles del metro. Por Juan F. Trillo [Conciertos]","author":"Tomajazz","date":"25 febrero, 2020","format":false,"excerpt":"Juan F. Trillo repasa la actuaci\u00f3n de Lucky Chops, Crazy Jazzers, Broken Brothers Brass Band en el Music Fest 25, o lo que es lo mismo, Jazz en los t\u00faneles del metro de Bilbao.","rel":"","context":"En \u00abConciertos...\u00bb","block_context":{"text":"Conciertos...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/conciertos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/02\/Bryan-H-Laura-G-Ainhoa-Z..jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/02\/Bryan-H-Laura-G-Ainhoa-Z..jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/02\/Bryan-H-Laura-G-Ainhoa-Z..jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=48250"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48250\/revisions"}],"predecessor-version":[{"id":49092,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48250\/revisions\/49092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/48252"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=48250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=48250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=48250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}