{"id":48362,"date":"2020-01-11T15:42:20","date_gmt":"2020-01-11T14:42:20","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=48362"},"modified":"2022-08-25T18:01:28","modified_gmt":"2022-08-25T16:01:28","slug":"jazzx5169-quintette-du-hot-club-de-france-georgia-on-my-mind-minipodcast","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/jazzx5169-quintette-du-hot-club-de-france-georgia-on-my-mind-minipodcast\/","title":{"rendered":"JazzX5#169. Quintette du Hot Club de France: Georgia On My Mind [Minipodcast]"},"content":{"rendered":"<p>Por\u00a0<strong>Pachi Tapiz<\/strong>.<\/p>\n<p style=\"text-align: left;\"><span style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-48364 size-medium\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/Django-Reinhardt_Georgia-On-My-Mind-200x150.jpg\" alt=\"\" width=\"200\" height=\"150\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/Django-Reinhardt_Georgia-On-My-Mind-200x150.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/Django-Reinhardt_Georgia-On-My-Mind-73x55.jpg 73w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/Django-Reinhardt_Georgia-On-My-Mind.jpg 480w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\u00abGeorgia On My Mind\u00bb<br \/>\nQuintette du Hot Club de France: Stephane Grappelli, Django Reinhardt, Pierre Ferret, Louis Vola, Freddy Taylor<br \/>\n<\/span><\/p>\n<p>S\u00e1bado a la ma\u00f1ana. En la radio suena el programa\u00a0<em>A vivir que son dos d\u00edas<\/em> que dirige Javier del Pino. En una de las secciones de la parte inicial suena y se habla acerca de \u00abShine On You Crazy Diamonds\u00bb. En la secci\u00f3n se pasa de Pink Floyd a Stephane Grappelli (el grupo cont\u00f3 con la colaboraci\u00f3n del violinista), y de all\u00ed el paso a hablar acerca del genial guitarrista Django Reinhardt ha sido algo natural. En el programa suena \u00abGeorgia On My Mind\u00bb. \u00a1Gracias Javier del Pino y compa\u00f1\u00eda por la Inspiraci\u00f3n!<\/p>\n<p style=\"text-align: right;\"><span style=\"text-align: right;\">\u00a9 <\/span><strong style=\"text-align: right;\">Pachi Tapiz<\/strong><span style=\"text-align: right;\">, 2020<br \/>\n<\/span><\/p>\n<p><iframe id=\"audio_46381591\" style=\"border: 1px solid #EEE; box-sizing: border-box; width: 100%;\" src=\"https:\/\/www.ivoox.com\/player_ej_46381591_4_1.html?c1=ff6600\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>JazzX5<\/strong> es un minipodcast de HDO de la Factor\u00eda Tomajazz presentado, editado y producido por\u00a0<strong>Pachi Tapiz<\/strong>.<br \/>\n<strong>JazzX5<\/strong> comenz\u00f3 su andadura el 24 de junio de 2019.<br \/>\nTodas las entregas de <strong>JazzX5<\/strong> est\u00e1n disponibles en <strong><a href=\"https:\/\/tomajazz.com\/web\/?cat=23120\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tomajazz.com\/web\/?cat=23120<\/a> \/ <a href=\"https:\/\/www.ivoox.com\/jazzx5_bk_list_642835_1.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ivoox.com\/jazzx5_bk_list_642835_1.html<\/a><\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En JazzX169 y por \u00abculpa\u00bb de A vivir que son dos d\u00edas, el programa de radio de Javier del Pino, suena \u00abGeorgia On My Mind\u00bb del Quintette du Hot Club de France con Stephane Grappelli, Django Reinhardt, Pierre Ferret, Louis Vola y Freddy Taylor.<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/jazzx5169-quintette-du-hot-club-de-france-georgia-on-my-mind-minipodcast\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":48365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15518,17847,23120,12814,1038],"tags":[1207,24180,23118,24179,31,24178,24177,1751],"class_list":["entry","author-pachi","has-excerpt","post-48362","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sonidos","category-pachi-tapiz","category-jazzx5","category-podcast","category-contenidos","tag-django-reinhardt","tag-freddy-taylor","tag-jazzx5","tag-louis-vola","tag-pachi-tapiz","tag-pierre-ferret","tag-quintette-du-hot-club-de-france","tag-grappelli-stephane"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2020\/01\/JazzX5_169.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":26057,"url":"https:\/\/tomajazz.com\/web\/django-reinhardt-la-odisea-de-la-musica-afroamericana-061-podcast\/","url_meta":{"origin":48362,"position":0},"title":"Django Reinhardt. La Odisea de la M\u00fasica Afroamericana (061) [Podcast]","author":"Tomajazz","date":"29 agosto, 2016","format":false,"excerpt":"El guitarrista belga Django Reinhardt es el protagonista del cap\u00edtulo 61 de La Odisea de la M\u00fasica Afroamericana. Este m\u00fasico gitano consigui\u00f3 el reconocimiento de grandes m\u00fasicos de jazz contempor\u00e1neos. La Odisea de la M\u00fasica Afroamericana es un programa de radio dirigido, presentado y producido por Luis Escalante Ozalla, autor\u2026","rel":"","context":"En \u00ab*_Luis Escalante Ozalla\u00bb","block_context":{"text":"*_Luis Escalante Ozalla","link":"https:\/\/tomajazz.com\/web\/category\/luis-escalante-ozalla\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/08\/Django-Reinhardt_1946-por-William-P.-Gottlieb.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/08\/Django-Reinhardt_1946-por-William-P.-Gottlieb.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/08\/Django-Reinhardt_1946-por-William-P.-Gottlieb.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/08\/Django-Reinhardt_1946-por-William-P.-Gottlieb.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2016\/08\/Django-Reinhardt_1946-por-William-P.-Gottlieb.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":60075,"url":"https:\/\/tomajazz.com\/web\/tomajazz-remembers-7-django-reinhardt-all-of-me-minipodcast-de-jazz-por-juan-f-trillo\/","url_meta":{"origin":48362,"position":1},"title":"Tomajazz Remembers #7. Django Reinhardt: \u201cAll of Me\u201d [Minipodcast de jazz] Por Juan F. Trillo","author":"Tomajazz","date":"10 enero, 2022","format":false,"excerpt":"En la s\u00e9ptima entrega de Tomajazz Remembers suena la versi\u00f3n del cl\u00e1sico \"All Of Me\" por Django Reinhardt. Tomajazz Remembers es una secci\u00f3n de Juan F. Trillo.","rel":"","context":"En \u00abTomajazz Remembers (Podcast de jazz)\u00bb","block_context":{"text":"Tomajazz Remembers (Podcast de jazz)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/a_time_to_remember\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_007.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_007.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_007.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/01\/ATTR_007.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1794,"url":"https:\/\/tomajazz.com\/web\/django-reinhardt-un-gitano-en-paris-por-sergio-zeni\/","url_meta":{"origin":48362,"position":2},"title":"Django Reinhardt. Un gitano en Par\u00eds. Por Sergio Zeni","author":"Tomajazz","date":"1 noviembre, 2012","format":false,"excerpt":"El XXV Festival de Jazz de Badajoz arranc\u00f3 el jueves 8 de noviembre de 2012 con la presentaci\u00f3n del libro escrito por Juan Pedro Jim\u00e9nez y Emile Durand en el Teatro L\u00f3pez de Ayala. En el acto, que reuni\u00f3 a uno de los autores, el profesor y guitarrista Juan Pedro\u2026","rel":"","context":"En \u00ab*_Sergio Zeni\u00bb","block_context":{"text":"*_Sergio Zeni","link":"https:\/\/tomajazz.com\/web\/category\/sergio-zeni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/perfiles\/reinhardt_django_ugep\/Django-reinhardt-un-gitano-en-paris_gde.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5114,"url":"https:\/\/tomajazz.com\/web\/raul-marquez-trio-tributo-a-grappelli-jazzazza-aljezares-murcia-16-ii-2013\/","url_meta":{"origin":48362,"position":3},"title":"Ra\u00fal M\u00e1rquez Tr\u00edo Tributo a Grappelli (Jazzazza, Aljezares, Murcia, 16-II-2013)","author":"Tomajazz","date":"24 febrero, 2013","format":false,"excerpt":"Fecha: 16 de febrero de 2013 Lugar: Jazzazza Jazz Club, Aljezares (Murcia) Componentes\u00a0: Ra\u00fal M\u00e1rquez Tr\u00edo Tributo a Grappelli Ra\u00fal M\u00e1rquez: viol\u00edn. Javier S\u00e1nchez: guitarra el\u00e9ctrica. Gerardo Ramos: contrabajo. Comentario: Tributo a Grappelli es el proyecto con el que acudi\u00f3 el joven violinista aragon\u00e9s Ra\u00fal M\u00e1rquez al Jazzazza Jazz Club,\u2026","rel":"","context":"En \u00ab*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez\u00bb","block_context":{"text":"*_Jos\u00e9 Antonio Garc\u00eda L\u00f3pez","link":"https:\/\/tomajazz.com\/web\/category\/jose-antonio-garcia-lopez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/RAUL-MARQUEZ.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4954,"url":"https:\/\/tomajazz.com\/web\/varios-autores-sala-clamores-30-anos-indigo-records-2012\/","url_meta":{"origin":48362,"position":4},"title":"Varios autores: Sala Clamores. 30 a\u00f1os (Indigo Records, 2012)","author":"Tomajazz","date":"14 febrero, 2013","format":false,"excerpt":"El libro-CD-DVD Sala Clamores 30 a\u00f1os es un artefacto que se puede calificar como extra\u00f1o. Mientras el libro y el DVD se centran en la sala madrile\u00f1a para celebrar su aniversario desde distintos enfoques (distintos textos, recortes de prensa, un documental), el CD no est\u00e1 dedicado a recopilar momentos de\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/clamores-30-a%C3%B1os.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/clamores-30-a%C3%B1os.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/clamores-30-a%C3%B1os.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/clamores-30-a%C3%B1os.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":79971,"url":"https:\/\/tomajazz.com\/web\/stephane-grappelli-sacha-distel-tr34\/","url_meta":{"origin":48362,"position":5},"title":"St\u00e9phane Grappelli &#8211; Sacha Distel. \u201cHoneysuckle Rose\u201d. Por Juan F. Trillo. Tomajazz Remembers #34 [Minipodcast de jazz]","author":"Tomajazz","date":"1 noviembre, 2023","format":false,"excerpt":"\u201cHoneysuckle Rose\u201d por St\u00e9phane Grappelli - Sacha Distel. es el tema elegido por Juan F. Trillo para su entrega mensuel de Tomajazz Remembers.","rel":"","context":"En \u00abTomajazz Remembers (Podcast de jazz)\u00bb","block_context":{"text":"Tomajazz Remembers (Podcast de jazz)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/a_time_to_remember\/"},"img":{"alt_text":"St\u00e9phane Grappelli - Sacha Distel. \u201cHoneysuckle Rose\u201d. Por Juan F. Trillo. Tomajazz Remembers #34 [Minipodcast de jazz] - Tomajazz 9.0 - \u201cHoneysuckle Rose\u201d por St\u00e9phane Grappelli - Sacha Distel.  es el tema elegido por Juan F. Trillo para su entrega mensuel de Tomajazz Remembers.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/ATTR-034.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/ATTR-034.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/ATTR-034.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/11\/ATTR-034.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=48362"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48362\/revisions"}],"predecessor-version":[{"id":48370,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/48362\/revisions\/48370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/48365"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=48362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=48362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=48362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}