{"id":6633,"date":"2013-05-30T11:00:46","date_gmt":"2013-05-30T09:00:46","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=6633"},"modified":"2016-11-13T21:28:41","modified_gmt":"2016-11-13T20:28:41","slug":"mulgrew-miller-in-memorian","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/mulgrew-miller-in-memorian\/","title":{"rendered":"Mulgrew Miller: In Memorian"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6634\" alt=\"mulgrew_miller\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/05\/mulgrew_miller.jpg\" width=\"175\" height=\"263\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/05\/mulgrew_miller.jpg 175w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/05\/mulgrew_miller-99x150.jpg 99w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/05\/mulgrew_miller-36x55.jpg 36w\" sizes=\"auto, (max-width: 175px) 100vw, 175px\" \/><\/p>\n<p><strong>Kenny Barron<\/strong> es la sapiencia. Otro que va detr\u00e1s de <strong>Kenny Barron<\/strong>, que tambi\u00e9n es la sapiencia, pero que no es tan mayor es <strong>Mulgrew Miller<\/strong>. Un m\u00fasico con una gran solidez.<\/p>\n<p>Juan Claudio Cifuentes \u00abCifu\u00bb en <em><a href=\"http:\/\/www.tomajazz.com\/web\/?p=315\" target=\"_blank\">Juan Claudio Cifuentes, Cifu: 25 a\u00f1os de Jazz entre amigos<\/a><\/em>\u00a0(entrevista en Tomajazz).<\/p>\n<p>Fotograf\u00eda:<a href=\"http:\/\/www.tomajazz.com\/conciertos\/2007\/06\/carter_malone_miller_mostoles.htm\" target=\"_blank\"> Ron Carter, Mulgrew Miller, Russell Malone \u00abThe Golden Striker Trio\u00bb, III Festival de Jazz de M\u00f3stoles, 2007<\/a>. \u00a9 Sergio Cabanillas, 2007<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kenny Barron es la sapiencia. Otro que va detr\u00e1s de Kenny Barron, que tambi\u00e9n es la sapiencia, pero que no es tan mayor es Mulgrew Miller. Un m\u00fasico con una gran solidez. Juan Claudio Cifuentes \u00abCifu\u00bb en Juan Claudio Cifuentes, Cifu: 25 a\u00f1os de Jazz entre amigos\u00a0(entrevista en Tomajazz). Fotograf\u00eda:<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/mulgrew-miller-in-memorian\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17850,78,15504,9,1038],"tags":[118,6656,1889,187,16099,16100],"class_list":["entry","author-pachi","post-6633","post","type-post","status-publish","format-standard","category-sergio-cabanillas","category-afondo","category-articulos-afondo","category-perfiles","category-contenidos","tag-cifu","tag-in-memorian","tag-juan-claudio-cifuentes","tag-sergio-cabanillas","tag-toma-jazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":17606,"url":"https:\/\/tomajazz.com\/web\/que-seais-buenos-en-memoria-de-juan-claudio-cifuentes-cifu-por-arturo-mora\/","url_meta":{"origin":6633,"position":0},"title":"Que se\u00e1is buenos. En memoria de Juan Claudio Cifuentes \u00abCifu\u00bb. Por Arturo Mora","author":"Tomajazz","date":"17 marzo, 2015","format":false,"excerpt":"No recuerdo cu\u00e1ndo fue la primera vez que escuch\u00e9 a Cifu. De hecho dudo que hubiera una primera vez. Su voz sabia y cercana ha formado parte de mi subconsciente desde que tengo uso de raz\u00f3n. Tanto en mi caso como en el de otros miles de aficionados, su buen\u2026","rel":"","context":"En \u00ab*_Arturo Mora Rioja\u00bb","block_context":{"text":"*_Arturo Mora Rioja","link":"https:\/\/tomajazz.com\/web\/category\/arturo-mora-rioja\/"},"img":{"alt_text":"Juan Claudio Cifuentes \"Cifu\" \u00a9 Sergio Cabanillas, 2015","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2015\/02\/CIFU_3680.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17594,"url":"https:\/\/tomajazz.com\/web\/un-dia-triste-para-todos-por-carlos-lara\/","url_meta":{"origin":6633,"position":1},"title":"Un d\u00eda triste para todos. Por Carlos Lara","author":"Tomajazz","date":"17 marzo, 2015","format":false,"excerpt":"El s\u00e1bado 14 de marzo ha sido el \u00faltimo d\u00eda que escuch\u00e9 a Cifu. Un programa dedicado a Charlie Parker. Como siempre, una grabaci\u00f3n hist\u00f3rica. De las que a \u00e9l le gustaba poner. Siempre se aprend\u00eda algo nuevo escuchando a Cifu. Sus comentarios transmit\u00edan la emoci\u00f3n de quien est\u00e1 viviendo\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Juan Claudio Cifuentes \"Cifu\" \u00a9 Sergio Cabanillas, 2015","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/02\/CIFU_3673.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17667,"url":"https:\/\/tomajazz.com\/web\/jam-session-para-cifu-por-pilar-chozas\/","url_meta":{"origin":6633,"position":2},"title":"Jam Session para Cifu. Por Pilar Chozas","author":"Tomajazz","date":"19 marzo, 2015","format":false,"excerpt":"Se ha ido otro grande del jazz. La primera vez que vi a Cifu fue en el Whisky Jazz, en Madrid, de la mano de Michel. Fue en el 87, ya lo hab\u00eda visto en Jazz entre amigos, y escuchado en la radio. Pero all\u00ed en aquel garito entra\u00f1able lleno\u2026","rel":"","context":"En \u00ab*_Pilar Chozas\u00bb","block_context":{"text":"*_Pilar Chozas","link":"https:\/\/tomajazz.com\/web\/category\/pilar-chozas\/"},"img":{"alt_text":"Juan Claudio Cifuentes \"Cifu\" Emisi\u00f3n 40 Aniversario de \"Jazz Porque S\u00ed\" C.M.U. San Juan Evangelista, 04\/11\/2011 \u00a9 Sergio Cabanillas, 2011","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_1124_ENTREGA_PLACA_JOHNNY_2011.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17661,"url":"https:\/\/tomajazz.com\/web\/toda-la-oscuridad-no-sera-capaz-de-apagar-tu-luz-por-enrique-farelo\/","url_meta":{"origin":6633,"position":3},"title":"Toda la oscuridad no ser\u00e1 capaz de apagar tu luz. Por Enrique Farelo","author":"Tomajazz","date":"19 marzo, 2015","format":false,"excerpt":"Mentir\u00eda si dijera que conoc\u00eda a Cifu e igualmente lo har\u00eda si sostuviera que \u00e9ramos amigos entra\u00f1ables; faltar\u00eda a la verdad si contara an\u00e9cdotas que no est\u00e1n en mi memoria simplemente porque no existieron. Pero dir\u00eda la verdad si hablara desde la lejan\u00eda y las pocas palabras que intercambiamos a\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"\"Cifu\", en la inauguraci\u00f3n de Bogui, Madrid 28\/06\/2005 \u00a9 Sergio Cabanillas, 2005","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_3584_INAUGURACION_BOGUI_2005.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_3584_INAUGURACION_BOGUI_2005.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_3584_INAUGURACION_BOGUI_2005.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17627,"url":"https:\/\/tomajazz.com\/web\/round-about-cifu-por-juanma-castro-medina\/","url_meta":{"origin":6633,"position":4},"title":"Round About Cifu. Por Juanma Castro Medina","author":"Tomajazz","date":"18 marzo, 2015","format":false,"excerpt":"El mayor experto en jazz de nuestro pa\u00eds, mago de las ondas y aut\u00e9ntico divulgador de esta m\u00fasica en la piel de toro, cae enfermo. Un ictus. Tras un par de semanas en el hospital le dan el alta, queda como nuevo y prosigue su labor al frente de sus\u2026","rel":"","context":"En \u00ab*_Juanma Castro Medina\u00bb","block_context":{"text":"*_Juanma Castro Medina","link":"https:\/\/tomajazz.com\/web\/category\/juanma-castro-medina\/"},"img":{"alt_text":"Juan Claudio Cifuentes \"Cifu\" Emisi\u00f3n 40 Aniversario de \"Jazz Porque S\u00ed\" C.M.U. San Juan Evangelista, 04\/11\/2011 \u00a9 Sergio Cabanillas, 2011","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_1153_ENTREGA_PLACA_JOHNNY_2011.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17625,"url":"https:\/\/tomajazz.com\/web\/cifu-un-gran-tipo-por-pachi-tapiz\/","url_meta":{"origin":6633,"position":5},"title":"Cifu: un gran tipo. Por Pachi Tapiz","author":"Tomajazz","date":"18 marzo, 2015","format":false,"excerpt":"Cifu: un tipo entra\u00f1able y cercano. Alguien que si no existiera habr\u00eda que inventarlo. En definitiva, un gran tipo. Todos los aficionados del jazz llevamos dentro a un programador de jazz. Ese disc-jockey interior que servidor lleva dentro hay veces que echa de menos a muchos m\u00fasicos y estilos en\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"\"Cifu\", Jos\u00e9 Ram\u00f3n Rubio, Germ\u00e1n P\u00e9rez, Alejandro Reyes Emisi\u00f3n 40 Aniversario de \"Jazz Porque S\u00ed\" C.M.U. San Juan Evangelista, 04\/11\/2011 \u00a9 Sergio Cabanillas, 2011","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_1145_ENTREGA_PLACA_JOHNNY_2011-e1426688116918.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_1145_ENTREGA_PLACA_JOHNNY_2011-e1426688116918.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/03\/CIFU_1145_ENTREGA_PLACA_JOHNNY_2011-e1426688116918.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/6633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=6633"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/6633\/revisions"}],"predecessor-version":[{"id":6638,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/6633\/revisions\/6638"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=6633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=6633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=6633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}