{"id":69936,"date":"2023-01-19T12:00:48","date_gmt":"2023-01-19T11:00:48","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=69936"},"modified":"2023-01-18T22:34:30","modified_gmt":"2023-01-18T21:34:30","slug":"joan-claver-mist-cd-2023","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/joan-claver-mist-cd-2023\/","title":{"rendered":"Joan Claver: Mist (autoproducido 2023) Por Enrique Farelo [Grabaci\u00f3n de jazz]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-69937 size-medium\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB-300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB-465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB-500x500.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En 2015 el pianista y compositor Joan Claver forma su primer tr\u00edo c\u00f3mo l\u00edder publicando su disco de debut, <em>Triangle<\/em> (Fresh Sound New Talent 2016), siendo acompa\u00f1ado por Pedro Campos al contrabajo y Jos\u00e9 Ben\u00edtez a la bater\u00eda; ahora regresa con este <em>Mist, <\/em>un \u00e1lbum autoproducido y que el propio Joan Claver lo define como personal, inspirado en la naturaleza, el universo y en el comportamiento humano entorno a la vida y las emociones.<\/p>\n<p>Puedes comenzar la escucha por el orden establecido o bien por el final como he elegido.<\/p>\n<p>\u201cJupiter\u201d abrocha <em>Mist<\/em> y lo distingue del resto de composiciones por la inclusi\u00f3n del violonchelo de Oriol Catal\u00e1 confiri\u00e9ndole un sonido melanc\u00f3lico, repetitivamente pausado y elegante. Antes y a modo de introducci\u00f3n, la nost\u00e1lgica y reflexiva miniatura \u201cGanimedes\u201d (sat\u00e9lite natural de J\u00fapiter), sirve de excusa a Joan Claver para su lucimiento personal a piano solo.<\/p>\n<p>El resto del programa es a tr\u00edo, comenzando por la din\u00e1mica, alegre y obsesiva \u201cTupananchiskama\u201d que vierte su caudal en la miniatura disonante y vanguardista \u201cDark\u201d que a su vez se funde en un abrazo sonoro con la hom\u00f3nima, po\u00e9tica y minimalista \u201cMist\u201d, rememorando esencias emotivas del Esbj\u00f6rn Svensson Trio.<\/p>\n<p>Una vez m\u00e1s encontramos la delicada obsesi\u00f3n buc\u00f3lica y <em>swingueante<\/em> en \u201cTrampe L&#8217;oil\u201d y, \u201cClimbing up the Walls\u201d nos acerca al <em>rock<\/em> alternativo de Radiohead, en una versi\u00f3n reconocible e interpretada\u00a0 a <em>tempo lento<\/em> de final solemne.<\/p>\n<p>\u201cTurn Down\u201d es suave y aterciopelada, una brisa que acaricia los sentidos, <em>be-bop<\/em> que rebosa <em>feeling<\/em> y <em>swing<\/em> a partes iguales.<\/p>\n<p>La evocadora y brumosa \u201cThe Revenants\u201d se sustenta en un desarrollo instrumental s\u00f3lido de marcado sentir rom\u00e1ntico, no muy alejado de la siguiente composici\u00f3n \u201cDirtyland\u201d, si bien \u00e9sta es m\u00e1s intensa y vigorosa.<\/p>\n<h4 style=\"text-align: right;\">Texto: \u00a9 <strong><a href=\"https:\/\/elescribadeljazz.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Enrique Farelo<\/a><\/strong>, 2022<\/h4>\n<h4>Joan Claver: <em>Mist<\/em> (autoproducido 2023)<\/h4>\n<p>Joan Claver (piano), Artemi Agr\u00e0s (contrabajo) y Xavi Reija (bater\u00eda). Colabora Oriol Catal\u00e1 (violonchelo) en \u201cJupiter\u201d.<\/p>\n<p>Composiciones:\u00a0\u201cTupananchiskama\u201d, \u201cDark\u201d, \u201cMist\u201d, \u201cTrampe L&#8217;oil\u201d, \u201cClimbing up the Walls\u201d, \u201cTurn Down\u201d, \u201cThe Revenants\u201d, \u201cDirtyland\u201d, \u201cGanimedes\u201d y \u201cJupiter\u201d.<br \/>\nTodos los temas compuestos por Joan Claver excepto \u201cClimbing up the Walls\u201d de Radiohead.<\/p>\n<p>Grabado en La Casa Murada el 24 y 25 de noviembre de 2021.<\/p>\n<h4>M\u00e1s informaci\u00f3n sobre Joan Claver<\/h4>\n<p><a href=\"https:\/\/joanclaver.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/joanclaver.com\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=joan+claver&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=joan+claver&amp;submit=Search<\/a><\/p>\n<h4>Enrique Farelo en Tomajazz<\/h4>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17848\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17848<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enrique Farelo se estrena en 2023 en Tomajazz repasando la grabaci\u00f3n Mist (Autoproducido, 2023) de Joan Claver. <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/joan-claver-mist-cd-2023\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":69937,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,17848,15517,1038],"tags":[28298,304,17238,28299,7645],"class_list":["entry","author-pachi","has-excerpt","post-69936","post","type-post","status-publish","format-standard","has-post-thumbnail","category-grabaciones","category-enrique-farelo","category-textos","category-contenidos","tag-artemi-agras","tag-enrique-farelo","tag-joan-claver","tag-oriol-catala","tag-xavi-reija"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/01\/Joan-Claver-MistWEB.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":75934,"url":"https:\/\/tomajazz.com\/web\/dusan-jevtovic-city-hustling-2023\/","url_meta":{"origin":69936,"position":0},"title":"Dusan Jevtovic: City Hustling (Autoproducido, 2023) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"11 julio, 2023","format":false,"excerpt":"Dusan Jevtovic: ha publicado una nueva grabaci\u00f3n titulada City Hustling (Autoproducido, 2023). Enrique Farelo la repasa.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Dusan Jevtovic: City Hustling (Autoproducido, 2023) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz 9.0 - Dusan Jevtovic: ha publicado una nueva grabaci\u00f3n titulada City Hustling (Autoproducido, 2023). Enrique Farelo la repasa.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/07\/Dusan-Jevtovic-City-Hustling-Autoproducido-2023-Tomajazz-Grabaciones.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/07\/Dusan-Jevtovic-City-Hustling-Autoproducido-2023-Tomajazz-Grabaciones.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/07\/Dusan-Jevtovic-City-Hustling-Autoproducido-2023-Tomajazz-Grabaciones.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":82469,"url":"https:\/\/tomajazz.com\/web\/rufaca-folk-jazz-orchestra-2023\/","url_meta":{"origin":69936,"position":1},"title":"Rufaca Folk Jazz Orchestra &#8211; Esbart Catal\u00e0 de Dansaires &#8211; IEA Oriol Martorell \u201cLocus Amoenus\u201d (Casino l\u2019Alian\u00e7a del Poblenou, 2023-12-03. Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"11 enero, 2024","format":false,"excerpt":"El proyecto Rufaca Folk Jazz Orchestra - Esbart Catal\u00e0 de Dansaires - IEA Oriol Martorell \u201cLocus Amoenus\u201d actuaron el 3 de diciembre de 2023 en el Casino l\u2019Alian\u00e7a del Poblenou de Barcelona. Joan Cort\u00e8s retrata la actuaci\u00f3n en INSTANTZZ","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Rufaca Folk Jazz Orchestra - Esbart Catal\u00e0 de Dansaires - IEA Oriol Martorell \u201cLocus Amoenus\u201d (Casino l\u2019Alian\u00e7a del Poblenou, 2023-12-03. Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - El proyecto Rufaca Folk Jazz Orchestra - Esbart Catal\u00e0 de Dansaires - IEA Oriol Martorell \u201cLocus Amoenus\u201d actuaron el 3 de diciembre de 2023 en el Casino l\u2019Alian\u00e7a del Poblenou de Barcelona. Joan Cort\u00e8s retrata la actuaci\u00f3n en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/03-Rfk-Flk-Jzz-rchstr-%C2%A9Joan-Cortes-03dsm23-CPN.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/03-Rfk-Flk-Jzz-rchstr-%C2%A9Joan-Cortes-03dsm23-CPN.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/01\/03-Rfk-Flk-Jzz-rchstr-%C2%A9Joan-Cortes-03dsm23-CPN.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":85022,"url":"https:\/\/tomajazz.com\/web\/jaume-vilaseca-the-music-of-yes-2023\/","url_meta":{"origin":69936,"position":2},"title":"Jaume Vilaseca: Four Suites &#8211; The Music of YES (1971-1977) (DiscMedi Blau, 2023) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"22 marzo, 2024","format":false,"excerpt":"Four Suites - The Music of YES (1971-1977) (DiscMedi Blau, 2023) es la nueva grabaci\u00f3n de Jaume Vilaseca. Enrique Farelo repasa el homenaje en clave de jazz a la m\u00fasica de YES. Participan Jaume Vilaseca, Sergio Del Boccio, Roger Mir, Estefy Chamorro, Adri\u00e0 Pinto, Joan Codina, V\u00edctor Carrascosa , Mar\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Jaume Vilaseca: Four Suites - The Music of YES (1971-1977) (DiscMedi Blau, 2023) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - Four Suites - The Music of YES (1971-1977) (DiscMedi Blau, 2023) es la nueva grabaci\u00f3n de Jaume Vilaseca. Enrique Farelo repasa el homenaje en clave de jazz a la m\u00fasica de YES. Participan Jaume Vilaseca, Sergio Del Boccio, Roger Mir, Estefy Chamorro, Adri\u00e0 Pinto, Joan Codina, V\u00edctor Carrascosa , Mar Vilaseca","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/03\/Jaume-Vilaseca-Four-Suites-2023.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/03\/Jaume-Vilaseca-Four-Suites-2023.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/03\/Jaume-Vilaseca-Four-Suites-2023.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":54184,"url":"https:\/\/tomajazz.com\/web\/javier-navas-quartet-fresh-stars-autoeditado-2018-grabacion-de-jazz-por-enrique-farelo\/","url_meta":{"origin":69936,"position":3},"title":"Javier Navas Quartet: Fresh Stars (Autoeditado, 2018) [Grabaci\u00f3n de jazz] Por Enrique Farelo","author":"Tomajazz","date":"31 marzo, 2021","format":false,"excerpt":"Enrique Farelo repasa la grabaci\u00f3n \"Fresh Start\" del vibrafonista Javier Navas.","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/03\/Javier-Navas-Quartet_Fresh-Stars.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8624,"url":"https:\/\/tomajazz.com\/web\/joan-diaz-dalirogena-retrato-sonoro-de-salvador-dali-por-enrique-farelo\/","url_meta":{"origin":69936,"position":4},"title":"Joan D\u00edaz: Dalir\u00f2gena, retrato sonoro de Salvador Dal\u00ed por Enrique Farelo","author":"Sergio Cabanillas","date":"2 febrero, 2007","format":false,"excerpt":"\u00a0 \u00a0 Dalir\u00f2gena vino como un sue\u00f1o, pero no es El sue\u00f1o de una noche de verano de Shakespeare. Tampoco es aquello que inmortaliz\u00f3 Calder\u00f3n de la Barca: \"la vida es sue\u00f1o y, los sue\u00f1os, sue\u00f1os son\". Dalir\u00f2gena, es el sue\u00f1o de vida de un artista, hecho realidad, \"un homenaje\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Joan D\u00edaz-Dalir\u00f2gena (Satchmo Jazz Records 2004)","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/dalirogena.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":100717,"url":"https:\/\/tomajazz.com\/web\/entrevista-ruben-reinaldo-a-proposito-de-fusion-olivica-2025\/","url_meta":{"origin":69936,"position":5},"title":"Pr\u00f3ximamente&#8230; Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz]","author":"Tomajazz","date":"20 octubre, 2025","format":false,"excerpt":"El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","rel":"","context":"En \u00abEntrevistas...\u00bb","block_context":{"text":"Entrevistas...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/entrevistas-criticas\/"},"img":{"alt_text":"Entrevista con el guitarrista Rub\u00e9n Reinaldo a prop\u00f3sito de Fusi\u00f3n Ol\u00edvica. Por Carlos Lara, Enrique Farelo y Pachi Tapiz [Entrevista de jazz] - Tomajazz - El guitarrista Rub\u00e9n Reinaldo ha publicado Fusi\u00f3n Ol\u00edvica (Free Code Jazz Records; 2025), su primera grabaci\u00f3n como l\u00edder. Carlos Lara, Enrique Farelo y Pachi Tapiz lo entrevistan con tal ocasi\u00f3n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/DESTACADA-IMG-0163.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/69936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=69936"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/69936\/revisions"}],"predecessor-version":[{"id":69941,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/69936\/revisions\/69941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/69937"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=69936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=69936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=69936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}