{"id":70756,"date":"2023-02-07T13:06:23","date_gmt":"2023-02-07T12:06:23","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=70756"},"modified":"2023-02-07T13:11:58","modified_gmt":"2023-02-07T12:11:58","slug":"ensemble-interdisciplinari-improject-montmusic-2022-img","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/ensemble-interdisciplinari-improject-montmusic-2022-img\/","title":{"rendered":"Ensemble Interdisciplinari Improject MontMusic \u00abLes quatre estacions\u00bb (6\u00e8 MontMusic Festival \/ Teatre Pare Casals, 2022-12-03. Sant Esteve de Palautordera &#8211; Barcelona-) [III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]"},"content":{"rendered":"<h3><a href=\"http:\/\/montmusicfestival.com\/\" target=\"_blank\" rel=\"noopener\">6\u00e8 MontMusic Festival<\/a><\/h3>\n<h3><strong>Ensemble Interdisciplinari Improject MontMusic<\/strong><\/h3>\n<ul>\n<li>Fecha: S\u00e1bado, 03 de diciembre de 2022<\/li>\n<li>Lugar: Teatre Pare Casals (Sant Esteve Palautordera -Barcelona-)<\/li>\n<li>Componentes:<br \/>\nN\u00faria Andorr\u00e0, percusi\u00f3n<br \/>\nTom Chant, saxo soprano y tenor<br \/>\nMarc Egea, viola de roda o zanfo\u00f1a<br \/>\nRaimon Mol\u00e0, piano<br \/>\nOriol Roca, bater\u00eda<br \/>\nNan\u00e1 Rovira, clarinete bajo<br \/>\nAriadna Torner, viol\u00edn<br \/>\nMiquel Fiol, danza<br \/>\nOna Fust\u00e9, danza<br \/>\nRoberta Legros Stepankova, danza<br \/>\nMaria Mora, danza<br \/>\nAlmudena Pardo, danza<br \/>\nS\u00f2nia S\u00e1nchez, danza<br \/>\nMag\u00ed Serra, danza<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70757\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/01_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/01_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/01_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/01_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70758\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/02_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/02_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/02_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/02_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-366x550.jpg 366w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/02_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-333x500.jpg 333w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70759\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70760\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/04_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/04_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/04_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/04_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-366x550.jpg 366w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/04_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-333x500.jpg 333w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70761\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/05_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/05_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/05_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/05_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70762\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/06_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/06_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/06_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/06_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70763\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/07_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"399\" height=\"600\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/07_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 399w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/07_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-200x300.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/07_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-366x550.jpg 366w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/07_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-333x500.jpg 333w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70764\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/08_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/08_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/08_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/08_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70765\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/09_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/09_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/09_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/09_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70766\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/10_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/10_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/10_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/10_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70767\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/11_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/11_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/11_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/11_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70768\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/12_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/12_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/12_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/12_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70769\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/13_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/13_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/13_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/13_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70770\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/14_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg\" alt=\"\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/14_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/14_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-300x200.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/14_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP-465x309.jpg 465w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <a href=\"https:\/\/www.facebook.com\/joan.cortesbenages\" target=\"_blank\" rel=\"noopener\"><strong>Joan Cort\u00e8s<\/strong><\/a>, 2023<\/p>\n<h4>M\u00e1s informaci\u00f3n<\/h4>\n<blockquote class=\"wp-embedded-content\" data-secret=\"tSG7rDDQwh\"><p><a href=\"https:\/\/tomajazz.com\/web\/sonia-sanchez-montmusic-2022-img\/\">S\u00f2nia S\u00e1nchez \u201cLes ombres del riu\u201d (6\u00e8 MontMusic Festival \/ Riera de la Tordera, 2022-12-03. Sant Esteve de Palautordera -Barcelona-) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abS\u00f2nia S\u00e1nchez \u201cLes ombres del riu\u201d (6\u00e8 MontMusic Festival \/ Riera de la Tordera, 2022-12-03. Sant Esteve de Palautordera -Barcelona-) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/sonia-sanchez-montmusic-2022-img\/embed\/#?secret=FBSDbiZpcU#?secret=tSG7rDDQwh\" data-secret=\"tSG7rDDQwh\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"HZxIOVYrtK\"><p><a href=\"https:\/\/tomajazz.com\/web\/impro-presentacio-6e-montmusic-festival-2022\/\">Impro Presentaci\u00f3 (6\u00e8 MontMusic Festival -presentaci\u00f3-\/ L\u2019Autom\u00e0tica, 2022-11-17. Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abImpro Presentaci\u00f3 (6\u00e8 MontMusic Festival -presentaci\u00f3-\/ L\u2019Autom\u00e0tica, 2022-11-17. Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/impro-presentacio-6e-montmusic-festival-2022\/embed\/#?secret=HArjruW5hJ#?secret=HZxIOVYrtK\" data-secret=\"HZxIOVYrtK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h4>Joan Cort\u00e8s en Tomajazz<\/h4>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17853\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17853<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En INSTANTZZ las im\u00e1genes del Ensemble Interdisciplinari Improject MontMusic \u00abLes quatre estacions\u00bb en el 6\u00e8 MontMusic Festival. Joan Cort\u00e8s fue el autor de las im\u00e1genes, que se tomaron en el Teatre Pare Casals en Sant Esteve de Palautordera de Barcelona. <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/ensemble-interdisciplinari-improject-montmusic-2022-img\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":70765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11261,17853,11262,15516,1038],"tags":[28360,24842,28356,1041,22262,92,20669,28357,25869,28199,12368,9113,28358,1045,26218,28359,6038,1129],"class_list":["entry","author-pachi","has-excerpt","post-70756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-instantzz","category-joan-cortes","category-photoblogs","category-imagenes","category-contenidos","tag-almudena-pardo","tag-ariadna-torner","tag-ensemble-interdisciplinari-improject-montmusic","tag-joan-cortes","tag-magi-serra","tag-marc-egea","tag-maria-mora","tag-miquel-fiol","tag-montmusic-festival","tag-montmusic-festival-2022","tag-nana-rovira","tag-nuria-andorra","tag-ona-fuste","tag-oriol-roca","tag-raimon-mola","tag-roberta-legros-stepankova","tag-sonia-sanchez","tag-tom-chant"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/09_nsmbl-ntrdscplnr-\u00a9Joan-Cortes_03des22_6MMF_TPC_SsP.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":70913,"url":"https:\/\/tomajazz.com\/web\/juguem-la-fava-montmusic-2022\/","url_meta":{"origin":70756,"position":0},"title":"Juguem &#038; La Fava (6\u00e8 MontMusic Festival \/ La Quadra, 2022-12-04. Santa Maria de Palautordera &#8211; Barcelona-) [V] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"11 febrero, 2023","format":false,"excerpt":"Juguem & La Fava participaron en el 6\u00e8 MontMusic Festivalde 2022 en La Quadra, Santa Maria de Palautordera - Barcelona-. Joan Cort\u00e8s retrat\u00f3 a las dos formaciones en su actuaci\u00f3n.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Juguem & La Fava participaron en el 6\u00e8 MontMusic Festivalde 2022 en La Quadra, Santa Maria de Palautordera - Barcelona-. Joan Cort\u00e8s retrat\u00f3 a las dos formaciones en su actuaci\u00f3n.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/002_Jgm-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/002_Jgm-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/002_Jgm-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":70831,"url":"https:\/\/tomajazz.com\/web\/escolta-montmusic-2022-img\/","url_meta":{"origin":70756,"position":1},"title":"Escolta (6\u00e8 MontMusic Festival \/ La Quadra, 2022-12-04. Santa Maria de Palautordera &#8211; Barcelona-) [IV] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"9 febrero, 2023","format":false,"excerpt":"Joan Cort\u00e8s retrata en INSTANTZZ al cuarteto Escolta en su actuaci\u00f3n en el 6\u00e8 MontMusic Festival de 2022, celebrado en Santa Maria de Palautordera, Barcelona.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Joan Cort\u00e8s retrata en INSTANTZZ al cuarteto Escolta en su actuaci\u00f3n en el 6\u00e8 MontMusic Festival de 2022, celebrado en Santa Maria de Palautordera, Barcelona.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_sclt-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_sclt-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/03_sclt-%C2%A9Joan-Cortes_04des22_6MntMscFstvl_L-Qdr_St-Mr-Pltrdr.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":68706,"url":"https:\/\/tomajazz.com\/web\/programa-montmusic-festival-2022\/","url_meta":{"origin":70756,"position":2},"title":"MontMusic Festival 2022 \/ Movimiento, sonido e interacci\u00f3n (Santa Maria de Palautordera, Sant Esteve de Palautordera, Circ Cric. 2 al 4 de diciembre de 2022) [Noticias de Jazz]","author":"Tomajazz","date":"30 noviembre, 2022","format":false,"excerpt":"Entre el 2 y el 4 de diciembre tendr\u00e1 lugar el Montmusic Festival 2022 en Santa Maria de Palautordera, Sant Esteve de Palautordera, Circ Cric.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/"},"img":{"alt_text":"Entre el 2 y el 4 de diciembre tendr\u00e1 lugar el Montmusic Festival 2022 en Santa Maria de Palautordera, Sant Esteve de Palautordera, Circ Cric.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/CartelMontMusicfestival2022.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/CartelMontMusicfestival2022.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/CartelMontMusicfestival2022.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/CartelMontMusicfestival2022.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":81877,"url":"https:\/\/tomajazz.com\/web\/ensemble-montmusic-montmusic-2023\/","url_meta":{"origin":70756,"position":3},"title":"Ensemble MontMusic + Dansa (7\u00e8 MontMusic Festival 2023, Teatre Pare Casals, 2023-11-11. Sant Esteve de Palautordera -Barcelona-) [2\/3] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"23 diciembre, 2023","format":false,"excerpt":"Ensemble MontMusic + Dansa fue una de las propuestas del 7\u00e8 MontMusic Festival. La actuaci\u00f3n tuvo lugar el 11 de noviembre de 2023 en Teatre Pare Casals, en Sant Esteve de Palautordera (Barcelona). Joan Cort\u00e8s retrata la actuaci\u00f3n en INSTANTZZ","rel":"","context":"En \u00ab7\u00e8 MontMusic Festival 2023\u00bb","block_context":{"text":"7\u00e8 MontMusic Festival 2023","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/7e-montmusic-festival-2023\/"},"img":{"alt_text":"Ensemble MontMusic + Dansa (7\u00e8 MontMusic Festival 2023, Teatre Pare Casals, 2023-11-11. Sant Esteve de Palautordera -Barcelona-) [2\/3] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0 - Ensemble MontMusic + Dansa fue una de las propuestas del 7\u00e8 MontMusic Festival. La actuaci\u00f3n tuvo lugar el 11 de noviembre de 2023 en Teatre Pare Casals, en Sant Esteve de Palautordera (Barcelona). Joan Cort\u00e8s retrata la actuaci\u00f3n en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/02-nsmbl-MntMsc-%C2%A9Joan-Cortes-11dsm23-7FMM-TPC-SsP-Ensemble-MontMusic-Dansa-7e-MontMusic-Festival-2023-11-11-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/02-nsmbl-MntMsc-%C2%A9Joan-Cortes-11dsm23-7FMM-TPC-SsP-Ensemble-MontMusic-Dansa-7e-MontMusic-Festival-2023-11-11-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/02-nsmbl-MntMsc-%C2%A9Joan-Cortes-11dsm23-7FMM-TPC-SsP-Ensemble-MontMusic-Dansa-7e-MontMusic-Festival-2023-11-11-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":81967,"url":"https:\/\/tomajazz.com\/web\/eimm-vl-7e-montmusic-festival-2023\/","url_meta":{"origin":70756,"position":4},"title":"EIMM &#038; VL \u00abHomenatge a Marianne Brull\u00bb (7\u00e8 MontMusic Festival 2023, Teatre Pare Casals, 2023-11-11. Sant Esteve de Palautordera -Barcelona-) [3\/3] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"26 diciembre, 2023","format":false,"excerpt":"EIMM (Ensemble Interdisciplinar MontMusic) & VL (Veus Lliures) actuaron en el 7\u00e8 MontMusic Festival, en el Teatre Pare Casals, el 11 de noviembre de 2023, en Sant Esteve de Palautordera de Barcelona, celebrando un \"Homenatge a Marianne Brull\". Con esta tercera entrega Joan Cort\u00e8s termina en INSTANTZZ el especial dedicado\u2026","rel":"","context":"En \u00ab7\u00e8 MontMusic Festival 2023\u00bb","block_context":{"text":"7\u00e8 MontMusic Festival 2023","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/7e-montmusic-festival-2023\/"},"img":{"alt_text":"EIMM & VL (7\u00e8 MontMusic Festival 2023, Teatre Pare Casals, 2023-11-11. Sant Esteve de Palautordera -Barcelona-) [3\/3] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0 - EIMM (Ensemble Interdisciplinar MontMusic) & VL (Veus Lliures) actuaron en el 7\u00e8 MontMusic Festival, en el Teatre Pare Casals, el 11 de noviembre de 2023, en Sant Esteve de Palautordera de Barcelona. Con esta tercera entrega Joan Cort\u00e8s termina en INSTANTZZ el especial dedicado al MontMusic Festival","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/12-nmMM-VL-%C2%A9Joan-Cortes-11nvm23-7MMF-TPC-SsP-EIMM-VL-7e-MontMusic-Festival-Teatre-Pare-Casals-2023-11-11-Barcelona-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/12-nmMM-VL-%C2%A9Joan-Cortes-11nvm23-7MMF-TPC-SsP-EIMM-VL-7e-MontMusic-Festival-Teatre-Pare-Casals-2023-11-11-Barcelona-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/12\/12-nmMM-VL-%C2%A9Joan-Cortes-11nvm23-7MMF-TPC-SsP-EIMM-VL-7e-MontMusic-Festival-Teatre-Pare-Casals-2023-11-11-Barcelona-Por-Joan-Cortes-INSTANTZZ-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":59433,"url":"https:\/\/tomajazz.com\/web\/instantzz-zlatko-kaucic-montmusic-ensemble-inhumankind-self-deification-mont-music-festival-2021-teatre-pare-casals-sant-esteve-de-palautordera-barcelona-2021-10-16-iv\/","url_meta":{"origin":70756,"position":5},"title":"INSTANTZZ: Zlatko Kau\u010di\u010d &#038; Montmusic Ensemble \/ Inhumankind \u201cSelf-Deification\u201d (Mont Music Festival 2021\/ Teatre Pare Casals, Sant Esteve de Palautordera -Barcelona-. 2021-10-16) (IV) [Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Por Joan Cort\u00e8s","author":"Tomajazz","date":"13 diciembre, 2021","format":false,"excerpt":"Zlatko Kau\u010di\u010d & Montmusic Ensemble y Inhumankind \u201cSelf-Deification\u201d son los grupos protagonistas de la cuarta entrega de Joan Cort\u00e8s dedicada al Mont Music Festival 2021.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"INSTANTZZ: Zlatko Kau\u010di\u010d & Montmusic Ensemble \/ Inhumankind \u201cSelf-Deification\u201d (Mont Music Festival 2021\/ Teatre Pare Casals, Sant Esteve de Palautordera -Barcelona-. 2021-10-16) (IV) [Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] Por Joan Cort\u00e8s","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/11_nhmnknd-Joan-Cortes_16oct21_MMF21_Ptr-Pr-Csls_St-stv-Pltrdr.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/11_nhmnknd-Joan-Cortes_16oct21_MMF21_Ptr-Pr-Csls_St-stv-Pltrdr.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/11_nhmnknd-Joan-Cortes_16oct21_MMF21_Ptr-Pr-Csls_St-stv-Pltrdr.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/70756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=70756"}],"version-history":[{"count":3,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/70756\/revisions"}],"predecessor-version":[{"id":70778,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/70756\/revisions\/70778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/70765"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=70756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=70756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=70756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}