{"id":72545,"date":"2023-03-24T19:23:41","date_gmt":"2023-03-24T18:23:41","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=72545"},"modified":"2023-03-24T21:58:07","modified_gmt":"2023-03-24T20:58:07","slug":"itziar-yague-paul-san-martin-jazzx5","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/itziar-yague-paul-san-martin-jazzx5\/","title":{"rendered":"\u00abReckless Blues\u00bb [Itziar Yag\u00fce &#8211; Paul San Mart\u00edn (2023)] Por Pachi Tapiz. JazzX5 #577 [Minipodcast de jazz]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-72546 size-medium\" title=\"Reckless Blues [Itziar Yag\u00fce \u2013 Paul San Mart\u00edn (2023)] Por Pachi Tapiz. JazzX5 #577 [Minipodcast de jazz] Tomajazz 9.0 Itziar Yague Paul San Martin Reckless Blues Live Berlin CafeJazzX5\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-300x300.jpg\" alt=\"Reckless Blues [Itziar Yag\u00fce \u2013 Paul San Mart\u00edn (2023)] Por Pachi Tapiz. JazzX5 #577 [Minipodcast de jazz] Itziar Yague Paul San Martin Reckless Blues Live Berlin CafeJazzX5 Tomajazz 9.0 - En JazzX5 #577, suena la versi\u00f3n del cl\u00e1sico de Bessie Smith, Reckless Blues, interpretado en directo por Itziar Yag\u00fce y Paul San Mart\u00edn. JazzX5 es un podcast de Pachi Tapiz.\" width=\"300\" height=\"300\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-768x768.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5-500x500.jpg 500w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/Itziar-Yague-Paul-San-Martin-Reckless-Blues-Live-Berlin-CafeJazzX5.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00abReckless Blues\u00bb<br \/>\n<strong>Itziar Yag\u00fce &#8211; Paul San Mart\u00edn<\/strong><br \/>\nItziar Yag\u00fce, Paul San Mart\u00edn. Composici\u00f3n por Bessie Smith<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <strong>Pachi Tapiz<\/strong>, 2023<\/p>\n<p>Tema grabado en directo en Caf\u00e9 Berl\u00edn en el concierto presentaci\u00f3n de la nueva grabaci\u00f3n de Itziar Yag\u00fce, <em>Girl Like Me<\/em>. El tema es una composici\u00f3n de Bessie Smith, que como me dijo alguien, en concreto una cantante que tiene muy buen gusto, es \u00abla m\u00e1s grande\u00bb: no puedo estar m\u00e1s de acuerdo.<br \/>\nSe encarg\u00f3 de la grabaci\u00f3n en directo Antonio S\u00e1nchez, mientras que la mezcla y master son obra de Joel Lozano.<\/p>\n<h4>Escuchar \u00abReckless Blues\u00bb: Itziar Yag\u00fce &#8211; Paul San Mart\u00edn<\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.ivoox.com\/player_ej_105141332_6_1.html?c1=2fa295\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>M\u00e1s informaci\u00f3n<\/h3>\n<p><a href=\"https:\/\/www.facebook.com\/itziaryaguemusic\/?locale=es_ES\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/itziaryaguemusic\/?locale=es_ES<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=itziar+yague&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=itziar+yague&amp;submit=Search<\/a><\/p>\n<h3>En anteriores episodios de JazzX5 \/ HDO \/ LODLMA \/ Maltidos Jazztardos \/ Tomajazz Remembers \/JazzX5 Centennial \/ Universos Paralelos\u2026<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"meGmHBFHNh\"><p><a href=\"https:\/\/tomajazz.com\/web\/en-concierto-con-itziar-yague-por-pachi-tapiz-hdo-542-podcast-de-jazz\/\">En concierto con&#8230; Itziar Yag\u00fce. Por Pachi Tapiz. HDO 542 [Podcast de jazz]<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abEn concierto con&#8230; Itziar Yag\u00fce. Por Pachi Tapiz. HDO 542 [Podcast de jazz]\u00bb \u2014 Tomajazz\" src=\"https:\/\/tomajazz.com\/web\/en-concierto-con-itziar-yague-por-pachi-tapiz-hdo-542-podcast-de-jazz\/embed\/#?secret=NwRDvNApyw#?secret=meGmHBFHNh\" data-secret=\"meGmHBFHNh\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h3>M\u00e1s informaci\u00f3n sobre JazzX5<\/h3>\n<p><strong>JazzX5<\/strong>\u00a0es un minipodcast de HDO de la Factor\u00eda Tomajazz presentado, editado y producido por\u00a0<strong>Pachi Tapiz<\/strong>.<\/p>\n<p><strong>JazzX5<\/strong>\u00a0comenz\u00f3 su andadura el 24 de junio de 2019.<\/p>\n<p>Todas las entregas de\u00a0<strong>JazzX5<\/strong>\u00a0est\u00e1n disponibles en\u00a0<strong><a href=\"https:\/\/tomajazz.com\/web\/?cat=23120\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tomajazz.com\/web\/?cat=23120<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.ivoox.com\/jazzx5_bk_list_642835_1.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ivoox.com\/jazzx5_bk_list_642835_1.html<\/a><\/strong>.<\/p>\n<p>Las sugerencias, quejas, felicitaciones, opiniones y el contacto en general en jazzx5 @ tomajazz.com Tambi\u00e9n por WhatsApp en el tel\u00e9fono de contacto.<\/p>\n<h4>JazzX5 y los podcast de Tomajazz en Telegram<\/h4>\n<p>En Tomajazz hemos abierto un canal de\u00a0<strong>Telegram<\/strong>\u00a0para que est\u00e9s al tanto, al instante, de los nuevos podcast. Puedes suscribirte en\u00a0<a href=\"https:\/\/t.me\/TomajazzPodcast\" target=\"_blank\" rel=\"noopener\">https:\/\/t.me\/TomajazzPodcast<\/a>.<\/p>\n<h4>Pachi Tapiz en Tomajazz<\/h4>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17847\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17847<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En JazzX5 #577, suena la versi\u00f3n del cl\u00e1sico de Bessie Smith, \u00abReckless Blues\u00bb, interpretado en directo por Itziar Yag\u00fce y Paul San Mart\u00edn. JazzX5 es un podcast de Pachi Tapiz.<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/itziar-yague-paul-san-martin-jazzx5\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":72547,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[23120,17847,12814,15518,1038],"tags":[7496,26585,23118,25554,31,14117,15310],"class_list":["entry","author-pachi","has-excerpt","post-72545","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jazzx5","category-pachi-tapiz","category-podcast","category-sonidos","category-contenidos","tag-bessie-smith","tag-itziar-yague","tag-jazzx5","tag-minipodcast-de-jazz","tag-pachi-tapiz","tag-paul-san-martin","tag-podcast-de-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/JazzX5-0577.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":68558,"url":"https:\/\/tomajazz.com\/web\/girl-like-me-itziar-yague-jazzx5\/","url_meta":{"origin":72545,"position":0},"title":"\u00abGirl Like Me\u00bb [Itziar Yag\u00fce (Single adelanto nueva grabaci\u00f3n, 2022)] Por Pachi Tapiz. JazzX5 #550 [Minipodcast de jazz]","author":"Tomajazz","date":"22 noviembre, 2022","format":false,"excerpt":"En JazzX5 escuchamos el tema \"Girl Like You\", single adelanto de la nueva grabaci\u00f3n de Itziar Yag\u00fce que se ha publicado el 22 de noviembre de 2022. JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"En JazzX5 escuchamos el tema \"Girl Like You\", single adelanto de la nueva grabaci\u00f3n de Itziar Yag\u00fce que se ha publicado el 22 de noviembre de 2022. JazzX5 es un podcast de Pachi Tapiz.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/JazzX5_0550_OK.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/JazzX5_0550_OK.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/JazzX5_0550_OK.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/11\/JazzX5_0550_OK.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100385,"url":"https:\/\/tomajazz.com\/web\/jazz-sin-fronteras-2025\/","url_meta":{"origin":72545,"position":1},"title":"Jazz sin fronteras: seis viajes sonoros entre el homenaje y la reinvenci\u00f3n. Por Pachi Tapiz [Grabaciones de jazz]","author":"Tomajazz","date":"12 octubre, 2025","format":false,"excerpt":"Jazz sin fronteras: seis viajes sonoros entre el homenaje y la reinvenci\u00f3n. Por Pachi Tapiz. Recalamos en Transcendence: Music of Pat Metheny (FMR Records) \/ Hard Bop Messengers: Live at Old Rock House. Play jazz interpretations of the Grateful Dead. (autoeditado) \/ Obed Calvaire, Bob Franceschini, Kevin Hays, Orlando Le\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Jazz sin fronteras: seis viajes sonoros entre el homenaje y la reinvenci\u00f3n. Por Pachi Tapiz [Grabaciones de jazz] - Tomajazz - Jazz sin fronteras: seis viajes sonoros entre el homenaje y la reinvenci\u00f3n. Por Pachi Tapiz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Jazz-sin-fronteras-Seis-viajes-sonoros-entre-el-homenaje-y-la-reinvencion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Jazz-sin-fronteras-Seis-viajes-sonoros-entre-el-homenaje-y-la-reinvencion-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Jazz-sin-fronteras-Seis-viajes-sonoros-entre-el-homenaje-y-la-reinvencion-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Jazz-sin-fronteras-Seis-viajes-sonoros-entre-el-homenaje-y-la-reinvencion-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61114,"url":"https:\/\/tomajazz.com\/web\/en-concierto-con-itziar-yague-por-pachi-tapiz-hdo-542-podcast-de-jazz\/","url_meta":{"origin":72545,"position":2},"title":"En concierto con&#8230; Itziar Yag\u00fce. Por Pachi Tapiz. HDO 542 [Podcast de jazz]","author":"Tomajazz","date":"14 febrero, 2022","format":false,"excerpt":"En HDO 542 escuchamos a la cantante Itziar Yag\u00fce y presentamos sus pr\u00f3ximos conciertos en Madrid y Sabi\u00f1\u00e1nigo. HDO es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abHDO\u00bb","block_context":{"text":"HDO","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/hablando-de-oidas-hdo\/"},"img":{"alt_text":"En concierto con... Itziar Yag\u00fce HDO 542","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Collage_programa-0542_En-concierto-con-Itziar-Yague.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Collage_programa-0542_En-concierto-con-Itziar-Yague.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Collage_programa-0542_En-concierto-con-Itziar-Yague.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Collage_programa-0542_En-concierto-con-Itziar-Yague.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72552,"url":"https:\/\/tomajazz.com\/web\/paul-san-martin-jazzx5\/","url_meta":{"origin":72545,"position":3},"title":"\u00abWhat Can I Do\u00bb [Paul San Mart\u00edn: A French Session (Gaztelupeko Hotsak &#8211; Big Spoon Records, 2023)] Por Pachi Tapiz. JazzX5 #578 [Minipodcast de jazz]","author":"Tomajazz","date":"25 marzo, 2023","format":false,"excerpt":"En JazzX5 #578 suena una versi\u00f3n del tema \"What Can I Do\" de Charles \"Hungry\" Williams que aparece en la grabaci\u00f3n de Paul San Mart\u00edn, A French Session (Gaztelupeko Hotsak - Big Spoon Records, 2023). JazzX5 es un podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"What Can I Do [Paul San Mart\u00edn: A French Session (Gaztelupeko Hotsak &#8211; Big Spoon Records, 2023)] Por Pachi Tapiz. JazzX5 #578 [Minipodcast de jazz] - Tomajazz 9.0 -","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/JazzX5-0578.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/JazzX5-0578.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/JazzX5-0578.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/03\/JazzX5-0578.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49714,"url":"https:\/\/tomajazz.com\/web\/primera-entrega-de-jazz-on-lockdown-jazz-en-contencion-noticias-yomequedoencasa-istayathome\/","url_meta":{"origin":72545,"position":4},"title":"Primera entrega de Jazz On Lockdown &#8211; Jazz en contenci\u00f3n [Noticias] #YoMeQuedoEnCasa \/ #IStayAtHome","author":"Tomajazz","date":"15 marzo, 2020","format":false,"excerpt":"Ya est\u00e1 disponible la primera tanda de conciertos del proyecto Jazz On Lockdown - Jazz en contenci\u00f3n, con m\u00fasica de Pablo Mart\u00edn Caminero Quintet, Tressit, Gnawa Collective, Manolo Pereira Tr\u00edo, Itziar Yag\u00fce Tr\u00edo y David Regueiro Tr\u00edo. #YoMeQuedoEnCasa \/ #IStayAtHome","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/03\/Jazz-On-Lockdown.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/03\/Jazz-On-Lockdown.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/03\/Jazz-On-Lockdown.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/03\/Jazz-On-Lockdown.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":59493,"url":"https:\/\/tomajazz.com\/web\/jazzx5363-o-sister-the-boswell-sisters-song-nobody-cares-blue-asteroid-records-2020-minipodcast-de-jazz-por-pachi-tapiz\/","url_meta":{"origin":72545,"position":5},"title":"JazzX5#363. O Sister!: \u00abThe Boswell Sisters Song\u00bb [Nobody Cares (Blue Asteroid Records, 2020)] [Minipodcast de jazz] Por Pachi Tapiz","author":"Tomajazz","date":"14 diciembre, 2021","format":false,"excerpt":"En JazzX5 el homenaje de O Sister!: \"The Boswell Sisters Song\" que aparec\u00eda en Nobody Cares (Blue Asteroid Records, 2020). JazzX5 es un Podcast de Pachi Tapiz.","rel":"","context":"En \u00abJazzX5\u00bb","block_context":{"text":"JazzX5","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/sonidos\/podcast\/jazzx5\/"},"img":{"alt_text":"JazzX5#363. O Sister!: \"The Boswell Sisters Song\" [Nobody Cares (Blue Asteroid Records, 2020)] [Minipodcast de jazz] Por Pachi Tapiz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_363.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_363.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_363.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/12\/JazzX5_363.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=72545"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72545\/revisions"}],"predecessor-version":[{"id":72551,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72545\/revisions\/72551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/72547"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=72545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=72545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=72545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}