{"id":72878,"date":"2023-04-06T12:00:25","date_gmt":"2023-04-06T10:00:25","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=72878"},"modified":"2023-04-05T22:14:56","modified_gmt":"2023-04-05T20:14:56","slug":"impro-homenaje-a-marianne-brull","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/impro-homenaje-a-marianne-brull\/","title":{"rendered":"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz]"},"content":{"rendered":"<h3>Impro homenaje a Marianne Brull<\/h3>\n<p>El programa \u201cClub de Jazz\u201d de Carlos P\u00e9rez Cruz, verso singular de la audiodifusi\u00f3n musical estatal, rinde recuerdo y homenaje a Marianne Brull, la gran dama libertaria de la m\u00fasica Impro de la escena catalana, que falleci\u00f3 el pasado 8 de marzo, cinco semanas antes de cumplir ochenta y ocho a\u00f1os. Nacida en Suiza, ciudadana parisina y finalmente barcelonesa, resid\u00eda desde hace unas tres d\u00e9cadas en el popular y bullicioso barrio de Poble Sec. Fue uno de los pulmones b\u00e1sicos de Ruedo Ib\u00e9rico (1961-1982), editorial antifranquista, entre otros antis, y en la primera d\u00e9cada del dos mil promovi\u00f3 la web <a href=\"http:\/\/www.ruedoiberico.org\" target=\"_blank\" rel=\"noopener\">www.ruedoiberico.org<\/a><\/p>\n<p><figure id=\"attachment_72879\" aria-describedby=\"caption-attachment-72879\" style=\"width: 868px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-72879 size-full\" title=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] Tomajazz 9.0 M1 Marianne Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio 15 de abril de 2023 Centro Cultural Albareda de Poble Sec Por Joan Cortes Noticias de jazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg\" alt=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] - Tomajazz 9.0 - El pr\u00f3ximo s\u00e1bado 15 de abril, a las 19h, en el Centro Cultural Albareda de Poble Sec, improvisaran seis de los m\u00fasicos que m\u00e1s encandilaban a Marianne Brull, repartidos en dos formaciones, LIQUID TRIO, con Agust\u00ed Fern\u00e1ndez al piano, Albert Cirera\u00a0 a los saxos y Ramon Prats a la bater\u00eda, y MARS TRIO, con la pianista Jordina Mill\u00e0 (la ni\u00f1a de sus ojos), las percusiones de N\u00faria Andorr\u00e0 y el baile de S\u00f2nia S\u00e1nchez (la bruja como a veces la llamaba). Y, a lo mejor, un ensemble con los seis improvisadores como punto final.\" width=\"868\" height=\"236\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg 868w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--300x82.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--600x163.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--768x209.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--465x126.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--695x189.jpg 695w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/><figcaption id=\"caption-attachment-72879\" class=\"wp-caption-text\">Marianne Brull \u2022 Jordina Mill\u00e0 \u2022 S\u00f2nia S\u00e1nchez<\/figcaption><\/figure><em>\u201c\u2026 en la fabricaci\u00f3n de libros, peque\u00f1as botellas en el mar de la incultura de entonces, grandes mensajes en el desierto ideol\u00f3gico que hab\u00eda sido el franquismo, la confusi\u00f3n que fue el antifranquismos, el p\u00e1ramo pol\u00edtico que ha sido luego la Transici\u00f3n (que bonito nombre para algo que no lleg\u00f3 a ser \u00e9poca, simplemente per\u00edodo, bisagra, intermediaci\u00f3n)\u2026\u201d (G\u00e9rard Imbert Mart\u00ed\/2010)<\/em><\/p>\n<p>Mujer \u00e1crata, de pensamiento y actitud, amante de la cultura (en un sentido amplio, m\u00fasica, lectura -ensayo y literatura-, pintura, fotograf\u00eda, gastronom\u00eda, \u2026), fumadora empedernida, singularmente elegante, cr\u00edtica argumentada, afable y sensible. Tejedora de complicidades y aglutinadora comunitaria.<\/p>\n<p><figure id=\"attachment_72880\" aria-describedby=\"caption-attachment-72880\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-72880\" title=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] Tomajazz 9.0 M2 Mars muntatge Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio 15 de abril de 2023 Centro Cultural Albareda de Poble Sec Por Joan Cortes Noticias de jazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg\" alt=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] - Tomajazz 9.0 - El pr\u00f3ximo s\u00e1bado 15 de abril, a las 19h, en el Centro Cultural Albareda de Poble Sec, improvisaran seis de los m\u00fasicos que m\u00e1s encandilaban a Marianne Brull, repartidos en dos formaciones, LIQUID TRIO, con Agust\u00ed Fern\u00e1ndez al piano, Albert Cirera\u00a0 a los saxos y Ramon Prats a la bater\u00eda, y MARS TRIO, con la pianista Jordina Mill\u00e0 (la ni\u00f1a de sus ojos), las percusiones de N\u00faria Andorr\u00e0 y el baile de S\u00f2nia S\u00e1nchez (la bruja como a veces la llamaba). Y, a lo mejor, un ensemble con los seis improvisadores como punto final.\" width=\"1024\" height=\"236\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg 1024w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--300x69.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--600x138.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--768x177.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--465x107.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M2-Mars-muntatge-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--695x160.jpg 695w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-72880\" class=\"wp-caption-text\">N\u00faria Andorr\u00e0 \u2022 Jordina Mill\u00e0 \u2022 S\u00f2nia S\u00e1nchez<\/figcaption><\/figure>Militante de las sesiones de m\u00fasica Impro, desde los lejanos encuentros de los IBA -Improvisadors de Barcelona Associats-, que se reun\u00edan, en el intercambio de siglo, todos los lunes en el peque\u00f1o club JazzS\u00ed del Taller de M\u00fasics, hasta las m\u00e1s recientes sesiones de impro de los martes, en el comedor popular del Ateneu de La Base, donde ella confeccionaba a su gusto y criterio, que no era precisamente pocos, las formaciones que iba programando, que a su vez nos publicitaba por internet. Sin olvidar las free sessions de Robadors 23, que como nos recordaba el saxofonista Albert Cirera, en m\u00e1s de una ocasi\u00f3n, hab\u00eda sido la \u00fanica, privilegiada y siempre cr\u00edtica oyente.<\/p>\n<p><figure id=\"attachment_72881\" aria-describedby=\"caption-attachment-72881\" style=\"width: 825px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-72881\" title=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] Tomajazz 9.0 M3 Liquid Trio Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio 15 de abril de 2023 Centro Cultural Albareda de Poble Sec Por Joan Cortes Noticias de jazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg\" alt=\"Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio (15 de abril de 2023. Centro Cultural Albareda de Poble Sec) Por Joan Cort\u00e8s [Noticias de jazz] - Tomajazz 9.0 - El pr\u00f3ximo s\u00e1bado 15 de abril, a las 19h, en el Centro Cultural Albareda de Poble Sec, improvisaran seis de los m\u00fasicos que m\u00e1s encandilaban a Marianne Brull, repartidos en dos formaciones, LIQUID TRIO, con Agust\u00ed Fern\u00e1ndez al piano, Albert Cirera\u00a0 a los saxos y Ramon Prats a la bater\u00eda, y MARS TRIO, con la pianista Jordina Mill\u00e0 (la ni\u00f1a de sus ojos), las percusiones de N\u00faria Andorr\u00e0 y el baile de S\u00f2nia S\u00e1nchez (la bruja como a veces la llamaba). Y, a lo mejor, un ensemble con los seis improvisadores como punto final.\" width=\"825\" height=\"236\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg 825w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--300x86.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--600x172.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--768x220.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--465x133.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M3-Liquid-Trio-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz--695x199.jpg 695w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><figcaption id=\"caption-attachment-72881\" class=\"wp-caption-text\">Marianne Brull \u2022 Albert Cirera \u2022 Agust\u00ed Fern\u00e1ndez \u2022 Albert Cirera \u2022 Ramon Prats<\/figcaption><\/figure>El pr\u00f3ximo s\u00e1bado 15 de abril, a las 19h, en el Centro Cultural Albareda de Poble Sec, improvisaran seis de los m\u00fasicos que m\u00e1s encandilaban a Marianne Brull, repartidos en dos formaciones, LIQUID TRIO, con Agust\u00ed Fern\u00e1ndez al piano, Albert Cirera\u00a0 a los saxos y Ramon Prats a la bater\u00eda, y MARS TRIO, con la pianista Jordina Mill\u00e0 (la ni\u00f1a de sus ojos), las percusiones de N\u00faria Andorr\u00e0 y el baile de S\u00f2nia S\u00e1nchez (la bruja como a veces la llamaba). Y, a lo mejor, un ensemble con los seis improvisadores como punto final.<\/p>\n<p>Los precios de la velada, muy m\u00f3dicos, son de 7\u20ac para los no socios del programa y de 3\u20ac para los socios. La recaudaci\u00f3n ser\u00e1 para cubrir los gastos del alquiler del piano, el t\u00e9cnico de sonido y los viajes. Los seis m\u00fasicos participan desinteresadamente.<\/p>\n<p style=\"text-align: right;\">Fotograf\u00edas y texto: \u00a9 <a href=\"https:\/\/www.facebook.com\/joan.cortesbenages\" target=\"_blank\" rel=\"noopener\"><strong>Joan Cort\u00e8s<\/strong><\/a>, 2023<\/p>\n<h3>M\u00e1s informaci\u00f3n sobre la Impro homenaje a Marianne Brull con Liquid Trio y Mars Trio<\/h3>\n<p><a href=\"https:\/\/ajuntament.barcelona.cat\/ccivics\/albareda\/p\/52009\/marianne-brull-la-dona-lliure-\" target=\"_blank\" rel=\"noopener\">https:\/\/ajuntament.barcelona.cat\/ccivics\/albareda\/p\/52009\/marianne-brull-la-dona-lliure-<\/a><\/p>\n<h3>Joan Cort\u00e8s en Tomajazz<\/h3>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17853\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17853<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 15 de abril, a las 19h, en el Centro Cultural Albareda de Poble Sec, se realizar\u00e1 una Impro Homenaje a Marianne Brull. En ella improvisaran seis de los m\u00fasicos que m\u00e1s encandilaban a Marianne Brull, repartidos en dos formaciones, LIQUID TRIO, con Agust\u00ed Fern\u00e1ndez al piano, Albert Cirera\u00a0 a los saxos y Ramon Prats a la bater\u00eda, y MARS TRIO, con la pianista Jordina Mill\u00e0 (la ni\u00f1a de sus ojos), las percusiones de N\u00faria Andorr\u00e0 y el baile de S\u00f2nia S\u00e1nchez (la bruja como a veces la llamaba). Y, a lo mejor, un ensemble con los seis improvisadores como punto final.<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/impro-homenaje-a-marianne-brull\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":72879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15795,17853,1038],"tags":[1041,16959],"class_list":["entry","author-pachi","has-excerpt","post-72878","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-2","category-joan-cortes","category-contenidos","tag-joan-cortes","tag-marianne-brull"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/M1-Marianne-Impro-homenaje-a-Marianne-Brull-con-Liquid-Trio-y-Mars-Trio-15-de-abril-de-2023-Centro-Cultural-Albareda-de-Poble-Sec-Por-Joan-Cortes-Noticias-de-jazz-.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":74074,"url":"https:\/\/tomajazz.com\/web\/recordant-marianne-brull-2023-2\/","url_meta":{"origin":72878,"position":0},"title":"Recordant Marianne Brull \u201cNou Impros\u201d (Ateneu Cooperatiu La Base, 2023-04-02. Barcelona) [segunda parte] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"23 mayo, 2023","format":false,"excerpt":"Recordant Marianne Brull \u201cNou Impros\u201d es el homenaje de los improvisadores de Barcelona a Marianne Brull. Joan Cort\u00e8s retrata en INSTANTZZ la segunda y \u00faltima parte del homenaje a la gran dama de la improvisaci\u00f3n.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Recordant Marianne Brull \u201cNou Impros\u201d (Ateneu Cooperatiu La Base, 2023-04-02. Barcelona) [segunda parte] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0 - Recordant Marianne Brull \u201cNou Impros\u201d es el homenaje de los improvisadores de Barcelona a Marianne Brull. Joan Cort\u00e8s retrata en INSTANTZZ la segunda y \u00faltima parte del homenaje a la gran dama de la improvisaci\u00f3n.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/36-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-2-Joan-Cortes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/36-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-2-Joan-Cortes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/36-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-2-Joan-Cortes.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":74024,"url":"https:\/\/tomajazz.com\/web\/recordant-marianne-brull-2023-1\/","url_meta":{"origin":72878,"position":1},"title":"Recordant Marianne Brull \u201cNou Impros\u201d (Ateneu Cooperatiu La Base, 2023-04-02. Barcelona) [primera parte] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"19 mayo, 2023","format":false,"excerpt":"Recordant Marianne Brull \u201cNou Impros\u201d es el homenaje de los improvisadores de Barcelona a Marianne Brull. Joan Cort\u00e8s retrata en INSTANTZZ el homenaje a la gran dama de la improvisaci\u00f3n, con la participaci\u00f3n, entre otros, de Agust\u00ed Fern\u00e1ndez, Ramon Prats, Marco Mezquida o S\u00f2nia S\u00e1nchez, entre otros.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Recordant Marianne Brull \u201cNou Impros\u201d (Ateneu Cooperatiu La Base, 2023-04-02. Barcelona) [primera parte] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/20-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-1-Joan-Cortes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/20-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-1-Joan-Cortes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/05\/20-Mrnn-Brll-n-Mmrn-%C2%A9Joan-Cortes-02brl23-tn-L-Bs-Bcn-Recordant-Marianne-Brull-Nou-Impros-2023-04-02-Barcelona-parte-1-Joan-Cortes.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":63750,"url":"https:\/\/tomajazz.com\/web\/marianne-brull-87-aniversario-menjador-de-lateneu-cooperatiu-la-base-barcelona-2022-04-05-i-ii-por-joan-cortes-instantzz-aka-galeria-fotografica-aka-fotoblog-de-jazz-impro-y\/","url_meta":{"origin":72878,"position":2},"title":"Marianne Brull 87 aniversario (Menjador de l\u2019Ateneu Cooperatiu La Base, Barcelona. 2022-04-05) -I\/II- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"26 mayo, 2022","format":false,"excerpt":"Marianne Brull, y la celebraci\u00f3n de su 87 cumplea\u00f1os junto a m\u00fasicos como Agust\u00ed Fern\u00e1ndez, Albert Cirera, Liba Villavecchia, S\u00f2nia S\u00e1nchez, N\u00faria Andorr\u00e0 o Jordina Mill\u00e0 es la protagonista de INSTANTZZ. Joan Cort\u00e8s fue el autor de la galer\u00eda fotogr\u00e1fica. En Tomajazz publicamos la primera entrega de este homenaje a\u2026","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Marianne Brull 87 aniversario (Menjador de l\u2019Ateneu Cooperatiu La Base, Barcelona. 2022-04-05) -I\/II- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] 02 Mrnn Brll 87 \u00a9Joan Cortes 05brl22 Mnjdr tn Cprt l Bs Bcn Tomajazz 9.0 - Marianne Brull, y la celebraci\u00f3n de su 87 cumplea\u00f1os junto a m\u00fasicos como Agust\u00ed Fern\u00e1ndez, Albert Cirera, Liba Villavecchia, S\u00f2nia S\u00e1nchez, N\u00faria Andorr\u00e0 o Jordina Mill\u00e0 es la protagonista de INSTANTZZ. Joan Cort\u00e8s fue el autor de la galer\u00eda fotogr\u00e1fica. En Tomajazz publicamos la primera entrega de este homenaje a esta veterana aficionada a la m\u00fasica improvisada.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/05\/02_Mrnn-Brll-87-%C2%A9Joan-Cortes_05brl22_Mnjdr-tn-Cprt-l-Bs_Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":63772,"url":"https:\/\/tomajazz.com\/web\/marianne-brull-87-aniversario-menjador-de-lateneu-cooperatiu-la-base-barcelona-2022-04-05-ii-ii-por-joan-cortes-instantzz-aka-galeria-fotografica-aka-fotoblog-de-jazz-impro-y\/","url_meta":{"origin":72878,"position":3},"title":"Marianne Brull 87 aniversario (Menjador de l\u2019Ateneu Cooperatiu La Base, Barcelona. 2022-04-05) -II\/II- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"28 mayo, 2022","format":false,"excerpt":"Publicamos en INSTANTZZ la segunda parte de la celebraci\u00f3n del 87\u00ba cumplea\u00f1os de Marianne Brull. Joan Cort\u00e8s es el autor de la galer\u00eda fotogr\u00e1fica.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Marianne Brull 87 aniversario (Menjador de l\u2019Ateneu Cooperatiu La Base, Barcelona. 2022-04-05) -I\/II- Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] 20 Mrnn Brll 87 \u00a9Joan Cortes 05brl22 Mnjdr tn Cprt l Bs Bcn Tomajazz 9.0 - Marianne Brull, y la celebraci\u00f3n de su 87 cumplea\u00f1os junto a m\u00fasicos como Agust\u00ed Fern\u00e1ndez, Albert Cirera, Liba Villavecchia, S\u00f2nia S\u00e1nchez, N\u00faria Andorr\u00e0 o Jordina Mill\u00e0 es la protagonista de INSTANTZZ. Joan Cort\u00e8s fue el autor de la galer\u00eda fotogr\u00e1fica. En Tomajazz publicamos la primera entrega de este homenaje a esta veterana aficionada a la m\u00fasica improvisada.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/05\/20_Mrnn-Brll-87-%C2%A9Joan-Cortes_05brl22_Mnjdr-tn-Cprt-l-Bs_Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/05\/20_Mrnn-Brll-87-%C2%A9Joan-Cortes_05brl22_Mnjdr-tn-Cprt-l-Bs_Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/05\/20_Mrnn-Brll-87-%C2%A9Joan-Cortes_05brl22_Mnjdr-tn-Cprt-l-Bs_Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":86595,"url":"https:\/\/tomajazz.com\/web\/felix-chant-faraldo-3r-nu-vilafranca-2024\/","url_meta":{"origin":72878,"position":4},"title":"F\u00e8lix-Chant-Faraldo \u201cHomenatge a Marianne Brull\u201d (3r Nu -cicle de m\u00fasica i vins nus-, Capella St. Joan, 2024-04-24. Vilafranca del Pened\u00e8s -Barcelona-) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"18 mayo, 2024","format":false,"excerpt":"El tr\u00edo F\u00e8lix-Chant-Faraldo realiz\u00f3 un \u201cHomenatge a Marianne Brull\u201d en el 3r Nu -cicle de m\u00fasica i vins nus-, en Vilafranca del Pened\u00e8s -Barcelona-, el 24 de abril de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron M\u00edriam F\u00e8lix, \u00c1ngel Faraldo, Tom Chant","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"F\u00e8lix-Chant-Faraldo \u201cHomenatge a Marianne Brull\u201d (3r Nu -cicle de m\u00fasica i vins nus-, Capella St. Joan, 2024-04-24. Vilafranca del Pened\u00e8s -Barcelona-) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - El tr\u00edo F\u00e8lix-Chant-Faraldo realiz\u00f3 un \u201cHomenatge a Marianne Brull\u201d en el 3r Nu -cicle de m\u00fasica i vins nus-, en Vilafranca del Pened\u00e8s -Barcelona-, el 24 de abril de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron M\u00edriam F\u00e8lix, \u00c1ngel Faraldo, Tom Chant\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/destacada-Felix-Chant-Faraldo-Vilafranca-del-Penedes-Tomajazz-Photo-by-Joan-Cortes-2024-005.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":87633,"url":"https:\/\/tomajazz.com\/web\/joni-sigil-vasco-trilla-la-garriga-2024\/","url_meta":{"origin":72878,"position":5},"title":"Joni Sigil &#038; Vasco Trilla \u201cHomenatge a Marianne Brull\u201d (13\u00e8 Festival de Jazz de la Garriga, Llibreria Strogoff, 2024-05-24. La Garriga -Barcelona- [III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"2 julio, 2024","format":false,"excerpt":"Joni Sigil & Vasco Trilla realizaron un \u201cHomenatge a Marianne Brull\u201d en el 13\u00e8 Festival de Jazz de la Garriga, el 24 de mayo de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab13 Festival de Jazz de la Garriga 2024\u00bb","block_context":{"text":"13 Festival de Jazz de la Garriga 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/13-festival-de-jazz-de-la-garriga-2024\/"},"img":{"alt_text":"Joni Sigil & Vasco Trilla \u201cHomenatge a Marianne Brull\u201d (13\u00e8 Festival de Jazz de la Garriga, Llibreria Strogoff, 2024-05-24. La Garriga -Barcelona- [III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Joni Sigil & Vasco Trilla realizaron un \u201cHomenatge a Marianne Brull\u201d en el 13\u00e8 Festival de Jazz de la Garriga, el 24 de mayo de 2024. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/destacada-Joni-Sigil-Vasco-Trilla-La-Garriga-2024-Tomajazz-Photo-by-Joan-Cortes-2024-003-copia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/destacada-Joni-Sigil-Vasco-Trilla-La-Garriga-2024-Tomajazz-Photo-by-Joan-Cortes-2024-003-copia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/destacada-Joni-Sigil-Vasco-Trilla-La-Garriga-2024-Tomajazz-Photo-by-Joan-Cortes-2024-003-copia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=72878"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72878\/revisions"}],"predecessor-version":[{"id":72888,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/72878\/revisions\/72888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/72879"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=72878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=72878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=72878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}