{"id":73184,"date":"2023-04-23T14:17:40","date_gmt":"2023-04-23T12:17:40","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=73184"},"modified":"2024-10-27T13:27:52","modified_gmt":"2024-10-27T12:27:52","slug":"nu2-juan-sebastian-bar-huesca-2023-news","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/nu2-juan-sebastian-bar-huesca-2023-news\/","title":{"rendered":"NU2 (Baldo Mart\u00ednez &#8211; Juan Saiz) en concierto (Juan Sebasti\u00e1n Bar, Huesca. 2023-04-27) [Noticias de jazz]"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-73185\" title=\"NU2 (Baldo Mart\u00ednez \u2013 Juan Saiz) en concierto (Juan Sebasti\u00e1n Bar, Huesca. 2023-04-27) [Noticias de jazz] Tomajazz 9.0 NU2 Baldo Martinez Juan Saiz @ Juan Sebastian Bar Huesca Jueves 27 de abril de 2023 20 23 horas NEWS Tomajazz com\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com-425x600.jpg\" alt=\"NU2 (Baldo Mart\u00ednez \u2013 Juan Saiz) en concierto (Juan Sebasti\u00e1n Bar, Huesca. 2023-04-27) [Noticias de jazz] - Tomajazz 9.0 - El jueves 27 de abril a las 20:30 actuar\u00e1 NU2 (Baldo Mart\u00ednez, Juan Saiz), en Juan Sebasti\u00e1n Bar de Huesca.\" width=\"425\" height=\"600\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com-425x600.jpg 425w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com-212x300.jpg 212w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com-389x550.jpg 389w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com-354x500.jpg 354w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com.jpg 566w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n<p>El jueves 27 de abril a las 20:30 actuar\u00e1 NU2 (Baldo Mart\u00ednez, Juan Saiz), en Juan Sebasti\u00e1n Bar de Huesca (Calle Rold\u00e1n, 27).<br \/>\nEntrada 8 euros. Consumici\u00f3n m\u00ednima 2&#8217;50 euros.<\/p>\n<h3>M\u00e1s informaci\u00f3n\u00a0sobre\u00a0Juan Sebasti\u00e1n Bar<\/h3>\n<p><a href=\"https:\/\/www.facebook.com\/lorenzo.casajusibor\/?locale=es_ES\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/lorenzo.casajusibor\/?locale=es_ES<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=juan+sebastian+bar&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=juan+sebastian+bar&amp;submit=Search<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 27 de abril a las 20:30 actuar\u00e1 NU2 (Baldo Mart\u00ednez, Juan Saiz), en Juan Sebasti\u00e1n Bar de Huesca.<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/nu2-juan-sebastian-bar-huesca-2023-news\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":73185,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15795,17858,30743,1038],"tags":[14449],"class_list":["entry","author-pachi","has-excerpt","post-73184","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-2","category-redaccion","category-juan-sebastian-bar-huesca","category-contenidos","tag-juan-sebastian-bar"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-Baldo-Martinez-Juan-Saiz-@-Juan-Sebastian-Bar-Huesca-Jueves-27-de-abril-de-2023-20-23-horas-NEWS-Tomajazz-com.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":73377,"url":"https:\/\/tomajazz.com\/web\/nu2-juan-saiz-baldo-martinez-huesca-2023\/","url_meta":{"origin":73184,"position":0},"title":"NU2 (Juan Saiz &#8211; Baldo Mart\u00ednez) (Juan Sebasti\u00e1n Bar, Huesca. 2023-04-27) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"30 abril, 2023","format":false,"excerpt":"NU2 (Juan Saiz - Baldo Mart\u00ednez) actuaron en Juan Sebasti\u00e1n Bar de Huesca, el pasado 27 de abril de 2023-04-27. Fabio Galicia retrata el concierto en INSTANTZZ.","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"NU2 (Juan Saiz - Baldo Mart\u00ednez) (Juan Sebasti\u00e1n Bar, Huesca. 2023-04-27) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz 9.0 - NU2 (Juan Saiz - Baldo Mart\u00ednez) actuaron en Juan Sebasti\u00e1n Bar de Huesca, el pasado 27 de abril de 2023-04-27. Fabio Galicia retrata el concierto en INSTANTZZ.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/04\/NU2-28-NU2-Juan-Saiz-Baldo-Martinez-Juan-Sebastian-Bar-Huesca-2023-04-27-Por-Fabio-Galicia-INSTANTZZ.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":90405,"url":"https:\/\/tomajazz.com\/web\/pm4et-juan-sebastian-bar-huesca-2024\/","url_meta":{"origin":73184,"position":1},"title":"Pablo Maza 4et en Juan Sebasti\u00e1n Bar (Huesca. 17 de octubre de 2024) [Noticias de jazz]","author":"Tomajazz","date":"13 octubre, 2024","format":false,"excerpt":"Pablo Mazz 4et actuar\u00e1 el jueves 17 de octubre de 2024 a las 20:30 en Juan Sebasti\u00e1n Bar de Huesca #FestivalDeJazz #Festivalesdejazz #Noticiasdejazz","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/"},"img":{"alt_text":"Pablo Maza 4et en Juan Sebasti\u00e1n Bar (Huesca. 17 de octubre de 2024) [Noticias de jazz] - Tomajazz - Pablo Mazz 4et actuar\u00e1 el jueves 17 de octubre de 2024 a las 20:30 en Juan Sebasti\u00e1n Bar de Huesca #FestivalDeJazz #Festivalesdejazz #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/Pablo-Maza-4et-Juan-Sebastian-Bar-2024-10-17-Noticias-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/Pablo-Maza-4et-Juan-Sebastian-Bar-2024-10-17-Noticias-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/Pablo-Maza-4et-Juan-Sebastian-Bar-2024-10-17-Noticias-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":71197,"url":"https:\/\/tomajazz.com\/web\/vessel-trio-juan-sebastian-bar-huesca-2023\/","url_meta":{"origin":73184,"position":2},"title":"Vessel Trio (Juan Sebasti\u00e1n Bar, Huesca. 2023-02-23) [Noticias de jazz]","author":"Tomajazz","date":"19 febrero, 2023","format":false,"excerpt":"El jueves 23 de febrero de 2023 a las 20:30 actuar\u00e1 Vessel Trio en Juan Sebasti\u00e1n Bar (C\/Rold\u00e1n, 27) de Huesca.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/"},"img":{"alt_text":"Vessel Trio Juan Sebastian Bar Huesca 2023-02-23","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Vessel-Trio-Juan-Sebastian-Bar-Huesca-2023-02-23WEB.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Vessel-Trio-Juan-Sebastian-Bar-Huesca-2023-02-23WEB.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Vessel-Trio-Juan-Sebastian-Bar-Huesca-2023-02-23WEB.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Vessel-Trio-Juan-Sebastian-Bar-Huesca-2023-02-23WEB.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":95204,"url":"https:\/\/tomajazz.com\/web\/roca-falcon-trujillo-juan-sebastian-bar-2025-nws\/","url_meta":{"origin":73184,"position":3},"title":"Roca &#8211; Falc\u00f3n &#8211; Trujillo en Juanse (Juan Sebasti\u00e1n Bar. Huesca. 27 de marzo de 2025) [Noticias de jazz]","author":"Tomajazz","date":"21 marzo, 2025","format":false,"excerpt":"El tr\u00edo Roca - Falc\u00f3n - Trujillo actuar\u00e1 en Juan Sebasti\u00e1n Bar de Huesca el 27 de marzo de 2025 #Noticiasdejazz","rel":"","context":"En \u00abJuan Sebasti\u00e1n Bar (Huesca)\u00bb","block_context":{"text":"Juan Sebasti\u00e1n Bar (Huesca)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/juan-sebastian-bar-huesca\/"},"img":{"alt_text":"Roca - Falc\u00f3n - Trujillo en Juanse (Juan Sebasti\u00e1n Bar. Huesca. 27 de marzo de 2025) [Noticias de jazz] - Tomajazz - El tr\u00edo Roca - Falc\u00f3n - Trujillo actuar\u00e1 en en Juan Sebasti\u00e1n Bar: 27 de marzo de 2025 a las 20:30","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/03\/Roca-Falcon-Trujillo-Juan-Sebastian-Bar-Juanse-20250327-noticias-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/03\/Roca-Falcon-Trujillo-Juan-Sebastian-Bar-Juanse-20250327-noticias-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/03\/Roca-Falcon-Trujillo-Juan-Sebastian-Bar-Juanse-20250327-noticias-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/03\/Roca-Falcon-Trujillo-Juan-Sebastian-Bar-Juanse-20250327-noticias-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":71487,"url":"https:\/\/tomajazz.com\/web\/implositions-juan-sebastian-bar-huesca-2023-03-02-noticias-de-jazz\/","url_meta":{"origin":73184,"position":4},"title":"Implositions  (Juan Sebasti\u00e1n Bar, Huesca. 2023-03-02) [Noticias de jazz]","author":"Tomajazz","date":"27 febrero, 2023","format":false,"excerpt":"El jueves 2 de marzo de 2023 a las 20:30 actuar\u00e1 el tr\u00edo Implositions en Juan Sebasti\u00e1n Bar.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/noticias-2\/"},"img":{"alt_text":"El jueves 2 de febrero de 2023 a las 20:30 actuar\u00e1 el tr\u00edo Implositions en Juan Sebasti\u00e1n Bar.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Implositions-Juan-Sebastian-Bar-2023-03-02WEB.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Implositions-Juan-Sebastian-Bar-2023-03-02WEB.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Implositions-Juan-Sebastian-Bar-2023-03-02WEB.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2023\/02\/Implositions-Juan-Sebastian-Bar-2023-03-02WEB.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":90658,"url":"https:\/\/tomajazz.com\/web\/pablo-maza-4tet-juanse-2024\/","url_meta":{"origin":73184,"position":5},"title":"Pablo Maza 4tet (Juan Sebasti\u00e1n Bar, Huesca. 2024-10-17) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"20 octubre, 2024","format":false,"excerpt":"Pablo Maza 4tet actu\u00f3 en el Juan Sebasti\u00e1n Bar de Huesca, el 17 de octubre de 2024. Fabio Galicia retrata el concierto en INSTANTZZ. Actuaron Pablo Maza, Eneko Di\u00e9guez, Jorgito, Eneko Arbea","rel":"","context":"En \u00abJuan Sebasti\u00e1n Bar (Huesca)\u00bb","block_context":{"text":"Juan Sebasti\u00e1n Bar (Huesca)","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/juan-sebastian-bar-huesca\/"},"img":{"alt_text":"Pablo Maza 4tet  (Juan Sebasti\u00e1n Bar, Huesca. 2024-10-17) Por Fabio Galicia [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Pablo Maza 4tet  actu\u00f3 en el Juan Sebasti\u00e1n Bar de Huesca, el 17 de octubre de 2024. Fabio Galicia retrata el concierto en INSTANTZZ. Actuaron Pablo Maza, Eneko Di\u00e9guez, Jorgito, Eneko Arbea\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/241017-PABLO-MAZA-4tet-23.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/73184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=73184"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/73184\/revisions"}],"predecessor-version":[{"id":73187,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/73184\/revisions\/73187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/73185"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=73184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=73184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=73184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}