{"id":87116,"date":"2024-06-07T12:00:03","date_gmt":"2024-06-07T10:00:03","guid":{"rendered":"https:\/\/www.tomajazz.com\/web\/?p=87116"},"modified":"2024-11-09T07:59:10","modified_gmt":"2024-11-09T06:59:10","slug":"kevin-kastning-mark-wingfield-rubicon-ii-2024","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/kevin-kastning-mark-wingfield-rubicon-ii-2024\/","title":{"rendered":"Kevin Kastning &#8211; Mark Wingfield: Rubicon II (Greydisc Records, 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-87117 size-medium\" title=\"Kevin Kastning - Mark Wingfield: Rubicon II (Greydisc Records, 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] Tomajazz Kevin Kastning Mark Wingfield Rubicon II Greydisc Records 2024 Tomajazz Grabaciones de jazz\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-300x300.jpg\" alt=\"Kevin Kastning - Mark Wingfield: Rubicon II (Greydisc Records, 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz\" width=\"300\" height=\"300\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-768x768.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz-500x500.jpg 500w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Implementando libertades de colores que combinan texturas y emociones, creando atm\u00f3sferas interminables, reinventando sonidos inh\u00f3spitos, explorando caminos sinuosos que convergen en pasajes sonoros imaginarios.<\/p>\n<p>Kevin Kastning y Mark Wingfield son dos caudalosos r\u00edos que desembocan en un profundo oc\u00e9ano oscuro, fraternal y hermanados en 8 po\u00e9ticas p\u00e1ginas: <em>I walked into the silver darkness<\/em> (Greydisc Records; 2011), <em>An Illustrated Silence<\/em> (Greydisc<em> Records<\/em>; 2012), <em>Dark Sonatas<\/em> (Greydisc<em> Records<\/em>; 2013), <em>In Stories<\/em> (Greydis<em>c Records<\/em>; 2014), <em>Eleven Rooms<\/em> (<em>Greydisc Records<\/em>; 2015), <em>The Line to Three<\/em> (Greydisc<em> Records<\/em>; 2017), <em>Rubicon I<\/em> (<em>Greydisc Records<\/em>; 2021), <em>I dreamed of invisible journeys<\/em> (<em>Greydisc Records<\/em>; 2022).<\/p>\n<p>En <em>Rubicon II <\/em>se funden dos sonoridades diferentes pero complementarias, una el\u00e9ctrica representada por Mark Wingfield y la otra ac\u00fastica por Kevin Kastning, tan diferentes y cercanas que sorprende por la naturalidad y el entendimiento de estos dos visionarios adelantados a su tiempo.<\/p>\n<p>M\u00fasica de c\u00e1mara, m\u00fasica intimista, introspectiva, imaginativa e innovadora que parte de instrumentos inventados como guitarra cl\u00e1sica extendida de 15 cuerdas de Kevin Kastning y las distorsiones lastimeras y dolientes de la guitarra el\u00e9ctrica de Mark Wingfield que tiene su culmen dialogante en piezas como \u201cObservation Light Constant\u201d.<\/p>\n<p><em>Rubicon II<\/em> evoca la extra\u00f1a y serena belleza negra, el misterio parad\u00f3jico y luminoso que funde sonidos contrarios que se complementan como el Yin\/Yan en la inicial \u201cRedshift Expansion\u201d y en \u201cParticle Apparent\u201d.<\/p>\n<p>La composici\u00f3n de mayor extensi\u00f3n la encontramos en la inquietante y dialogante \u201cTidal Radius Thermalized\u201d, una pieza para disfrute de un piano quebrado y contempor\u00e1neo en manos de Kevin Kastning al que responde un Mark Wingfield quejumbroso y reivindicativo, y que da como resultado una sonoridad dram\u00e1tica y densa, de atm\u00f3sferas oscuras y reverberaciones profundas.<\/p>\n<p>Negra poes\u00eda, m\u00fasica g\u00f3tica para los siglos venideros, caminos curvados y sin explotar, b\u00fasqueda del silencio, de la pausa reflexiva, m\u00fasica para elegidos en la \u201cinfinita\u201d \u201cVariance Tensor Minus\u201d.<\/p>\n<p>Y, para terminar, lo que nunca parece finalizar con \u201cGravitational Well Inception\u201d, una propuesta de sonido cristalino con un Kevin Kastning rememorando a Ralph Towner y un Mark Wingfield que solloza hasta la extinci\u00f3n.<\/p>\n<p style=\"text-align: right;\">Tomajazz: \u00a9 <strong><a href=\"https:\/\/elescribadeljazz.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Enrique Farelo<\/a><\/strong>, 2024<\/p>\n<h3>Kevin Kastning &#8211; Mark Wingfield: <em>Rubicon II<\/em><\/h3>\n<p>Mark Wingfield (guitarra el\u00e9ctrica y <em>soundscapes<\/em>), Kevin Kastning (guitarra cl\u00e1sica extendida de 15 cuerdas, piano)<\/p>\n<p>\u201cRedshift Expansion\u201d, \u201cObservation Light Constant\u201d, \u201cParticle Apparent\u201d, \u201cTidal Radius Thermalized\u201d, \u201cVariance Tensor Minus\u201d y \u201cGravitational Well Inception\u201d.<br \/>\nTemas compuestos por Kevin Kastning y Mark Wingfield.<\/p>\n<p>Grabado en vivo en estudio, sin sobregrabaciones, en el <em>Studio Traumwald<\/em> en Groton, Massachusetts, EE. UU., del 17 al 18 de agosto de 2018. Publicado en 2024 por Greydisc Records.<\/p>\n<h3>M\u00e1s informaci\u00f3n<\/h3>\n<p><a href=\"https:\/\/www.markwingfield.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.markwingfield.com\/<\/a><\/p>\n<p><a href=\"http:\/\/www.kevinkastning.com\/index.htm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.kevinkastning.com\/index.htm<\/a><\/p>\n<p><a href=\"http:\/\/www.greydisc.com\/releases.htm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.greydisc.com\/releases.htm<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=mark+wingfield&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=mark+wingfield&amp;submit=Search<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=kevin+kastningd&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=kevin+kastning&amp;submit=Search<\/a><\/p>\n<h4>Enrique Farelo en Tomajazz<\/h4>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17848\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17848<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rubicon II (Greydisc Records, 2024), es la nueva grabaci\u00f3n de Kevin Kastning &#8211; Mark Wingfield. Enrique Farelo la repasa. <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/kevin-kastning-mark-wingfield-rubicon-ii-2024\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":87117,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,17848,15517,1038],"tags":[304,26539,31238,17607],"class_list":["entry","author-pachi","has-excerpt","post-87116","post","type-post","status-publish","format-standard","has-post-thumbnail","category-grabaciones","category-enrique-farelo","category-textos","category-contenidos","tag-enrique-farelo","tag-kevin-kastning","tag-kevin-kastning-mark-wingfield","tag-mark-wingfield"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/06\/Kevin-Kastning-Mark-Wingfield-Rubicon-II-Greydisc-Records-2024-Tomajazz-Grabaciones-de-jazz.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":60784,"url":"https:\/\/tomajazz.com\/web\/kevin-kastning-soheil-peyghambari-the-first-realm-greydisc-records-2021-grabacion-de-jazz-por-enrique-farelo\/","url_meta":{"origin":87116,"position":0},"title":"Kevin Kastning &#8211; Soheil Peyghambari: The First Realm (Greydisc Records 2021) [Grabaci\u00f3n de jazz] Por Enrique Farelo","author":"Tomajazz","date":"2 febrero, 2022","format":false,"excerpt":"Kevin Kastning estudi\u00f3 en Berklee College of Music (Boston) y con el guitarrista Pat Metheny. Compositor de m\u00e1s de 200 obras para diversas instrumentaciones solistas y de grupos de c\u00e1mara adem\u00e1s de grabar junto a Michael Manring, Alex de Grassi, Carl Clements, Mark Wingfield o Sandor Szabo. Inventor de la\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Kevin Kastning Soheil Peyghambari-The First Realm 21","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Kevin-Kastning-Soheil-Peyghambari-The-First-Realm-21.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":100427,"url":"https:\/\/tomajazz.com\/web\/kevin-kastning-unico-e-inclasificable-2025\/","url_meta":{"origin":87116,"position":1},"title":"Kevin Kastning \u00fanico e inclasificable. Por Enrique Farelo [Art\u00edculo de jazz]","author":"Tomajazz","date":"13 octubre, 2025","format":false,"excerpt":"Kevin Kastning \u00fanico e inclasificable. Enrique Farelo repasa en su art\u00edculo la trayectoria del guitarrista, centr\u00e1ndose en sus \u00faltimas grabaciones a fecha de septiembre de 2025","rel":"","context":"En \u00abArt\u00edculos...\u00bb","block_context":{"text":"Art\u00edculos...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/articulos\/"},"img":{"alt_text":"Kevin Kastning \u00fanico e inclasificable. Por Enrique Farelo [Art\u00edculo de jazz] - Tomajazz - Kevin Kastning \u00fanico e inclasificable. Enrique Farelo repasa en su art\u00edculo la trayectoria del guitarrista","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Kevin-Kastning-unico-e-inclasificable-Portada-Tomajazz-2025-ok.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Kevin-Kastning-unico-e-inclasificable-Portada-Tomajazz-2025-ok.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Kevin-Kastning-unico-e-inclasificable-Portada-Tomajazz-2025-ok.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Kevin-Kastning-unico-e-inclasificable-Portada-Tomajazz-2025-ok.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Kevin-Kastning-unico-e-inclasificable-Portada-Tomajazz-2025-ok.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":61057,"url":"https:\/\/tomajazz.com\/web\/kevin-kastning-balazs-major-sandor-szabo-ethereal-v-greydisc-records-2022-grabacion-de-jazz-por-enrique-farelo\/","url_meta":{"origin":87116,"position":2},"title":"Kevin Kastning, Balazs Major, S\u00e1ndor Szab\u00f3: Ethereal V (Greydisc Records 2022) [Grabaci\u00f3n de jazz] Por Enrique Farelo","author":"Tomajazz","date":"11 febrero, 2022","format":false,"excerpt":"Enrique Farelo repasa la grabaci\u00f3n Ethereal V (Greydisc Records, 2022), de Kevin Kastning, Balazs Major, S\u00e1ndor Szab\u00f3.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Kevin Kastning, Balazs Major, S\u00e1ndor Szab\u00f3 Ethereal V","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Kevin-Kastning-Balazs-Major-Sandor-Szabo-Ethereal-V.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Kevin-Kastning-Balazs-Major-Sandor-Szabo-Ethereal-V.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Kevin-Kastning-Balazs-Major-Sandor-Szabo-Ethereal-V.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2022\/02\/Kevin-Kastning-Balazs-Major-Sandor-Szabo-Ethereal-V.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103372,"url":"https:\/\/tomajazz.com\/web\/mark-wingfield-the-gathering-2024-vrsn-2026\/","url_meta":{"origin":87116,"position":3},"title":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"12 enero, 2026","format":false,"excerpt":"The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":87890,"url":"https:\/\/tomajazz.com\/web\/universos-paralelos-emision-t29-p34\/","url_meta":{"origin":87116,"position":4},"title":"Especial Kevin Kastning. Fin de temporada Universos Paralelos: emisi\u00f3n 11 de julio de 2024 (UP.T.29 P.34) [Noticias de jazz]","author":"Tomajazz","date":"11 julio, 2024","format":false,"excerpt":"La edici\u00f3n de Universos Paralelos del 11 de julio de 2024 pone punto final a la temporada 29 del programa dirigido por Sergio Cabanillas con un especial dedicado a Kevin Kastning #Noticiasdejazz","rel":"","context":"En \u00ab*_Redacci\u00f3n\u00bb","block_context":{"text":"*_Redacci\u00f3n","link":"https:\/\/tomajazz.com\/web\/category\/redaccion\/"},"img":{"alt_text":"Especial Kevin Kastning. Fin de temporada Universos Paralelos: emisi\u00f3n 11 de julio de 2024 (UP.T.29 P.334) [Noticias de jazz] - Tomajazz - La edici\u00f3n de Universos Paralelos del 11 de julio de 2024 pone punto final a la temporada 29 del programa dirigido por Sergio Cabanillas con un especial dedicado a Kevin Kastning #Noticiasdejazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/UP-Especial-Kastning-2024-Tomajazz-Noticias.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/UP-Especial-Kastning-2024-Tomajazz-Noticias.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/UP-Especial-Kastning-2024-Tomajazz-Noticias.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/07\/UP-Especial-Kastning-2024-Tomajazz-Noticias.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":86588,"url":"https:\/\/tomajazz.com\/web\/mark-wingfield-the-gathering-2024\/","url_meta":{"origin":87116,"position":5},"title":"Mark Wingfield: The Gathering (MoonJune Records, 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"17 mayo, 2024","format":false,"excerpt":"The Gathering (MoonJune Records, 2024) es la nueva obra de Mark Wingfield. Enrique Farelo repasa la grabaci\u00f3n. Participan Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Mark Wingfield: The Gathering (MoonJune Records, 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - The Gathering (MoonJune Records, 2024) es la nueva obra de Mark Wingfield. Enrique Farelo repasa la grabaci\u00f3n.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/05\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/87116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=87116"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/87116\/revisions"}],"predecessor-version":[{"id":91524,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/87116\/revisions\/91524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/87117"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=87116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=87116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=87116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}