{"id":8898,"date":"2013-10-30T11:00:12","date_gmt":"2013-10-30T10:00:12","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=8898"},"modified":"2016-11-13T17:17:16","modified_gmt":"2016-11-13T16:17:16","slug":"mirage-mirage-clean-feed-2013","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/mirage-mirage-clean-feed-2013\/","title":{"rendered":"Mirage: <i>Mirage<\/i> (Clean Feed, 2013)"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><a href=\"http:\/\/www.tomajazz.com\/web\/?attachment_id=8903\" rel=\"attachment wp-att-8903\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-8903\" alt=\"Mirage Mirage Clean Feed 2013\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Mirage-Mirage-Clean-Feed-2013.jpg\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Mirage-Mirage-Clean-Feed-2013.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Mirage-Mirage-Clean-Feed-2013-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Mirage-Mirage-Clean-Feed-2013-54x55.jpg 54w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Mirage<\/i> es una grabaci\u00f3n de improvisaciones en tr\u00edo de Ellery Eskelin (saxo), Michael Formanek (contrabajo) y Susan Alcorn (<i>pedal Steel gitar<\/i>, instrumento habitual en la m\u00fasica <i>country<\/i>). En los temas m\u00e1s breves el disco transcurre mayoritariamente tranquilo y a medio tiempo, buscando y encontrando melod\u00edas. Esa contenci\u00f3n (no tanto en la m\u00fasica sino en la duraci\u00f3n) se rompe con el extenso \u201cDownburst\u201d (27 minutos), en el que el grupo no es capaz de mostrar mucho m\u00e1s de lo que logra en cada uno de los temas del resto del disco con duraciones de entre tres y cinco minutos.<\/p>\n<p style=\"text-align: right;\">\u00a0\u00a9\u00a0Pachi Tapiz, 2013<\/p>\n<p>Mirage: <em>Mirage<\/em> (Clean Feed, 2013) ***<\/p>\n<p>Publicado en el n\u00famero de verano de 2013 de la revista\u00a0<em>M\u00e1s Jazz<\/em>\u00a0en la rese\u00f1a conjunta\u00a0<em>Clean Feed: en tr\u00edo y en cuarteto<\/em>.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Mirage es una grabaci\u00f3n de improvisaciones en tr\u00edo de Ellery Eskelin (saxo), Michael Formanek (contrabajo) y Susan Alcorn (pedal Steel gitar, instrumento habitual en la m\u00fasica country). En los temas m\u00e1s breves el disco transcurre mayoritariamente tranquilo y a medio tiempo, buscando y encontrando melod\u00edas. Esa contenci\u00f3n (no tanto en<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/mirage-mirage-clean-feed-2013\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":8903,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,5,1038],"tags":[12651,1577,6609,12696,13,12415,15295,7673,7672,31,7674,16099,77,16100],"class_list":["entry","author-pachi","post-8898","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-grabaciones","category-contenidos","tag-cd","tag-clean-feed","tag-ellery-eskelin","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-michael-formanek","tag-mirage","tag-pachi-tapiz","tag-susan-alcorn","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Mirage-Mirage-Clean-Feed-2013.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":10035,"url":"https:\/\/tomajazz.com\/web\/harris-eisenstadt-september-trio-the-destructive-element-clean-feed-2013\/","url_meta":{"origin":8898,"position":0},"title":"Harris Eisenstadt September Trio: The Destructive Element (Clean Feed, 2013)","author":"Tomajazz","date":"23 enero, 2014","format":false,"excerpt":"El baterista Harris Eisenstadt publica The Destructive Element con su formaci\u00f3n September Trio. El saxofonista Ellery Eskelin y la pianista Angelica Sanchez son sus acompa\u00f1antes nuevamente. Eisenstadt, que durante los \u00faltimos a\u00f1os est\u00e1 mostrando ser un gran compositor, es el autor de los nueve temas. Estos resultan muy variados en\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Harris Eisenstadt The Desctrutive Element","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/01\/Harris-Eisenstadt-The-Desctrutive-Element-200x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8394,"url":"https:\/\/tomajazz.com\/web\/harris-eisenstadt-september-trio-destructive-element-clean-feed-2013\/","url_meta":{"origin":8898,"position":1},"title":"Harris Eisenstadt September Trio: Destructive Element (Clean Feed, 2013)","author":"Tomajazz","date":"11 octubre, 2013","format":false,"excerpt":"El baterista Harris Eisenstadt publica The Destructive Element con su formaci\u00f3n September Trio. El saxofonista Ellery Eskelin y la pianista Angelica Sanchez son sus acompa\u00f1antes nuevamente. Eisenstadt, que durante los \u00faltimos a\u00f1os est\u00e1 mostrando ser un gran compositor, es el autor de los nueve temas. Estos resultan muy variados en\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"Harris Eisenstadt september trio destructive elements","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/10\/Harris-Eisenstadt-september-trio-destructive-elements.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8129,"url":"https:\/\/tomajazz.com\/web\/brian-landrus-kaleidoscope-mirage-blueland-records-2013\/","url_meta":{"origin":8898,"position":2},"title":"Brian Landrus Kaleidoscope: Mirage (Blueland Records, 2013)","author":"Tomajazz","date":"10 septiembre, 2013","format":false,"excerpt":"El saxofonista y compositor Brian Landrus presenta su \u00faltimo trabajo al frente del grupo Kaleidoscope. En Mirage el m\u00fasico neoyorkino incide en las ideas ya anunciadas en el anterior (Capsule de 2012), e insiste en hacer un jazz electro-ac\u00fastico salpicado con algunos toques de otros g\u00e9neros musicales. En esta ocasi\u00f3n,\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Brian_Landrus_Kaleidoscope_Mirage","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/09\/Brian_Landrus_Kaleidoscope_Mirage.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2452,"url":"https:\/\/tomajazz.com\/web\/harris-eisenstadt-september-trio-clean-feed-2011\/","url_meta":{"origin":8898,"position":3},"title":"Harris Eisenstadt: September Trio (Clean Feed, 2011)","author":"Tomajazz","date":"27 diciembre, 2011","format":false,"excerpt":"El baterista Harris Eisenstadt ha irrumpido con fuerza en el jazz durante los \u00faltimos a\u00f1os, a pesar de que ni es precisamente un novato (naci\u00f3 en 1975), ni un reci\u00e9n llegado (cuenta en su haber con m\u00e1s de diez discos a su nombre, y ha participado en m\u00e1s de cuarenta\u2026","rel":"","context":"En \u00abToma Jazz\u00bb","block_context":{"text":"Toma Jazz","link":"https:\/\/tomajazz.com\/web\/tag\/toma-jazz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/1.bp.blogspot.com\/-2vTJdElRn3M\/TvnlO7_GFFI\/AAAAAAAAD2Q\/8nzBSzG07Zk\/s200\/eisenstadt_CF229.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2353,"url":"https:\/\/tomajazz.com\/web\/devin-gray-dirigo-rataplan-skirl-records-2012\/","url_meta":{"origin":8898,"position":4},"title":"Devin Gray: Dirigo Rataplan (Skirl Records, 2012)","author":"Tomajazz","date":"19 abril, 2012","format":false,"excerpt":"El baterista de 28 a\u00f1os Devin Gray ha elegido muy buenas compa\u00f1\u00edas para su estreno discogr\u00e1fico como l\u00edder. El saxofonista Ellery Eskelin especialmente, pero tambi\u00e9n el trompetista Dave Ballou y el contrabajista Michael Formanek son unos m\u00fasicos con unas carreras muy notables a sus espaldas, que acostumbran a participar en\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-Wx0re7vGIVw\/T5COJhPB6JI\/AAAAAAAAEfc\/wUA39BydA5o\/s200\/devin%2Bgray_dirigo%2Brataplan.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":710,"url":"https:\/\/tomajazz.com\/web\/billy-cobham-palindrome-grabado-en-hsb-studios-y-backyard-studios-berna-suiza-publicado-en-2010\/","url_meta":{"origin":8898,"position":5},"title":"Billy Cobham &#8211; Palindrome (Grabado en HSB Studios y Backyard Studios, Berna (Suiza). Publicado en 2010)","author":"Autor1","date":"6 mayo, 2011","format":false,"excerpt":"Bater\u00eda m\u00edtico en los albores del jazz fusion, Billy Cobham nos regala un trabajo excelente fuertemente asentado en las ra\u00edces de dicho g\u00e9nero. Confirma su enorme pegada y buen sentido del groove, pero se ofrece tambi\u00e9n como compositor de los nueve originales que forman este Palindrome (algunos de ellos retomados\u2026","rel":"","context":"En \u00ab*_Arturo Mora Rioja\u00bb","block_context":{"text":"*_Arturo Mora Rioja","link":"https:\/\/tomajazz.com\/web\/category\/arturo-mora-rioja\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2011\/05\/Billy-Cobham.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/8898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=8898"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/8898\/revisions"}],"predecessor-version":[{"id":8906,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/8898\/revisions\/8906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/8903"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=8898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=8898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=8898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}