{"id":9215,"date":"2013-11-15T11:15:03","date_gmt":"2013-11-15T10:15:03","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=9215"},"modified":"2016-11-13T16:33:08","modified_gmt":"2016-11-13T15:33:08","slug":"imatjazz-christian-scott","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/imatjazz-christian-scott\/","title":{"rendered":"IMATJAZZ: Christian Scott"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.tomajazz.com\/web\/?attachment_id=9168\" rel=\"attachment wp-att-9168\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9168 aligncenter\" alt=\"IMJ019_CHRISTIAN SCOTT (\u00a9Joan Cort\u00e8s)_30oct13_Jamboree Jazz Club Festival_Jamboree_Bcn\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn.jpg\" width=\"600\" height=\"399\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn-150x99.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn-300x199.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn-82x55.jpg 82w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn-60x40.jpg 60w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/IMJ019_CHRISTIAN-SCOTT-\u00a9Joan-Cort\u00e8s_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn-120x80.jpg 120w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Christian Scott<br \/>\nJamboree Jazz Club Festival<br \/>\nJamboree, Barcelona. 2013-10-30<\/p>\n<p>\u00a9 Joan Cort\u00e8s, 2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christian Scott Jamboree Jazz Club Festival Jamboree, Barcelona. 2013-10-30 \u00a9 Joan Cort\u00e8s, 2013<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/imatjazz-christian-scott\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17853,15516,1038,7292,4758],"tags":[1187,12656,15275,7462,13,1041,12657,16099,77,16100],"class_list":["entry","author-pachi","post-9215","post","type-post","status-publish","format-standard","category-joan-cortes","category-imagenes","category-contenidos","category-imatjazz","category-blogs","tag-christian-scott","tag-fotoblog","tag-galeria-fotografica","tag-imatjazz-2","tag-jazz","tag-joan-cortes","tag-photoblog","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9672,"url":"https:\/\/tomajazz.com\/web\/imatjazz-luques-curtis\/","url_meta":{"origin":9215,"position":0},"title":"IMATJAZZ: Luques Curtis","author":"Tomajazz","date":"13 diciembre, 2013","format":false,"excerpt":"Luques Curtis Christian Scott Quintet Jamboree Jazz Club Festival Jamboree, Barcelona. 2013-10-05 \u00a9 Joan Cort\u00e8s","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/IMJ027_LUQUES-CURTIS-%C2%A9Joan-Cort%C3%A8s_Christian-Scott-5t_30oct13_Jamboree-Jazz-Club-Festival_Jamboree_Bcn_rec.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":104436,"url":"https:\/\/tomajazz.com\/web\/juanma-trujillo-baldo-martinez-cdj25-2026\/","url_meta":{"origin":9215,"position":1},"title":"Juanma Trujillo &#038; Baldo Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"17 marzo, 2026","format":false,"excerpt":"Juanma Trujillo & Baldo Mart\u00ednez actuaron en Jamboree en el 25 aniversario de Club de Jazz. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"Juanma Trujillo & Baldo Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [I] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Juanma Trujillo & Baldo Mart\u00ednez actuaron en Jamboree en el 25 aniversario de Club de Jazz. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-11-Jnm-Trjll-Bld-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr01-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104591,"url":"https:\/\/tomajazz.com\/web\/marco-mezquida-25cdj-2026\/","url_meta":{"origin":9215,"position":2},"title":"Marco Mezquida (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [y III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"26 marzo, 2026","format":false,"excerpt":"Marco Mezquida actu\u00f3 en Jamboree en la celebraci\u00f3n CDJ25, el 14 de febrero de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Marco Mezquida (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [y III] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Marco Mezquida actu\u00f3 en Jamboree en la celebraci\u00f3n CDJ25, el 14 de febrero de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-10-Mrc-Mzqd-Photo-by-Joan-Cortes-14fbr26-25CdJ-Jmbrr01-Bcn-.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103903,"url":"https:\/\/tomajazz.com\/web\/diego-amador-ebano-marfil-jamboree-2025\/","url_meta":{"origin":9215,"position":3},"title":"Diego Amador \u201c\u00c9bano &#038; Marfil\u201d (Jamboree-03, 2025-12-12 \/ Barcelona) Por Joan Cort\u00e8s [Flamencuras AKA INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"7 febrero, 2026","format":false,"excerpt":"Diego Amador \u201c\u00c9bano & Marfil\u201d actu\u00f3 en Jamboree el 12 de diciembre de 2025. Joan Cort\u00e8s lo retrata en las Flamencuras de INSTANTZZ","rel":"","context":"En \u00abFlamencuras\u00bb","block_context":{"text":"Flamencuras","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/flamencuras\/"},"img":{"alt_text":"Diego Amador \u201c\u00c9bano & Marfil\u201d (Jamboree-03, 2025-12-12 \/ Barcelona) Por Joan Cort\u00e8s [Flamencuras AKA INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Diego Amador \u201c\u00c9bano & Marfil\u201d actu\u00f3 en Jamboree el 12 de diciembre de 2025. Joan Cort\u00e8s lo retrata en las Flamencuras de INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-06-Dg-mdr-Photo-by-Joan-Cortes-12dsm25-Jmbr-03-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-06-Dg-mdr-Photo-by-Joan-Cortes-12dsm25-Jmbr-03-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/02\/destacada-06-Dg-mdr-Photo-by-Joan-Cortes-12dsm25-Jmbr-03-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":104518,"url":"https:\/\/tomajazz.com\/web\/agusti-fernandez-sonia-sanchez-lucia-martinez-cdj25-2026\/","url_meta":{"origin":9215,"position":4},"title":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez &#038; Luc\u00eda Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"22 marzo, 2026","format":false,"excerpt":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez actuaron en Jamboree, Barcelona, en el 25 aniversario de CDJ. Joan Cort\u00e8s lo retrata en INSTANTZZ","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez (25 aniversario Club de Jazz \/ Jamboree-01, 2026-02-14 \/ Barcelona) [II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Agust\u00ed Fern\u00e1ndez, S\u00f2nia S\u00e1nchez & Luc\u00eda Mart\u00ednez actuaron en Jamboree, Barcelona, en el 25 aniversario de CDJ. Joan Cort\u00e8s lo retrata en INSTANTZZ","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/03\/destacada-07-Frnndz-Snchz-Mrtnz-Photo-by-Joan-Cortes-14fbr26-25nCdJ-Jmbr-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103584,"url":"https:\/\/tomajazz.com\/web\/marcin-masecki-jamboree-2025\/","url_meta":{"origin":9215,"position":5},"title":"Marcin Masecki \u201cBoleros y m\u00e1s\u201d (Jamboree, 2025-12-03 \/ Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"20 enero, 2026","format":false,"excerpt":"Marcin Masecki \u201cBoleros y m\u00e1s\u201d actu\u00f3 en Jamboree, el 3 de diciembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron Marcin Masecki, Jerzy Rogiewicz, Filip Botor","rel":"","context":"En \u00abINSTANTZZ\u00bb","block_context":{"text":"INSTANTZZ","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/imagenes\/photoblogs\/instantzz\/"},"img":{"alt_text":"Marcin Masecki \u201cBoleros y m\u00e1s\u201d (Jamboree, 2025-12-03 \/ Barcelona) Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Marcin Masecki \u201cBoleros y m\u00e1s\u201d actu\u00f3 en Jamboree, el 3 de diciembre de 2025. Joan Cort\u00e8s lo retrata en INSTANTZZ. Actuaron Marcin Masecki, Jerzy Rogiewicz, Filip Botor\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacada-09-Mrcn-Msck-Tr-Photo-By-Joan-Cortes-03dsm25-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacada-09-Mrcn-Msck-Tr-Photo-By-Joan-Cortes-03dsm25-Jmbr-Bcn.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/destacada-09-Mrcn-Msck-Tr-Photo-By-Joan-Cortes-03dsm25-Jmbr-Bcn.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=9215"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9215\/revisions"}],"predecessor-version":[{"id":9218,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9215\/revisions\/9218"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=9215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=9215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=9215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}