{"id":9239,"date":"2013-11-15T11:00:43","date_gmt":"2013-11-15T10:00:43","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=9239"},"modified":"2016-11-13T15:55:21","modified_gmt":"2016-11-13T14:55:21","slug":"tomajazz-recupera-dusan-jevtovic-on-the-edge","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/tomajazz-recupera-dusan-jevtovic-on-the-edge\/","title":{"rendered":"Dusan Jevtovic: On The Edge (Indi Records, 2009; CD)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.tomajazz.com\/web\/?attachment_id=9240\" rel=\"attachment wp-att-9240\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9240\" alt=\"Dusan_Jevtovic-On_the_edge\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan_Jevtovic-On_the_edge.jpg\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan_Jevtovic-On_the_edge.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan_Jevtovic-On_the_edge-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan_Jevtovic-On_the_edge-55x55.jpg 55w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Comentario:<b> <\/b>Todo lo apuntado y madurado por Dusan Jevtovic en el Xavi Reija Electric Quintet se muestra este trabajo de <em>jazz-rock <\/em>progresivo, <em>On The Edge<\/em>.<\/p>\n<p style=\"text-align: justify;\">El guitarrista serbio cuenta para su proyecto con dos viejos amigos del nombrado quinteto, es decir, Bernat Hern\u00e1ndez y el solvente Xavi Reija a la bater\u00eda. Dusan Jevtovic y Sava Miletic se reparten el aparente protagonismo a lo largo del disco para darle un car\u00e1cter de uniformidad estil\u00edstica <em>setentera <\/em>que raya a gran altura, donde es dif\u00edcil destacar un tema de otro y se realiza un gui\u00f1o reminiscente al <em>rock Canterbury <\/em>o a la fusi\u00f3n progresiva.<\/p>\n<p style=\"text-align: justify;\">Los otros dos miembros del cuarteto, los nombrados Bernat Hern\u00e1ndez y Xavi Reija, sirven de nexo de uni\u00f3n el primero y de potencia r\u00edtmica el segundo; sin ellos no podr\u00eda entenderse la labor del cuarteto.<\/p>\n<p style=\"text-align: justify;\"><em>On The Edge <\/em>es una obra cerebral concebida desde el prisma de la imaginaci\u00f3n y fuertemente estructurada, donde la guitarra de Dusan Jevtovic se muestra corrosiva, \u00e1cida y quejumbrosa; apoyada en una t\u00e9cnica impecable nos lleva a recordar a Allan Holdsworth e incluso a Jimi Hendrix o John McLaughlin. Sava Miletic nos acerca al trabajo realizado por Alan Pasqua en el disco de la Tony Willians Lifetime, <em>Believe It<\/em>; Bernat Hernandez a Jeff Berlin y Xavi Reija, unas veces a Tony Willians, otras a Jon Hiseman o a Nigel Morris, del grupo ingl\u00e9s Isotope.<\/p>\n<p style=\"text-align: justify;\">Con todo lo argumentado no quiero decir que haya que comparar a estos m\u00fasicos con aquellos, sino que estos tienen una solvencia instrumental y creativa a toda prueba y que con este <em>On The Edge <\/em>han logrado alcanzar uno de los momentos m\u00e1s brillantes y destacados del <em>jazz-rock <\/em>progresivo en nuestro pa\u00eds en los \u00faltimos a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Vuelvo a insistir en no querer destacar ning\u00fan tema por encima de otro, para m\u00ed todos tienen el mismo reconocimiento y quiero dejar que se\u00e1is vosotros los encargados de encumbrar un disco que tiene, para m\u00ed, todos los honores.<\/p>\n<p align=\"right\">\u00a9 Enrique Farelo, 2009<\/p>\n<p>Rese\u00f1a publicada originalmente en 2009.<\/p>\n<p>Dusan Jevtovic: <em>On The Edge<\/em><\/p>\n<p style=\"text-align: justify;\" align=\"right\">Composiciones:<b> <\/b>\u201cOn More Day\u201d, \u201cFollow Me\u201d, \u201cThe Wall\u201d, \u201cOn The Edge\u201d, \u201cFear Inside\u201d, \u201cIn The Last Moment\u201d, \u201cWingin\u2018 It\u201d, \u201cI\u2019ve Never Been In Holland\u201d, \u201cGracias Y Perdon\u201d<\/p>\n<p>Todas las Composiciones de Dusan Jevtovic, excepto 1 y 3 de Dusan Jevtovic y Bernat Hernandez y 8 de Bernat Hern\u00e1ndez.<\/p>\n<p>M\u00fasicos:<b> <\/b>Dusan Jevtovic (guitarra); Sava Miletic (Fender Rhodes); Bernat Hern\u00e1ndez (bajo el\u00e9ctrico); Xavi Reija (bater\u00eda)<\/p>\n<p>Grabado el 2 y 3 de septiembre de 2009 en Indi Records Estudios de Vic (Barcelona).<br \/>\n2009 Indi Records<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comentario: Todo lo apuntado y madurado por Dusan Jevtovic en el Xavi Reija Electric Quintet se muestra este trabajo de jazz-rock progresivo, On The Edge. El guitarrista serbio cuenta para su proyecto con dos viejos amigos del nombrado quinteto, es decir, Bernat Hern\u00e1ndez y el solvente Xavi Reija a la<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/tomajazz-recupera-dusan-jevtovic-on-the-edge\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":9240,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17848,7895,5,1038,6669],"tags":[7761,12651,7759,304,12696,7762,13,12415,15295,7760,16099,77,16100,7645],"class_list":["entry","author-pachi","post-9239","post","type-post","status-publish","format-standard","has-post-thumbnail","category-enrique-farelo","category-disco-antiguo","category-grabaciones","category-contenidos","category-tomajazz-recupera","tag-bernat-hernandez","tag-cd","tag-dusan-jevtovic","tag-enrique-farelo","tag-grabaciones","tag-indi-records","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-sava-miletic","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-xavi-reija"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan_Jevtovic-On_the_edge.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9298,"url":"https:\/\/tomajazz.com\/web\/dusan-jevtovic-am-i-walking-wrong-moonjune-records-2013\/","url_meta":{"origin":9239,"position":0},"title":"Dusan Jevtovic: Am I Walking Wrong? (Moonjune Records, 2013)","author":"Tomajazz","date":"19 noviembre, 2013","format":false,"excerpt":"Comentario:\u00a0Tercer trabajo discogr\u00e1fico del guitarrista serbio Dusan Jevtovic. Atr\u00e1s quedaron D.X. Project (Dusan Jevtovic y Xavier Reija) y su disco 2sides del a\u00f1o 2005 del desaparecido sello catal\u00e1n Satchmo. Y su primer disco en solitario On the Edge (L\u2019indi music 2008). Ahora vuelve con la fuerza que le caracteriza con\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Dusan-Jevtovic-Am-I-Walking-Wrong.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11921,"url":"https:\/\/tomajazz.com\/web\/xavi-reija-electric-quintet-dream-land-batiendo-records-2006\/","url_meta":{"origin":9239,"position":1},"title":"Xavi Reija Electric Quintet: Dream Land (Batiendo Records, 2006)","author":"Tomajazz","date":"6 mayo, 2014","format":false,"excerpt":"Lejanos y tan cercanos son los tiempos en los que en Espa\u00f1a triunfaba el jazz-rock, con representantes tan cualificados y, reconocidos como Iceberg, M\u00fasica Urbana, Fusioon o Guadalquivir, por nombrar a algunos. Han tenido que pasar tres d\u00e9cadas para que volviera a renacer un estilo que parec\u00eda olvidado y lo\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Xavi Reija DreamLand","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/web\/wp-content\/uploads\/2014\/05\/Xavi-Reija-DreamLand-200x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":18347,"url":"https:\/\/tomajazz.com\/web\/dusan-jevtovic-live-moonjune-records-2015-cd-y-ed-digital\/","url_meta":{"origin":9239,"position":2},"title":"Dusan Jevtovic: Live (Moonjune records 2015. CD y ed. digital)","author":"Tomajazz","date":"11 mayo, 2015","format":"image","excerpt":"El guitarrista serbio Dusan Jevtovic edita en formato digital su disco Live con composiciones de su \u00faltimo trabajo Am I Walking Wrong? del a\u00f1o 2013 y editado por Moonjune records. Colaborador de los proyectos del baterista espa\u00f1ol Xavi Reija (Resolution Moonjune records 2014, Dream Land 2006, Ritual 2008), nos ofrece\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/05\/Dusan-Jevtovic-Live.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/05\/Dusan-Jevtovic-Live.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/05\/Dusan-Jevtovic-Live.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19080,"url":"https:\/\/tomajazz.com\/web\/xadu-xavi-reija-dusan-jevtovic-random-abstract-moonjune-records-2015-cd\/","url_meta":{"origin":9239,"position":3},"title":"XADU: Xavi Reija \/ Dusan Jevtovic: Random Abstract (Moonjune Records, 2015; CD)","author":"Tomajazz","date":"17 julio, 2015","format":"link","excerpt":"\u201cTanto monta, monta tanto\u201d, face to face o un tuya m\u00eda es \u00e9ste Random Abstract que firman al alim\u00f3n Xavi Reija y Dusan Jevtovic. Ambos forman, obviamente, el d\u00fao denominado XADU: Xavi y Dusan. Sin duda un matrimonio bien avenido y duradero en el tiempo. Desde el lejano D. X.\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/XADU_Xavi-Reija-Dusan-Jevtovic_Random-Abstract_CD_2015-e1437124552102.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/XADU_Xavi-Reija-Dusan-Jevtovic_Random-Abstract_CD_2015-e1437124552102.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/07\/XADU_Xavi-Reija-Dusan-Jevtovic_Random-Abstract_CD_2015-e1437124552102.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19902,"url":"https:\/\/tomajazz.com\/web\/dusan-jevtovic-cafe-berlin-madrid-2015-09-24\/","url_meta":{"origin":9239,"position":4},"title":"Dusan Jevtovic (Caf\u00e9 Berl\u00edn, Madrid. 2015-09-24)","author":"Sergio Cabanillas","date":"30 septiembre, 2015","format":"image","excerpt":"Fecha: 24 de Septiembre de 2015. Lugar: Caf\u00e9 Berl\u00edn, Madrid. Grupo: Dusan Jevtovic, guitarra el\u00e9ctrica Tom\u00e1s Merlo, bajo Miguel Benito, bater\u00eda Dusan Jevtovic nacido en Serbia se dio a conocer al lado del bater\u00eda de jazz-fusion Xavi Reija all\u00e1 por el a\u00f1o 2003 en Barcelona, ciudad a la que se\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Dusan Jevtovic Trio \u00a9 Sergio Cabanillas, 2015","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/DUSAN_JEVTOVIC_TRIO_6867.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/DUSAN_JEVTOVIC_TRIO_6867.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/09\/DUSAN_JEVTOVIC_TRIO_6867.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12821,"url":"https:\/\/tomajazz.com\/web\/dusan-jevtovic-avanzando-bien-hacia-el-lado-oscuro-de-la-improvisacion-por-enrique-farelo-carlos-lara-y-sergio-cabanillas\/","url_meta":{"origin":9239,"position":5},"title":"Dusan Jevtovic: avanzando bien hacia el lado  oscuro de la improvisaci\u00f3n, por Enrique Farelo, Carlos Lara y Sergio Cabanillas","author":"Sergio Cabanillas","date":"25 junio, 2014","format":false,"excerpt":"El serbio afincado en Barcelona Dusan Jevtovic es uno de los guitarristas m\u00e1s innovadores del momento, formando parte de una generaci\u00f3n de m\u00fasicos para quienes el rock y el jazz forman parte de un crisol en el que confluyen varias fuerzas creativas. Su propuesta musical ha merecido la confianza de\u2026","rel":"","context":"En \u00ab*_Carlos Lara\u00bb","block_context":{"text":"*_Carlos Lara","link":"https:\/\/tomajazz.com\/web\/category\/carlos-lara\/"},"img":{"alt_text":"Dusan Jevtovic \u00a9 Endika Ussia","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/06\/Dusan_Jevtovic_por_Endika_Ussia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=9239"}],"version-history":[{"count":4,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9239\/revisions"}],"predecessor-version":[{"id":22891,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9239\/revisions\/22891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/9240"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=9239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=9239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=9239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}