{"id":93290,"date":"2024-12-26T12:00:49","date_gmt":"2024-12-26T11:00:49","guid":{"rendered":"https:\/\/tomajazz.com\/web\/?p=93290"},"modified":"2024-12-25T20:09:55","modified_gmt":"2024-12-25T19:09:55","slug":"luca-calabrese-i-shin-den-shin-2024","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/luca-calabrese-i-shin-den-shin-2024\/","title":{"rendered":"Luca Calabrese: I Shin Den Shin (MoonJune Records 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-93291 size-medium\" title=\"Luca Calabrese: I Shin Den Shin (MoonJune Records 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] Tomajazz Luca Calabrese I Shin Den Shin MoonJune Records 2024\" src=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--300x300.jpg\" alt=\"Luca Calabrese: I Shin Den Shin (MoonJune Records 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - Enrique Farelo repasa I Shin Den Shin (MoonJune Records 2024) de Luca Calabrese. Intervienen en la grabaci\u00f3n Luca Calabrese, Nguy\u00ean L\u00ea, Mark Wingfield, Markus Reuter, Alexander Dowerk\" width=\"300\" height=\"300\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--300x300.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--600x600.jpg 600w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--200x200.jpg 200w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--768x768.jpg 768w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--465x465.jpg 465w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024--500x500.jpg 500w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024-.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><em>I-shin-den-shin<\/em> es un concepto japon\u00e9s que se suele traducir como: \u201cLo que la mente piensa, el coraz\u00f3n lo transmite\u201d, lo que supone la transmisi\u00f3n de emociones y pensamientos sin necesidad de una comunicaci\u00f3n verbal. Aclarado el concepto, parece que el trompetista Luca Calabrese quisiera llevarnos por ese camino de espiritualidad budista o el confucianismo \u201ctelep\u00e1tico\u201d.<\/p>\n<p>Y desde la inicial \u201cDissolution\u201d, ya apunta hacia esa espiritualidad ingr\u00e1vida e intimista de atm\u00f3sferas densas y oscuras como ofrenda hacia un viaje al interior del ser.<\/p>\n<p>La propuesta zen contin\u00faa alimentada en la segunda de las estaciones po\u00e9tico-sonoras, (\u201cAppointment with the Truth\u201d) confluyendo la electroac\u00fastica multisensorial de la trompeta de bolsillo de Luca Calabrese y la diversidad guitarr\u00edstica.<\/p>\n<p>\u201cA New Reality\u201d aporta texturas <em>dark ambient<\/em>, cruce de instrumentos dispuestos en capas sonoras que apuntan en diversas direcciones, desde Jon Hassell a David Sylvian o al propio Richard Barbieri, con el que trabaj\u00f3 en el proyecto <em>Planets + Personaen<\/em> en el a\u00f1o 2017.<\/p>\n<p>\u201cPure Mind (without a body)\u201d vuelve o, mejor, no abandona la quietud ni la calma, m\u00e1s bien profundiza en ella desde una visi\u00f3n experimental y contempor\u00e1nea tan indolente como misteriosa, espectral y en ocasiones delirante.<\/p>\n<p>\u201cHeart to Heart\u201d, paisajes desolados e inh\u00f3spitos y bucles de <em>nu-jazz<\/em> o <em>dark jazz <\/em>con Arve Henriksen o Bohren &amp; der Club of Gore.<\/p>\n<p>\u201cMagnetic Soul\u201d, define tonalidades et\u00e9reas y fr\u00edas cercanas al \u00e1rtico. Trance, meditaci\u00f3n y psicolog\u00eda transpersonal.<\/p>\n<p style=\"text-align: right;\">Texto: \u00a9 <strong><a href=\"https:\/\/elescribadeljazz.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Enrique Farelo<\/a><\/strong>, 2024<\/p>\n<h3>Luca Calabrese: <em>I Shin Den Shin<\/em><\/h3>\n<p>M\u00fasicos: Luca Calabrese (trompeta de bolsillo), Nguy\u00ean L\u00ea y Mark Wingfield (guitarra el\u00e9ctrica), Markus Reuter y Alexander Dowerk (Touch Guitar AU8, <em>Soundscapes<\/em>).<\/p>\n<p>Composiciones: 1\/ \u201cDissolution\u201d, 2\/ \u201cAppointment with the Truth\u201d, 3\/ \u201cA New Reality\u201d, 4\/ \u201cPure Mind (without a body)\u201d, 5\/ \u201cHeart to Heart\u201d y 6\/ \u201cMagnetic Soul\u201d.<br \/>\nComposiciones de Calabrese\/Reuter\/L\u00ea\/Wingfield\/Dowerk, excepto \u201cMagnetic Soul\u201d de Reuter\/Calabrese.<\/p>\n<p>Grabado en La Casa Murada, estudios de Jes\u00fas Rovira, Banyeres del Pened\u00e9s, Catalunya, Espa\u00f1a, el 5 de septiembre de 2022. Publicado por MoonJune Records en 2024.<\/p>\n<h3>M\u00e1s informaci\u00f3n<\/h3>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lucalab.jimdofree.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/lucalab.jimdofree.com\/<\/a><\/p>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?s=luca+calabrese&amp;submit=Search\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?s=luca+calabrese&amp;submit=Search<\/a><\/p>\n<h4>Enrique Farelo en Tomajazz<\/h4>\n<p><a href=\"https:\/\/tomajazz.com\/web\/?cat=17848\" target=\"_blank\" rel=\"noopener\">https:\/\/tomajazz.com\/web\/?cat=17848<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enrique Farelo repasa I Shin Den Shin (MoonJune Records 2024) de Luca Calabrese. Intervienen en la grabaci\u00f3n Luca Calabrese, Nguy\u00ean L\u00ea, Mark Wingfield, Markus Reuter, Alexander Dowerk <span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/luca-calabrese-i-shin-den-shin-2024\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":93291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,17848,15517,1038],"tags":[31535,304,31536,17607,20430,5991,7737],"class_list":["entry","author-pachi","has-excerpt","post-93290","post","type-post","status-publish","format-standard","has-post-thumbnail","category-grabaciones","category-enrique-farelo","category-textos","category-contenidos","tag-alexander-dowerk","tag-enrique-farelo","tag-luca-calabrese","tag-mark-wingfield","tag-markus-reuter","tag-moonjune-records","tag-nguyen-le"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2024\/12\/Luca-Calabrese-I-Shin-Den-Shin-MoonJune-Records-2024-.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":90211,"url":"https:\/\/tomajazz.com\/web\/calabrese-reuter-dowerk-moonjune-2024\/","url_meta":{"origin":93290,"position":0},"title":"Calabrese-Reuter-Dowerk (III Festival Internacional MoonJune Music Festival 2024. Guadamur, Toledo. 22 de septiembre de 2024) Por Enrique Farelo [Concierto de jazz]","author":"Tomajazz","date":"6 octubre, 2024","format":false,"excerpt":"Calabrese-Reuter-Dowerk actuaron en el III Festival Internacional MoonJune Music Festival 2024, en Guadamur, Toledo, el 22 de septiembre de 2024. Por Enrique Farelo. Actuaron Markus Reuter, Alexander Dowerk, Luca Calabrese","rel":"","context":"En \u00abIII Festival Internacional MoonJune Music Festival 2024\u00bb","block_context":{"text":"III Festival Internacional MoonJune Music Festival 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/iii-festival-internacional-moonjune-music-festival-2024\/"},"img":{"alt_text":"Calabrese-Reuter-Dowerk  (III Festival Internacional MoonJune Music Festival 2024. Guadamur, Toledo. 22 de septiembre de 2024) Por Enrique Farelo [Concierto de jazz] - Tomajazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/01-Calabrese-Reuter-Dowerk.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/01-Calabrese-Reuter-Dowerk.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/01-Calabrese-Reuter-Dowerk.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":101158,"url":"https:\/\/tomajazz.com\/web\/markus-reuter-stefano-castagna-sky-on-the-ground-2025\/","url_meta":{"origin":93290,"position":1},"title":"Markus Reuter &#8211; Stefano Castagna: Sky on The Ground (Iapetus records 2025) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"30 octubre, 2025","format":false,"excerpt":"Sky on The Ground (Iapetus records 2025) es lo nuevo de Markus Reuter - Stefano Castagna. Enrique Farelo repasa la grabaci\u00f3n. Con Markus Reuter, Stefano Castagna, Mimmo Impiombato, Luca Calabrese, Alessandro Castagna","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"Markus Reuter - Stefano Castagna: Sky on The Ground (Iapetus records 2025) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - Sky on The Ground (Iapetus records 2025) es lo nuevo de Markus Reuter - Stefano Castagna. Enrique Farelo repasa la grabaci\u00f3n. Con Markus Reuter, Stefano Castagna, Mimmo Impiombato, Luca Calabrese, Alessandro Castagna\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Markus-Reuter-Stefano-Castagna-Sky-on-The-Ground-Iapetus-records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Markus-Reuter-Stefano-Castagna-Sky-on-The-Ground-Iapetus-records-2025-Tomajazz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Markus-Reuter-Stefano-Castagna-Sky-on-The-Ground-Iapetus-records-2025-Tomajazz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/10\/Markus-Reuter-Stefano-Castagna-Sky-on-The-Ground-Iapetus-records-2025-Tomajazz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103372,"url":"https:\/\/tomajazz.com\/web\/mark-wingfield-the-gathering-2024-vrsn-2026\/","url_meta":{"origin":93290,"position":2},"title":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"12 enero, 2026","format":false,"excerpt":"The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52877,"url":"https:\/\/tomajazz.com\/web\/markus-reuter-oculus-nothing-is-sacred-moonjune-records-2020-grabacion-de-jazz-por-enrique-farelo\/","url_meta":{"origin":93290,"position":3},"title":"Markus Reuter Oculus: Nothing Is Sacred (MoonJune Records 2020) [Grabaci\u00f3n de Jazz] Por Enrique Farelo","author":"Tomajazz","date":"9 noviembre, 2020","format":false,"excerpt":"Enrique Farelo repasa Nothing Is Sacred (MoonJune Records), de Markus Reuter Oculus.","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/11\/Markus-Reuter_Oculus.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/11\/Markus-Reuter_Oculus.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/11\/Markus-Reuter_Oculus.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/11\/Markus-Reuter_Oculus.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2020\/11\/Markus-Reuter_Oculus.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":90238,"url":"https:\/\/tomajazz.com\/web\/gary-husband-nguyen-le-moonjune-2024\/","url_meta":{"origin":93290,"position":4},"title":"Gary Husband &#038; Nguy\u00ean L\u00ea (III Festival Internacional MoonJune Music Festival 2024. Guadamur, Toledo. 22 de septiembre de 2024) Por Enrique Farelo [Concierto de jazz]","author":"Tomajazz","date":"7 octubre, 2024","format":false,"excerpt":"Gary Husband & Nguy\u00ean L\u00ea actuaron en el III Festival Internacional MoonJune Music Festival 2024, el 22 de septiembre de 2024 en Guadamur, Toledo. Enrique Farelo lo retrata y relata","rel":"","context":"En \u00abIII Festival Internacional MoonJune Music Festival 2024\u00bb","block_context":{"text":"III Festival Internacional MoonJune Music Festival 2024","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/iii-festival-internacional-moonjune-music-festival-2024\/"},"img":{"alt_text":"Gary Husband & Nguy\u00ean L\u00ea (III Festival Internacional MoonJune Music Festival 2024. Guadamur, Toledo. 22 de septiembre de 2024) Por Enrique Farelo [Concierto de jazz] - Tomajazz","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/04-Nguyen-Le-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/04-Nguyen-Le-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2024\/10\/04-Nguyen-Le-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":96409,"url":"https:\/\/tomajazz.com\/web\/leonardo-pavkovic-de-ny-a-toledo-1\/","url_meta":{"origin":93290,"position":5},"title":"Leonardo Pavkovic y la Luna de Junio (primera parte): de Nueva York a Toledo, una vida entre el jazz, el rock progresivo y la independencia\u00a0musical. Por Enrique Farelo [Entrevista de jazz]","author":"Tomajazz","date":"11 junio, 2025","format":false,"excerpt":"Descubre la historia de Leonardo Pavkovic, fundador de MoonJune Records, en esta entrevista exclusiva por Enrique Farelo realizada en 2025. Desde Nueva York hasta Toledo, un viaje vital y musical entre el jazz, el rock progresivo y la independencia creativa.","rel":"","context":"En \u00abEntrevistas...\u00bb","block_context":{"text":"Entrevistas...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/entrevistas-criticas\/"},"img":{"alt_text":"Leonardo Pavkovic y la Luna de Junio: de Nueva York a Toledo, una vida entre el jazz, el rock progresivo y la independencia\u00a0musical. Por Enrique Farelo [Entrevista de jazz] - Tomajazz - Descubre la historia de Leonardo Pavkovic, fundador de MoonJune Records, en esta entrevista exclusiva por Enrique Farelo. Desde Nueva York hasta Toledo, un viaje vital y musical entre el jazz, el rock progresivo y la independencia creativa.","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/06\/Luna-llena-luna-de-fresa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/06\/Luna-llena-luna-de-fresa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/06\/Luna-llena-luna-de-fresa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2025\/06\/Luna-llena-luna-de-fresa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/93290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=93290"}],"version-history":[{"count":1,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/93290\/revisions"}],"predecessor-version":[{"id":93292,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/93290\/revisions\/93292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/93291"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=93290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=93290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=93290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}