{"id":9449,"date":"2013-11-27T11:10:44","date_gmt":"2013-11-27T10:10:44","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=9449"},"modified":"2016-11-13T16:00:47","modified_gmt":"2016-11-13T15:00:47","slug":"marc-ducret-tower-vol-3-ayler-records-2013","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/marc-ducret-tower-vol-3-ayler-records-2013\/","title":{"rendered":"Marc Ducret: <i>Tower vol. 3<\/i> (Ayler Records, 2013)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.tomajazz.com\/web\/?attachment_id=9450\" rel=\"attachment wp-att-9450\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9450 alignleft\" alt=\"Marc Ducret Tower Vol 3\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Marc-Ducret-Tower-Vol-3.jpg\" width=\"200\" height=\"175\" title=\"\"><\/a>Con <i>Tower vol. 3<\/i> el guitarrista franc\u00e9s Marc Ducret y su nuevo grupo hace una nueva aportaci\u00f3n al ciclo de composiciones de la serie Tower que le han ocupado los \u00faltimos cuatro discos y proyectos con m\u00fasicos de diversas nacionalidades. Hasta el momento guitarra solista, cuarteto, quinteto, el sexteto reciente y una orquesta de 12 miembros, la Tower-Bridge Orchestra, que a\u00fan no ha entrado en estudio, son las formaciones con las que ha trabajo Ducret. La grabaci\u00f3n de <i>Tower vol. 3<\/i>, con todos sus miembros franceses, se ha llevado a cabo despu\u00e9s de una de las giras de la Tower-Bridge Orchestra. El ciclo comenz\u00f3 en 2008 como un proyecto que pretend\u00eda reflejar la textura musical de un cap\u00edtulo de la novela de Vladimir Nabokov <i>Ada o el Ardor<\/i>.<\/p>\n<p style=\"text-align: justify;\">Las cuatro composiciones de <i>Tower vol. 3<\/i>, con duraciones individuales que superan los diez minutos, aportan diferentes perspectivas sonoras con una poco com\u00fan formaci\u00f3n de tres trombonistas, un multipercusionista, un pianista y el propio Ducret en la guitarra el\u00e9ctrica. Como ha comentado el propio Ducret se trata de nuevas matizaciones a piezas ya anteriormente grabadas. \u201cTratamos de descubrir y diseccionar trabajos previos aparecidos en los primeros dos vol\u00famenes. Al tiempo que se remarca la v\u00eda politonal y la mezcla de una instrumentaci\u00f3n divergente, los tres trombonistas aportan importantes contrastes, as\u00ed como mayor fortaleza al grupo\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00abReal Thing #1\u201d y \u201cReal Thing #2\u201d, ya se recogieron en el primer cap\u00edtulo de la serie grabado por un quinteto franco-dan\u00e9s, donde tambi\u00e9n particip\u00f3 el trombonista Matthias Mahler. Las dos \u00faltimas composiciones, \u00abReal Thing #3\u00bb y \u00abSoftly Her Tower Crumbled in the Sweet Silent Sun,\u00bb fueron grabadas originalmente en el segundo capitulo por un cuarteto cuarteto franco-americano.<\/p>\n<p style=\"text-align: justify;\">Las piezas se caracterizan por unas construcciones tensas, donde el espacio, el tiempo y el silencio entre los trombones contrastan con la guitarra, la percusi\u00f3n y el piano. La tercera pieza es la m\u00e1s experimental de las cuatro. La que cierra el \u00e1lbum \u00abSoftly Her Tower Crumbled in the Sweet Silent Sun,\u00bb se inicia con un movimiento circular al estilo de Philip Glass o John Cage y se desarrolla con una mayor carga dram\u00e1tica que el resto, provocado por el martilleo del percusionista Sylvain Lem\u00eatre inspirandose en los sonidos de las campanas de una iglesia, y con un giro inesperado en el que la pieza adquiere un tono m\u00e1s r\u00edtmico.<\/p>\n<p style=\"text-align: justify;\">Un disco muy recomendable, en el que cada miembro del sexto aporta su personalidad y un lenguaje creativo de altos vuelos, posibilitando diferentes texturas sonoras en esta nueva apuesta experimental del m\u00e1s arriesgado y quiz\u00e1 innovador de los guitarristas actuales.<\/p>\n<p style=\"text-align: right;\">\u00a9\u00a0Carlos Lara, 2013<\/p>\n<p>Marc Ducret: <em>Tower vol. 3<\/em><\/p>\n<p>Composiciones: \u201cReal Thing #1\u201d, \u201cReal Thing #2\u201d, \u201cReal Thing #3\u201d y \u201cSoftly Her Tower Crumbled in the Sweet Silent Sun\u201d.<\/p>\n<p>M\u00fasicos: Marc Ducret (guitarra el\u00e9ctrica y composiciones), Fidel Fourneyron (tromb\u00f3n), Matthias Mahler (tromb\u00f3n), Alexis Persigan (tromb\u00f3n), Antonin Rayon (piano y celesta) y Sylvain Lem\u00eatre (vibrafono, xilof\u00f3n, marimba y percusi\u00f3n).<\/p>\n<p>Grabado el 17,18 y 19 de diciembre de 2012 en Salle Colonne de Paris.<\/p>\n<p>Editado en 2013 por Ayler Records.\u00a0AYLCD 120<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con Tower vol. 3 el guitarrista franc\u00e9s Marc Ducret y su nuevo grupo hace una nueva aportaci\u00f3n al ciclo de composiciones de la serie Tower que le han ocupado los \u00faltimos cuatro discos y proyectos con m\u00fasicos de diversas nacionalidades. Hasta el momento guitarra solista, cuarteto, quinteto, el sexteto reciente<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/marc-ducret-tower-vol-3-ayler-records-2013\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":9450,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17849,5,1038],"tags":[7855,7856,7853,84,12651,7854,12696,13,12415,15295,7529,7208,7857,16099,77,16100],"class_list":["entry","author-pachi","post-9449","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carlos-lara","category-grabaciones","category-contenidos","tag-alexis-persigan","tag-antonin-rayon","tag-ayler-rercords","tag-carlos-lara","tag-cd","tag-fidel-fourneyron","tag-grabaciones","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-marc-ducret","tag-matthias-mahler","tag-sylvain-lemetre","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/11\/Marc-Ducret-Tower-Vol-3.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2511,"url":"https:\/\/tomajazz.com\/web\/marc-ducret-tower-vol-2-ayler-records-2011\/","url_meta":{"origin":9449,"position":0},"title":"Marc Ducret: Tower vol. 2 (Ayler Records, 2011)","author":"Tomajazz","date":"6 octubre, 2011","format":false,"excerpt":"El segundo volumen del proyecto Tower de Marc Ducret se podr\u00eda decir que es una reuni\u00f3n de viejos conocidos. El guitarrista ha tocado a lo largo de su carrera en distintas formaciones con el violinista Dominique Pifar\u00e9ly. Ambos m\u00fasicos tambi\u00e9n acompa\u00f1aron, aunque con una mayor consistencia el primero que el\u2026","rel":"","context":"En \u00abGrabaciones...\u00bb","block_context":{"text":"Grabaciones...","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/textos\/grabaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/1.bp.blogspot.com\/-XJagfQgG8qk\/To4Q5K10TII\/AAAAAAAADeM\/YFTIfTvJsiw\/s200\/Ducret_tower-vol2_aylcd-119.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14556,"url":"https:\/\/tomajazz.com\/web\/21eme-festival-jazz-a-junas-y-iii-gran-ensemble-koa-shono-nils-landgren-funk-unit-junas-francia-2014-07-23\/","url_meta":{"origin":9449,"position":1},"title":"21\u00e8me Festival Jazz \u00c0 Junas (y III): Gran Ensemble Koa \/ Shono \/ Nils Landgren Funk Unit (Junas, Francia. 2014-07-23)","author":"Tomajazz","date":"13 octubre, 2014","format":false,"excerpt":"Gran Ensemble Koa Fecha: S\u00e1bado, 26 de julio de 2014 Lugar: Exteriores de Junas y Place l\u2019Avenir Componentes: Samuel Mastorakis: vibr\u00e1fono Julien Gregoire, bater\u00eda Pascal Pouvier: tromb\u00f3n Matthieu Ch\u00e9deville, saxo soprano Armel Courr\u00e9e: saxo alto J\u00e9r\u00f4me Dufour:\u00a0saxo tenor Daniel Moreau: teclados Matia L\u00e9vrero: guitarra Alfred Vilayleck: direcci\u00f3n y bajo Shono\u2026","rel":"","context":"En \u00ab*_Joan Cort\u00e8s\u00bb","block_context":{"text":"*_Joan Cort\u00e8s","link":"https:\/\/tomajazz.com\/web\/category\/joan-cortes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/01_DUET-KOA-%C2%A9Joan-Cort%C3%A8s_25jul14_Junas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/01_DUET-KOA-%C2%A9Joan-Cort%C3%A8s_25jul14_Junas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2014\/10\/01_DUET-KOA-%C2%A9Joan-Cort%C3%A8s_25jul14_Junas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103372,"url":"https:\/\/tomajazz.com\/web\/mark-wingfield-the-gathering-2024-vrsn-2026\/","url_meta":{"origin":9449,"position":2},"title":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz]","author":"Tomajazz","date":"12 enero, 2026","format":false,"excerpt":"The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"Mark Wingfield: The Gathering (MoonJune Records; 2024) Por Enrique Farelo [Grabaci\u00f3n de jazz] - Tomajazz - The Gathering (MoonJune Records; 2024) es la grabaci\u00f3n de Mark Wingfield rese\u00f1ada por Enrique Farelo. Con Mark Wingfield, Gary Husband, Asaf Sirkis, Tony Levin, Percy Jones\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/01\/Mark-Wingfield-The-Gathering-MoonJune-Records-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30596,"url":"https:\/\/tomajazz.com\/web\/rs-faktor-akufeno-errabaljazz-2016-cd\/","url_meta":{"origin":9449,"position":3},"title":"RS Faktor: Ak\u00fafeno (Errabaljazz 2016) [CD]","author":"Tomajazz","date":"17 mayo, 2017","format":false,"excerpt":"Tanto el comentario como la escucha de esta obra pueden hacerse de forma libre agrupando las composiciones por grupos; as\u00ed podr\u00edamos empezar con RS Atlantic Faktor y subdividiendo \u00e9ste, a su vez, en el que intervienen Luc\u00eda Souto y Nani Garc\u00eda (\u201cVer\u00f3nica\u201d y \u201cH\u00e9rcules Tower\u201d) o en el resto que\u2026","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/RS-Faktor_Akufeno_Errabal-Jazz_2016.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/RS-Faktor_Akufeno_Errabal-Jazz_2016.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2017\/05\/RS-Faktor_Akufeno_Errabal-Jazz_2016.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":57133,"url":"https:\/\/tomajazz.com\/web\/angel-ontalva-angel-on-a-tower-octoberxart-records-2021-grabacion-de-jazz-por-enrique-farelo\/","url_meta":{"origin":9449,"position":4},"title":"\u00c1ngel Ontalva: Angel on a Tower (OctoberXart Records, 2021) [Grabaci\u00f3n de jazz] Por Enrique Farelo","author":"Tomajazz","date":"17 septiembre, 2021","format":false,"excerpt":"Enrique Farelo rese\u00f1a Angel on a Tower (octoberXart Records, 2021) de \u00c1ngel Ontalva.","rel":"","context":"En \u00ab*_Enrique Farelo\u00bb","block_context":{"text":"*_Enrique Farelo","link":"https:\/\/tomajazz.com\/web\/category\/enrique-farelo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/Angel-Ontalva_Angel-On-A-Tower.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/Angel-Ontalva_Angel-On-A-Tower.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/Angel-Ontalva_Angel-On-A-Tower.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2021\/09\/Angel-Ontalva_Angel-On-A-Tower.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2336,"url":"https:\/\/tomajazz.com\/web\/who-the-fuck-ivory-tower-matthew-sweet-2011-0118-07052012\/","url_meta":{"origin":9449,"position":5},"title":"Who The Fuck?: \u201cIvory Tower\u201d (Matthew Sweet, 2011) [0118, 07\/05\/2012]","author":"Tomajazz","date":"6 mayo, 2012","format":false,"excerpt":"\u201cIvory Tower\u201dMatthew SweetModern ArtMissing Piece (2011)","rel":"","context":"En \u00abbun\u00bb","block_context":{"text":"bun","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/blogs\/bun\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-ETOlSEjaSV4\/T6bmKb96oMI\/AAAAAAAAEmc\/pdUVgAo3-R0\/s200\/Matthew_sweet_modern_art.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=9449"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9449\/revisions"}],"predecessor-version":[{"id":9452,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9449\/revisions\/9452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/9450"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=9449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=9449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=9449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}