{"id":9612,"date":"2013-12-11T11:20:52","date_gmt":"2013-12-11T10:20:52","guid":{"rendered":"http:\/\/www.tomajazz.com\/web\/?p=9612"},"modified":"2016-11-13T17:17:01","modified_gmt":"2016-11-13T16:17:01","slug":"xiu-xiu-nina-graveface-records-2013","status":"publish","type":"post","link":"https:\/\/tomajazz.com\/web\/xiu-xiu-nina-graveface-records-2013\/","title":{"rendered":"Xiu Xiu: <i>Nina<\/i> (Graveface Records, 2013)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.tomajazz.com\/web\/?attachment_id=9613\" rel=\"attachment wp-att-9613\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-9613\" alt=\"xiu_xiu_nina\" src=\"http:\/\/www.tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/xiu_xiu_nina.jpg\" width=\"200\" height=\"200\" title=\"\" srcset=\"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/xiu_xiu_nina.jpg 300w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/xiu_xiu_nina-150x150.jpg 150w, https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/xiu_xiu_nina-54x55.jpg 54w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>El cantante Jamie Stewart, alma m\u00e1ter del colectivo Xiu Xiu, , realiza en\u00a0<em>Nina<\/em>\u00a0un recorrido por once temas popularizados por Nina Simone\u00a0acompa\u00f1ado por una magn\u00edfica representaci\u00f3n multi-generacional de m\u00fasicos de jazz de primera l\u00ednea. Una alineaci\u00f3n de primeras figuras: Tim Berne, Mary Halvorson, Andrea Parkins y Tony Malaby, m\u00e1s el componente de las \u00faltimas encarnaciones de Xiu Xiu, el baterista Ches Smith).<\/p>\n<p style=\"text-align: justify;\">Todos los temas revisitados fueron grabados en la primera d\u00e9cada de la carrera discogr\u00e1fica de Eunice Kathleen Waymon, entre 1958 y 1967. Por tanto, aqu\u00ed no est\u00e1n las versiones de temas del pop y del rock que fueron habituales en la carrera de Nina Simone en las d\u00e9cadas posteriores.<\/p>\n<p style=\"text-align: justify;\">Esos temas son recreados por el sexteto de m\u00fasicos con aproximaciones diversas que explotan distintos matices. La magn\u00edfica voz de Jamie Stewart reivindica su capacidad interpretativa poniendo el alma al repertorio seleccionado. El quinteto acompa\u00f1ante (compuesto por dos saxos, guitarra, acorde\u00f3n y bater\u00eda) sirve de magn\u00edfico veh\u00edculo para llevar en volandas a la voz, con unos arreglos que se van variando y adapt\u00e1ndose a cada uno de los temas. La otra cara es la aproximaci\u00f3n jazz\u00edstica, que incluye prote\u00ednicos pasos por la libertad del <em>free<\/em>\u00a0o una vuelta a las reminiscencias africanas de las versiones originales.<\/p>\n<p style=\"text-align: right;\">\u00a9 Pachi Tapiz, 2013<\/p>\n<p style=\"text-align: justify;\">Xiu Xiu: <em>Nina<\/em> (Graveface Records, 2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Jamie Stewart, alma m\u00e1ter del colectivo Xiu Xiu, , realiza en\u00a0Nina\u00a0un recorrido por once temas popularizados por Nina Simone\u00a0acompa\u00f1ado por una magn\u00edfica representaci\u00f3n multi-generacional de m\u00fasicos de jazz de primera l\u00ednea. Una alineaci\u00f3n de primeras figuras: Tim Berne, Mary Halvorson, Andrea Parkins y Tony Malaby, m\u00e1s el componente<span class=\"more-link\"><a href=\"https:\/\/tomajazz.com\/web\/xiu-xiu-nina-graveface-records-2013\/\">Contin\u00faa leyendo<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":9613,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17847,5,1038],"tags":[5585,12651,5468,12696,7939,13,12415,15295,5584,7940,31,5583,16099,77,16100,649,7938],"class_list":["entry","author-pachi","post-9612","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pachi-tapiz","category-grabaciones","category-contenidos","tag-andrea-parkins","tag-cd","tag-ches-smith","tag-grabaciones","tag-graveface-records","tag-jazz","tag-jazz-en-espana","tag-jazz-en-espanol","tag-mary-halvorson","tag-nina-simone","tag-pachi-tapiz","tag-tim-berne","tag-toma-jazz","tag-tomajazz","tag-tomajazz-toma-jazz","tag-tony-malaby","tag-xiu-xiu"],"jetpack_featured_media_url":"https:\/\/tomajazz.com\/web\/wp-content\/uploads\/2013\/12\/xiu_xiu_nina.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5121,"url":"https:\/\/tomajazz.com\/web\/ches-smith-and-these-arches-hammered-clean-feed-2013\/","url_meta":{"origin":9612,"position":0},"title":"Ches Smith and These Arches: Hammered (Clean Feed, 2013)","author":"Tomajazz","date":"25 febrero, 2013","format":false,"excerpt":"En Hammered, segunda entrega del proyecto These Arches del baterista y percusionista Ches Smith, el grupo que grab\u00f3\u00a0Finally out of my Hands\u00a0se incrementa en una unidad con un componente de lujo: el saxofonista\u00a0Tim Berne. De ese modo, These Arches son en esta grabaci\u00f3n Berne, el saxofonista Tony Malaby, la guitarrista\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2013\/02\/ches-smith-and-these-arches.-Hammered-Clean-Feed-2013.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2596,"url":"https:\/\/tomajazz.com\/web\/ches-smith-and-these-arches-finally-out-of-my-hands-skirl-records-2010\/","url_meta":{"origin":9612,"position":1},"title":"Ches Smith and These Arches: Finally Out Of My Hands (Skirl Records, 2010)","author":"Tomajazz","date":"16 junio, 2011","format":false,"excerpt":"Magn\u00edfica la compa\u00f1\u00eda elegida por el baterista Ches Smith para su proyecto These Arches: la guitarrista Mary Halvorson, el saxofonista Tony Malaby, y la acordeonista, teclista y aqu\u00ed tambi\u00e9n emple\u00e1ndose en electr\u00f3nica, Andrea Parkins. Finally Out Of My Hands, su estreno discogr\u00e1fico, apenas llega a los 35 minutos de duraci\u00f3n.\u2026","rel":"","context":"En \u00abToma Jazz\u00bb","block_context":{"text":"Toma Jazz","link":"https:\/\/tomajazz.com\/web\/tag\/toma-jazz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-MgL5lqB8Pog\/TfpjgV_y0cI\/AAAAAAAAC6w\/ZEPhLF7YTUk\/s200\/ches_smith_these-arches.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":105154,"url":"https:\/\/tomajazz.com\/web\/ches-smith-clone-row-festival-jazz-terrassa-2026\/","url_meta":{"origin":9612,"position":2},"title":"Ches Smith Clone Row (45\u00e8 Festival Jazz Terrassa \/ Nova Jazz Cava, 2026-03-19 \/ Terrassa -Barcelona-) [y II] Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s]","author":"Tomajazz","date":"2 mayo, 2026","format":false,"excerpt":"Ches Smith Clone Row particip\u00f3 en el 45\u00e8 Festival Jazz Terrassa, el 19 de marzo de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ. Ches Smith Clone Row son Ches Smith, Mary Halvorson, Liberty Ellman, Nick Dunston","rel":"","context":"En \u00ab45\u00e8 Festival Jazz Terrassa 2026\u00bb","block_context":{"text":"45\u00e8 Festival Jazz Terrassa 2026","link":"https:\/\/tomajazz.com\/web\/category\/contenidos\/especial-contenidos\/45e-festival-jazz-terrassa-2026\/"},"img":{"alt_text":"Ches Smith Clone Row (45\u00e8 Festival Jazz Terrassa \/ Nova Jazz Cava, 2026-03-19 \/ Terrassa -Barcelona-) [y II]  Por Joan Cort\u00e8s [INSTANTZZ AKA Galer\u00eda fotogr\u00e1fica AKA Fotoblog de jazz, impro\u2026 y algo m\u00e1s] - Tomajazz - Ches Smith Clone Row particip\u00f3 en el 45\u00e8 Festival Jazz Terrassa, el 19 de marzo de 2026. Joan Cort\u00e8s lo retrata en INSTANTZZ. Ches Smith Clone Row son Ches Smith, Mary Halvorson, Liberty Ellman, Nick Dunston\n","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-05-Chs-Smth-Cln-Rn-Photo-by-Joan-Cortes-45FJT-NJC-Trrss.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-05-Chs-Smth-Cln-Rn-Photo-by-Joan-Cortes-45FJT-NJC-Trrss.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2026\/05\/destacada-05-Chs-Smth-Cln-Rn-Photo-by-Joan-Cortes-45FJT-NJC-Trrss.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3110,"url":"https:\/\/tomajazz.com\/web\/mary-halvorson-una-guitarrista-para-el-futuro\/","url_meta":{"origin":9612,"position":3},"title":"Mary Halvorson: una guitarrista para el futuro","author":"Tomajazz","date":"11 marzo, 2009","format":false,"excerpt":"Con menos de 30 a\u00f1os la guitarrista Mary Halvorson se ha convertido en una acompa\u00f1ante inseparable de Anthony Braxton durante los \u00faltimos a\u00f1os al igual que sucediera en la d\u00e9cada de los ochenta con la pianista Marylin Crispell. Junto al trompetista y cornetista Taylor Ho Bynum ha participado en grabaciones\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.tomajazz.com\/bun\/uploaded_images\/mary_halvorson_7513-713953.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2402,"url":"https:\/\/tomajazz.com\/web\/wish-ill-be-there-zurich-new-york-intakt-records-at-the-stone-nueva-york-1-al-15-de-marzo-de-2012\/","url_meta":{"origin":9612,"position":4},"title":"Wish I&#8217;ll Be There: Z\u00fcrich &#8211; New York. Intakt Records at the Stone (Nueva York, 1 al 15 de marzo de 2012)","author":"Tomajazz","date":"24 febrero, 2012","format":false,"excerpt":"Durante la primera quincena de marzo el sello suizo Intakt Records va a desembarcar en The Stone. El local neoyorquino albergar\u00e1 las actuaciones de distintos grupos y formaciones en las que participar\u00e1nn Fred Frith, Pierre Favre, Sylvie Courvoisier, Mark Feldman, Tim Berne, Lucas Niggli, Achille Succi, Oliver Lake, Tony Malaby,\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2012\/02\/nycjazzrecord_zh-ny_12.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18143,"url":"https:\/\/tomajazz.com\/web\/tim-bernes-snakeoil-youve-been-watching-me-ecm-2015\/","url_meta":{"origin":9612,"position":5},"title":"Tim Berne&#8217;s Snakeoil: You&#8217;ve Been Watching Me (ECM, 2015)","author":"Tomajazz","date":"23 abril, 2015","format":"image","excerpt":"He le\u00eddo unas cuantas cosas acerca de Tim Berne. No s\u00e9 si tener un sonido reconocible es algo bueno o malo. No s\u00e9 si escuchar una composici\u00f3n de\u00a0Berne y saber que lo est\u00e1s escuchando es bueno o malo. Pero estos son dos hechos cuando uno escucha los proyectos de Tim\u2026","rel":"","context":"En \u00ab*_Pachi Tapiz\u00bb","block_context":{"text":"*_Pachi Tapiz","link":"https:\/\/tomajazz.com\/web\/category\/pachi-tapiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tomajazz.com\/web\/wp-content\/uploads\/2015\/04\/Tim-Bernes-Snakeoil_Youve-Been-Watching-Me_ECM_2015.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/comments?post=9612"}],"version-history":[{"count":2,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9612\/revisions"}],"predecessor-version":[{"id":9656,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/posts\/9612\/revisions\/9656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media\/9613"}],"wp:attachment":[{"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/media?parent=9612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/categories?post=9612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tomajazz.com\/web\/wp-json\/wp\/v2\/tags?post=9612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}